{"id":4170,"date":"2026-09-02T13:05:41","date_gmt":"2026-09-02T11:05:41","guid":{"rendered":"https:\/\/www.aibi.it\/coopaibc\/?p=4170"},"modified":"2026-09-02T13:05:41","modified_gmt":"2026-09-02T11:05:41","slug":"la-famiglia-nel-bosco-verso-il-ricongiungimento-cosa-ci-insegna-questa-vicenda","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/coopaibc\/la-famiglia-nel-bosco-verso-il-ricongiungimento-cosa-ci-insegna-questa-vicenda\/","title":{"rendered":"La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda"},"content":{"rendered":"<h2>Il Tribunale dei minorenni dell&#8217;Aquila ha deciso per un graduale ritorno dei figli della \u201cfamiglia nel bosco\u201d con i loro genitori. Una storia emblematica che pu\u00f2 insegnare molte cose sui servizi sociali, il diritto dei minori e il nostro modo di approcciarci a questi argomenti<\/h2>\n<p><!--more--><\/p>\n<p>La lunga e <a href=\"https:\/\/www.aibi.it\/ita\/bambini-bosco-serena-cruz\/\">chiacchierata vicenda<\/a> della cosiddetta \u201c<strong>famiglia nel bosco<\/strong>\u201d pare arrivata a un nuovo capitolo che si spera possa gradualmente far tornare i bambini a vivere insieme ai genitori, in sicurezza. Il Tribunale dei minorenni dell&#8217;Aquila ha infatti deciso di avviare un percorso \u201ca tappe\u201d che prevede la possibilit\u00e0 che, inizialmente, <strong>i bambini tornino a casa durante il giorno<\/strong>, con il monitoraggio dei servizi sociali e, da ottobre, possano fermarsi anche a dormire, almeno durante il weekend. Un \u201csignificativo passo avanti\u201d \u2013 ha commentato il legale della coppia <strong>Simone Pillon<\/strong> \u2013 anche se il \u201cpercorso giudiziario pare ancora lontano dal necessario e auspicabile pieno ricongiungimento familiare\u201d.<\/p>\n<h3>Il superiore interesse del minore<\/h3>\n<p>Eppure, sebbene la soluzione auspicata dai genitori e dal loro avvocato non sia ancora stata raggiunta, \u00e8 indubbio che la decisione del Tribunale vada in tal senso e, soprattutto, riconosca che <strong>i genitori stanno facendo ci\u00f2 che giudici e Servizi Sociali chiedevano <\/strong>come condizione per la riunificazione con i propri figli: regolarizzare la situazione abitativa, avviare dei percorsi sanitari, collaborare con i Servizi, inserire i bambini nel sistema scolastico\u2026 In sostanza, come sottolinea un articolo di <strong>Avvenire<\/strong>, costruire quelle condizioni che erano state indicate come essenziali per poter considerare il ritorno a casa dei bambini come l\u2019<strong>opzione migliore<\/strong> per il loro futuro.<br \/>\nAl di l\u00e0 della vicenda in s\u00e9, per\u00f2, quanto successo \u2013 prosegue Avvenire &#8211; apre a riflessioni pi\u00f9 ampie riguardo la fragilit\u00e0 del sistema, nonch\u00e9 \u201c<strong>le distorsioni con cui l\u2019opinione pubblica guarda<\/strong> alla tutela dei minori\u201d. Il quotidiano della CEI elenca, dunque, cinque \u201clezioni\u201d che, a partire da quanto sollevato con la vicenda della \u201cfamiglia nel bosco\u201d, possono essere utili per un dibattito collettivo pi\u00f9 ampio.<\/p>\n<h3>Ogni caso \u00e8 a s\u00e9<\/h3>\n<p>Innanzitutto, \u00e8 doveroso tenere in considerazione il fatto che <strong>un caso specifico non \u00e8 \u201cil sistema\u201d.<\/strong> Per mesi si \u00e8 discusso di una singola storia quando i dati dicono che i minori fuori famiglia sono circa <strong>31mila<\/strong>, divisi quasi equamente tra chi \u00e8 in comunit\u00e0 e chi \u00e8 in affido. Dietro a ciascuno di questi casi c\u2019\u00e8 una storia specifica; ci sono traumi e vicende dolorose che rimangono lontane dai riflettori. Prendere un singolo caso per riflettere sull\u2019intero sistema \u00e8 un errore, che, in pi\u00f9, finisce inevitabilmente per <strong>polarizzare la discussione<\/strong> e formare degli schieramenti, attribuendo alla vicenda un valore che non pu\u00f2 avere e facendo smettere di \u201cinterrogarsi su tutto ci\u00f2 che resta invisibile\u201d.<\/p>\n<h3>Stringere i tempi<\/h3>\n<p>La seconda lezione \u00e8 che, nonostante quello che dica il diritto, ovvero che al centro ci debba essere sempre il \u201c<strong>superiore interesse dei minori<\/strong>\u201d, questa vicenda ha mostrato come il dibattito sia quasi sempre incentrato sul <strong>punto di vista dei genitori<\/strong>. Eppure, per un adulto qualche settimana di tempo pu\u00f2 essere, nel complesso, un tempo trascurabile, mentre per un minore costituisce una \u201cparte significativa della propria crescita\u201d. Da qui la necessit\u00e0 non solo di utilizzare prudenza in ogni decisione che si prende, ma anche <strong>cercare di essere il pi\u00f9 possibile rapidi<\/strong>: \u201cil tempo dell\u2019infanzia non coincide con quello dei procedimenti giudiziari\u201d.<\/p>\n<h3>Evitare le battaglie ideologiche<\/h3>\n<p>La terza lezione richiama in un certo senso la prima: fare della tutela minorile (e per di pi\u00f9 di un singolo caso) il campo per una <strong>battaglia ideologica<\/strong> \u00e8 un errore grossolano che, ancora una volta, finisce per penalizzare chi \u201crimane in mezzo\u201d, ovvero i bambini. \u00c8 evidente come, fin da subito, la vicenda della \u201cfamiglia nel bosco\u201d sia diventata il terreno per un duello di posizione, per un <strong>attacco generalizzato all\u2019operato dei giudici <\/strong>piuttosto che una <strong>difesa a spada tratta delle decisioni dei servizi<\/strong>. Questa polarizzazione non fa bene a nessuno, meno che mai a tutti i bambini che sono lontani dalle loro famiglie.<\/p>\n<h3>La decisione finale \u00e8 solo la punta di un iceberg<\/h3>\n<p>La quarta lezione \u00e8 proprio sul <strong>funzionamento sei Servizi Sociali<\/strong>: quanto accaduto ha mostrato come il dibattito si sia acceso nel momento della \u201cdecisione finale\u201d sei Servizi, ovvero l\u2019allontanamento dei minori. Ma, prima, sono venuti mesi e mesi di lavoro, monitoraggio, richieste, interventi educativi\u2026 Come sottolinea <strong>Avvenire<\/strong>: \u201cQuando si arriva alla limitazione della responsabilit\u00e0 genitoriale significa che, secondo la valutazione dei giudici, <strong>gli strumenti meno invasivi non sono stati sufficienti<\/strong>\u201d.<br \/>\nCon questo non si vuole dire che il sistema sia infallibile, ma che, ancora una volta, un singolo caso, preso a partire dalla decisione \u201cfinale\u201d di un percorso, non possa in alcun modo trasformarsi in una \u201cdelegittimazione indiscriminata di magistrati, assistenti sociali, psicologi ed educatori\u201d.<\/p>\n<h3>Cambiare si pu\u00f2<\/h3>\n<p>Infine, la quinta lezione ci dice che \u201cil cambiamento \u00e8 possibile\u201d. Se per mesi ci si \u00e8 accaniti tra l\u2019immagine di una famiglia perseguitata e quella di due genitori incapaci di cambiare il loro stile di vita per il bene dei bambini, la decisione del Tribunale ha invece mostrato che <strong>un percorso pi\u00f9 graduale di cambiamento \u00e8 possibile<\/strong>. \u00c8 possibile, per\u00f2, solo se le istituzioni coinvolte, dalla magistratura ai genitori, lavorano affinch\u00e9 \u201ci bambini possano tornare a crescere in un contesto ritenuto adeguato. Collaborando tra loro, non facendosi la guerra!\u201d<br \/>\nPerch\u00e9 bisogna ricordare, come detto, che per una vicenda che, si spera, si avvia verso la conclusione, ce ne sono migliaia di altre che cercano la loro soluzione lontano dei riflettori.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Tribunale dei minorenni dell&rsquo;Aquila ha deciso per un graduale ritorno dei figli della &ldquo;famiglia nel bosco&rdquo; con i loro genitori. Una storia emblematica che pu&ograve; insegnare molte cose sui servizi sociali, il diritto dei minori e il nostro modo di approcciarci a questi argomenti<\/p>\n","protected":false},"author":10,"featured_media":4171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11],"class_list":{"0":"post-4170","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"tag-famiglia"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda\" \/>\n<meta property=\"og:description\" content=\"Il Tribunale dei minorenni dell&rsquo;Aquila ha deciso per un graduale ritorno dei figli della &ldquo;famiglia nel bosco&rdquo; con i loro genitori. Una storia emblematica che pu&ograve; insegnare molte cose sui servizi sociali, il diritto dei minori e il nostro modo di approcciarci a questi argomenti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/\" \/>\n<meta property=\"og:site_name\" content=\"AIBC\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T11:05:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2026\/09\/famiglia-nel-bosco-ricongiungimento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francescoE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"francescoE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/la-famiglia-nel-bosco-verso-il-ricongiungimento-cosa-ci-insegna-questa-vicenda\/\"},\"author\":{\"name\":\"francescoE\",\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/#\/schema\/person\/29ad36869e080d9e3fe4cf7707235543\"},\"headline\":\"La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda\",\"datePublished\":\"2026-09-02T11:05:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/la-famiglia-nel-bosco-verso-il-ricongiungimento-cosa-ci-insegna-questa-vicenda\/\"},\"wordCount\":906,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2026\/09\/famiglia-nel-bosco-ricongiungimento.jpg\",\"keywords\":[\"famiglia\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/la-famiglia-nel-bosco-verso-il-ricongiungimento-cosa-ci-insegna-questa-vicenda\/\",\"url\":\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/\",\"name\":\"La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda\",\"isPartOf\":{\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2026\/09\/famiglia-nel-bosco-ricongiungimento.jpg\",\"datePublished\":\"2026-09-02T11:05:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#primaryimage\",\"url\":\"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2026\/09\/famiglia-nel-bosco-ricongiungimento.jpg\",\"contentUrl\":\"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2026\/09\/famiglia-nel-bosco-ricongiungimento.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.aibi.it\/coopaibc\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/#website\",\"url\":\"https:\/\/www.aibi.it\/coopaibc\/\",\"name\":\"AIBC\",\"description\":\"Cooperativa Sociale\",\"publisher\":{\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.aibi.it\/coopaibc\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/#organization\",\"name\":\"AIBC\",\"url\":\"https:\/\/www.aibi.it\/coopaibc\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2016\/11\/cropped-logo-aibc-arancio-neg-150-1.png\",\"contentUrl\":\"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2016\/11\/cropped-logo-aibc-arancio-neg-150-1.png\",\"width\":150,\"height\":88,\"caption\":\"AIBC\"},\"image\":{\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/#\/schema\/person\/29ad36869e080d9e3fe4cf7707235543\",\"name\":\"francescoE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.aibi.it\/coopaibc\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eb25bc3259115f3cc20fd1978e06816ae94cd44934e33996da7a734be3641d43?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eb25bc3259115f3cc20fd1978e06816ae94cd44934e33996da7a734be3641d43?s=96&d=mm&r=g\",\"caption\":\"francescoE\"},\"url\":\"https:\/\/www.aibi.it\/coopaibc\/author\/francescoe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"it_IT","og_type":"article","og_title":"La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda","og_description":"Il Tribunale dei minorenni dell&rsquo;Aquila ha deciso per un graduale ritorno dei figli della &ldquo;famiglia nel bosco&rdquo; con i loro genitori. Una storia emblematica che pu&ograve; insegnare molte cose sui servizi sociali, il diritto dei minori e il nostro modo di approcciarci a questi argomenti","og_url":"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/","og_site_name":"AIBC","article_published_time":"2026-09-02T11:05:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2026\/09\/famiglia-nel-bosco-ricongiungimento.jpg","type":"image\/jpeg"}],"author":"francescoE","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"francescoE","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/coopaibc\/la-famiglia-nel-bosco-verso-il-ricongiungimento-cosa-ci-insegna-questa-vicenda\/"},"author":{"name":"francescoE","@id":"https:\/\/www.aibi.it\/coopaibc\/#\/schema\/person\/29ad36869e080d9e3fe4cf7707235543"},"headline":"La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda","datePublished":"2026-09-02T11:05:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/coopaibc\/la-famiglia-nel-bosco-verso-il-ricongiungimento-cosa-ci-insegna-questa-vicenda\/"},"wordCount":906,"commentCount":0,"publisher":{"@id":"https:\/\/www.aibi.it\/coopaibc\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2026\/09\/famiglia-nel-bosco-ricongiungimento.jpg","keywords":["famiglia"],"articleSection":["News"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/coopaibc\/la-famiglia-nel-bosco-verso-il-ricongiungimento-cosa-ci-insegna-questa-vicenda\/","url":"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/","name":"La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda","isPartOf":{"@id":"https:\/\/www.aibi.it\/coopaibc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2026\/09\/famiglia-nel-bosco-ricongiungimento.jpg","datePublished":"2026-09-02T11:05:41+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#primaryimage","url":"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2026\/09\/famiglia-nel-bosco-ricongiungimento.jpg","contentUrl":"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2026\/09\/famiglia-nel-bosco-ricongiungimento.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/famiglia-nel-bosco-ricongiungimento-insegna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/coopaibc\/"},{"@type":"ListItem","position":2,"name":"La famiglia nel bosco verso il ricongiungimento. Cosa ci insegna questa vicenda"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/coopaibc\/#website","url":"https:\/\/www.aibi.it\/coopaibc\/","name":"AIBC","description":"Cooperativa Sociale","publisher":{"@id":"https:\/\/www.aibi.it\/coopaibc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/coopaibc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/coopaibc\/#organization","name":"AIBC","url":"https:\/\/www.aibi.it\/coopaibc\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/coopaibc\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2016\/11\/cropped-logo-aibc-arancio-neg-150-1.png","contentUrl":"https:\/\/www.aibi.it\/coopaibc\/wp-content\/uploads\/2016\/11\/cropped-logo-aibc-arancio-neg-150-1.png","width":150,"height":88,"caption":"AIBC"},"image":{"@id":"https:\/\/www.aibi.it\/coopaibc\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.aibi.it\/coopaibc\/#\/schema\/person\/29ad36869e080d9e3fe4cf7707235543","name":"francescoE","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/coopaibc\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eb25bc3259115f3cc20fd1978e06816ae94cd44934e33996da7a734be3641d43?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb25bc3259115f3cc20fd1978e06816ae94cd44934e33996da7a734be3641d43?s=96&d=mm&r=g","caption":"francescoE"},"url":"https:\/\/www.aibi.it\/coopaibc\/author\/francescoe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/posts\/4170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/comments?post=4170"}],"version-history":[{"count":1,"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/posts\/4170\/revisions"}],"predecessor-version":[{"id":4172,"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/posts\/4170\/revisions\/4172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/media\/4171"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/media?parent=4170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/categories?post=4170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/coopaibc\/wp-json\/wp\/v2\/tags?post=4170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}