﻿


{"id":192951,"date":"2021-10-11T15:07:53","date_gmt":"2021-10-11T13:07:53","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?page_id=192951"},"modified":"2021-10-29T15:57:58","modified_gmt":"2021-10-29T13:57:58","slug":"test-sad-italia","status":"publish","type":"page","link":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/","title":{"rendered":"Adozione a Distanza in Italia"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css=&#8221;.vc_custom_1634572810132{padding-top: 0px !important;padding-right: 2% !important;padding-bottom: 0px !important;padding-left: 2% !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column][vc_gallery interval=&#8221;3&#8243; images=&#8221;193738&#8243; img_size=&#8221;large&#8221; onclick=&#8221;&#8221; el_class=&#8221;shadow&#8221;][vc_custom_heading text=&#8221;Perch\u00e8 Adottare a Distanza in Italia&#8221; font_container=&#8221;tag:h2|font_size:40|text_align:left|color:%23ee7d0c&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_column_text]Ai.Bi. supporta l\u2019infanzia abbandonata in Italia,\u00a0 le attivit\u00e0 di Adozione a Distanza sono rivolte alla tutela e protezione dei bambini in grave difficolt\u00e0 familiare.<\/p>\n<p>Le campagne\u00a0 di raccolta fondi <strong>Pan di Zucchero<\/strong> e<strong> Fame di Mamma<\/strong> sono a sostegno delle strutture che ospitano i bambini con le loro madri e gli adolescenti in necessita.[\/vc_column_text][vc_row_inner equal_height=&#8221;yes&#8221; gap=&#8221;10&#8243; disable_element=&#8221;yes&#8221;][vc_column_inner width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1634802794639{border-top-width: 3px !important;border-right-width: 3px !important;border-bottom-width: 3px !important;border-left-width: 3px !important;padding-bottom: 3px !important;background-color: #f9f9f9 !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;border-top-color: #ffffff !important;border-top-style: solid !important;border-bottom-color: #ffffff !important;border-bottom-style: solid !important;border-radius: 25px !important;}&#8221;][vc_custom_heading text=&#8221;In Kenya grazie al tuo aiuto sar\u00e0 possibile garantire:&#8221; font_container=&#8221;tag:h2|font_size:40|text_align:left|color:%23ee7d0c&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_custom_heading text=&#8221;Alimentazione&#8221; font_container=&#8221;tag:h4|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;193296&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_border_circle_2&#8243; border_color=&#8221;white&#8221; css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1634810023807{margin-top: 20px !important;margin-bottom: 20px !important;padding-right: 80px !important;padding-left: 80px !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1634571321024{border-top-width: 3px !important;border-right-width: 3px !important;border-bottom-width: 3px !important;border-left-width: 3px !important;background-color: #f9f9f9 !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;border-top-color: #ffffff !important;border-top-style: solid !important;border-bottom-color: #ffffff !important;border-bottom-style: solid !important;border-radius: 25px !important;}&#8221;][vc_custom_heading text=&#8221;Acqua potabile&#8221; font_container=&#8221;tag:h4|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;189108&#8243; img_size=&#8221;&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_border_circle_2&#8243; border_color=&#8221;white&#8221; css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1624555672059{margin-top: 20px !important;margin-bottom: 20px !important;padding-right: 80px !important;padding-left: 80px !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1634571343179{border-top-width: 3px !important;border-right-width: 3px !important;border-bottom-width: 3px !important;border-left-width: 3px !important;background-color: #f9f9f9 !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;border-top-color: #ffffff !important;border-top-style: solid !important;border-bottom-color: #ffffff !important;border-bottom-style: solid !important;border-radius: 25px !important;}&#8221;][vc_custom_heading text=&#8221;Un letto su cui dormire&#8221; font_container=&#8221;tag:h4|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;193298&#8243; img_size=&#8221;&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_border_circle_2&#8243; border_color=&#8221;white&#8221; css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1634810077317{margin-top: 20px !important;margin-bottom: 20px !important;padding-right: 80px !important;padding-left: 80px !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1634571355995{border-top-width: 3px !important;border-right-width: 3px !important;border-bottom-width: 3px !important;border-left-width: 3px !important;background-color: #f9f9f9 !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;border-top-color: #ffffff !important;border-top-style: solid !important;border-bottom-color: #ffffff !important;border-bottom-style: solid !important;border-radius: 25px !important;}&#8221;][vc_custom_heading text=&#8221;Vestiario&#8221; font_container=&#8221;tag:h4|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;189063&#8243; img_size=&#8221;&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_border_circle_2&#8243; border_color=&#8221;white&#8221; css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1624555702300{margin-top: 20px !important;margin-bottom: 20px !important;padding-right: 80px !important;padding-left: 80px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; gap=&#8221;10&#8243; disable_element=&#8221;yes&#8221;][vc_column_inner width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1634571329788{border-top-width: 3px !important;border-right-width: 3px !important;border-bottom-width: 3px !important;border-left-width: 3px !important;padding-bottom: 3px !important;background-color: #f9f9f9 !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;border-top-color: #ffffff !important;border-top-style: solid !important;border-bottom-color: #ffffff !important;border-bottom-style: solid !important;border-radius: 25px !important;}&#8221;][vc_custom_heading text=&#8221;Cure mediche&#8221; font_container=&#8221;tag:h4|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;193299&#8243; img_size=&#8221;&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_border_circle_2&#8243; border_color=&#8221;white&#8221; css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1634810185706{margin-top: 20px !important;margin-bottom: 20px !important;padding-right: 80px !important;padding-left: 80px !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1634571321024{border-top-width: 3px !important;border-right-width: 3px !important;border-bottom-width: 3px !important;border-left-width: 3px !important;background-color: #f9f9f9 !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;border-top-color: #ffffff !important;border-top-style: solid !important;border-bottom-color: #ffffff !important;border-bottom-style: solid !important;border-radius: 25px !important;}&#8221;][vc_custom_heading text=&#8221;Scuola&#8221; font_container=&#8221;tag:h4|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;193300&#8243; img_size=&#8221;&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_border_circle_2&#8243; border_color=&#8221;white&#8221; css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1634810217443{margin-top: 20px !important;margin-bottom: 20px !important;padding-right: 80px !important;padding-left: 80px !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1634571343179{border-top-width: 3px !important;border-right-width: 3px !important;border-bottom-width: 3px !important;border-left-width: 3px !important;background-color: #f9f9f9 !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;border-top-color: #ffffff !important;border-top-style: solid !important;border-bottom-color: #ffffff !important;border-bottom-style: solid !important;border-radius: 25px !important;}&#8221;][vc_custom_heading text=&#8221;Gioco&#8221; font_container=&#8221;tag:h4|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;193301&#8243; img_size=&#8221;&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_border_circle_2&#8243; border_color=&#8221;white&#8221; css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1634810252521{margin-top: 20px !important;margin-bottom: 20px !important;padding-right: 80px !important;padding-left: 80px !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243; css=&#8221;.vc_custom_1634571355995{border-top-width: 3px !important;border-right-width: 3px !important;border-bottom-width: 3px !important;border-left-width: 3px !important;background-color: #f9f9f9 !important;border-left-color: #ffffff !important;border-left-style: solid !important;border-right-color: #ffffff !important;border-right-style: solid !important;border-top-color: #ffffff !important;border-top-style: solid !important;border-bottom-color: #ffffff !important;border-bottom-style: solid !important;border-radius: 25px !important;}&#8221;][vc_custom_heading text=&#8221;Reinserimento in famiglia&#8221; font_container=&#8221;tag:h4|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_single_image image=&#8221;193302&#8243; img_size=&#8221;&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_border_circle_2&#8243; border_color=&#8221;white&#8221; css_animation=&#8221;none&#8221; css=&#8221;.vc_custom_1634810285528{margin-top: 20px !important;margin-bottom: 20px !important;padding-right: 80px !important;padding-left: 80px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1573665055921{background-color: #ffffff !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Adotta a Distanza i Bambini in Italia&#8221; font_container=&#8221;tag:h2|font_size:40|text_align:left|color:%23ee7d0c&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_tta_tabs shape=&#8221;round&#8221; color=&#8221;sky&#8221; spacing=&#8221;5&#8243; active_section=&#8221;1&#8243;][vc_tta_section i_icon_fontawesome=&#8221;fas fa-home&#8221; add_icon=&#8221;true&#8221; title=&#8221;Progetto Fame di Mamma&#8221; tab_id=&#8221;fame-di-mamma&#8221; el_class=&#8221;shadow&#8221;][vc_row_inner][vc_column_inner][vc_column_text]\n<h3>Sostegno a &#8220;Fame di Mamma&#8221;: Italia<\/h3>\n<p><em>Casa, cura, protezione, ascolto, comprensione, supporto, fiducia:<\/em> di questo hanno bisogno i bambini, gli adolescenti fuori famiglia e le mamme che, rese fragili da maltrattamenti, malattie, povert\u00e0, rischiano di abbandonare i loro figli.<\/p>\n<p><em>E questo \u00e8 quello che assicuriamo aprendo le nostre braccia 24 ore su 24<\/em>.<\/p>\n<div class=\"wpz-sc-box normal   \">\n<p style=\"font-weight: 400;\"><strong>Fame di Mamma<\/strong> \u00e8 la campagna di Ai.Bi. e della Cooperativa AIBC per dire basta all&#8217;abbandono in Italia: i bisogni vitali di un bambino, specie se abbandonato, mettono in risalto la necessit\u00e0 di un nutrimento non soltanto fisico, bens\u00ec interiore e affettivo, una vera e propria \u201c<b>Fame di Mamma<\/b>\u201d.<\/p>\n<p style=\"font-weight: 400;\">La Campagna sostiene tutte le nostre strutture di accoglienza in Italia.<\/p>\n<\/div>[\/vc_column_text][vc_toggle title=&#8221;Comunit\u00e0 e Alloggi Mamma-Bambino&#8221; style=&#8221;round&#8221;]<div class=\"wpz-sc-box normal   \">\n<h3><strong>\u201cFamily House\u201d \u2013 Clinica per la cura dell\u2019abbandono\u00a0<\/strong><\/h3>\n<p>La prima struttura in Italia ad alta specializzazione in grado di fornire servizi a 360\u00b0 sull\u2019abbandono e sull\u2019accoglienza. Un luogo che mette al centro la salute del cuore e dell\u2019anima del bambino e della famiglia in difficolt\u00e0 e dove mamme e bambini vulnerabili trovano una casa, ascolto e protezione. La struttura ospita:<\/p>\n<p>1 Culla per la Vita\u00a0<strong>\u201cLa Chioccia<\/strong>\u201c\/ 2 Comunit\u00e0 Mamma \u2013 Bambino \u201c<strong>Casa Irene\u201d<\/strong>\u00a0e \u201c<strong>Casa Caterina\u201d<\/strong>\u00a0\/ 2 Appartamento di Semi Autonomia\u00a0<strong>\u201cCasa Angela\u201d<\/strong>\u00a0e\u00a0<strong>\u201cCasa Aurora\u201d<\/strong>\/ 1 Appartamento di Alta Autonomia\u00a0<strong>\u201cCasa Gioia\u201d<\/strong>\/ 1 Spazio Neutro\u00a0<strong>\u201cBeniamino\u201d<\/strong><\/div>\n<div class=\"wpz-sc-box normal   \">\n<h3><strong>La Tua Casa<\/strong><\/h3>\n<p>Da bene confiscato alla \u2018ndrangheta a sistema integrato di accoglienza<strong>\u00a0<\/strong>che accompagna le madri in difficolt\u00e0 ad acquisire e rafforzare le competenze genitoriali e la propria sicurezza per essere donne e madri pi\u00f9 consapevoli, forti e autonome, per s\u00e9 e per i propri figli.\u00a0<strong>La Tua Casa<\/strong>, ospita al suo interno una comunit\u00e0 mamma-bambino,\u00a0<strong>Casa Tina<\/strong>, che accoglie fino a 5 mamme in situazione di rischio insieme ai propri figlie, e due appartamenti di alta autonomia,\u00a0<strong>Casa Giuditta\u00a0<\/strong>e<strong>\u00a0Casa Maria<\/strong>, che accolgono 3 mamme con bambini pronte ad intraprendere la strada per \u00a0l\u2019autonomia.<\/p>\n<\/div>\n<div class=\"wpz-sc-box normal   \">\n<h3><strong>Il Bocciolo<\/strong><\/h3>\n<p>C\u2019\u00e8 uno spazio in cui ogni donna pu\u00f2 rifiorire come donna e come madre: \u00e8<strong>\u00a0Il Bocciolo<\/strong><strong>.\u00a0<\/strong>Un luogo sicuro per tutte le donne che hanno subito abusi e\/o violenza\u00a0 e che hanno bisogno di essere sostenute per \u201cripartire\u201d con pi\u00f9 energia e autonomia. Un appartamento ad alta autonomia che accoglie fino a 3 mamme con bambini con l\u2019obiettivo di prevenire l\u2019abbandono e sostenere la maternit\u00e0 attraverso il mantenimento ed il sostegno della relazione mamma-bambino.<\/p>\n<\/div>\n<div class=\"wpz-sc-box normal   \">\n<h3><strong>Il Bocciolo<\/strong><\/h3>\n<p>C\u2019\u00e8 uno spazio in cui ogni donna pu\u00f2 rifiorire come donna e come madre: \u00e8<strong>\u00a0Il Bocciolo<\/strong><strong>.\u00a0<\/strong>Un luogo sicuro per tutte le donne che hanno subito abusi e\/o violenza\u00a0 e che hanno bisogno di essere sostenute per \u201cripartire\u201d con pi\u00f9 energia e autonomia. Un appartamento ad alta autonomia che accoglie fino a 3 mamme con bambini con l\u2019obiettivo di prevenire l\u2019abbandono e sostenere la maternit\u00e0 attraverso il mantenimento ed il sostegno della relazione mamma-bambino.<\/p>\n<\/div>[\/vc_toggle][vc_toggle title=&#8221;Comunit\u00e0 e Alloggi per Giovani&#8221; style=&#8221;round&#8221;]<div class=\"wpz-sc-box normal   \">\n<h3>Casa Pinocchio<\/h3>\n<p><em>Fragilit\u00e0<\/em>. \u00c8 questo l\u2019elemento che accomuna tutti gli adolescenti e giovani, privi della sicurezza e dell\u2019amore che solo una famiglia pu\u00f2 assicurare. Ispirata al mondo delle favole e al burattino nato dalla penna di Collodi,<strong>\u00a0Casa Pinocchio<\/strong>\u00a0\u00e8 un luogo di passaggio per 8 ragazzi fuori famiglia, italiani e stranieri non accompagnati, che hanno bisogno di un breve periodo di tempo per sedimentare il loro vissuto, per poi passare ad essere accolti in una famiglia che temporaneamente possa prendersi cura di loro e accompagnarli all\u2019et\u00e0 adulta.<\/p>\n<\/div>\n<div class=\"wpz-sc-box normal   \">\n<h3>Casa Francesco<\/h3>\n<p>Dedicata ai giovani neo maggiorenni che vivono fuori dalle loro famiglie di origine\u00a0<em>(Careleaver),<\/em>\u00a0<strong>Casa Francesco<\/strong>\u00a0\u00e8 un appartamento tutelato dove intraprendere un percorso di progressiva indipendenza e passaggio all\u2019et\u00e0 adulta. Un servizio dove poter vivere un\u2019esperienza educativa che permette loro di imparare a gestire una casa, organizzare il proprio tempo, in funzione del lavoro o dello studio, e gestire le proprie risorse economiche, sotto la supervisione di una figura educativa di riferimento.<\/p>\n<\/div>\n<div class=\"wpz-sc-box normal   \">\n<h3>Casa Giuseppe<\/h3>\n<p>Dedicata ai giovani neo maggiorenni che vivono fuori dalle loro famiglie di origine\u00a0<em>(Careleaver),<\/em>\u00a0<strong>Casa Giuseppe<\/strong>\u00a0\u00e8 un appartamento tutelato dove intraprendere un percorso di progressiva indipendenza e passaggio all\u2019et\u00e0 adulta. Un servizio dove poter vivere un\u2019esperienza educativa che permette loro di imparare a gestire una casa, organizzare il proprio tempo, in funzione del lavoro o dello studio, e gestire le proprie risorse economiche, sotto la supervisione di una figura educativa di riferimento.<\/p>\n<\/div>[\/vc_toggle][vc_toggle title=&#8221;Comunit\u00e0 Familiari&#8221; style=&#8221;round&#8221;]<div class=\"wpz-sc-box normal   \">\n<h3><strong>\u201cFamily House\u201d \u2013 Clinica per la cura dell\u2019abbandono\u00a0<\/strong><\/h3>\n<p>La prima struttura in Italia ad alta specializzazione in grado di fornire servizi a 360\u00b0 sull\u2019abbandono e sull\u2019accoglienza. Un luogo che mette al centro la salute del cuore e dell\u2019anima del bambino e della famiglia in difficolt\u00e0 e dove mamme e bambini vulnerabili trovano una casa, ascolto e protezione. La struttura ospita:<\/p>\n<p>1 Culla per la Vita\u00a0<strong>\u201cLa Chioccia<\/strong>\u201c\/ 2 Comunit\u00e0 Mamma \u2013 Bambino \u201c<strong>Casa Irene\u201d<\/strong>\u00a0e \u201c<strong>Casa Caterina\u201d<\/strong>\u00a0\/ 2 Appartamento di Semi Autonomia\u00a0<strong>\u201cCasa Angela\u201d<\/strong>\u00a0e\u00a0<strong>\u201cCasa Aurora\u201d<\/strong>\/ 1 Appartamento di Alta Autonomia\u00a0<strong>\u201cCasa Gioia\u201d<\/strong>\/ 1 Spazio Neutro\u00a0<strong>\u201cBeniamino\u201d<\/strong><\/div>\n<div class=\"wpz-sc-box normal   \">\n<h3><strong>La Tua Casa<\/strong><\/h3>\n<p>Da bene confiscato alla \u2018ndrangheta a sistema integrato di accoglienza<strong>\u00a0<\/strong>che accompagna le madri in difficolt\u00e0 ad acquisire e rafforzare le competenze genitoriali e la propria sicurezza per essere donne e madri pi\u00f9 consapevoli, forti e autonome, per s\u00e9 e per i propri figli.\u00a0<strong>La Tua Casa<\/strong>, ospita al suo interno una comunit\u00e0 mamma-bambino,\u00a0<strong>Casa Tina<\/strong>, che accoglie fino a 5 mamme in situazione di rischio insieme ai propri figlie, e due appartamenti di alta autonomia,\u00a0<strong>Casa Giuditta\u00a0<\/strong>e<strong>\u00a0Casa Maria<\/strong>, che accolgono 3 mamme con bambini pronte ad intraprendere la strada per \u00a0l\u2019autonomia.<\/p>\n<\/div>\n<div class=\"wpz-sc-box normal   \">\n<h3><strong>Il Bocciolo<\/strong><\/h3>\n<p>C\u2019\u00e8 uno spazio in cui ogni donna pu\u00f2 rifiorire come donna e come madre: \u00e8<strong>\u00a0Il Bocciolo<\/strong><strong>.\u00a0<\/strong>Un luogo sicuro per tutte le donne che hanno subito abusi e\/o violenza\u00a0 e che hanno bisogno di essere sostenute per \u201cripartire\u201d con pi\u00f9 energia e autonomia. Un appartamento ad alta autonomia che accoglie fino a 3 mamme con bambini con l\u2019obiettivo di prevenire l\u2019abbandono e sostenere la maternit\u00e0 attraverso il mantenimento ed il sostegno della relazione mamma-bambino.<\/p>\n<\/div>\n<div class=\"wpz-sc-box normal   \">\n<h3><strong>Il Bocciolo<\/strong><\/h3>\n<p>C\u2019\u00e8 uno spazio in cui ogni donna pu\u00f2 rifiorire come donna e come madre: \u00e8<strong>\u00a0Il Bocciolo<\/strong><strong>.\u00a0<\/strong>Un luogo sicuro per tutte le donne che hanno subito abusi e\/o violenza\u00a0 e che hanno bisogno di essere sostenute per \u201cripartire\u201d con pi\u00f9 energia e autonomia. Un appartamento ad alta autonomia che accoglie fino a 3 mamme con bambini con l\u2019obiettivo di prevenire l\u2019abbandono e sostenere la maternit\u00e0 attraverso il mantenimento ed il sostegno della relazione mamma-bambino.<\/p>\n<\/div>[\/vc_toggle]\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/?scelta=25&amp;progetto=Italia\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n[\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;fas fa-home&#8221; add_icon=&#8221;true&#8221; title=&#8221;Progetto Pan di Zucchero&#8221; tab_id=&#8221;pan-di-zucchero&#8221; el_class=&#8221;shadow&#8221;][vc_row_inner][vc_column_inner][vc_column_text]\n<h3>Sostegno a &#8220;Pan di Zucchero&#8221;: Italia<\/h3>\n<p><strong>Cosa sono<\/strong><\/p>\n<p>Nato dall\u2019intuizione francese delle \u201c<strong>Les Pates au beurre<\/strong>\u201d, spazi di supporto socio-psico-pedagogico con la \u201ccucina\u201d quale principale luogo di relazione e dialogo tra famiglie e operatori, \u201c<strong>I Pan di Zucchero<\/strong>\u201d valorizzano il concetto di\u00a0\u201crelazione\u201d: operatori e volontari si mettono in ascolto di bambini, adolescenti e famiglie, dando vita a spazi nei quali potersi raccontare liberamente e sostenersi reciprocamente.<\/p>\n<p><strong>Come operano<\/strong><\/p>\n<p>Dislocati su tutto\u00a0il territorio nazionale, i Pan di Zucchero \u201cCentri Servizi alla Famiglia\u201d nascono oltre 10 anni fa come spazi gratuiti di formazione, accompagnamento, incontro, ascolto e sostegno a famiglie e minori gestiti da figure educative, professionisti, volontari e famiglie del movimento di Ai.Bi.<\/p>\n<p>I Pan di Zucchero rafforzano il sistema di inclusione sociale e di welfare locale, contrastano la povert\u00e0 relazionale ed educativa di bambini e adolescenti a rischio di povert\u00e0 e marginalit\u00e0 sociale, e delle loro famiglie.<\/p>\n<p>Dinanzi alle restrizioni imposte dalle misure di prevenzione da covid19 i Pan di Zucchero si sono reinventati offrendo, attraverso il FARIS &#8211; Family Relationship International School, anche spazi e servizi online pur di stare al fianco dei bambini che, gi\u00e0 fragili, sono stati i pi\u00f9 esposti alle conseguenze dell\u2019isolamento.<\/p>\n<p><strong>Cosa offrono<\/strong><\/p>\n<p>Sostegno educativo, laboratori e attivit\u00e0 ricreative per bambini e adolescenti, aiuto compiti e supporto scolastico per bambini con difficolt\u00e0 di apprendimento;<\/p>\n<p>Counseling socio-psico-pedagogico, individuale e di gruppo in presenza e da remoto dedicato a famiglie e adolescenti in difficolt\u00e0;<\/p>\n<p>Consulenze legali, psicologiche, pediatriche e di supporto ai genitori o alle figure adulte di riferimento dei bambini in presenza<\/p>\n<p>Spazi di crescita e opportunit\u00e0 di costruire relazioni<\/p>\n<p>Percorsi di formazione e orientamento professionale<\/p>\n<p>Supporto materiale alle famiglie in difficolt\u00e0 economica attraverso la distribuzione di social card per l\u2019acquisto di materiale educativo e bene di necessit\u00e0<\/p>\n<p>Formazione e accompagnamento delle famiglie accoglienti, affidatarie e adottive<\/p>\n<p><strong>Dove sono?<\/strong><\/p>\n<p><strong>Trentino Alto Adige <\/strong>Bolzano, <strong>Veneto <\/strong>Mestre, <strong>Lombardia\u00a0 <\/strong>Milano e Val Sabbia (BS), <strong>Emilia Romagna\u00a0 <\/strong>Monghidoro (Bo), <strong>Toscana\u00a0 <\/strong>Firenze, <strong>Lazio\u00a0<\/strong>Roma, <strong>Abruzzo\u00a0<\/strong>L\u2019Aquila, <strong>Campania\u00a0<\/strong>Salerno, <strong>Puglia\u00a0<\/strong>Barletta, <strong>Sardegna\u00a0<\/strong>Cagliari<\/p>\n<div class=\"wpz-sc-box normal   \">\n<p style=\"font-weight: 400;\">La Campagna sostiene i Centri Servizi alla Famiglia (PDZ) attivi sul territorio Italiano.<\/p>\n<\/div>[\/vc_column_text]\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*168342-start*\/\n#btnsx-168342{margin-top:0px;margin-bottom:20px;margin-left:0px;margin-right:0px;padding-top:20px;padding-bottom:20px;padding-left:40px;padding-right:40px;}\n#btnsx-168342 .btnsx-text-primary{font-size:30px;line-height:30px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-168342:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-168342{background-color:#ef7b0b!important;}\n#btnsx-168342:hover{background-color:#eab20b!important;}\n#btnsx-168342{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-168342{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-168342:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*168342-end*\/\n<\/style><div id=\"btnsx-168342-wrap\" class=\"btnsx-wrap-center\" align=\"center\"><div id=\"btnsx-168342-container\" class=\"btnsx-btn-container\">\n<a href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/?scelta=25&amp;progetto=Italia\" id=\"btnsx-168342\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-embossed\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">Adotta a Distanza Italia<\/span><\/a>\n<\/div><\/div>\n<!-- Buttons X - End -->\n[\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][\/vc_tta_tabs][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1632845063478{background-color: #ee7d0c !important;}&#8221; el_class=&#8221;shadow&#8221;][vc_column][vc_custom_heading text=&#8221;News&#8221; font_container=&#8221;tag:h2|font_size:40|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:Damion%3Aregular|font_style:400%20regular%3A400%3Anormal&#8221; css=&#8221;.vc_custom_1635515875145{margin-top: 0px !important;}&#8221;][vc_separator color=&#8221;white&#8221; align=&#8221;align_left&#8221; border_width=&#8221;2&#8243; el_width=&#8221;80&#8243;][vc_column_text]<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-shadow pt-cv-bb pt-cv-pgregular\" id=\"pt-cv-view-3b8bb766rg\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"3\"><div class=\"col-md-4 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"237266\"><div class='pt-cv-pinmas'><h3 class=\"pt-cv-title\"><a href=\"https:\/\/www.aibi.it\/ita\/educare-domani-monghidoro-conti-sorrisi\/\" class=\"_self cvplbd\" target=\"_self\" >Educare il Domani. Monghidoro (BO) \u201cFar quadrare\u201d i conti\u2026 e i sorrisi<\/a><\/h3>\n<a href=\"https:\/\/www.aibi.it\/ita\/educare-domani-monghidoro-conti-sorrisi\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow no-lazyload  skip-lazy  cvplazy\" alt=\"Educare il Domani. Monghidoro (BO) \u201cFar quadrare\u201d i conti\u2026 e i sorrisi\" data-cvpsrc=\"https:\/\/www.aibi.it\/ita\/images\/2026\/04\/monghidoro-educare-il-domani-2-571x300.jpg\" \/><\/a>\n<div class=\"pt-cv-content\">Le attivit\u00e0 dei Centri per la Famiglia di Ai.Bi. Amici dei bambini, come il Pan di Zucchero \u201cI Talenti\u201d di ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.aibi.it\/ita\/educare-domani-monghidoro-conti-sorrisi\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leggi tutto<\/a><\/div><\/div>\n<span class=\"dashicons dashicons-format-standard pt-cv-pficon\"><\/span><\/div><\/div>\n<div class=\"col-md-4 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"236759\"><div class='pt-cv-pinmas'><h3 class=\"pt-cv-title\"><a href=\"https:\/\/www.aibi.it\/ita\/comunita-familiare-accoglienza-inizio-fine\/\" class=\"_self cvplbd\" target=\"_self\" >Fame di mamma. Dove l\u2019accoglienza non ha inizio n\u00e9 fine. Semplicemente, \u201c\u00e8\u201d<\/a><\/h3>\n<a href=\"https:\/\/www.aibi.it\/ita\/comunita-familiare-accoglienza-inizio-fine\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow no-lazyload  skip-lazy  cvplazy\" alt=\"Fame di mamma. Dove l\u2019accoglienza non ha inizio n\u00e9 fine. Semplicemente, \u201c\u00e8\u201d\" data-cvpsrc=\"https:\/\/www.aibi.it\/ita\/images\/2026\/03\/albero-Koala-comunita-familiare-571x300.jpg\" \/><\/a>\n<div class=\"pt-cv-content\">Ettorina \u00e8 la \u201ccustode dell\u2019accoglienza\u201d de L\u2019albero dei Koala, comunit\u00e0 familiare di Amici dei Bambini e della Cooperativa AIBC. Una ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.aibi.it\/ita\/comunita-familiare-accoglienza-inizio-fine\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leggi tutto<\/a><\/div><\/div>\n<span class=\"dashicons dashicons-format-standard pt-cv-pficon\"><\/span><\/div><\/div>\n<div class=\"col-md-4 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"236245\"><div class='pt-cv-pinmas'><h3 class=\"pt-cv-title\"><a href=\"https:\/\/www.aibi.it\/ita\/fame-mamma-prima-volta-regalo-figlia\/\" class=\"_self cvplbd\" target=\"_self\" >Fame di mamma. &#8220;Per la prima volta ho fatto un regalo a mia figlia&#8221;<\/a><\/h3>\n<a href=\"https:\/\/www.aibi.it\/ita\/fame-mamma-prima-volta-regalo-figlia\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow no-lazyload  skip-lazy  cvplazy\" alt=\"Fame di mamma. &quot;Per la prima volta ho fatto un regalo a mia figlia&quot;\" data-cvpsrc=\"https:\/\/www.aibi.it\/ita\/images\/2026\/03\/fatto-un-regalo-a-mia-figlia-571x300.jpg\" \/><\/a>\n<div class=\"pt-cv-content\">La storia di una\u00a0 mamma che, per la giovane et\u00e0 e l\u2019inesperienza, ha finito per perdere la rotta , ritrovandosi\u00a0 ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.aibi.it\/ita\/fame-mamma-prima-volta-regalo-figlia\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leggi tutto<\/a><\/div><\/div>\n<span class=\"dashicons dashicons-format-standard pt-cv-pficon\"><\/span><\/div><\/div><\/div><\/div>\n<div class=\"text-left pt-cv-pagination-wrapper\"><ul class=\"pt-cv-pagination pt-cv-ajax pagination\" data-totalpages=\"82\" data-currentpage=\"1\" data-sid=\"3b8bb766rg\" data-unid=\"\" data-isblock=\"\" data-postid=\"\"><li class=\"active\"><a href=\"#\">1<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/192951\/?_page=2\">2<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/192951\/?_page=3\">3<\/a><\/li>\n\t<li ><a href=\"#\">&hellip;<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/192951\/?_page=82\">82<\/a><\/li>\n\t<li ><a class=\" \" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/192951\/?_page=2\">&rsaquo;<\/a><\/li>\n\t<\/ul><img loading=\"lazy\" decoding=\"async\" width=\"15\" height=\"15\" class=\"pt-cv-spinner\" alt=\"Loading...\" src=\"data:image\/gif;base64,R0lGODlhDwAPALMPAMrKygwMDJOTkz09PZWVla+vr3p6euTk5M7OzuXl5TMzMwAAAJmZmWZmZszMzP\/\/\/yH\/C05FVFNDQVBFMi4wAwEAAAAh+QQFCgAPACwAAAAADwAPAAAEQvDJaZaZOIcV8iQK8VRX4iTYoAwZ4iCYoAjZ4RxejhVNoT+mRGP4cyF4Pp0N98sBGIBMEMOotl6YZ3S61Bmbkm4mAgAh+QQFCgAPACwAAAAADQANAAAENPDJSRSZeA418itN8QiK8BiLITVsFiyBBIoYqnoewAD4xPw9iY4XLGYSjkQR4UAUD45DLwIAIfkEBQoADwAsAAAAAA8ACQAABC\/wyVlamTi3nSdgwFNdhEJgTJoNyoB9ISYoQmdjiZPcj7EYCAeCF1gEDo4Dz2eIAAAh+QQFCgAPACwCAAAADQANAAAEM\/DJBxiYeLKdX3IJZT1FU0iIg2RNKx3OkZVnZ98ToRD4MyiDnkAh6BkNC0MvsAj0kMpHBAAh+QQFCgAPACwGAAAACQAPAAAEMDC59KpFDll73HkAA2wVY5KgiK5b0RRoI6MuzG6EQqCDMlSGheEhUAgqgUUAFRySIgAh+QQFCgAPACwCAAIADQANAAAEM\/DJKZNLND\/kkKaHc3xk+QAMYDKsiaqmZCxGVjSFFCxB1vwy2oOgIDxuucxAMTAJFAJNBAAh+QQFCgAPACwAAAYADwAJAAAEMNAs86q1yaWwwv2Ig0jUZx3OYa4XoRAfwADXoAwfo1+CIjyFRuEho60aSNYlOPxEAAAh+QQFCgAPACwAAAIADQANAAAENPA9s4y8+IUVcqaWJ4qEQozSoAzoIyhCK2NFU2SJk0hNnyEOhKR2AzAAj4Pj4GE4W0bkJQIAOw==\" \/><div class=\"clear pt-cv-clear-pagination\"><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-b6a62b7tp1\">#pt-cv-view-3b8bb766rg .pt-cv-title a, #pt-cv-view-3b8bb766rg  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-3b8bb766rg .pt-cv-readmore  { font-size: 15px !important; line-height: 1.3 !important; color: #ffffff !important; background-color: #1e73be !important; }\n@media (min-width: 768px) and (max-width: 991px) {#pt-cv-view-3b8bb766rg .pt-cv-readmore  { font-size: 15px !important }}\n#pt-cv-view-3b8bb766rg .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-3b8bb766rg  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-3b8bb766rg  + .pt-cv-pagination-wrapper .pagination .active a { color: #606060 !important; background-color: #e8e8e8 !important; }<\/style>\r\n\t\t\t[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&rdquo;.vc_custom_1634572810132{padding-top: 0px !important;padding-right: 2% !important;padding-bottom: 0px !important;padding-left: 2% !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&rdquo;][vc_column][vc_gallery interval=&rdquo;3&Prime; images=&rdquo;193738&Prime; img_size=&rdquo;large&rdquo; onclick=&rdquo;&rdquo; el_class=&rdquo;shadow&rdquo;][vc_custom_heading text=&rdquo;Perch&egrave; Adottare a Distanza in Italia&rdquo; font_container=&rdquo;tag:h2|font_size:40|text_align:left|color:%23ee7d0c&rdquo; google_fonts=&rdquo;font_family:Montserrat%3Aregular%2C700|font_style:400%20regular%3A400%3Anormal&rdquo;][vc_column_text]Ai.Bi. supporta l&rsquo;infanzia abbandonata in Italia,&nbsp; le attivit&agrave; di Adozione a Distanza sono rivolte alla tutela e protezione dei bambini in grave [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":159090,"parent":164877,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/full-width.php","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-192951","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione a Distanza in Italia - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Fame di Mamma\u00a0\u00e8 la campagna di Amici dei Bambini per dire basta all\u2019abbandono in Italia. Il Sostegno a distanza aiuta i bambini Italiani nei progetti Ai.Bi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sostegno a distanza in Italia\" \/>\n<meta property=\"og:description\" content=\"Fame di Mamma\u00a0\u00e8 la campagna di Amici dei Bambini per dire basta all\u2019abbandono in Italia. Il Sostegno a distanza aiuta i bambini Italiani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-29T13:57:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/lad-fame-di-mamma_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Sostegno a distanza in Italia\" \/>\n<meta name=\"twitter:description\" content=\"Fame di Mamma\u00a0\u00e8 la campagna di Amici dei Bambini per dire basta all\u2019abbandono in Italia. Il Sostegno a distanza aiuta i bambini Italiani.\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-a-distanza\\\/test-sad-italia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-a-distanza\\\/test-sad-italia\\\/\",\"name\":\"Adozione a Distanza in Italia - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-a-distanza\\\/test-sad-italia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-a-distanza\\\/test-sad-italia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/lad-fame-di-mamma_fb.jpg\",\"datePublished\":\"2021-10-11T13:07:53+00:00\",\"dateModified\":\"2021-10-29T13:57:58+00:00\",\"description\":\"Fame di Mamma\u00a0\u00e8 la campagna di Amici dei Bambini per dire basta all\u2019abbandono in Italia. Il Sostegno a distanza aiuta i bambini Italiani nei progetti Ai.Bi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-a-distanza\\\/test-sad-italia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-a-distanza\\\/test-sad-italia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-a-distanza\\\/test-sad-italia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/lad-fame-di-mamma_fb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/lad-fame-di-mamma_fb.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-a-distanza\\\/test-sad-italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione a Distanza\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-a-distanza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione a Distanza in Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione a Distanza in Italia - Ai.Bi. Amici dei Bambini","description":"Fame di Mamma\u00a0\u00e8 la campagna di Amici dei Bambini per dire basta all\u2019abbandono in Italia. Il Sostegno a distanza aiuta i bambini Italiani nei progetti Ai.Bi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/","og_locale":"it_IT","og_type":"article","og_title":"Sostegno a distanza in Italia","og_description":"Fame di Mamma\u00a0\u00e8 la campagna di Amici dei Bambini per dire basta all\u2019abbandono in Italia. Il Sostegno a distanza aiuta i bambini Italiani.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_modified_time":"2021-10-29T13:57:58+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/lad-fame-di-mamma_fb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Sostegno a distanza in Italia","twitter_description":"Fame di Mamma\u00a0\u00e8 la campagna di Amici dei Bambini per dire basta all\u2019abbandono in Italia. Il Sostegno a distanza aiuta i bambini Italiani.","twitter_site":"@amicideibambini","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/","url":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/","name":"Adozione a Distanza in Italia - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/lad-fame-di-mamma_fb.jpg","datePublished":"2021-10-11T13:07:53+00:00","dateModified":"2021-10-29T13:57:58+00:00","description":"Fame di Mamma\u00a0\u00e8 la campagna di Amici dei Bambini per dire basta all\u2019abbandono in Italia. Il Sostegno a distanza aiuta i bambini Italiani nei progetti Ai.Bi.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/lad-fame-di-mamma_fb.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/lad-fame-di-mamma_fb.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/test-sad-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione a Distanza","item":"https:\/\/www.aibi.it\/ita\/adozione-a-distanza\/"},{"@type":"ListItem","position":3,"name":"Adozione a Distanza in Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:20:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/192951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=192951"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/192951\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/164877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/159090"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=192951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=192951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=192951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}