﻿


{"id":206986,"date":"2022-11-22T10:02:03","date_gmt":"2022-11-22T09:02:03","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?page_id=206986"},"modified":"2024-05-21T15:36:50","modified_gmt":"2024-05-21T13:36:50","slug":"siria-empowerment-of-civil-society-in-idlib-governorate","status":"publish","type":"page","link":"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/","title":{"rendered":"Siria: &#8220;Sawyan &#8211; Empowerment of Civil Society in Idlib Governorate\u201d"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css=&#8221;.vc_custom_1504711418355{background-color: #f2f2f2 !important;}&#8221;][vc_column][vc_column_text]<strong>Paese<\/strong>: Siria, Provincia di Idlib<br \/>\n<strong>Capofila<\/strong>: Ai.Bi. Associazione Amici dei Bambini<br \/>\n<strong>Partner<\/strong>: Kids Paradise<br \/>\n<strong>Finanziatore istituzionale:<\/strong> Unione Europea<br \/>\n<strong>Budget:<\/strong> 520.680,67 \u20ac<br \/>\n<strong>Durata:<\/strong> 23 mesi (01\/01\/2022-30\/11\/2023)<\/p>\n<p><!--more-->[\/vc_column_text][vc_single_image image=&#8221;205340&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]L\u2019intervento \u00e8 localizzato in 8 sub-distretti del Governatorato di Idlib, nella Siria nordoccidentale, e mira al rafforzamento strategico delle Organizzazioni della Societ\u00e0 Civile (OSC) di quell\u2019area, migliorando e sviluppando le loro competenze tecniche perch\u00e9 possano essere il motore di una ripresa del Paese.<\/p>\n<p>Staff e volontari delle 51 OSC selezionate parteciperanno a un programma di formazione su argomenti quali, la pianificazione strategica, la gestione finanziaria e progettuale, la raccolta fondi e la promozione, che permetter\u00e0 loro di lavorare pi\u00f9 efficientemente ed efficacemente con le loro comunit\u00e0, per identificarne i bisogni, costruire partenariati, co-progettare risposte in modo partecipativo e attirare finanziamenti.<\/p>\n<p>Alla fase di formazione seguir\u00e0 una fase operativa in cui le OSC selezionate verranno invitate a presentare una loro proposta progettuale, mettendo cos\u00ec alla prova le competenze acquisite, e cogliendo l\u2019opportunit\u00e0 di ricevere un finanziamento per implementare interventi a beneficio della loro comunit\u00e0. Sulla base di criteri predefiniti, un Comitato di valutazione selezioner\u00e0 almeno 10 progetti di 10 diverse OSC, le quali riceveranno un finanziamento di \u20ac 10.000,00 ciascuna per avviare interventi a promozione della stabilit\u00e0 e della coesione sociale.[\/vc_column_text][vc_single_image image=&#8221;203403&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][vc_column_text]Infine, attraverso l\u2019organizzazione di eventi pubblici a rafforzamento della percezione delle OSC come partner affidabili ed efficaci nel promuovere cambiamenti positivi all\u2019interno delle comunit\u00e0, il progetto intende anche promuovere la creazione di 15 comitati civici e lo sviluppo di una rete di OSC locali &#8211; la cosiddetta &#8220;Sawyan Network&#8221;, che consentiranno maggiore cooperazione e coordinamento delle iniziative a medio termine.<\/p>\n<p>Una migliore stabilit\u00e0 organizzativa, il potenziamento delle risorse umane, la maggiore trasparenza attraverso pratiche di buona governance e l&#8217;adozione di prospettive pi\u00f9 strategiche, contribuiranno anche a creare un ambiente favorevole per la creazione di partenariati a lungo termine.<\/p>\n<p>Ai.Bi. realizzer\u00e0 l\u2019intervento in collaborazione con il suo lo storico partner locale, Kids Paradise, il quale ha una conoscenza del contesto tale da capire i bisogni della popolazione locale e da suggerire quali azioni siano necessarie.<\/p>\n<h3>Vuoi saperne di pi\u00f9?<\/h3>\n<p>Chiama il numero<strong> 02\/988221<\/strong> o invia una e-mail a: <strong>aibi@aibi.it<\/strong><\/p>\n<p>Verrai messo direttamente in comunicazione con un nostro responsabile.[\/vc_column_text][vc_column_text css=&#8221;&#8221;]\n<!-- Buttons X - Start -->\n<style type=\"text\/css\" scoped>\/*146655-start*\/\n#btnsx-146655{margin-top:0px;margin-bottom:25px;margin-left:0px;margin-right:0px;padding-top:16px;padding-bottom:15px;padding-left:43px;padding-right:44px;}\n#btnsx-146655 .btnsx-text-primary{text-transform:uppercase;font-size:20px;line-height:20px;font-family:Montserrat;color:#ffffff;padding-top:0px;padding-bottom:0px;padding-left:0px;padding-right:0px;}\n#btnsx-146655:hover .btnsx-text-primary{color:#ffffff;}\n#btnsx-146655{background-color:#ee7d0c!important;}\n#btnsx-146655:hover{background-color:#e8630b!important;}\n#btnsx-146655{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:none;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-146655:hover{border-top-width:0px;border-bottom-width:0px;border-left-width:0px;border-right-width:0px;border-style:solid;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-left-radius:25px;border-bottom-right-radius:25px;}\n#btnsx-146655{-webkit-box-shadow:none;box-shadow:none;}\n#btnsx-146655:hover{-webkit-box-shadow:none;box-shadow:none;}\n\/*146655-end*\/\n<\/style>\n<a href=\"https:\/\/dona.aibi.it\/dona-ora\/?act=cplt&amp;tipo=0&amp;caus=4189\" id=\"btnsx-146655\" target=\"_blank\" class=\"btnsx-btn btnsx-btn-block\"  data-font-primary=\"Montserrat\">\n\t<span class=\"btnsx-text-primary \">DONA ORA<\/span><\/a>\n\n<!-- Buttons X - End -->\n[\/vc_column_text][vc_custom_heading text=&#8221;Aggiornamenti dal progetto&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ee7e0d&#8221; google_fonts=&#8221;font_family:Montserrat%3Aregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_column_text css=&#8221;&#8221;]<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-shadow pt-cv-bb pt-cv-pgregular\" id=\"pt-cv-view-d629b459zh\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"3\"><div class=\"col-md-4 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"218983\"><div class='pt-cv-pinmas'><h3 class=\"pt-cv-title\"><a href=\"https:\/\/www.aibi.it\/ita\/siria-sawyan-risultati-progetto-territorio\/\" class=\"_self cvplbd\" target=\"_self\" >Siria. Sawyan: i risultati di un progetto di quasi due anni sul territorio<\/a><\/h3>\n<a href=\"https:\/\/www.aibi.it\/ita\/siria-sawyan-risultati-progetto-territorio\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow no-lazyload  skip-lazy  cvplazy\" alt=\"Siria. Sawyan: i risultati di un progetto di quasi due anni sul territorio\" data-cvpsrc=\"https:\/\/www.aibi.it\/ita\/images\/2024\/01\/Siria-evento-finale-Sawyan-571x300.jpg\" \/><\/a>\n<div class=\"pt-cv-content\">Si sono concluse le attivit\u00e0 del progetto di Cooperazione Internazionale <em>Sawyan - Empowering of Civil Society Organization in Idlib Governorate<\/em>, ... <a href=\"https:\/\/www.aibi.it\/ita\/siria-sawyan-risultati-progetto-territorio\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Leggi tutto<\/a><\/div>\n<span class=\"dashicons dashicons-format-standard pt-cv-pficon\"><\/span><\/div><\/div>\n<div class=\"col-md-4 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"217735\"><div class='pt-cv-pinmas'><h3 class=\"pt-cv-title\"><a href=\"https:\/\/www.aibi.it\/ita\/siria-fianco-societa-civile\/\" class=\"_self cvplbd\" target=\"_self\" >Siria. Al fianco della societ\u00e0 civile siriana: ecco cosa abbiamo realizzato in 20 mesi<\/a><\/h3>\n<a href=\"https:\/\/www.aibi.it\/ita\/siria-fianco-societa-civile\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow no-lazyload  skip-lazy  cvplazy\" alt=\"Siria. Al fianco della societ\u00e0 civile siriana: ecco cosa abbiamo realizzato in 20 mesi\" data-cvpsrc=\"https:\/\/www.aibi.it\/ita\/images\/2023\/11\/siria-evento-Unicatt-per-news-571x300.jpg\" \/><\/a>\n<div class=\"pt-cv-content\"><strong>Luned\u00ec 27 novembre, alle 18.30, all\u2019Universit\u00e0 Cattolica di Milano si terr\u00e0 un incontro per raccontare, anche con l\u2019intervento dei cooperanti ... <a href=\"https:\/\/www.aibi.it\/ita\/siria-fianco-societa-civile\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Leggi tutto<\/a><\/strong><\/div>\n<span class=\"dashicons dashicons-format-standard pt-cv-pficon\"><\/span><\/div><\/div>\n<div class=\"col-md-4 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"210613\"><div class='pt-cv-pinmas'><h3 class=\"pt-cv-title\"><a href=\"https:\/\/www.aibi.it\/ita\/siria-dodici-anni-guerra\/\" class=\"_self cvplbd\" target=\"_self\" >Siria. Dodici anni di guerra e sofferenze in un Paese che non trova pace<\/a><\/h3>\n<a href=\"https:\/\/www.aibi.it\/ita\/siria-dodici-anni-guerra\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow no-lazyload  skip-lazy  cvplazy\" alt=\"Siria. Dodici anni di guerra e sofferenze in un Paese che non trova pace\" data-cvpsrc=\"https:\/\/www.aibi.it\/ita\/images\/2023\/03\/12-anni-guerra-in-Siria-571x300.jpg\" \/><\/a>\n<div class=\"pt-cv-content\">La guerra in Siria non si ferma e la situazione si \u00e8 aggravata anche a causa del terremoto. Amici dei ... <a href=\"https:\/\/www.aibi.it\/ita\/siria-dodici-anni-guerra\/\" class=\"_self pt-cv-readmore pt-cv-textlink cvplbd\" target=\"_self\">Leggi tutto<\/a><\/div>\n<span class=\"dashicons dashicons-format-standard pt-cv-pficon\"><\/span><\/div><\/div><\/div><\/div>\n<div class=\"text-left pt-cv-pagination-wrapper\"><ul class=\"pt-cv-pagination pt-cv-ajax pagination\" data-totalpages=\"3\" data-currentpage=\"1\" data-sid=\"d629b459zh\" data-unid=\"\" data-isblock=\"\" data-postid=\"\"><li class=\"active\"><a href=\"#\">1<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/206986\/?_page=2\">2<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/206986\/?_page=3\">3<\/a><\/li>\n\t<li ><a class=\" \" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/206986\/?_page=2\">&rsaquo;<\/a><\/li>\n\t<\/ul><img loading=\"lazy\" decoding=\"async\" width=\"15\" height=\"15\" class=\"pt-cv-spinner\" alt=\"Loading...\" src=\"data:image\/gif;base64,R0lGODlhDwAPALMPAMrKygwMDJOTkz09PZWVla+vr3p6euTk5M7OzuXl5TMzMwAAAJmZmWZmZszMzP\/\/\/yH\/C05FVFNDQVBFMi4wAwEAAAAh+QQFCgAPACwAAAAADwAPAAAEQvDJaZaZOIcV8iQK8VRX4iTYoAwZ4iCYoAjZ4RxejhVNoT+mRGP4cyF4Pp0N98sBGIBMEMOotl6YZ3S61Bmbkm4mAgAh+QQFCgAPACwAAAAADQANAAAENPDJSRSZeA418itN8QiK8BiLITVsFiyBBIoYqnoewAD4xPw9iY4XLGYSjkQR4UAUD45DLwIAIfkEBQoADwAsAAAAAA8ACQAABC\/wyVlamTi3nSdgwFNdhEJgTJoNyoB9ISYoQmdjiZPcj7EYCAeCF1gEDo4Dz2eIAAAh+QQFCgAPACwCAAAADQANAAAEM\/DJBxiYeLKdX3IJZT1FU0iIg2RNKx3OkZVnZ98ToRD4MyiDnkAh6BkNC0MvsAj0kMpHBAAh+QQFCgAPACwGAAAACQAPAAAEMDC59KpFDll73HkAA2wVY5KgiK5b0RRoI6MuzG6EQqCDMlSGheEhUAgqgUUAFRySIgAh+QQFCgAPACwCAAIADQANAAAEM\/DJKZNLND\/kkKaHc3xk+QAMYDKsiaqmZCxGVjSFFCxB1vwy2oOgIDxuucxAMTAJFAJNBAAh+QQFCgAPACwAAAYADwAJAAAEMNAs86q1yaWwwv2Ig0jUZx3OYa4XoRAfwADXoAwfo1+CIjyFRuEho60aSNYlOPxEAAAh+QQFCgAPACwAAAIADQANAAAENPA9s4y8+IUVcqaWJ4qEQozSoAzoIyhCK2NFU2SJk0hNnyEOhKR2AzAAj4Pj4GE4W0bkJQIAOw==\" \/><div class=\"clear pt-cv-clear-pagination\"><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-10b6958bfh\">#pt-cv-view-d629b459zh .pt-cv-title a, #pt-cv-view-d629b459zh  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-d629b459zh .pt-cv-readmore  { font-size: 15px !important; line-height: 1.3 !important; }\n@media (min-width: 768px) and (max-width: 991px) {#pt-cv-view-d629b459zh .pt-cv-readmore  { font-size: 15px !important }}\n#pt-cv-view-d629b459zh .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-d629b459zh  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-d629b459zh  + .pt-cv-pagination-wrapper .pagination .active a { color: #606060 !important; background-color: #e8e8e8 !important; }<\/style>\r\n\t\t\t[\/vc_column_text][\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221;][vc_column][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;205720,205352,204440,199996,196848&#8243;][vc_custom_heading text=&#8221;News Cooperazione Internazionale&#8221; font_container=&#8221;tag:h2|font_size:40|text_align:left|color:%23ee7d0c&#8221; google_fonts=&#8221;font_family:Damion%3Aregular|font_style:400%20regular%3A400%3Anormal&#8221;][vc_separator color=&#8221;orange&#8221; align=&#8221;align_left&#8221; border_width=&#8221;2&#8243; el_width=&#8221;80&#8243;][vc_column_text]<div class=\"pt-cv-wrapper\"><div class=\"pt-cv-view pt-cv-pinterest pt-cv-colsys pt-cv-shadow pt-cv-bb pt-cv-pgregular\" id=\"pt-cv-view-dc08dd43dl\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"3\"><div class=\"col-md-4 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"237792\"><div class='pt-cv-pinmas'><h3 class=\"pt-cv-title\"><a href=\"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/\" class=\"_self cvplbd\" target=\"_self\" >Nuovo progetto Ai.Bi. in Ghana: al via l&#8217;iniziativa per la tutela dei minori e il reinserimento familiare<\/a><\/h3>\n<a href=\"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow no-lazyload  skip-lazy  cvplazy\" alt=\"Nuovo progetto Ai.Bi. in Ghana: al via l&#039;iniziativa per la tutela dei minori e il reinserimento familiare\" data-cvpsrc=\"https:\/\/www.aibi.it\/ita\/images\/2026\/05\/progetto-in-Ghana-Aibi-CAI-571x300.jpg\" \/><\/a>\n<div class=\"pt-cv-content\"><strong>Finanziato dalla CAI (Commissione per le Adozioni Internazionali), il programma di cooperazione punta a contrastare l\u2019istituzionalizzazione e a supportare oltre ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.aibi.it\/ita\/progetto-ghana-aibi-tutela-minori-reinserimento-familiare\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leggi tutto<\/a><\/div><\/strong><\/div>\n<span class=\"dashicons dashicons-format-standard pt-cv-pficon\"><\/span><\/div><\/div>\n<div class=\"col-md-4 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"237491\"><div class='pt-cv-pinmas'><h3 class=\"pt-cv-title\"><a href=\"https:\/\/www.aibi.it\/ita\/elektrovent-occhi-speranza-trasforma-vita-bambini\/\" class=\"_self cvplbd\" target=\"_self\" >Kenya. Insieme a Elektrovent, il progetto \u201cOcchi di Speranza\u201d continua a trasformare la vita dei bambini<\/a><\/h3>\n<a href=\"https:\/\/www.aibi.it\/ita\/elektrovent-occhi-speranza-trasforma-vita-bambini\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow no-lazyload  skip-lazy  cvplazy\" alt=\"Kenya. Insieme a Elektrovent, il progetto \u201cOcchi di Speranza\u201d continua a trasformare la vita dei bambini\" data-cvpsrc=\"https:\/\/www.aibi.it\/ita\/images\/2026\/04\/Occhi-di-speranza-Kenya-Elektrovent-Shelter7-571x300.jpg\" \/><\/a>\n<div class=\"pt-cv-content\">Prosegue il progetto pluriennale di Ai.Bi. Amici dei Bambini in Kenya sostenuto da Elektrovent, per migliorare la qualit\u00e0 della vita ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.aibi.it\/ita\/elektrovent-occhi-speranza-trasforma-vita-bambini\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leggi tutto<\/a><\/div><\/div>\n<span class=\"dashicons dashicons-format-standard pt-cv-pficon\"><\/span><\/div><\/div>\n<div class=\"col-md-4 col-sm-4 col-xs-12 pt-cv-content-item pt-cv-1-col\"  data-pid=\"237480\"><div class='pt-cv-pinmas'><h3 class=\"pt-cv-title\"><a href=\"https:\/\/www.aibi.it\/ita\/guerra-ucraina-dimenticata\/\" class=\"_self cvplbd\" target=\"_self\" >BAMBINIxLAPACE. Ucraina. I numeri di una guerra dimenticata: 2000 droni, 1400 bombe, 60 missili in una settimana<\/a><\/h3>\n<a href=\"https:\/\/www.aibi.it\/ita\/guerra-ucraina-dimenticata\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default cvplbd cvp-lazy-container\" target=\"_self\" ><img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"300\" src=\"https:\/\/www.aibi.it\/ita\/wp-content\/plugins\/pt-content-views-pro\/public\/assets\/images\/lazy_image.png\" class=\"pt-cv-thumbnail img-shadow no-lazyload  skip-lazy  cvplazy\" alt=\"BAMBINIxLAPACE. Ucraina. I numeri di una guerra dimenticata: 2000 droni, 1400 bombe, 60 missili in una settimana\" data-cvpsrc=\"https:\/\/www.aibi.it\/ita\/images\/2026\/04\/guerra-in-Ucraina-guerra-dimenticata-571x300.jpg\" \/><\/a>\n<div class=\"pt-cv-content\">Solo nell\u2019ultima settimana sono stati lanciati contro l\u2019Ucraina circa 2000 droni, 1400 bombe e 60 missili. Eppure in pochi se ...<br \/><div class=\"pt-cv-rmwrap\"><a href=\"https:\/\/www.aibi.it\/ita\/guerra-ucraina-dimenticata\/\" class=\"_self pt-cv-readmore btn btn-success cvplbd\" target=\"_self\">Leggi tutto<\/a><\/div><\/div>\n<span class=\"dashicons dashicons-format-standard pt-cv-pficon\"><\/span><\/div><\/div><\/div><\/div>\n<div class=\"text-left pt-cv-pagination-wrapper\"><ul class=\"pt-cv-pagination pt-cv-ajax pagination\" data-totalpages=\"998\" data-currentpage=\"1\" data-sid=\"dc08dd43dl\" data-unid=\"\" data-isblock=\"\" data-postid=\"\"><li class=\"active\"><a href=\"#\">1<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/206986\/?_page=2\">2<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/206986\/?_page=3\">3<\/a><\/li>\n\t<li ><a href=\"#\">&hellip;<\/a><\/li>\n\t<li ><a class=\"\" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/206986\/?_page=998\">998<\/a><\/li>\n\t<li ><a class=\" \" href=\"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/206986\/?_page=2\">&rsaquo;<\/a><\/li>\n\t<\/ul><img loading=\"lazy\" decoding=\"async\" width=\"15\" height=\"15\" class=\"pt-cv-spinner\" alt=\"Loading...\" src=\"data:image\/gif;base64,R0lGODlhDwAPALMPAMrKygwMDJOTkz09PZWVla+vr3p6euTk5M7OzuXl5TMzMwAAAJmZmWZmZszMzP\/\/\/yH\/C05FVFNDQVBFMi4wAwEAAAAh+QQFCgAPACwAAAAADwAPAAAEQvDJaZaZOIcV8iQK8VRX4iTYoAwZ4iCYoAjZ4RxejhVNoT+mRGP4cyF4Pp0N98sBGIBMEMOotl6YZ3S61Bmbkm4mAgAh+QQFCgAPACwAAAAADQANAAAENPDJSRSZeA418itN8QiK8BiLITVsFiyBBIoYqnoewAD4xPw9iY4XLGYSjkQR4UAUD45DLwIAIfkEBQoADwAsAAAAAA8ACQAABC\/wyVlamTi3nSdgwFNdhEJgTJoNyoB9ISYoQmdjiZPcj7EYCAeCF1gEDo4Dz2eIAAAh+QQFCgAPACwCAAAADQANAAAEM\/DJBxiYeLKdX3IJZT1FU0iIg2RNKx3OkZVnZ98ToRD4MyiDnkAh6BkNC0MvsAj0kMpHBAAh+QQFCgAPACwGAAAACQAPAAAEMDC59KpFDll73HkAA2wVY5KgiK5b0RRoI6MuzG6EQqCDMlSGheEhUAgqgUUAFRySIgAh+QQFCgAPACwCAAIADQANAAAEM\/DJKZNLND\/kkKaHc3xk+QAMYDKsiaqmZCxGVjSFFCxB1vwy2oOgIDxuucxAMTAJFAJNBAAh+QQFCgAPACwAAAYADwAJAAAEMNAs86q1yaWwwv2Ig0jUZx3OYa4XoRAfwADXoAwfo1+CIjyFRuEho60aSNYlOPxEAAAh+QQFCgAPACwAAAIADQANAAAENPA9s4y8+IUVcqaWJ4qEQozSoAzoIyhCK2NFU2SJk0hNnyEOhKR2AzAAj4Pj4GE4W0bkJQIAOw==\" \/><div class=\"clear pt-cv-clear-pagination\"><\/div><\/div><\/div>\t\t\t<style type=\"text\/css\" id=\"pt-cv-inline-style-defd7f35iw\">#pt-cv-view-dc08dd43dl .pt-cv-title a, #pt-cv-view-dc08dd43dl  .panel-title { font-weight: 600 !important; }\n#pt-cv-view-dc08dd43dl .pt-cv-readmore  { font-size: 15px !important; line-height: 1.3 !important; color: #ffffff !important; background-color: #1e73be !important; }\n@media (min-width: 768px) and (max-width: 991px) {#pt-cv-view-dc08dd43dl .pt-cv-readmore  { font-size: 15px !important }}\n#pt-cv-view-dc08dd43dl .pt-cv-readmore:hover  { color: #ffffff !important; background-color: #00aeef !important; }\n#pt-cv-view-dc08dd43dl  + .pt-cv-pagination-wrapper .pt-cv-more , #pt-cv-view-dc08dd43dl  + .pt-cv-pagination-wrapper .pagination .active a { color: #606060 !important; background-color: #e8e8e8 !important; }<\/style>\r\n\t\t\t[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&rdquo;.vc_custom_1504711418355{background-color: #f2f2f2 !important;}&rdquo;][vc_column][vc_column_text]Paese: Siria, Provincia di Idlib Capofila: Ai.Bi. Associazione Amici dei Bambini Partner: Kids Paradise Finanziatore istituzionale: Unione Europea Budget: 520.680,67 &euro; Durata: 23 mesi (01\/01\/2022-30\/11\/2023)<\/p>\n","protected":false},"author":94,"featured_media":205340,"parent":59840,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[970],"tags":[404],"class_list":["post-206986","page","type-page","status-publish","has-post-thumbnail","category-progetti-conclusi","tag-siria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Siria: &quot;Sawyan - Empowerment of Civil Society in Idlib Governorate\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"L\u2019intervento \u00e8 localizzato in 8 sub-distretti del Governatorato di Idlib, nella Siria nordoccidentale, e mira al rafforzamento strategico delle Organizzazioni della Societ\u00e0 Civile\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siria: &quot;Sawyan - Empowerment of Civil Society in Idlib Governorate\u201d\" \/>\n<meta property=\"og:description\" content=\"L\u2019intervento \u00e8 localizzato in 8 sub-distretti del Governatorato di Idlib, nella Siria nordoccidentale, e mira al rafforzamento strategico delle Organizzazioni della Societ\u00e0 Civile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T13:36:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/aibi-sad-siria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/attivita\\\/cooperazione-internazionale-2\\\/siria-empowerment-of-civil-society-in-idlib-governorate\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/attivita\\\/cooperazione-internazionale-2\\\/siria-empowerment-of-civil-society-in-idlib-governorate\\\/\",\"name\":\"Siria: \\\"Sawyan - Empowerment of Civil Society in Idlib Governorate\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/attivita\\\/cooperazione-internazionale-2\\\/siria-empowerment-of-civil-society-in-idlib-governorate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/attivita\\\/cooperazione-internazionale-2\\\/siria-empowerment-of-civil-society-in-idlib-governorate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/aibi-sad-siria.jpg\",\"datePublished\":\"2022-11-22T09:02:03+00:00\",\"dateModified\":\"2024-05-21T13:36:50+00:00\",\"description\":\"L\u2019intervento \u00e8 localizzato in 8 sub-distretti del Governatorato di Idlib, nella Siria nordoccidentale, e mira al rafforzamento strategico delle Organizzazioni della Societ\u00e0 Civile\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/attivita\\\/cooperazione-internazionale-2\\\/siria-empowerment-of-civil-society-in-idlib-governorate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/attivita\\\/cooperazione-internazionale-2\\\/siria-empowerment-of-civil-society-in-idlib-governorate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/attivita\\\/cooperazione-internazionale-2\\\/siria-empowerment-of-civil-society-in-idlib-governorate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/aibi-sad-siria.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2022\\\/10\\\/aibi-sad-siria.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/attivita\\\/cooperazione-internazionale-2\\\/siria-empowerment-of-civil-society-in-idlib-governorate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attivit\u00e0\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/attivita\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cooperazione internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/attivita\\\/cooperazione-internazionale-2\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Siria: &#8220;Sawyan &#8211; Empowerment of Civil Society in Idlib Governorate\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Siria: \"Sawyan - Empowerment of Civil Society in Idlib Governorate\u201d - Ai.Bi. Amici dei Bambini","description":"L\u2019intervento \u00e8 localizzato in 8 sub-distretti del Governatorato di Idlib, nella Siria nordoccidentale, e mira al rafforzamento strategico delle Organizzazioni della Societ\u00e0 Civile","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"it_IT","og_type":"article","og_title":"Siria: \"Sawyan - Empowerment of Civil Society in Idlib Governorate\u201d","og_description":"L\u2019intervento \u00e8 localizzato in 8 sub-distretti del Governatorato di Idlib, nella Siria nordoccidentale, e mira al rafforzamento strategico delle Organizzazioni della Societ\u00e0 Civile","og_url":"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_modified_time":"2024-05-21T13:36:50+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/aibi-sad-siria.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@amicideibambini","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/","url":"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/","name":"Siria: \"Sawyan - Empowerment of Civil Society in Idlib Governorate\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/aibi-sad-siria.jpg","datePublished":"2022-11-22T09:02:03+00:00","dateModified":"2024-05-21T13:36:50+00:00","description":"L\u2019intervento \u00e8 localizzato in 8 sub-distretti del Governatorato di Idlib, nella Siria nordoccidentale, e mira al rafforzamento strategico delle Organizzazioni della Societ\u00e0 Civile","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/aibi-sad-siria.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2022\/10\/aibi-sad-siria.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/siria-empowerment-of-civil-society-in-idlib-governorate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Attivit\u00e0","item":"https:\/\/www.aibi.it\/ita\/attivita\/"},{"@type":"ListItem","position":3,"name":"Cooperazione internazionale","item":"https:\/\/www.aibi.it\/ita\/attivita\/cooperazione-internazionale-2\/"},{"@type":"ListItem","position":4,"name":"Siria: &#8220;Sawyan &#8211; Empowerment of Civil Society in Idlib Governorate\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:58:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/206986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/94"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=206986"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/206986\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/pages\/59840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/205340"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=206986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=206986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=206986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}