﻿


{"id":110831,"date":"2015-09-04T18:38:22","date_gmt":"2015-09-04T16:38:22","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=110831"},"modified":"2015-09-08T18:31:15","modified_gmt":"2015-09-08T16:31:15","slug":"equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/","title":{"rendered":"Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-110832\" style=\"margin: 5px;\" alt=\"accoglienza germania\" src=\"https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania.jpg\" width=\"400\" height=\"286\" data-id=\"110832\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>\u201cGermania, Germania\u201d gridano da giorni <b>le migliaia di profughi siriani<\/b> stipate nella stazione di Budapest. Ne hanno ben ragione: Berlino, infatti, <b>si \u00e8 impegnata ad accogliere 800mila rifugiati <\/b>provenienti dal Paese asiatico, martoriato da 4 anni di guerra civile. Una cifra pari all\u20191% della popolazione tedesca e a <b>4 volte quella dei migranti accolti nel 2014<\/b>. Le autorit\u00e0 ungheresi non li fanno passare, non li vogliono e arrivano a chiudere la stazione della capitale, dopo aver costruito una barriera di filo spinato lungo il confine con la Serbia. Ma i siriani insistono: vogliono andare in Germania, soprattutto in Baviera. Un sogno alimentato dalle <b>recenti parole della cancelliera Merkel<\/b>, che ha annunciato l\u2019apertura delle frontiere proprio a chi arriva dalla Siria, e dal <b>sistema di accoglienza tedesco<\/b>. Un sistema gi\u00e0 ampiamente <b>collaudato nei decenni scorsi<\/b> e in grado di assicurare <b>un\u2019equa distribuzione<\/b> dei profughi nei 16 Lander che compongono la Repubblica Federale, ma soprattutto <b>una dignit\u00e0 e un calore<\/b> che altrove, Italia compresa, i rifugiati faticano a trovare, ammassati come sono nei centri di accoglienza perennemente al collasso.<\/p>\n<p>Dal 2014, infatti, in Germania \u00e8 attivo <b>un sistema basato sull\u2019ospitalit\u00e0 familiare dei migranti<\/b>. Ruota attorno a un sito web, <b>\u201cRefugee Welcome\u201d<\/b>, ideato da due giovani berlinesi che, durante un viaggio al Cairo, si sono resi conto del degrado sociale di molti cittadini egiziani, costretti a emigrare in Europa per trovare condizioni di vita dignitose. L\u2019obiettivo del portale \u00e8 raccogliere la disponibilit\u00e0 da parte di cittadini tedeschi ad accogliere in casa loro dei rifugiati. In pochi mesi gi\u00e0 <b>780 tedeschi hanno messo a disposizione una stanza<\/b> e 107 profughi hanno trovato ospitalit\u00e0 presso di loro. A differenza di quanto accade in Italia, in Germania <b>questa forma di accoglienza \u00e8 incoraggiata dallo Stato<\/b>: i governi locali delle regioni autonome, infatti, forniscono una forma di sussidio, parti a circa 300 euro mensili, a chi accoglie un profugo a casa propria.<\/p>\n<p>Inoltre, fin dagli anni 50, il Paese si \u00e8 dimostrato in grado di distribuire con metodicit\u00e0 gli immigrati sul suo territorio, evitando la formazione di ghetti e investendo i 16 Lander di un\u2019equa responsabilit\u00e0. A garantire l\u2019equilibrio, in questo caso, \u00e8 una sorta di <b>chiave di ripartizione<\/b> basata su 2 fattori: <b>la popolazione della regione e le sue entrate fiscali<\/b>. Le regioni pi\u00f9 ricche e popolose devono sopportare l\u2019onere maggiore nell\u2019accogliere nuovi stranieri.<\/p>\n<p>L\u2019efficacia di questo sistema \u00e8 evidente. In alcuni decenni la Germania <b>ha integrato milioni di turchi<\/b>. Nel solo 2014 ha concesso <b>l\u2019asilo 47.555 persone<\/b> (pi\u00f9 di Italia e Francia messe insieme) e nel primo trimestre 2015 ha ricevuto altre 73.120 richieste, il 32% in pi\u00f9 rispetto al periodo ottobre-dicembre 2014.<\/p>\n<p>Anche l\u2019atteggiamento della societ\u00e0 civile \u00e8 favorevole all\u2019accoglienza. Il 60% dei tedeschi, secondo il settimanale \u201cDer Spiegel\u201d, <b>ritiene \u201cgestibile\u201d l\u2019arrivo in massa dei profughi<\/b>. Un\u2019ondata senza precedenza che in Germania viene percepita come \u201cun peso ma anche una possibilit\u00e0 di creare <b>un Paese pi\u00f9 cosmopolita e generoso<\/b>\u201d. L\u2019economia e la societ\u00e0 stesse hanno bisogno dei migranti: si \u00e8 calcolato che la Germania deve accogliere almeno 300mila immigrati per evitare un forte invecchiamento della popolazione.<\/p>\n<p>Per questo non c\u2019\u00e8 citt\u00e0 tedesca in cui non sia attivo <b>almeno un progetto che miri all\u2019integrazione dei migranti<\/b>. A Erlange, in Baviera, per esempio, un gruppo di aziende ha costituito un consorzio per garantire <b>l\u2019accesso gratuito a Internet<\/b> per gli stranieri che cos\u00ec, recandosi in alcuni caff\u00e8, possono mantenere i contatti con i propri familiari. A Rostock, importante citt\u00e0 portuale sul Baltico, l\u2019associazione \u201cTi ricordi il 1945?\u201d ha creato <b>una rete di aiuti e sostegno <\/b>per armeni, afghani ed eritrei finalizzata al loro inserimento lavorativo. A Gottinga, invece, sono stati inaugurati 80 <b>\u201cGiardini internazionali\u201d per l\u2019interscambio<\/b> con mediatori culturali e altri 60 sono in fase di realizzazione. Tutti esempi che dimostrano come l\u2019accoglienza non sia un\u2019impresa impossibile: basta applicare un sistema semplice, fondato sull\u2019ospitalit\u00e0 di piccoli gruppi, sulla ricchezza sociale e lo scambio di culture.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonti: Corriere della Sera, La Repubblica, La Stampa, <a href=\"http:\/\/www.sonda.life\/profughi-in-germania-il-primo-portale-web-per-laccoglienza-dei-migranti\/\">Sonda.life<\/a>, <a href=\"http:\/\/bedaromano.blog.ilsole24ore.com\/2015\/07\/22\/immigrati-metodi-tedeschi-nellaccoglienza-e-ricollocamento\/\">Il Sole 24 Ore<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cGermania, Germania\u201d gridano da giorni\u00a0<b>le migliaia di profughi siriani<\/b>\u00a0stipate nella stazione di Budapest. Ne hanno ben ragione: Berlino, infatti,\u00a0<b>si \u00e8 impegnata ad accogliere 800mila rifugiati\u00a0<\/b>provenienti dal Paese asiatico, martoriato da 4 anni di guerra civile.<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114],"tags":[],"class_list":["post-110831","post","type-post","status-publish","format-standard","category-aibinews","category-bambini-in-alto-mare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire\" \/>\n<meta property=\"og:description\" content=\"\u201cGermania, Germania\u201d gridano da giorni\u00a0le migliaia di profughi siriani\u00a0stipate nella stazione di Budapest. Ne hanno ben ragione: Berlino, infatti,\u00a0si \u00e8 impegnata ad accogliere 800mila rifugiati\u00a0provenienti dal Paese asiatico, martoriato da 4 anni di guerra civile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-04T16:38:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-08T16:31:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire\",\"datePublished\":\"2015-09-04T16:38:22+00:00\",\"dateModified\":\"2015-09-08T16:31:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/\"},\"wordCount\":669,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/accoglienza-germania.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/\",\"name\":\"Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/accoglienza-germania.jpg\",\"datePublished\":\"2015-09-04T16:38:22+00:00\",\"dateModified\":\"2015-09-08T16:31:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/accoglienza-germania.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/accoglienza-germania.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/","og_locale":"it_IT","og_type":"article","og_title":"Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire","og_description":"\u201cGermania, Germania\u201d gridano da giorni\u00a0le migliaia di profughi siriani\u00a0stipate nella stazione di Budapest. Ne hanno ben ragione: Berlino, infatti,\u00a0si \u00e8 impegnata ad accogliere 800mila rifugiati\u00a0provenienti dal Paese asiatico, martoriato da 4 anni di guerra civile.","og_url":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2015-09-04T16:38:22+00:00","article_modified_time":"2015-09-08T16:31:15+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire","datePublished":"2015-09-04T16:38:22+00:00","dateModified":"2015-09-08T16:31:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/"},"wordCount":669,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania.jpg","articleSection":["AiBiNews","Bambini in alto mare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/","url":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/","name":"Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania.jpg","datePublished":"2015-09-04T16:38:22+00:00","dateModified":"2015-09-08T16:31:15+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/accoglienza-germania.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/equa-familiare-e-incoraggiata-dallo-stato-ecco-perche-laccoglienza-tedesca-e-lesempio-da-seguire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Equa, familiare e incoraggiata dallo Stato: ecco perch\u00e9 l\u2019accoglienza tedesca \u00e8 l\u2019esempio da seguire"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:21:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/110831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=110831"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/110831\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=110831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=110831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=110831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}