﻿


{"id":111367,"date":"2015-09-15T16:35:28","date_gmt":"2015-09-15T14:35:28","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=111367"},"modified":"2015-09-22T18:17:27","modified_gmt":"2015-09-22T16:17:27","slug":"zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/","title":{"rendered":"Zampa (PD): &#8220;Ferma alla Camera la legge per un&#8217;accoglienza giusta dei minori stranieri non accompagnati&#8221;"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/zampa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-106177\" style=\"margin: 5px;\" alt=\"zampa\" src=\"https:\/\/www.aibi.it\/ita\/images\/zampa.jpg\" width=\"400\" height=\"286\" data-id=\"106177\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/zampa.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/zampa-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/zampa-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/zampa-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>La musica \u00e8 un po\u2019 sempre la stessa: <b>non ci sono soldi<\/b>. E a rimetterci \u2013 anche in questo caso \u00a0sembra di assistere a un film gi\u00e0 visto troppe volte \u2013 sono i pi\u00f9 fragili: <b>i minori stranieri non accompagnati<\/b>. Ragazzini, molto spesso bambini, che sbarcano sulle nostre coste senza un adulto di riferimento, completamente soli. Sono migliaia e molti di loro, subito dopo l\u2019arrivo, <b>fanno perdere le proprie tracce<\/b>, finendo il pi\u00f9 delle volte nel tunnel del traffico di esseri umani, della prostituzione, dell\u2019illegalit\u00e0. Eppure la loro salvezza non sarebbe difficile da ottenere: <b>basterebbe accoglierli in affido familiare<\/b>. Lo ha detto e ribadito pi\u00f9 volte, soprattutto recentemente, la Chiesa, che con <b>Papa Francesco<\/b> continua a <b>sollecitare le famiglie ad aprirsi all\u2019accoglienza<\/b> dei profughi, in particolare dei pi\u00f9 deboli. Lo hanno capito proprio <b>le famiglie che a migliaia hanno offerto la propria disponibilit\u00e0<\/b> a ospitare un Misna in casa propria. Chi fatica ancora a rendersi conto dell\u2019importanza di poter contare sulle famiglie come risorse gi\u00e0 pronte e disponibili all\u2019accoglienza \u00e8 <b>il mondo della politica<\/b>. E la ragione, come sempre, sarebbe prettamente economica.<\/p>\n<p>Ne \u00e8 consapevole l\u2019onorevole <b>Sandra Zampa<\/b>, deputata del Partito Democratico, che il 4 ottobre 2013 present\u00f2 <b><a href=\"https:\/\/www.aibi.it\/ita\/quattromila-minori-scomparsi-e-la-proposta-di-legge-zampa-giace-in-fondo-a-un-cassetto\/\">una proposta di legge<\/a> in materia di protezione dei minori stranieri non accompagnati<\/b>, il cui scopo \u00e8 quello di favorire l\u2019accoglienza di questi minori in famiglia. Si era all\u2019indomani del tragico naufragio del 3 ottobre, quando, al largo di Lampedusa, pi\u00f9 di 360 persone persero la vita in mare. La proposta di legge <b>ottenne un consenso politicamente trasversale<\/b>, venendo sottoscritta da una ventina di deputati sia della maggioranza che dell\u2019opposizione. Ma dopo due anni, non ha ancora ottenuto l\u2019approvazione definitiva e <b>non \u00e8 ancora diventata legge<\/b>.<\/p>\n<p><i>\u201cE\u2019 un problema di coperture economiche <\/i>\u2013 conferma l\u2019onorevole Zampa -. <i>Lo dimostra il fatto che il disegno di legge ha superato l\u2019esame di tutte le Commissioni della Camera dei Deputati ed \u00e8 <b>ora fermo in Commissione Affari Costituzionali<\/b>. \u00c8 comunque necessario riprendere al pi\u00f9 presto i lavori per l\u2019approvazione della legge\u201d<\/i>.<\/p>\n<p>Uno stallo che dura da troppo tempo, nonostante il ddl abbia ottenuto l\u2019apprezzamento dell\u2019Authority Garante per l\u2019infanzia e l\u2019adolescenza, sia stato al centro dell\u2019attenzione della I Commissione di Montecitorio che a settembre 2014 deliber\u00f2 un\u2019indagine conoscitiva in materia, e sia stato anche sollecitato <a href=\"https:\/\/www.aibi.it\/ita\/immigrazione-le-associazioni-chiedono-un-decreto-che-istituisca-una-cabina-di-regia-per-laccoglienza-dei-piccoli-migranti\/\">a maggio 2015<\/a> da una decina di associazioni, tra cui <b>Amici dei Bambini<\/b>, ch si occupano di diritti dei minori.<\/p>\n<p>L\u2019approvazione del ddl Zampa sarebbe fondamentale per risolvere l\u2019emergenza dell\u2019accoglienza Misna perch\u00e9 si propone di istituire <b>una cabina di regia<\/b> in grado di regolare in modo organico, su tutto il territorio nazionale, la protezione e l\u2019ospitalit\u00e0 dei piccoli migranti. Nello specifico, l\u2019articolo 8 mira a <b>promuovere \u201cl\u2019istituto dell\u2019affidamento familiare<\/b>, sulla base di significative esperienze\u201d.<\/p>\n<p>Insomma, il mondo della politica dovrebbe aprirsi al pi\u00f9 presto all\u2019appello del Pontefice. <i>\u201cNon passa giorno, infatti, che non sbarchino in Italia bambine, bambini e adolescenti<\/i> \u2013 ribadisce Zampa -. <i>Tra loro moltissimi sono senza genitori o parenti: <b>sono i pi\u00f9 fragili tra i fragili<\/b>. Occorre pertanto <b>approvare al pi\u00f9 presto una legge<\/b> che ne regolamenti le modalit\u00e0 di identificazione e i tempi e le modalit\u00e0 di accoglienza\u201d<\/i>.<\/p>\n<p>Entrando nel merito della sua proposta di legge, Zampa ricorda come essa preveda <i>\u201ctra l\u2019altro la possibilit\u00e0 di affido a famiglie disponibili ad accogliere giovani, <b>come avviene in molte parti d\u2019Europa<\/b>. Si tratterebbe di un\u2019importante opportunit\u00e0 che va <b>nella stessa direzione auspicata di recente da Papa Francesco<\/b>. Accogliere un minore in famiglia<\/i> \u2013 spiega la deputata dem \u2013 <i>significa dargli <b>la possibilit\u00e0 di integrazione<\/b> e <b>restituirgli un po\u2019 di quell\u2019affetto<\/b> che, solo, pu\u00f2 lenire le enormi sofferenze patite prima e durante il viaggio\u201d<\/i>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Amici dei Bambini sostiene l&#8217;affido familiare dei Misna come una delle principali modalit\u00e0 per garantire l&#8217;accoglienza giusta ai tanti bambini e adolescenti che sbarcano da soli sulle nostre coste. Lo fa attraverso con il Sostegno a Distanza e il Sostegno in Vicinanza per i suoi progetti\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/emergenza-profughi\/\" target=\"_blank\">Bambini in Alto Mare<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/emergenza-siria\/\" target=\"_blank\">Io non voglio andare via<\/a>, che si inseriscono nella campagna &#8220;Non restare a guardare&#8221;, finalizzata ad aiutare i piccoli migranti e i bambini siriani a costruirsi un futuro oltre le sofferenze.\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La musica \u00e8 un po\u2019 sempre la stessa:\u00a0<b>non ci sono soldi<\/b>. E a rimetterci \u2013 anche in questo caso \u00a0sembra di assistere a un film gi\u00e0 visto troppe volte \u2013 sono i pi\u00f9 fragili:\u00a0<b>i minori stranieri non accompagnati<\/b>. Ragazzini, molto spesso bambini, che sbarcano sulle nostre coste senza un adulto di riferimento, completamente soli.<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114],"tags":[],"class_list":["post-111367","post","type-post","status-publish","format-standard","category-aibinews","category-bambini-in-alto-mare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Zampa (PD): &quot;Ferma alla Camera la legge per un&#039;accoglienza giusta dei minori stranieri non accompagnati&quot;  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zampa (PD): &quot;Ferma alla Camera la legge per un&#039;accoglienza giusta dei minori stranieri non accompagnati&quot;\" \/>\n<meta property=\"og:description\" content=\"La musica \u00e8 un po\u2019 sempre la stessa:\u00a0non ci sono soldi. E a rimetterci \u2013 anche in questo caso \u00a0sembra di assistere a un film gi\u00e0 visto troppe volte \u2013 sono i pi\u00f9 fragili:\u00a0i minori stranieri non accompagnati. Ragazzini, molto spesso bambini, che sbarcano sulle nostre coste senza un adulto di riferimento, completamente soli.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-15T14:35:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-22T16:17:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/zampa.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Zampa (PD): &#8220;Ferma alla Camera la legge per un&#8217;accoglienza giusta dei minori stranieri non accompagnati&#8221;\",\"datePublished\":\"2015-09-15T14:35:28+00:00\",\"dateModified\":\"2015-09-22T16:17:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/\"},\"wordCount\":716,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/zampa.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/\",\"name\":\"Zampa (PD): \\\"Ferma alla Camera la legge per un'accoglienza giusta dei minori stranieri non accompagnati\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/zampa.jpg\",\"datePublished\":\"2015-09-15T14:35:28+00:00\",\"dateModified\":\"2015-09-22T16:17:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Zampa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Zampa.jpg\",\"width\":100,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zampa (PD): &#8220;Ferma alla Camera la legge per un&#8217;accoglienza giusta dei minori stranieri non accompagnati&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zampa (PD): \"Ferma alla Camera la legge per un'accoglienza giusta dei minori stranieri non accompagnati\"  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/","og_locale":"it_IT","og_type":"article","og_title":"Zampa (PD): \"Ferma alla Camera la legge per un'accoglienza giusta dei minori stranieri non accompagnati\"","og_description":"La musica \u00e8 un po\u2019 sempre la stessa:\u00a0non ci sono soldi. E a rimetterci \u2013 anche in questo caso \u00a0sembra di assistere a un film gi\u00e0 visto troppe volte \u2013 sono i pi\u00f9 fragili:\u00a0i minori stranieri non accompagnati. Ragazzini, molto spesso bambini, che sbarcano sulle nostre coste senza un adulto di riferimento, completamente soli.","og_url":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2015-09-15T14:35:28+00:00","article_modified_time":"2015-09-22T16:17:27+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/zampa.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Zampa (PD): &#8220;Ferma alla Camera la legge per un&#8217;accoglienza giusta dei minori stranieri non accompagnati&#8221;","datePublished":"2015-09-15T14:35:28+00:00","dateModified":"2015-09-22T16:17:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/"},"wordCount":716,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/zampa.jpg","articleSection":["AiBiNews","Bambini in alto mare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/","url":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/","name":"Zampa (PD): \"Ferma alla Camera la legge per un'accoglienza giusta dei minori stranieri non accompagnati\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/zampa.jpg","datePublished":"2015-09-15T14:35:28+00:00","dateModified":"2015-09-22T16:17:27+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Zampa.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Zampa.jpg","width":100,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/zampa-pd-ferma-alla-camera-la-legge-per-unaccoglienza-giusta-dei-minori-stranieri-non-accompagnati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Zampa (PD): &#8220;Ferma alla Camera la legge per un&#8217;accoglienza giusta dei minori stranieri non accompagnati&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:21:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/111367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=111367"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/111367\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=111367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=111367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=111367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}