﻿


{"id":111373,"date":"2015-09-15T16:35:35","date_gmt":"2015-09-15T14:35:35","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=111373"},"modified":"2015-09-15T16:35:35","modified_gmt":"2015-09-15T14:35:35","slug":"posso-accogliere-un-piccolo-migrante-anche-se-sono-single","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/","title":{"rendered":"Posso accogliere un piccolo migrante anche se sono single?"},"content":{"rendered":"<p><b>Buongiorno Ai.Bi.,<\/b><\/p>\n<p><b>sono una docente di 50 anni, nubile, e insegno in una scuola superiore di una cittadina umbra. Da qualche tempo ho concluso una bellissima esperienza di affido con un bambino nigeriano. Il piccolo \u00e8 stato con me un anno, si \u00e8 ambientato benissimo e ha stabilito una positiva rete di amicizie nella zona in cui vivo.<\/b><\/p>\n<p><b>Ora che questa esperienza \u00e8 terminata, vorrei tornare a mettere a disposizione la mia casa, il mio tempo e la mia preparazione per l\u2019accoglienza di un minore in stato di abbandono. Considerata l\u2019emergenza legata ai continui sbarchi di profughi sulle nostre coste, molti dei quali sono giovanissimi, avrei pensato proprio a uno di loro. <\/b><\/p>\n<p><b>Ho letto del vostro progetto Bambini in Alto Mare, che si propone di promuovere l\u2019affido di questi minori. Ho pertanto compilato il form sul vostro sito inserendo i miei dati. <\/b><\/p>\n<p><b>Vorrei capire quante possibilit\u00e0 ho che l\u2019affido si realizzi davvero, soprattutto alla luce del fatto che vivo da sola. Forse per l\u2019accoglienza di un bambino straniero e proveniente da una situazione traumatica come quella del suo Paese di provenienza, del viaggio e dell\u2019approdo in Italia su un barcone, \u00e8 necessaria una famiglia affidataria con due coniugi?<\/b><\/p>\n<p><b>Grazie, <\/b><\/p>\n<p><b>Virginia<\/b><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><a href=\"https:\/\/www.aibi.it\/ita\/images\/tenedini-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-108019\" style=\"margin: 5px;\" alt=\"tenedini-2\" src=\"https:\/\/www.aibi.it\/ita\/images\/tenedini-2.jpg\" width=\"400\" height=\"286\" data-id=\"108019\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/tenedini-2.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/tenedini-2-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/tenedini-2-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/tenedini-2-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>Cara Virginia,<\/p>\n<p>ha fatto benissimo a compilare il form sul nostro sito per offrire la sua disponibilit\u00e0 all\u2019affido familiare di un minore straniero non accompagnato. L\u2019essere nubile, secondo la legge italiana, non rappresenta infatti un ostacolo alla possibilit\u00e0 di accogliere un minore in affido, a differenza di quanto invece accade per l\u2019adozione. E l\u2019affido di un Misna non fa eccezione a questa regola.<\/p>\n<p>Tanto pi\u00f9 che lei proviene da una recente esperienza analoga. Amici dei Bambini, infatti, vaglia attentamente tutte le disponibilit\u00e0 inviate dalle famiglie interessate all\u2019accoglienza di giovani migranti, ma accorda una sorta di precedenza a coloro che hanno gi\u00e0 esperienze pregresse di accoglienza di minori, in affido o in adozione.<\/p>\n<p>Considero necessario, tuttavia, precisare due aspetti. Il primo: un minore straniero non accompagnato non pu\u00f2 essere considerato in stato di abbandono. Il fatto che sia giunto in Italia da solo, senza adulti di riferimento, a bordo di un barcone non implica necessariamente che sia privo di una famiglia. Anzi, nella maggior parte dei casi, i Misna partono per l\u2019Europa lasciando nei propri Paesi di origine genitori, fratelli e sorelle, con i quali, una volta giunti a destinazione, chiedono e hanno il diritto di restare in contatto. Il secondo: la maggior parte dei Misna non sono bambini, ma ragazzini adolescenti, di et\u00e0 compresa soprattutto nella fascia dai 13 ai 17 anni.<\/p>\n<p>Avendo compilato il form sul nostro sito, presto ricever\u00e0 una e-mail con la richiesta di ulteriori informazioni, quindi il suo nominativo verr\u00e0 inserito in un database insieme a tutte le altre famiglie disponibili. A questo punto la sede Ai.Bi. pi\u00f9 vicina a casa sua la contatter\u00e0 per invitarla a partecipare ai corsi di formazione per aspiranti famiglie affidatarie. Compiuto quest\u2019ultimo passaggio, si dovr\u00e0 attendere il via libera per l\u2019affido. Il quale, \u00e8 bene saperlo, rappresenta la fase pi\u00f9 difficile, vista la cronica e inspiegabile tendenza da parte delle istituzioni a non incoraggiare l\u2019affido familiare come modalit\u00e0 di accoglienza dei minori stranieri non accompagnati. Una circostanza che per\u00f2 non frena noi di Ai.Bi. dal batterci ogni giorno per un\u2019accoglienza giusta, familiare, dei Misna.<\/p>\n<p>Un caro saluto,<\/p>\n<p>&nbsp;<\/p>\n<p>Valentina Tenedini<\/p>\n<p>Area Italia Ai.Bi.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Vorrei capire quante possibilit\u00e0 ho che<strong> l\u2019affido di un minore stranieri non accompagnato<\/strong> si realizzi davvero, soprattutto alla luce del fatto che <strong>vivo da sola<\/strong>. Forse per l\u2019accoglienza di un bambino straniero \u00e8 necessaria una famiglia affidataria con due coniugi? &#8211; <em>Risponde Valentina Tenedini (nel ritratto)<\/em><\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,50],"tags":[],"class_list":["post-111373","post","type-post","status-publish","format-standard","category-bambini-in-alto-mare","category-lettere-al-direttore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Posso accogliere un piccolo migrante anche se sono single? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Posso accogliere un piccolo migrante anche se sono single?\" \/>\n<meta property=\"og:description\" content=\"Vorrei capire quante possibilit\u00e0 ho che l\u2019affido di un minore stranieri non accompagnato si realizzi davvero, soprattutto alla luce del fatto che vivo da sola. Forse per l\u2019accoglienza di un bambino straniero \u00e8 necessaria una famiglia affidataria con due coniugi? - Risponde Valentina Tenedini (nel ritratto)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-15T14:35:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/tenedini-2.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Posso accogliere un piccolo migrante anche se sono single?\",\"datePublished\":\"2015-09-15T14:35:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/\"},\"wordCount\":575,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tenedini-2.jpg\",\"articleSection\":[\"Bambini in alto mare\",\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/\",\"name\":\"Posso accogliere un piccolo migrante anche se sono single? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tenedini-2.jpg\",\"datePublished\":\"2015-09-15T14:35:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tenedini-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tenedini-2.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bambini in alto mare\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/bambini-in-alto-mare\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Posso accogliere un piccolo migrante anche se sono single?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Posso accogliere un piccolo migrante anche se sono single? - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/","og_locale":"it_IT","og_type":"article","og_title":"Posso accogliere un piccolo migrante anche se sono single?","og_description":"Vorrei capire quante possibilit\u00e0 ho che l\u2019affido di un minore stranieri non accompagnato si realizzi davvero, soprattutto alla luce del fatto che vivo da sola. Forse per l\u2019accoglienza di un bambino straniero \u00e8 necessaria una famiglia affidataria con due coniugi? - Risponde Valentina Tenedini (nel ritratto)","og_url":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2015-09-15T14:35:35+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/tenedini-2.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Posso accogliere un piccolo migrante anche se sono single?","datePublished":"2015-09-15T14:35:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/"},"wordCount":575,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/tenedini-2.jpg","articleSection":["Bambini in alto mare","Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/","url":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/","name":"Posso accogliere un piccolo migrante anche se sono single? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/tenedini-2.jpg","datePublished":"2015-09-15T14:35:35+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/tenedini-2.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/tenedini-2.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/posso-accogliere-un-piccolo-migrante-anche-se-sono-single\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Bambini in alto mare","item":"https:\/\/www.aibi.it\/ita\/category\/bambini-in-alto-mare\/"},{"@type":"ListItem","position":3,"name":"Posso accogliere un piccolo migrante anche se sono single?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:21:09","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/111373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=111373"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/111373\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=111373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=111373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=111373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}