﻿


{"id":111753,"date":"2015-09-21T17:31:10","date_gmt":"2015-09-21T15:31:10","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=111753"},"modified":"2015-09-21T18:33:35","modified_gmt":"2015-09-21T16:33:35","slug":"bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/","title":{"rendered":"Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi."},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/bam-nuovo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-111791\" style=\"margin: 5px;\" alt=\"bam-nuovo\" src=\"https:\/\/www.aibi.it\/ita\/images\/bam-nuovo.jpg\" width=\"400\" height=\"286\" data-id=\"111791\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/bam-nuovo.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/bam-nuovo-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/bam-nuovo-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/bam-nuovo-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>Abbiamo ancora tutti negli occhi l\u2019immagine forse pi\u00f9 drammatica degli ultimi mesi: quella che ritrae <b>il corpicino di Aylan<\/b>, un piccolo profugo siriano, giungere cadavere, annegato, su una spiaggia della Turchia. Aylan \u00e8 diventato, suo malgrado, <b>il simbolo di una realt\u00e0 molto pi\u00f9 grande di lui<\/b>, fatta di numeri impressionanti. Il Mediterraneo sta diventando sempre pi\u00f9 un cimitero di migliaia di persone che, in fuga dalla guerra o dalla miseria, tentano la traversata verso l\u2019Europa e troppo spesso, anzich\u00e9 una nuova vita, trovano la morte. Ma c\u2019\u00e8 una tragedia nella tragedia: sempre pi\u00f9 frequentemente, <b>le vittime dei naufragi sono \u00a0bambini<\/b> come Aylan, che travolti dalle onde spariscono per sempre alla vista dei loro genitori oppure viaggiano e muoiono da soli, ignorati da tutti. Quasi ogni giorno, ormai, si viene a sapere dalle cronache di <b>barconi stracolmi di migranti che si rovesciano<\/b> al largo delle coste italiane o greche e che portano con s\u00e9, sui fondali o sulle rive del Mediterraneo i corpicini di tanti piccoli Aylan. E anche per coloro che riescono a giungere a destinazione, la salvezza \u00e8 ancora lontana. Se non degnamente accolti, rischiano di <b>perdersi nel tunnel<\/b> dell\u2019illegalit\u00e0, dello sfruttamento, della prostituzione, della tratta di esseri umani.<\/p>\n<p>\u00c8 di fronte a tutto questo che <b>Amici dei Bambini<\/b> ha deciso di non restare solo a guardare, lanciando la campagna <em>Bambini in Alto Mare<\/em>. Un\u2019iniziativa che si fonda su due obiettivi: <b>aiutare i piccoli profughi a non partire<\/b>, facendo in modo che ritrovino la serenit\u00e0 e il diritto all\u2019infanzia anche nei loro martoriati Paesi, e <b>garantire un\u2019accoglienza a misura di bambino<\/b> ai piccoli migranti che arrivano in Italia. Si tratta di due missioni complesse, per le quali \u00e8 <b>necessario il sostegno di tutti<\/b>. Un sostegno che si pu\u00f2 concretizzare anche in piccoli gesti di solidariet\u00e0 a favore di quelli che senza esitazioni potremmo definire \u201ci pi\u00f9 fragili tra i fragili\u201d. Per questo da oggi, luned\u00ec 21 settembre, <b>Ai.Bi. attiva un numero verde<\/b> \u2013 <b>800224455<\/b> \u2013 a cui possono rivolgersi tutti coloro che intendono <b>effettuare una donazione <\/b>per un\u2019accoglienza a misura di bambino, ovvero per i nostri progetti dedicati ai piccoli profughi, <b><i><a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/emergenza-siria\/\">Io non voglio andare via<\/a><\/i> <\/b>e <i>Non lasciamoli soli<\/i>.<\/p>\n<p>Il primo \u00e8 l\u2019intervento di Ai.Bi. nel nord della Siria, una terra martoriata da pi\u00f9 di 4 anni di guerra civile e di atrocit\u00e0 di ogni sorta. Qui, vogliamo restituire ai bambini la possibilit\u00e0 di <b>sentirsi a casa nel loro Paese<\/b>, garantendo loro <b>il diritto al gioco, alla salute, al cibo, alla casa, allo studio<\/b>. Per farlo abbiamo gi\u00e0 realizzato <strong>l<\/strong><b>a ludoteca sotterranea<\/b>, in cui sia possibile giocare al riparo dalla bombe, <b>il forno<\/b> che produca 2 tonnellate di pane al giorno e sfami le famiglie pi\u00f9 povere, e <b>la sartoria<\/b> che dia lavoro a decine di mamme siriane.<\/p>\n<p><b><i><a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/emergenza-profughi\/\">N<\/a>on lasciamoli soli<\/i><\/b>\u00a0\u00e8 invece il progetto di Ai.Bi. che vuole garantire <b>la giusta accoglienza ai Minori stranieri non accompagnati<\/b> e alle mamme con figli piccoli che giungono da soli sulle coste italiane. Per loro, la giusta accoglienza non pu\u00f2 che essere quella familiare. Per questo, Ai.Bi. promuove con forza <b>l\u2019affido familiare<\/b>, un appello a cui hanno gi\u00e0 risposto circa 1.800 famiglie italiane che hanno offerto la propria disponibilit\u00e0 a questa forma di accoglienza a misura di bambini. Ma non solo: Ai.Bi. gestisce anche piccole <b>case di accoglienza per famiglie migranti<\/b>, convinta che la vera ospitalit\u00e0 si debba basare su numeri ridotti e contesti familiari. E ancora: reti di famiglie di pronta accoglienza a Lampedusa, ludoteche a Bolzano per i piccoli profughi in transito, gruppi di volontari, centri di servizi alle famiglie di Milano, Messina e Salerno per la formazione di coloro che si vogliono dedicare all\u2019accoglienza.<\/p>\n<p>A chiunque voglia offrire il proprio contributo in questo quadro sono dedicate <b>le serate organizzate da Ai.Bi. <a href=\"https:\/\/www.aibi.it\/ita\/chi-siamo\/aibi-in-italia\/\">in tutte le sue sedi italiane<\/a> nella settimana dal 22 al 27 settembre<\/b>. Da Torino a Barletta, da Bolzano a Messina, da Bologna a Cagliari, passando per Firenze, Roma e Salerno, tutte le sedi Ai.Bi. in Italia terranno <b>un incontro di approfondimento<\/b> sulla campagna <i>Bambini in Alto Mare<\/i> e in particolare sui due interventi, <i>Io non voglio andare via<\/i> e <i>Non lasciamoli soli<\/i>.<\/p>\n<p>Si comincer\u00e0 <b>marted\u00ec 22 settembre<\/b> nelle sedi di <b>Bologna e Firenze<\/b> alle ore 15, <b>Barletta<\/b> alle 18.30, <b>Cagliari<\/b> alle 19.30 e Milano (quartiere Affori) alle 21. Secondo giorno di incontri <b>mercoled\u00ec 23<\/b>: a <b>Messina<\/b> alle ore 19, a <b>Torino <\/b>e a <b>Roma<\/b> alle 21. <b>Gioved\u00ec 24<\/b> appuntamento a <b>Bolzano<\/b> alle 20, per chiudere, <b>sabato 26<\/b>, <b>a Salerno <\/b>alle 18.30 all\u2019Eco Bistrot sul lungomare Colombo 23\/25.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abbiamo ancora tutti negli occhi l\u2019immagine che ritrae\u00a0<b>il corpicino di Aylan<\/b>, un piccolo profugo siriano, giungere cadavere, annegato, su una spiaggia della Turchia. Aylan \u00e8 diventato, suo malgrado,\u00a0<b>il simbolo di una realt\u00e0 molto pi\u00f9 grande di lui<\/b>. Il Mediterraneo sta diventando sempre pi\u00f9 un cimitero di migliaia di persone che, in fuga dalla guerra o dalla miseria, tentano la traversata verso l\u2019Europa e troppo spesso, anzich\u00e9 una nuova vita, trovano la morte. Ma c\u2019\u00e8 una tragedia nella tragedia: sempre pi\u00f9 frequentemente,\u00a0<b>le vittime dei naufragi sono \u00a0bambini<\/b>\u00a0che travolti dalle onde spariscono per sempre alla vista dei loro genitori oppure viaggiano e muoiono da soli, ignorati da tutti.<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114],"tags":[],"class_list":["post-111753","post","type-post","status-publish","format-standard","category-aibinews","category-bambini-in-alto-mare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi.\" \/>\n<meta property=\"og:description\" content=\"Abbiamo ancora tutti negli occhi l\u2019immagine che ritrae\u00a0il corpicino di Aylan, un piccolo profugo siriano, giungere cadavere, annegato, su una spiaggia della Turchia. Aylan \u00e8 diventato, suo malgrado,\u00a0il simbolo di una realt\u00e0 molto pi\u00f9 grande di lui. Il Mediterraneo sta diventando sempre pi\u00f9 un cimitero di migliaia di persone che, in fuga dalla guerra o dalla miseria, tentano la traversata verso l\u2019Europa e troppo spesso, anzich\u00e9 una nuova vita, trovano la morte. Ma c\u2019\u00e8 una tragedia nella tragedia: sempre pi\u00f9 frequentemente,\u00a0le vittime dei naufragi sono \u00a0bambini\u00a0che travolti dalle onde spariscono per sempre alla vista dei loro genitori oppure viaggiano e muoiono da soli, ignorati da tutti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-21T15:31:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-21T16:33:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bam-nuovo.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi.\",\"datePublished\":\"2015-09-21T15:31:10+00:00\",\"dateModified\":\"2015-09-21T16:33:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/\"},\"wordCount\":767,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bam-nuovo.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/\",\"name\":\"Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bam-nuovo.jpg\",\"datePublished\":\"2015-09-21T15:31:10+00:00\",\"dateModified\":\"2015-09-21T16:33:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bam-nuovo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bam-nuovo.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi. - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/","og_locale":"it_IT","og_type":"article","og_title":"Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi.","og_description":"Abbiamo ancora tutti negli occhi l\u2019immagine che ritrae\u00a0il corpicino di Aylan, un piccolo profugo siriano, giungere cadavere, annegato, su una spiaggia della Turchia. Aylan \u00e8 diventato, suo malgrado,\u00a0il simbolo di una realt\u00e0 molto pi\u00f9 grande di lui. Il Mediterraneo sta diventando sempre pi\u00f9 un cimitero di migliaia di persone che, in fuga dalla guerra o dalla miseria, tentano la traversata verso l\u2019Europa e troppo spesso, anzich\u00e9 una nuova vita, trovano la morte. Ma c\u2019\u00e8 una tragedia nella tragedia: sempre pi\u00f9 frequentemente,\u00a0le vittime dei naufragi sono \u00a0bambini\u00a0che travolti dalle onde spariscono per sempre alla vista dei loro genitori oppure viaggiano e muoiono da soli, ignorati da tutti.","og_url":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2015-09-21T15:31:10+00:00","article_modified_time":"2015-09-21T16:33:35+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/bam-nuovo.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi.","datePublished":"2015-09-21T15:31:10+00:00","dateModified":"2015-09-21T16:33:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/"},"wordCount":767,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bam-nuovo.jpg","articleSection":["AiBiNews","Bambini in alto mare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/","url":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/","name":"Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bam-nuovo.jpg","datePublished":"2015-09-21T15:31:10+00:00","dateModified":"2015-09-21T16:33:35+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/bam-nuovo.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/bam-nuovo.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/bambini-in-alto-mare-il-numero-verde-da-chiamare-per-non-restare-solo-a-guardare-il-programma-degli-eventi-organizzati-dalle-sedi-ai-bi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Bambini in alto mare: il numero verde da chiamare per non restare solo a guardare. Il programma degli eventi organizzati dalle sedi Ai.Bi."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:21:26","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/111753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=111753"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/111753\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=111753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=111753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=111753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}