﻿


{"id":111840,"date":"2015-09-22T18:06:42","date_gmt":"2015-09-22T16:06:42","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=111840"},"modified":"2015-09-22T18:06:42","modified_gmt":"2015-09-22T16:06:42","slug":"come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/","title":{"rendered":"Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere?"},"content":{"rendered":"<p><b>Buongiorno Ai.Bi.<\/b><\/p>\n<p><b>So che vi occupate da tanti anni di bambini abbandonati e di trovare una\u00a0 famiglia a tanti minori, sia in Italia che nel mondo. Vi scrivo per chiedervi un consiglio su come comportarmi di fronte a un mio grave problema.<\/b><\/p>\n<p><b>Sono una ragazza di 20 anni e sto vivendo un momento di vera disperazione. Purtroppo ho fatto una sciocchezza e sono rimasta incinta. Mi sono accorta del mio stato di gravidanza quando ormai era troppo tardi, alla ventunesima settimana. Se da un lato so di non avere assolutamente la possibilit\u00e0 di tenere con me il bambino che nascer\u00e0 tra qualche mese, dall\u2019altro non intendo interrompere la mia gravidanza perch\u00e9 sono di principio contraria all\u2019aborto. Lo vorrei dare in adozione subito dopo la nascita, se possibile. Sapreste dirmi come fare?<\/b><\/p>\n<p><b>Grazie, <\/b><\/p>\n<p><b>Silvana<\/b><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><a href=\"https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-102719\" style=\"margin: 5px;\" alt=\"MARIA GALEAZZI (3)\" src=\"https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3.png\" width=\"400\" height=\"286\" data-id=\"102719\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3.png 400w, https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3-150x107.png 150w, https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3-300x215.png 300w, https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3-77x55.png 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>Cara Silvana,<\/p>\n<p>non c\u2019\u00e8 alcuna ragione di temere n\u00e9 per te n\u00e9 per tuo figlio. La legge italiana viene incontro al desiderio e alle necessit\u00e0 di quelle madri che decidono di mettere al mondo un bambino pur sapendo consapevolmente di non poterlo tenere con s\u00e9 e di non poterlo crescere.<\/p>\n<p>Quello che ti consigliamo di fare \u00e8 di portare a termine regolarmente la gravidanza e di andare a partorire in ospedale. Qui, potrai immediatamente dichiarare di voler partorire in anonimato. In tal modo, il neonato verr\u00e0 subito dichiarato adottabile e potr\u00e0 nel giro di poco tempo trovare una nuova famiglia attraverso una procedura di adozione nazionale.<\/p>\n<p>Il parto in anonimato in ospedale, per le donne che non intendono tenere con s\u00e9 il proprio figlio, \u00e8 la soluzione migliore per diversi aspetti. Innanzitutto la partoriente viene costantemente seguita e assistita dal personale medico e sanitario specializzato, al pari, ovviamente, di tutte le altre madri. In secondo luogo, la decisione di lasciare il neonato in ospedale dopo un parto in anonimato non \u00e8 considerato abbandono di minore e quindi non \u00e8 perseguibile come tale. Siamo nella situazione opposta, pertanto, ai frequenti drammatici casi in cui i neonati vengono partoriti in casa o per strada e abbandonati nei cassonetti o sotto i sedili dei treni. In quelle situazioni, la salute del nascituro e della madre \u00e8 ovviamente esposta a maggiori rischi e la donna \u00e8 perseguibile per il reato di abbandono di minore. Infine, le donne che decidono di partorire in anonimato in ospedale hanno diritto a rimanere segrete anche successivamente: il loro anonimato, quindi, resta tutelato e non vi \u00e8 il rischio, in futuro, che la loro identit\u00e0 venga resa nota ai figli senza autorizzazione delle stesse madri.<\/p>\n<p>Alla luce di questo, ti posso raccomandare di restare tranquilla e di concludere serenamente la tua gravidanza, nella certezza che il tuo bambino potr\u00e0 crescere in una famiglia adottiva fin dalle prime settimane successive alla sua nascita.<\/p>\n<p>Un caro saluto,<\/p>\n<p>&nbsp;<\/p>\n<p>Maria Galeazzi<\/p>\n<p>Area Italia di Ai.Bi.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Se da un lato so di non avere assolutamente la possibilit\u00e0 di <strong>tenere con me il bambino<\/strong> che nascer\u00e0 tra qualche mese, dall\u2019altro non intendo interrompere la mia gravidanza perch\u00e9 <strong>sono di principio contraria all\u2019aborto<\/strong>. Lo vorrei dare in adozione &#8211; <em>Risponde Maria Galeazzi (nel ritratto)<\/em><\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-111840","post","type-post","status-publish","format-standard","category-lettere-al-direttore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere?\" \/>\n<meta property=\"og:description\" content=\"Se da un lato so di non avere assolutamente la possibilit\u00e0 di tenere con me il bambino che nascer\u00e0 tra qualche mese, dall\u2019altro non intendo interrompere la mia gravidanza perch\u00e9 sono di principio contraria all\u2019aborto. Lo vorrei dare in adozione - Risponde Maria Galeazzi (nel ritratto)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-22T16:06:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3.png\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere?\",\"datePublished\":\"2015-09-22T16:06:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/\"},\"wordCount\":477,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MARIA-GALEAZZI-3.png\",\"articleSection\":[\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/\",\"name\":\"Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MARIA-GALEAZZI-3.png\",\"datePublished\":\"2015-09-22T16:06:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MARIA-GALEAZZI-3.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MARIA-GALEAZZI-3.png\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettere al direttore\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lettere-al-direttore\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere? - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/","og_locale":"it_IT","og_type":"article","og_title":"Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere?","og_description":"Se da un lato so di non avere assolutamente la possibilit\u00e0 di tenere con me il bambino che nascer\u00e0 tra qualche mese, dall\u2019altro non intendo interrompere la mia gravidanza perch\u00e9 sono di principio contraria all\u2019aborto. Lo vorrei dare in adozione - Risponde Maria Galeazzi (nel ritratto)","og_url":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2015-09-22T16:06:42+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3.png","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere?","datePublished":"2015-09-22T16:06:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/"},"wordCount":477,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3.png","articleSection":["Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/","url":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/","name":"Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3.png","datePublished":"2015-09-22T16:06:42+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/MARIA-GALEAZZI-3.png","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/come-posso-dare-in-adozione-il-figlio-che-partoriro-e-che-non-potro-tenere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lettere al direttore","item":"https:\/\/www.aibi.it\/ita\/category\/lettere-al-direttore\/"},{"@type":"ListItem","position":3,"name":"Come posso dare in adozione il figlio che partorir\u00f2 e che non potr\u00f2 tenere?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:56:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/111840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=111840"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/111840\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=111840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=111840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=111840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}