﻿


{"id":112366,"date":"2015-09-30T20:25:56","date_gmt":"2015-09-30T18:25:56","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=112366"},"modified":"2015-11-09T11:09:26","modified_gmt":"2015-11-09T10:09:26","slug":"adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/","title":{"rendered":"Adozione internazionale. Sudamerica. &#8220;Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare&#8221;"},"content":{"rendered":"<p><b><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-114814 alignleft\" style=\"margin: 5px;\" alt=\"08-15\" src=\"https:\/\/www.aibi.it\/ita\/images\/08-15.jpg\" width=\"200\" height=\"200\" data-id=\"114814\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/08-15.jpg 200w, https:\/\/www.aibi.it\/ita\/images\/08-15-150x150.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/08-15-55x55.jpg 55w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>E\u2019 un giovane e promettente \u201ccaballero\u201d del Sudamerica, ama stare all\u2019aria aperta e sta imparando tutto ci\u00f2 che ha a che fare con la campagna e il mondo delle fattorie.<\/b> Sta imparando soprattutto che c\u2019\u00e8 un mondo variopinto e colorato \u201cfuori\u201d, un mondo ricco di emozioni e creature con cui entrare in contatto. Tutto quello che finora aveva solo visto sui libri che a fatica riesce a leggere nonostante i suoi 10 anni.<\/p>\n<p>Ma non per qualche problema specifico a livello cognitivo, perch\u00e9 il nostro \u201ccaballero\u201d non ha nulla che non vada, <b>gli \u00e8 solo mancato finora qualcuno che gli insegnasse a leggere<\/b>. Che si sedesse accanto a lui e gli indicasse le lettere, le vocali, che gli raccontasse le favole seguendo con il dito le righe della pagina per poi sfogliarle con lui.<\/p>\n<p><b>Il nostro caballero \u00e8 senza una mamma e un pap\u00e0 e riporta sulla sua \u201cpelle\u201d e anima le conseguenze della solitudine<\/b>. Un male non impossibile da sconfiggere: \u00e8 bastato, infatti, stare in casa presso una famiglia affidataria che la sua mente e i suoi occhi si sono \u201caperti\u201d al mondo. <b>Gli \u00e8 bastato essere considerato, coccolato, ricevere attenzioni per rinascere a nuova vita e recuperare tutto il tempo perso.<\/b><\/p>\n<p>Ma non \u00e8 sufficiente: una famiglia affidataria non \u00e8 per sempre e <b>il rischio per il nostro caballero \u00e8 quello di ripiombare nel buio della solitudine<\/b>. Quella voragine che tutto divora <b>annullando qualsiasi voglia ed entusiasmo: di imparare, di conoscere, di vivere.<\/b><\/p>\n<p>Il \u201ccaballero\u201d non ha nessun problema fisico o psichico. E&#8217; entrato sotto protezione dello stato solo da poco pi\u00f9 di un anno, precedentemente ha vissuto a fasi alterne con la madre ed uno zio. \u00a0Al momento \u00e8 seguito da un nutrizionista poich\u00e9 la sua altezza non \u00e8 conforme all\u2019et\u00e0, situazione probabilmente dovuta ad una condizione alimentare non idonea per il bambino.<\/p>\n<p>Al suo ingresso \u00e8 stato seguito da uno psicologo per la sua iniziale difficolt\u00e0 nel risolvere i conflitti e imparare ad accettare norme e regole. Tutte conquiste che ha pian piano ha fatto proprie da quando si trova in famiglia affidataria: in pochi mesi, infatti, ha migliorato notevolmente la sua autostima, mostra affetto verso gli altri bambini accolti dalla famiglia, ascolta e accetta le osservazioni.<\/p>\n<p>La mamma biologica non ha mostrato nessun interesse a riprenderlo con s\u00e9 oltre a fare uso di droghe: d\u2019altra parte il bambino non chiede di lei e si \u00e8 ben integrato nella famiglia che lo ospita.<\/p>\n<p>Ma tutto questo pu\u00f2 dissolversi come una bolla d\u2019aria e fare tornare indietro il nostro caballero. <b>L\u2019unica cosa che potrebbe salvarlo \u00e8 una famiglia adottiva: una mamma e un pap\u00e0 che gli assicurino la loro presenza nel futuro, ora e doman<\/b>i. Dei punti di riferimento su cui fare affidamento, davanti ai quali abbassare le proprie difese e da cui imparare a leggere e ad amare gli altri e la vita.<\/p>\n<p>Se volete salvare la vita di questo piccolo grande caballero, potete cliccare <a href=\"https:\/\/www.aibi.it\/ita\/figli-in-attesa\/figli_in_attesa_scheda-0815.html\">qui<\/a>, dove sono riportate ulteriori info sul nostro bimbo e candidarvi ad essere i suoi genitori. Lui sta aspettando solo voi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><b>E\u2019 un giovane e promettente \u201ccaballero\u201d del Sudamerica<\/b>, ama stare all\u2019aria aperta e sta imparando tutto ci\u00f2 che ha a che fare con la campagna e il mondo delle fattorie. Grazie alla famiglia affidataria sta sconfiggendo il male della solitudine, ma ha bisogno di una mamma e di un pap\u00e0 che lo accolgano per sempre. Una famiglia affidataria non \u00e8 per sempre e\u00a0<b>il rischio per il nostro caballero \u00e8 quello di ripiombare nel buoi della solitudine.<\/b><\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89,71],"tags":[],"class_list":["post-112366","post","type-post","status-publish","format-standard","category-appelli-adozioni-internazionali-concluse","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. Sudamerica. &quot;Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare&quot; - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. Sudamerica. &quot;Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare&quot;\" \/>\n<meta property=\"og:description\" content=\"E\u2019 un giovane e promettente \u201ccaballero\u201d del Sudamerica, ama stare all\u2019aria aperta e sta imparando tutto ci\u00f2 che ha a che fare con la campagna e il mondo delle fattorie. Grazie alla famiglia affidataria sta sconfiggendo il male della solitudine, ma ha bisogno di una mamma e di un pap\u00e0 che lo accolgano per sempre. Una famiglia affidataria non \u00e8 per sempre e\u00a0il rischio per il nostro caballero \u00e8 quello di ripiombare nel buoi della solitudine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-30T18:25:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-09T10:09:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/08-15.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Adozione internazionale. Sudamerica. &#8220;Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare&#8221;\",\"datePublished\":\"2015-09-30T18:25:56+00:00\",\"dateModified\":\"2015-11-09T10:09:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/\"},\"wordCount\":527,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/08-15.jpg\",\"articleSection\":[\"Adozioni Realizzate\",\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/\",\"name\":\"Adozione internazionale. Sudamerica. \\\"Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/08-15.jpg\",\"datePublished\":\"2015-09-30T18:25:56+00:00\",\"dateModified\":\"2015-11-09T10:09:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/08-15.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/08-15.jpg\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozioni Realizzate\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/appelli-adozioni-internazionali-concluse\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. Sudamerica. &#8220;Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. Sudamerica. \"Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare\" - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. Sudamerica. \"Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare\"","og_description":"E\u2019 un giovane e promettente \u201ccaballero\u201d del Sudamerica, ama stare all\u2019aria aperta e sta imparando tutto ci\u00f2 che ha a che fare con la campagna e il mondo delle fattorie. Grazie alla famiglia affidataria sta sconfiggendo il male della solitudine, ma ha bisogno di una mamma e di un pap\u00e0 che lo accolgano per sempre. Una famiglia affidataria non \u00e8 per sempre e\u00a0il rischio per il nostro caballero \u00e8 quello di ripiombare nel buoi della solitudine.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2015-09-30T18:25:56+00:00","article_modified_time":"2015-11-09T10:09:26+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/08-15.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Adozione internazionale. Sudamerica. &#8220;Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare&#8221;","datePublished":"2015-09-30T18:25:56+00:00","dateModified":"2015-11-09T10:09:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/"},"wordCount":527,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/08-15.jpg","articleSection":["Adozioni Realizzate","AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/","name":"Adozione internazionale. Sudamerica. \"Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/08-15.jpg","datePublished":"2015-09-30T18:25:56+00:00","dateModified":"2015-11-09T10:09:26+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/08-15.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/08-15.jpg","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-sudamerica-anche-se-ho-gia-10-anni-e-nessuno-mi-ha-ancora-voluto-leggi-la-storia-della-mia-vita-almeno-questo-lo-puoi-fare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozioni Realizzate","item":"https:\/\/www.aibi.it\/ita\/category\/appelli-adozioni-internazionali-concluse\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. Sudamerica. &#8220;Anche se ho gi\u00e0 10 anni e nessuno mi ha ancora voluto, leggi la storia della mia vita: almeno questo lo puoi fare&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:49:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/112366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=112366"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/112366\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=112366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=112366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=112366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}