﻿


{"id":115690,"date":"2015-11-20T16:30:32","date_gmt":"2015-11-20T15:30:32","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=115690"},"modified":"2015-11-23T17:35:55","modified_gmt":"2015-11-23T16:35:55","slug":"tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/","title":{"rendered":"Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d"},"content":{"rendered":"<p><b><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-115691\" style=\"margin: 5px;\" alt=\"tatiana-400-286\" src=\"https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861.jpg\" width=\"400\" height=\"286\" data-id=\"115691\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>L\u2019ha saputo in diretta dalla sua amica del cuore che vive in Bolivia<\/b> e ha festeggiato con lei al telefono. Per poi <b>brindare con la sua famiglia adottiva che l\u2019ha accolta quando lei aveva solo 3 anni,<\/b> regalandole cos\u00ec una nuova chance di vita. Lei \u00e8 <b>Tatiana Salomoni<\/b>, 18 anni, <b>boliviana di nascita e italiana d\u2019adozione<\/b>. Studia grafica pubblicitaria ed \u00e8 una miscela insieme dolce e forte di accento bolognese e fierezza boliviana. <strong>Tatiana \u00e8 stata la prima bambina boliviana adottata da Ai.Bi.<\/strong> : a 3 anni ha attraversato l&#8217;Oceano per arrivare in Italia, a Bologna dove ad aspettarla c&#8217;era una mamma, un pap\u00e0 e due fratelli brasiliani.<\/p>\n<p>\u201c<b><i>Aspettavo con ansia ma anche con un buon margine di buona fede e ottimismo<\/i><\/b>\u2013 racconta Tatiana \u2013<i> la riapertura delle adozioni in Bolivia. Ora i \u2018miei\u2019 bambini avranno la possibilit\u00e0 concreta di essere felici. Cos\u00ec come \u00e8 successo a me 15 anni fa<\/i>\u201d.<\/p>\n<p>La notizia della <a href=\"https:\/\/www.aibi.it\/ita\/sensazionale-la-bolivia-riapre-le-adozioni-internazionali-ai-bi-accreditata-fino-al-2020\/\">riapertura delle adozioni<\/a> \u201c<i>\u00e8 il pi\u00f9 bel regalo che potessi ricevere dal mio Paese: il miglior modo per festeggiare la giornata internazionale dei diritti dell\u2019infanzia. <b>Grazie Bolivia, sei grande!\u00a0 Il pi\u00f9 bel regalo del mio Paese<\/b>: una notizia storica per un giorno storico<\/i>\u201d<\/p>\n<p>Tatiana \u00e8 nata a La Paz, dove ha vissuto per tre anni in un istituto. Poi un giorno arrivarono mamma e pap\u00e0 e Tatiana se ne vol\u00f2 via, fino in Emilia Romagna. In famiglia ad accoglierla, una sorella e un fratello brasiliani di nascita.<\/p>\n<p>\u201c<i>E\u2019 stato importantissimo per me trovare a casa due punti di riferimento come loro <\/i>\u2013 continua &#8211;<i>: spesso da piccola prendevo mia sorella come esempio, mi ha aiutato molto nella crescita. Anche i miei fratelli sono stati un dono, non solo, ovviamente, i miei genitori<\/i>\u201d.<\/p>\n<p>\u201c<i>L\u2019adozione offre la possibilit\u00e0 a un bambino di rifarsi una vita. Lo dico non solo perch\u00e9 l\u2019ho vissuto ma perch\u00e9 l\u2019ho visto <\/i>\u2013 continua \u2013<i> <b>Quando incontri i bambini degli istituti ti riempiono il cuore<\/b>: in quel momento sai che non hanno nessuno intorno a loro e solo l\u2019adozione pu\u00f2 dare loro l\u2019opportunit\u00e0 di una vita vera<\/i>\u201d.<\/p>\n<p><b>Tatiana fa una pausa e ricorda il viaggio in Bolivia nel 2012 insieme a suo padre.<\/b><\/p>\n<p>\u201c<i>E\u2019 stata <b>un\u2019esperienza che mi ha molto aiutato<\/b>. Prima di questo viaggio non avevo mai pensato di tornare nel mio paese natale. Ora invece ho deciso di tornarci questa estate: <b>andr\u00f2 a fare volontariato nello stesso istituto a La Paz dove ho vissuto i primi anni della mia vita<\/b>. Voglio stare al fianco dei bambini e dire loro <b>che la fortuna che ha toccato me, presto potr\u00e0 riguardare anche loro<\/b>\u201d.<\/i><\/p>\n<p>Oggi Tatiana \u00e8 referente per l\u2019Emilia Romagna del gruppo giovani di Amici dei Bambini \u201cAiBi G\u201d, che accoglie anche ragazzi non adottivi: si impegnano nel volontariato a livello locale, promuovendo lo spirito di accoglienza e solidariet\u00e0 che contraddistingue la missione dell\u2019associazione. Quando necessario, Tatiana e altri giovani di AibiG offrono la loro testimonianza durante eventi o convegni dedicati a chi si avvicina all\u2019adozione.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><b>L\u2019ha saputo in diretta dalla sua amica del cuore che vive in Bolivia<\/b>\u00a0e ha festeggiato con lei al telefono. Per poi\u00a0<b>brindare con la sua famiglia adottiva che l\u2019ha accolta quando lei aveva solo 3 anni,<\/b>\u00a0regalandole cos\u00ec una nuova chance di vita. Lei \u00e8\u00a0<b>Tatiana Salomoni<\/b>, 18 anni,\u00a0<b>boliviana di nascita e italiana d\u2019adozione<\/b>. Studia grafica pubblicitaria ed \u00e8 una miscela insieme dolce e forte di accento bolognese e fierezza boliviana.\u00a0<strong>Tatiana \u00e8 stata la prima bambina boliviana adottata da Ai.Bi.<\/strong><\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-115690","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d\" \/>\n<meta property=\"og:description\" content=\"L\u2019ha saputo in diretta dalla sua amica del cuore che vive in Bolivia\u00a0e ha festeggiato con lei al telefono. Per poi\u00a0brindare con la sua famiglia adottiva che l\u2019ha accolta quando lei aveva solo 3 anni,\u00a0regalandole cos\u00ec una nuova chance di vita. Lei \u00e8\u00a0Tatiana Salomoni, 18 anni,\u00a0boliviana di nascita e italiana d\u2019adozione. Studia grafica pubblicitaria ed \u00e8 una miscela insieme dolce e forte di accento bolognese e fierezza boliviana.\u00a0Tatiana \u00e8 stata la prima bambina boliviana adottata da Ai.Bi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-20T15:30:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-23T16:35:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d\",\"datePublished\":\"2015-11-20T15:30:32+00:00\",\"dateModified\":\"2015-11-23T16:35:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/\"},\"wordCount\":510,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tatiana-400-2861.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/\",\"name\":\"Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tatiana-400-2861.jpg\",\"datePublished\":\"2015-11-20T15:30:32+00:00\",\"dateModified\":\"2015-11-23T16:35:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tatiana-400-2861.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/tatiana-400-2861.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/","og_locale":"it_IT","og_type":"article","og_title":"Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d","og_description":"L\u2019ha saputo in diretta dalla sua amica del cuore che vive in Bolivia\u00a0e ha festeggiato con lei al telefono. Per poi\u00a0brindare con la sua famiglia adottiva che l\u2019ha accolta quando lei aveva solo 3 anni,\u00a0regalandole cos\u00ec una nuova chance di vita. Lei \u00e8\u00a0Tatiana Salomoni, 18 anni,\u00a0boliviana di nascita e italiana d\u2019adozione. Studia grafica pubblicitaria ed \u00e8 una miscela insieme dolce e forte di accento bolognese e fierezza boliviana.\u00a0Tatiana \u00e8 stata la prima bambina boliviana adottata da Ai.Bi.","og_url":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2015-11-20T15:30:32+00:00","article_modified_time":"2015-11-23T16:35:55+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d","datePublished":"2015-11-20T15:30:32+00:00","dateModified":"2015-11-23T16:35:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/"},"wordCount":510,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/","url":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/","name":"Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861.jpg","datePublished":"2015-11-20T15:30:32+00:00","dateModified":"2015-11-23T16:35:55+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/tatiana-400-2861.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/tatiana-salomoni-grazie-bolivia-sei-grande-e-il-piu-bel-regalo-per-la-giornata-mondiale-dei-diritti-dellinfanzia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Tatiana Salomoni. \u201cGrazie Bolivia, sei grande! \u00c8 il pi\u00f9 bel regalo per la giornata mondiale dei diritti dell\u2019infanzia\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:12:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/115690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=115690"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/115690\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=115690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=115690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=115690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}