﻿


{"id":11671,"date":"2010-03-08T12:58:12","date_gmt":"2010-03-08T11:58:12","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=11671"},"modified":"2010-03-08T13:02:34","modified_gmt":"2010-03-08T12:02:34","slug":"adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/","title":{"rendered":"Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione."},"content":{"rendered":"<p>E\u2019 possibile alzare delle barriere all\u2019adozione di alcune \u201ccategorie\u201d di bambini? Un genitore adottivo ti risponderebbe che l\u2019accoglienza di un figlio non ha limiti.<\/p>\n<p>Eppure l\u2019orientamento attuale di alcuni Tribunali per i Minorenni \u00e8 quello di emettere decreti vincolati (ossia con indicazioni specifiche rispetto al Paese di provenienza del minore, al suo stato di salute, all\u2019et\u00e0). Decisiva la scelta del presidente del Tribunale per i Minorenni <a href=\"https:\/\/www.aibi.it\/ita\/tribunale-di-roma-ritornano-i-%E2%80%9Cdecreti-vincolati%E2%80%9D\/\">Melita Cavallo<\/a> che ha stabilito di<strong> porre dei limiti nel decreto relativi all\u2019adozione di gruppi di fratelli e bambini con pi\u00f9 di otto anni.<\/strong><\/p>\n<p>La questione assume nuovi risvolti se si considera che il board della Conferenza internazionale di Diritto privato de l\u2019Aja ha elaborato, lo scorso giugno, un documento in cui esorta gli Stati membri a favorire l\u2019accoglienza dei bambini con \u201cbisogni speciali\u201d, ovvero minori con pi\u00f9 di sei anni, con problemi psichici o fisici o con pi\u00f9 fratelli. Sono questi i bambini che la maggior parte dei Paesi di origine ha deciso di destinare all\u2019adozione internazionale.<\/p>\n<p>Ecco quindi che i decreti vincolati mettono in luce un <strong>evidente paradosso<\/strong>: i bambini che potrebbero essere accolti con l\u2019adozione internazionale non hanno le caratteristiche di quelli indicati nei decreti vincolati. La questione pone nuove interrogativi sul futuro dell\u2019adozione internazionale. Come pu\u00f2 pensare l\u2019Italia di accogliere bambini con \u201cbisogni speciali\u201d se i Tribunali per i Minorenni continuano a emettere decreti vincolati?<\/p>\n<p>In pi\u00f9 occasioni Ai.Bi. ha denunciato che questi <strong>provvedimenti vanno contro l\u2019interesse supremo del minore di essere accolto in una famiglia<\/strong> e violano la legislazione nazionale e internazionale. Lo scorso agosto il Presidente della Repubblica Giorgio Napolitano ha comunicato ad Ai.Bi. che la denuncia dell&#8217;associazione in merito ai decreti vincolati del Tribunale per i Minorenni di Catania \u00e8 in esame al Consiglio Superiore della Magistratura per le valutazioni di competenza.<\/p>\n<p>Tuttavia resta molta strada da fare se si considera che gli orientamenti di diversi Tribunali per i minori sono favorevoli ai decreti vincolati.<\/p>\n<p><strong>Partecipa al sondaggio.<\/strong><\/p>\n[poll id=&#8221;14&#8243;]\n","protected":false},"excerpt":{"rendered":"<p>E&rsquo; possibile alzare delle barriere all&rsquo;adozione di alcune &ldquo;categorie&rdquo; di bambini? Un genitore adottivo ti risponderebbe che l&rsquo;accoglienza di un figlio non ha limiti. Eppure l&rsquo;orientamento attuale di alcuni Tribunali per i Minorenni &egrave; quello di emettere decreti vincolati (ossia con indicazioni specifiche rispetto al Paese di provenienza del minore, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-11671","post","type-post","status-publish","format-standard","category-sondaggi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione.\" \/>\n<meta property=\"og:description\" content=\"E&rsquo; possibile alzare delle barriere all&rsquo;adozione di alcune &ldquo;categorie&rdquo; di bambini? Un genitore adottivo ti risponderebbe che l&rsquo;accoglienza di un figlio non ha limiti. Eppure l&rsquo;orientamento attuale di alcuni Tribunali per i Minorenni &egrave; quello di emettere decreti vincolati (ossia con indicazioni specifiche rispetto al Paese di provenienza del minore, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-03-08T11:58:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-03-08T12:02:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione.\",\"datePublished\":\"2010-03-08T11:58:12+00:00\",\"dateModified\":\"2010-03-08T12:02:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\\\/\"},\"wordCount\":345,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"Sondaggi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\\\/\",\"name\":\"Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2010-03-08T11:58:12+00:00\",\"dateModified\":\"2010-03-08T12:02:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sondaggi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/sondaggi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione. - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione.","og_description":"E&rsquo; possibile alzare delle barriere all&rsquo;adozione di alcune &ldquo;categorie&rdquo; di bambini? Un genitore adottivo ti risponderebbe che l&rsquo;accoglienza di un figlio non ha limiti. Eppure l&rsquo;orientamento attuale di alcuni Tribunali per i Minorenni &egrave; quello di emettere decreti vincolati (ossia con indicazioni specifiche rispetto al Paese di provenienza del minore, [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-03-08T11:58:12+00:00","article_modified_time":"2010-03-08T12:02:34+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione.","datePublished":"2010-03-08T11:58:12+00:00","dateModified":"2010-03-08T12:02:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/"},"wordCount":345,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["Sondaggi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/","name":"Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2010-03-08T11:58:12+00:00","dateModified":"2010-03-08T12:02:34+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-ritornano-i-decreti-vincolati-esprimi-la-tua-opinione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Sondaggi","item":"https:\/\/www.aibi.it\/ita\/category\/sondaggi\/"},{"@type":"ListItem","position":3,"name":"Adozioni: ritornano i \u201cdecreti vincolati\u201d. Esprimi la tua opinione."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:47:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/11671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=11671"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/11671\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=11671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=11671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=11671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}