﻿


{"id":118231,"date":"2016-01-08T16:47:24","date_gmt":"2016-01-08T15:47:24","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=118231"},"modified":"2016-01-09T18:05:14","modified_gmt":"2016-01-09T17:05:14","slug":"perche-solo-bomboniere-per-i-bambini","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/","title":{"rendered":"Perch\u00e9 bomboniere solo per gli adulti?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-id=\"118281\"  src=\"https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1.jpg\" alt=\"Bomboniene Solidali\" width=\"683\" height=\"320\" class=\"alignright size-full wp-image-118281\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1.jpg 683w, https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1-150x70.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1-300x141.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1-117x55.jpg 117w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><\/p>\n<p>Al vostro matrimonio ci saranno anche tanti bambini? Pensiamo al loro intrattenimento. \u201cIo Donna\u201d segnala le bomboniere solidali di Ai.Bi. e, in particolare, il set di 12 matite colorate in un apposito contenitore dotato anche di temperino, per i piccoli invitati. Guarda <a href=\"https:\/\/www.aibi.it\/bomboniere-solidali\/\" target=\"_blank\">tutte le bomboniere solidali <\/a>di Ai.Bi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al vostro matrimonio ci saranno anche tanti bambini? Pensiamo al loro intrattenimento. \u201cIo Donna\u201d segnala le bomboniere solidali di Ai.Bi. e, in particolare, il set di 12 matite colorate in un apposito contenitore dotato anche di temperino, per i piccoli invitati. Guarda\u00a0<a href=\"https:\/\/www.aibi.it\/bomboniere-solidali\/\" target=\"_blank\">tutte le bomboniere solidali\u00a0<\/a>di Ai.Bi.<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-118231","post","type-post","status-publish","format-standard","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Perch\u00e9 bomboniere solo per gli adulti? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch\u00e9 bomboniere solo per gli adulti?\" \/>\n<meta property=\"og:description\" content=\"Al vostro matrimonio ci saranno anche tanti bambini? Pensiamo al loro intrattenimento. \u201cIo Donna\u201d segnala le bomboniere solidali di Ai.Bi. e, in particolare, il set di 12 matite colorate in un apposito contenitore dotato anche di temperino, per i piccoli invitati. Guarda\u00a0tutte le bomboniere solidali\u00a0di Ai.Bi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-08T15:47:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-09T17:05:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Perch\u00e9 bomboniere solo per gli adulti?\",\"datePublished\":\"2016-01-08T15:47:24+00:00\",\"dateModified\":\"2016-01-09T17:05:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/\"},\"wordCount\":55,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/fotonotizia_aibimbi1.jpg\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/\",\"name\":\"Perch\u00e9 bomboniere solo per gli adulti? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/fotonotizia_aibimbi1.jpg\",\"datePublished\":\"2016-01-08T15:47:24+00:00\",\"dateModified\":\"2016-01-09T17:05:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/fotonotizia_aibimbi1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/fotonotizia_aibimbi1.jpg\",\"width\":683,\"height\":320,\"caption\":\"Bomboniene Solidali\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-solo-bomboniere-per-i-bambini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Perch\u00e9 bomboniere solo per gli adulti?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Perch\u00e9 bomboniere solo per gli adulti? - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/","og_locale":"it_IT","og_type":"article","og_title":"Perch\u00e9 bomboniere solo per gli adulti?","og_description":"Al vostro matrimonio ci saranno anche tanti bambini? Pensiamo al loro intrattenimento. \u201cIo Donna\u201d segnala le bomboniere solidali di Ai.Bi. e, in particolare, il set di 12 matite colorate in un apposito contenitore dotato anche di temperino, per i piccoli invitati. Guarda\u00a0tutte le bomboniere solidali\u00a0di Ai.Bi.","og_url":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-01-08T15:47:24+00:00","article_modified_time":"2016-01-09T17:05:14+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Perch\u00e9 bomboniere solo per gli adulti?","datePublished":"2016-01-08T15:47:24+00:00","dateModified":"2016-01-09T17:05:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/"},"wordCount":55,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1.jpg","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/","url":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/","name":"Perch\u00e9 bomboniere solo per gli adulti? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1.jpg","datePublished":"2016-01-08T15:47:24+00:00","dateModified":"2016-01-09T17:05:14+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/fotonotizia_aibimbi1.jpg","width":683,"height":320,"caption":"Bomboniene Solidali"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/perche-solo-bomboniere-per-i-bambini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Perch\u00e9 bomboniere solo per gli adulti?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:20:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/118231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=118231"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/118231\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=118231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=118231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=118231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}