﻿


{"id":118873,"date":"2016-01-19T15:31:12","date_gmt":"2016-01-19T14:31:12","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=118873"},"modified":"2016-01-21T18:37:50","modified_gmt":"2016-01-21T17:37:50","slug":"sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/","title":{"rendered":"Sostegno a distanza Siria. La fame uccide ancora: \u201cI miei bambini mangiano solo foglie ed erba\u201d"},"content":{"rendered":"<p><i><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-118875\" style=\"margin: 5px;\" alt=\"bambina siria\" src=\"https:\/\/www.aibi.it\/ita\/images\/bambina-siria1.jpg\" width=\"400\" height=\"286\" data-id=\"118875\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/bambina-siria1.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/bambina-siria1-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/bambina-siria1-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/bambina-siria1-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Sostegno a distanza Siria.<\/i>\u00a0\u201c<i>Che colpa abbiamo?\u00a0<b>I miei bambini possono mangiare solo foglie ed erba.<\/b>\u00a0Stanno morendo. Portateci angeli.\u00a0<b>Per misericordia, aiutateci<\/b><\/i>\u201d. E\u2019 l\u2019appello disperato che arriva da uno degli abitanti di Madaya, un villaggio siriano sulle montagne vicino al confine con il Libano, sotto assedio da un mese da parte dell\u2019esercito di Damasco. L\u2019uomo parla in uno dei video e delle foto postate da attivisti locali per denunciare la situazione disperata in Siria.<\/p>\n<p>\u201c<i>La gente sta morendo al rallentatore\u00a0<\/i>\u2013 \u00e8 la testimonianza di Louay, un\u2019assistente sociale prigioniera anche lei da un mese -.\u00a0<b><i>La gente mangia foglie, fiori fatti crescere nei vasi in casa<\/i><\/b><i>.\u00a0<b>Ne ho mangiato un petalo, amarissimo, ma non abbiamo altro<\/b><\/i>\u201d.<\/p>\n<p>La Mezzaluna Rossa, parla di almeno\u00a0<b>40mila persone da assistere<\/b>, e servono\u00a0<b>aiuti ingenti<\/b>: \u201c<b><i>Uomini, donne, bambini, tutti, dai venti ai settan\u2019anni, hanno perso almeno quindici chili<\/i><\/b><i>. Ci sono\u00a0<b>bambini che sembrano scheletri<\/b>\u00a0<\/i>\u2013 racconta Ebrahem Abbas, un ex sergente dell\u2019esercito siriano che ha disertato e si era rifugiato nella cittadina &#8211;<i>. Non c\u2019\u00e8 un bambino che non abbia\u00a0<b>gli occhi incavati, persi nel vuoto per la fame<\/b><\/i>\u00bb. Un altro attivista, Sham Abdullah, racconta che i \u201c<i>bambini mangiano zuppe fatte di foglie, erba e acqua<\/i>\u201d.<\/p>\n<p>Una situazione drammatica confermata dal\u00a0<b>segretario generale dell&#8217;Onu, Ban Ki-moon<\/b>, che ha denunciato: \u201c<b><i>Affamare i civili \u00e8 un crimine di guerra<\/i><\/b>\u201d: proprio il cibo, infatti, rappresenta un&#8217;arma letale del conflitto siriano iniziato nel marzo 2011. \u00a0Sempre l\u2019Onu in un report riferisce che in citt\u00e0\u00a0<b>un singolo biscotto si vende ancora per 15 dollari e il latte per bambini costa 313 dollari al chilo.<\/b><\/p>\n<p>L&#8217;Onu stima che quasi 400 mila persone in Siria siano ancora intrappolate nelle zone assediate dalle diverse parti in conflitto e oltre\u00a0<b>30 persone sono morte di fame in un mese<\/b>\u00a0(da met\u00e0 dicembre 2015 a met\u00e0 gennaio 2016)<b>: ovvero una al giorno<\/b>.\u00a0<b>Altre decine necessitano di cure mediche immediate<\/b>\u00a0ma la Croce Rossa Internazionale e la Mezzaluna Rossa sono riuscite a evacuare pochissimi abitanti di Madaya finora.<\/p>\n<p>Ma oltre alle circa\u00a0<b>40.000 persone<\/b>\u00a0che compongono la popolazione di questa cittadina di montagna vicina al confine con il Libano,\u00a0<b>a soffrire sono anche i 20.000 civili<\/b>,\u00a0<b>bambini e adulti affamati, alcuni dei quali presentavano segni di grave malnutrizione<\/b>,\u00a0<b>nella provincia nord-occidentale di Idlib.<\/b><\/p>\n<p>Ecco perch\u00e9 \u00e8 ancora pi\u00f9 importante e\u00a0<strong>ogni giorno pi\u00f9 impellente il lavoro di Ai.Bi.<\/strong>\u00a0attiva nella distribuzione\u00a0<strong>a 1090 famiglie di sfollati interni, pari a oltre 7 mila persone, che si trovano all\u2019interno della regione di Idleb, a nord della Siria<\/strong>, ceste alimentari in grado di offrire pasti caldi e nutrienti in questi freddi mesi invernali.<\/p>\n<p>Il progetto\u00a0<b>\u201cIntervento di emergenza per la sicurezza alimentare della popolazione sfollata di Ibleb\u201d<\/b>\u00a0\u00e8 il frutto di un lavoro di squadra che vede protagonisti Ai.Bi. e il partner siriano\u00a0<b>Syrian Children Relief:\u00a0<\/b>\u00a0con questo progetto si risponde a una crisi senza precedenti non solo\u00a0<b>distribuendo lenticchie, riso, patate e pane<\/b>, ma consegnando anche un messaggio rassicurante e confortante che fa capire ai nostri beneficiari che\u00a0<b>noi siamo al loro fianco<\/b>\u00a0e vogliamo continuare a dare il massimo per riuscire a supportarli quanto pi\u00f9 possibile in questi momenti cos\u00ec tristi e cos\u00ec veri.<\/p>\n<p>Ma per fare tutto questo e soprattutto dare una continuit\u00e0 a questi interventi, \u00e8 necessario, se non fondamentale,\u00a0<b>il vostro aiuto<\/b>: anche tu puoi, infatti, sostenere e sfamare una famiglia siriana attraverso\u00a0<b>una donazione pari a 30 euro o piccolo grande gesto chiamato\u00a0<a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/emergenza-siria\/\">Sostegno a Distanza Siria<\/a>.<\/b><\/p>\n<p>Grazie a questo,\u00a0<b>con soli 25 euro al mese<\/b>,\u00a0<b>puoi garantire viveri e beni di prima necessit\u00e0 a mamme, pap\u00e0 e soprattutto bambini.\u00a0<\/b>Insieme ai diritti al gioco, alla salute, alla scuola, il cibo \u00e8 uno dei pilastri fondamentali del progetto di\u00a0<b><a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/emergenza-siria\/\">Sostegno a Distanza \u201cIo non voglio andare via\u201d<\/a>, \u00a0<\/b>portato avanti da Amici dei Bambini nell\u2019ambito del<b>\u00a0<\/b><a href=\"https:\/\/www.aibi.it\/ita\/sostieni-aibi\/emergenza-profughi\/\">campagna<b>\u00a0Bambini in Alto Mare<\/b><\/a><b>,\u00a0<\/b>nato con l\u2019obiettivo di permettere ai bambini della regione settentrionale di Idlib di continuare a sentirsi a casa nel proprio Paese.<\/p>\n<p>Fonte Reuters e www.lettera43.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p><i>Sostegno a distanza Siria.<\/i>\u00a0\u201c<i>Che colpa abbiamo?\u00a0<b>I miei bambini possono mangiare solo foglie ed erba.<\/b>\u00a0Stanno morendo. Portateci armi, portateci angeli.\u00a0<b>Per misericordia, aiutateci<\/b><\/i>\u201d. E\u2019 l\u2019appello disperato che arriva da uno degli abitanti di Madaya. Ed ecco perch\u00e9 \u00e8\u00a0<strong>ogni giorno pi\u00f9 impellente il lavoro di Ai.Bi.<\/strong>\u00a0attiva nella distribuzione\u00a0<strong>a 1090 famiglie di sfollati interni, pari a oltre 7 mila persone, che si trovano all\u2019interno della regione di Idleb, a nord della Siria<\/strong>, ceste alimentari in grado di offrire pasti caldi e nutrienti in questi freddi mesi invernali.\u00a0<strong>Tu puoi aiutarci ad aiutare.<\/strong><\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-118873","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sostegno a distanza Siria<\/title>\n<meta name=\"description\" content=\"Sostegno a distanza Siria. \u201cChe colpa abbiamo? I miei bambini possono mangiare solo foglie ed erba. Stanno morendo. Portateci armi, portateci angeli. Per misericordia, aiutateci\u201d. E\u2019 l\u2019appello disperato che arriva da uno degli abitanti di Madaya. Ed ecco perch\u00e9 \u00e8 ogni giorno pi\u00f9 impellente il lavoro di Ai.Bi. attiva nella distribuzione a 1090 famiglie di sfollati interni, pari a oltre 7 mila persone, che si trovano all\u2019interno della regione di Idleb, a nord della Siria, ceste alimentari in grado di offrire pasti caldi e nutrienti in questi freddi mesi invernali. Tu puoi aiutarci ad aiutare.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sostegno a distanza Siria. La fame uccide ancora: \u201cI miei bambini mangiano solo foglie ed erba\u201d\" \/>\n<meta property=\"og:description\" content=\"Sostegno a distanza Siria. \u201cChe colpa abbiamo? I miei bambini possono mangiare solo foglie ed erba. Stanno morendo. Portateci armi, portateci angeli. Per misericordia, aiutateci\u201d. E\u2019 l\u2019appello disperato che arriva da uno degli abitanti di Madaya. Ed ecco perch\u00e9 \u00e8 ogni giorno pi\u00f9 impellente il lavoro di Ai.Bi. attiva nella distribuzione a 1090 famiglie di sfollati interni, pari a oltre 7 mila persone, che si trovano all\u2019interno della regione di Idleb, a nord della Siria, ceste alimentari in grado di offrire pasti caldi e nutrienti in questi freddi mesi invernali. Tu puoi aiutarci ad aiutare.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-19T14:31:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-21T17:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bambina-siria1.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Sostegno a distanza Siria. La fame uccide ancora: \u201cI miei bambini mangiano solo foglie ed erba\u201d\",\"datePublished\":\"2016-01-19T14:31:12+00:00\",\"dateModified\":\"2016-01-21T17:37:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/\"},\"wordCount\":675,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambina-siria1.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/\",\"name\":\"Sostegno a distanza Siria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambina-siria1.jpg\",\"datePublished\":\"2016-01-19T14:31:12+00:00\",\"dateModified\":\"2016-01-21T17:37:50+00:00\",\"description\":\"Sostegno a distanza Siria. \u201cChe colpa abbiamo? I miei bambini possono mangiare solo foglie ed erba. Stanno morendo. Portateci armi, portateci angeli. Per misericordia, aiutateci\u201d. E\u2019 l\u2019appello disperato che arriva da uno degli abitanti di Madaya. Ed ecco perch\u00e9 \u00e8 ogni giorno pi\u00f9 impellente il lavoro di Ai.Bi. attiva nella distribuzione a 1090 famiglie di sfollati interni, pari a oltre 7 mila persone, che si trovano all\u2019interno della regione di Idleb, a nord della Siria, ceste alimentari in grado di offrire pasti caldi e nutrienti in questi freddi mesi invernali. Tu puoi aiutarci ad aiutare.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambina-siria1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bambina-siria1.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sostegno a distanza Siria. La fame uccide ancora: \u201cI miei bambini mangiano solo foglie ed erba\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sostegno a distanza Siria","description":"Sostegno a distanza Siria. \u201cChe colpa abbiamo? I miei bambini possono mangiare solo foglie ed erba. Stanno morendo. Portateci armi, portateci angeli. Per misericordia, aiutateci\u201d. E\u2019 l\u2019appello disperato che arriva da uno degli abitanti di Madaya. Ed ecco perch\u00e9 \u00e8 ogni giorno pi\u00f9 impellente il lavoro di Ai.Bi. attiva nella distribuzione a 1090 famiglie di sfollati interni, pari a oltre 7 mila persone, che si trovano all\u2019interno della regione di Idleb, a nord della Siria, ceste alimentari in grado di offrire pasti caldi e nutrienti in questi freddi mesi invernali. Tu puoi aiutarci ad aiutare.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/","og_locale":"it_IT","og_type":"article","og_title":"Sostegno a distanza Siria. La fame uccide ancora: \u201cI miei bambini mangiano solo foglie ed erba\u201d","og_description":"Sostegno a distanza Siria. \u201cChe colpa abbiamo? I miei bambini possono mangiare solo foglie ed erba. Stanno morendo. Portateci armi, portateci angeli. Per misericordia, aiutateci\u201d. E\u2019 l\u2019appello disperato che arriva da uno degli abitanti di Madaya. Ed ecco perch\u00e9 \u00e8 ogni giorno pi\u00f9 impellente il lavoro di Ai.Bi. attiva nella distribuzione a 1090 famiglie di sfollati interni, pari a oltre 7 mila persone, che si trovano all\u2019interno della regione di Idleb, a nord della Siria, ceste alimentari in grado di offrire pasti caldi e nutrienti in questi freddi mesi invernali. Tu puoi aiutarci ad aiutare.","og_url":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-01-19T14:31:12+00:00","article_modified_time":"2016-01-21T17:37:50+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/bambina-siria1.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Sostegno a distanza Siria. La fame uccide ancora: \u201cI miei bambini mangiano solo foglie ed erba\u201d","datePublished":"2016-01-19T14:31:12+00:00","dateModified":"2016-01-21T17:37:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/"},"wordCount":675,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bambina-siria1.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/","url":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/","name":"Sostegno a distanza Siria","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bambina-siria1.jpg","datePublished":"2016-01-19T14:31:12+00:00","dateModified":"2016-01-21T17:37:50+00:00","description":"Sostegno a distanza Siria. \u201cChe colpa abbiamo? I miei bambini possono mangiare solo foglie ed erba. Stanno morendo. Portateci armi, portateci angeli. Per misericordia, aiutateci\u201d. E\u2019 l\u2019appello disperato che arriva da uno degli abitanti di Madaya. Ed ecco perch\u00e9 \u00e8 ogni giorno pi\u00f9 impellente il lavoro di Ai.Bi. attiva nella distribuzione a 1090 famiglie di sfollati interni, pari a oltre 7 mila persone, che si trovano all\u2019interno della regione di Idleb, a nord della Siria, ceste alimentari in grado di offrire pasti caldi e nutrienti in questi freddi mesi invernali. Tu puoi aiutarci ad aiutare.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/bambina-siria1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/bambina-siria1.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/sostegno-a-distanza-siria-la-fame-uccide-ancora-i-miei-bambini-mangiano-solo-foglie-ed-erba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Sostegno a distanza Siria. La fame uccide ancora: \u201cI miei bambini mangiano solo foglie ed erba\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:32:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/118873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=118873"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/118873\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=118873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=118873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=118873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}