﻿


{"id":12240,"date":"2010-04-07T14:41:17","date_gmt":"2010-04-07T13:41:17","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=12240"},"modified":"2016-01-21T11:45:48","modified_gmt":"2016-01-21T10:45:48","slug":"addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/","title":{"rendered":"Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/Posta.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12241\" style=\"margin: 5px;\" title=\"Posta\" src=\"https:\/\/www.aibi.it\/ita\/images\/Posta.jpg\" alt=\"Posta\" width=\"150\" height=\"150\" \/><\/a><strong>Una petizione per richiedere l\u2019immediato ripristino delle tariffe agevolate per il Non Profit. <\/strong>E\u2019 quella lanciata sul sito di Vita.it che nel giro di poche ore ha raccolto gi\u00e0 quasi 2mila firme e ha raccolto le adesioni di associazioni, privati e famiglie.<\/p>\n<p>Il decreto interministeriale del 30 marzo 2010 pubblicato a tempo di record sulla Gazzetta Ufficiale del 31 marzo 2010 n. 75 ha abolito le tariffe agevolate postali per tutta l&#8217;editoria libraria, quotidiana e periodica, in vigore con effetto immediato dal primo aprile 2010. L\u2019aumento \u00e8 del 500% circa per ogni singola spedizione.<\/p>\n<p><strong>L\u2019aumento delle tariffe postali colpir\u00e0 in maniera significativa la raccolta fondi di tutte le organizzazioni Non Profit<\/strong>, causando un ingente aumento dei costi delle spedizioni, fondamentali per informare i donatori sulle attivit\u00e0 delle associazioni.<\/p>\n<p>Uno spiraglio si pu\u00f2 intravvedere nell\u2019ultimo articolo del decreto in cui si specifica che \u201c<em>con  successivo  decreto  potranno   essere   determinate   tariffe agevolate  per  i  residui  periodi  dell\u2019anno  2010,  in   caso   di sopravvenuto accertamento di disponibilit\u00e0 finanziarie  nell\u2019ambito del bilancio autonomo della Presidenza del Consiglio dei Ministri\u201d.<\/em><\/p>\n<p>Le organizzazioni Non Profit sono preoccupate per il periodo di vacatio legis tra l\u2019entrata in vigore del provvedimento e la verifica dell\u2019effettiva disponibilit\u00e0 nel bilancio, che comunque arriva in un momento dell\u2019anno in cui le organizzazioni realizzano delle spedizioni ai propri sostenitori.<\/p>\n<p>Le organizzazioni quindi s<strong>i appellano al governo affinch\u00e9 vengano immediatamente adottate delle misure che evitino un vertiginoso aumento del budget delle spedizioni <\/strong>che, anche in ragione delle tempistiche scelte per l\u2019entrata in vigore del provvedimento, non potr\u00e0 che tradursi in un decremento dei fondi destinati ai progetti.<\/p>\n<p><strong>Firma la petizione<\/strong> per chiedere il ripristino delle tariffe postali agevolate &gt;&gt;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una petizione per richiedere l\u2019immediato ripristino delle tariffe agevolate per il non profit. E\u2019 quella lanciata sul sito di Vita.it che nel giro di poche ore ha raccolto gi\u00e0 quasi 2mila firme e ha raccolto le adesioni di associazioni, privati e famiglie.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-12240","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta\" \/>\n<meta property=\"og:description\" content=\"Una petizione per richiedere l\u2019immediato ripristino delle tariffe agevolate per il non profit. E\u2019 quella lanciata sul sito di Vita.it che nel giro di poche ore ha raccolto gi\u00e0 quasi 2mila firme e ha raccolto le adesioni di associazioni, privati e famiglie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-07T13:41:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-21T10:45:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Posta.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta\",\"datePublished\":\"2010-04-07T13:41:17+00:00\",\"dateModified\":\"2016-01-21T10:45:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/\"},\"wordCount\":291,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Posta.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/\",\"name\":\"Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Posta.jpg\",\"datePublished\":\"2010-04-07T13:41:17+00:00\",\"dateModified\":\"2016-01-21T10:45:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Posta.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Posta.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/","og_locale":"it_IT","og_type":"article","og_title":"Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta","og_description":"Una petizione per richiedere l\u2019immediato ripristino delle tariffe agevolate per il non profit. E\u2019 quella lanciata sul sito di Vita.it che nel giro di poche ore ha raccolto gi\u00e0 quasi 2mila firme e ha raccolto le adesioni di associazioni, privati e famiglie.","og_url":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-04-07T13:41:17+00:00","article_modified_time":"2016-01-21T10:45:48+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Posta.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta","datePublished":"2010-04-07T13:41:17+00:00","dateModified":"2016-01-21T10:45:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/"},"wordCount":291,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Posta.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/","url":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/","name":"Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Posta.jpg","datePublished":"2010-04-07T13:41:17+00:00","dateModified":"2016-01-21T10:45:48+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Posta.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Posta.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/addio-alle-agevolazioni-postali-per-il-non-profit-le-associazioni-in-lotta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Addio alle agevolazioni postali per il Non Profit. Le associazioni in lotta"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:04:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/12240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=12240"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/12240\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=12240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=12240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=12240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}