﻿


{"id":123901,"date":"2016-04-05T15:51:13","date_gmt":"2016-04-05T13:51:13","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=123901"},"modified":"2016-04-08T17:10:59","modified_gmt":"2016-04-08T15:10:59","slug":"gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/","title":{"rendered":"&#8220;Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati&#8221;"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-109231\" style=\"margin: 5px;\" alt=\"renzi\" src=\"https:\/\/www.aibi.it\/ita\/images\/renzi4.jpg\" width=\"400\" height=\"286\" data-id=\"109231\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/renzi4.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/renzi4-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/renzi4-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/renzi4-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Ventiquattro enti autorizzati e 33 associazioni familiari riunite nel coordinamento Care, hanno firmato una lettera aperta al premier Matteo Renzi chiedendogli di farsi carico dell&#8217;impegno di risolvere l&#8217;attuale situazione di crisi delle adozioni internazionali in Italia, dovuta principalmente all&#8217;immobilismo delle nostre istituzioni. Di seguito riportiamo integralmente il testo della lettera, pubblicata marted\u00ec 5 aprile da quotidiano &#8220;La Repubblica&#8221;.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Gentile presidente del Consiglio dei ministri Matteo Renzi,<\/p>\n<p>ci rivolgiamo a Lei anche in qualit\u00e0 di Presidente della Commissione adozioni internazionali per manifestare le nostre preoccupazioni rispetto alla grave situazione delle adozioni internazionali in Italia.<\/p>\n<p>Il sistema italiano delle adozioni internazionali, che coinvolge migliaia di famiglie e di bambini, \u00e8 sempre stato un riconosciuto modello di eccellenza nel mondo per il ruolo propositivo e proattivo di tutte le istituzioni coinvolte e per la straordinaria capacit\u00e0 di accoglienza delle nostre famiglie.<\/p>\n<p>In un contesto di globale crisi delle adozioni internazionali l&#8217;Italia potrebbe continuare a svolgere un ruolo di eccellenza rispetto alla capacit\u00e0 di garantire il diritto alla famiglia a tanti bambini in stato di abbandono.<\/p>\n<p>Per raggiungere questo obiettivo per\u00f2 \u00e8 fondamentale avere un impegno forte di tutti gli attori coinvolti a partire dalla Commissione adozioni internazionali, istituzione preposta alla &#8220;regia&#8221; di tutto il sistema.<\/p>\n<p>In questi giorni molti media si stanno occupando nuovamente della situazione di quei bambini della Repubblica Democratica del Congo che ancora non hanno potuto raggiungere le loro famiglie in Italia e dell&#8217;inaccessibilit\u00e0 della vicepresidente della Commissione adozioni internazionali.<\/p>\n<p>Dobbiamo inoltre registrare che la Commissione adozioni non si riunisce dal novembre 2013, fatta eccezione per la riunione di insediamento del 26 giugno 2014; non vengono mantenute le necessarie relazioni internazionali, n\u00e9 con i Paesi da cui provengono i bambini adottati n\u00e9 da quelli che, come l&#8217;Italia, li accolgono.<\/p>\n<p>Non vengono rispettati gli impegni per il finanziamento dei progetti di prevenzione dell&#8217;abbandono messi in atto nei Paesi di provenienza dei bambini; non vengono riuniti gli enti autorizzati, come previsto per legge; non \u00e8 possibile n\u00e9 per gli enti n\u00e9 per le famiglie entrare in contatto con la Commissione; da due anno non vengono pubblicati i dati sulle adozioni.<\/p>\n<p>Il sistema adozioni italiano non si \u00e8 mai trovato in una situazione cos\u00ec grave pur avendo gi\u00e0 affrontato criticit\u00e0 importanti in passato.<\/p>\n<p>L&#8217;inazione della Commissione adozioni ha inevitabilmente un&#8217;immediata ricaduta sul futuro di bambini gi\u00e0 molto provati dalla vita, spesso con problemi di salute o di pesanti vissuti di maltrattamenti ed abusi.<\/p>\n<p>Conoscendo la sua sensibilit\u00e0 per i diritti dei pi\u00f9 piccoli, le chiediamo di farsi carico anche di questa situazione.<\/p>\n<p>Da parte nostra le garantiamo la pi\u00f9 completa collaborazione per l&#8217;adeguato funzionamento di tutto il sistema italiano delle adozioni internazionali.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ami, A.Mo, Crescere insieme onlus, Il Conventino, Fondazione Avsi, In cammino per la famiglia, International Adoption, Istituto La Casa, Centro adozioni La Maloca, Associazione Mehala, Nadia Onlus, Sjamo, Cifa, Naaa, Ai.Bi., Nova, I bambini dell&#8217;arcobaleno, Ciai, I fiori semplici onlus, Amici Trentini, Associazione adozioni alfabeto, Associazione bambini di Chernobyl, Associazione cicogna amici dei Chernobyl, Azione famiglie nuove, Care (coordinamento di 33 associazioni familiari)\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gentile presidente del Consiglio dei ministri <strong>Matteo Renzi<\/strong>, ci rivolgiamo a Lei anche in qualit\u00e0 di <strong>Presidente della Commissione adozioni internazionali<\/strong> per manifestare le nostre preoccupazioni rispetto alla <strong>grave situazione delle adozioni internazionali in Italia<\/strong>. Il sistema italiano delle adozioni internazionali, che <strong>coinvolge migliaia di famiglie e di bambini<\/strong>, \u00e8 sempre stato un riconosciuto modello di eccellenza nel mondo per il ruolo propositivo e proattivo di tutte le istituzioni coinvolte e per la straordinaria capacit\u00e0 di accoglienza delle nostre famiglie.<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,179],"tags":[],"class_list":["post-123901","post","type-post","status-publish","format-standard","category-aibinews","category-la-guerra-delle-adozioni-internazionali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati&quot; - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati&quot;\" \/>\n<meta property=\"og:description\" content=\"Gentile presidente del Consiglio dei ministri Matteo Renzi, ci rivolgiamo a Lei anche in qualit\u00e0 di Presidente della Commissione adozioni internazionali per manifestare le nostre preoccupazioni rispetto alla grave situazione delle adozioni internazionali in Italia. Il sistema italiano delle adozioni internazionali, che coinvolge migliaia di famiglie e di bambini, \u00e8 sempre stato un riconosciuto modello di eccellenza nel mondo per il ruolo propositivo e proattivo di tutte le istituzioni coinvolte e per la straordinaria capacit\u00e0 di accoglienza delle nostre famiglie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-05T13:51:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-08T15:10:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/renzi4.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"&#8220;Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati&#8221;\",\"datePublished\":\"2016-04-05T13:51:13+00:00\",\"dateModified\":\"2016-04-08T15:10:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/\"},\"wordCount\":517,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/renzi4.jpg\",\"articleSection\":[\"AiBiNews\",\"La guerra delle adozioni internazionali\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/\",\"name\":\"\\\"Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/renzi4.jpg\",\"datePublished\":\"2016-04-05T13:51:13+00:00\",\"dateModified\":\"2016-04-08T15:10:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/renzi4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/renzi4.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8220;Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati\" - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/","og_locale":"it_IT","og_type":"article","og_title":"\"Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati\"","og_description":"Gentile presidente del Consiglio dei ministri Matteo Renzi, ci rivolgiamo a Lei anche in qualit\u00e0 di Presidente della Commissione adozioni internazionali per manifestare le nostre preoccupazioni rispetto alla grave situazione delle adozioni internazionali in Italia. Il sistema italiano delle adozioni internazionali, che coinvolge migliaia di famiglie e di bambini, \u00e8 sempre stato un riconosciuto modello di eccellenza nel mondo per il ruolo propositivo e proattivo di tutte le istituzioni coinvolte e per la straordinaria capacit\u00e0 di accoglienza delle nostre famiglie.","og_url":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-04-05T13:51:13+00:00","article_modified_time":"2016-04-08T15:10:59+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/renzi4.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"&#8220;Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati&#8221;","datePublished":"2016-04-05T13:51:13+00:00","dateModified":"2016-04-08T15:10:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/"},"wordCount":517,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/renzi4.jpg","articleSection":["AiBiNews","La guerra delle adozioni internazionali"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/","url":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/","name":"\"Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/renzi4.jpg","datePublished":"2016-04-05T13:51:13+00:00","dateModified":"2016-04-08T15:10:59+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/renzi4.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/renzi4.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/gentile-premier-renzi-riapriamo-le-porte-ai-bimbi-abbandonati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"&#8220;Gentile premier Renzi, riapriamo le porte ai bimbi abbandonati&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:56:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/123901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=123901"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/123901\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=123901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=123901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=123901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}