﻿


{"id":125174,"date":"2016-04-20T13:00:48","date_gmt":"2016-04-20T11:00:48","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=125174"},"modified":"2016-04-22T18:00:55","modified_gmt":"2016-04-22T16:00:55","slug":"giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/","title":{"rendered":"Giovanardi (Idea): &#8220;Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la  Russia sospender\u00e0 l&#8217;adozione di bambini russi da parte dell&#8217;Italia&#8221;."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-98833\" style=\"margin: 5px;\" alt=\"giovanardi2\" src=\"https:\/\/www.aibi.it\/ita\/images\/giovanardi21.jpg\" width=\"400\" height=\"286\" data-id=\"98833\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/giovanardi21.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/giovanardi21-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/giovanardi21-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/giovanardi21-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>L&#8217;intervento del governo italiano e della Cai (Commissione per le adozioni internazionali) per evitare il congelamento dei rapporti con la Russia sulla questione delle adozioni. A chiederlo \u00e8 il senatore Carlo Giovanardi (Idea) in un interpellanza presentata al Presidente del Consiglio e al Ministro degli Esteri per sapere quali iniziative intendano prendere verso un Paese \u201c<i>dal quale proviene circa un terzo dei bambini adottati dalle famiglie italiane all&#8217;estero<\/i>&#8220;.<\/p>\n<p>Nell&#8217;interpellanza Giovanardi ricorda che la vice Presidente del Comitato del Consiglio della Federazione per gli Affari Costituzionali e l&#8217;Edificazione dello Stato, Elena Mizulina, in relazione alla proposta del Difensore Civico dell&#8217;Infanzia, Pavel Astakhov, di una moratoria dell&#8217;adozione dei bambini russi in Italia,<i> \u201c<b>ha invitato l&#8217;Italia a fornire esaurienti spiegazioni<\/b> sul decesso di un bambino adottivo russo nel luglio del 2014, <b>minacciando in caso contrario di sospendere o addirittura di vietare l&#8217;adozione<\/b> di bambini russi da parte dell&#8217;Italia<\/i>&#8220;.<\/p>\n<p>Spiegazioni sono state chieste, informa il parlamentare, anche in relazione &#8220;<i>al caso di un cittadino italiano di 52 anni che a Volgograd sarebbe stato accusato di presunte percosse al loro bambino adottato di otto anni, un orfano dell&#8217;Orfanatrofio di Kamyshin<\/i>&#8220;.<\/p>\n<p>Secondo la Mizulina, spiega Giovanardi, &#8220;<b><i>\u00e8 trascorso gi\u00e0 pi\u00f9 di un anno<\/i><\/b><i> senza che da parte italiana sia stato dato <b>alcun chiarimento<\/b> e quindi esiste la possibilit\u00e0 di porre la questione della denuncia dell&#8217;accordo bilaterale sulle adozioni in forza fra i nostri Paesi<\/i>&#8220;.<\/p>\n<p>\u201c<i>L&#8217;Ombudsman del Presidente della Federazione russa per i diritti dell&#8217;Infanzia Pavel Astakhov<\/i> &#8211; conclude Giovanardi &#8211; <i>in diretta al canale Russkoy sluzhby novostey ha suggerito un temporaneo congelamento delle adozioni dei bambini russi da parte di italiani, <b>se l&#8217;Italia non far\u00e0 avere la documentazione su questi due casi<\/b>, fissando il termine del <b>16 giugno<\/b> entro il quale l&#8217;Italia dovrebbe dare spiegazioni<\/i>&#8220;.<\/p>\n<p>Clicca qui per leggere <a href=\"http:\/\/www.senato.it\/japp\/bgt\/showdoc\/showText?tipodoc=Sindisp&amp;leg=17&amp;id=970770\" target=\"_blank\">il testo integrale dell&#8217;interpellanza<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;intervento del governo italiano e della Cai (Commissione per le adozioni internazionali) per evitare<strong> il congelamento dei rapporti con la Russia<\/strong> sulla questione delle adozioni. A chiederlo \u00e8 il senatore <strong>Carlo Giovanardi (Idea)<\/strong> in un interpellanza presentata al Presidente del Consiglio e al Ministro degli Esteri.<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,179],"tags":[],"class_list":["post-125174","post","type-post","status-publish","format-standard","category-aibinews","category-la-guerra-delle-adozioni-internazionali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Giovanardi (Idea): &quot;Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la Russia sospender\u00e0 l&#039;adozione di bambini russi da parte dell&#039;Italia&quot;. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giovanardi (Idea): &quot;Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la Russia sospender\u00e0 l&#039;adozione di bambini russi da parte dell&#039;Italia&quot;.\" \/>\n<meta property=\"og:description\" content=\"L&#039;intervento del governo italiano e della Cai (Commissione per le adozioni internazionali) per evitare il congelamento dei rapporti con la Russia sulla questione delle adozioni. A chiederlo \u00e8 il senatore Carlo Giovanardi (Idea) in un interpellanza presentata al Presidente del Consiglio e al Ministro degli Esteri.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-20T11:00:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-22T16:00:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/giovanardi21.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Giovanardi (Idea): &#8220;Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la Russia sospender\u00e0 l&#8217;adozione di bambini russi da parte dell&#8217;Italia&#8221;.\",\"datePublished\":\"2016-04-20T11:00:48+00:00\",\"dateModified\":\"2016-04-22T16:00:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/\"},\"wordCount\":337,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/giovanardi21.jpg\",\"articleSection\":[\"AiBiNews\",\"La guerra delle adozioni internazionali\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/\",\"name\":\"Giovanardi (Idea): \\\"Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la Russia sospender\u00e0 l'adozione di bambini russi da parte dell'Italia\\\". - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/giovanardi21.jpg\",\"datePublished\":\"2016-04-20T11:00:48+00:00\",\"dateModified\":\"2016-04-22T16:00:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/giovanardi21.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/giovanardi21.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Giovanardi (Idea): &#8220;Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la Russia sospender\u00e0 l&#8217;adozione di bambini russi da parte dell&#8217;Italia&#8221;.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Giovanardi (Idea): \"Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la Russia sospender\u00e0 l'adozione di bambini russi da parte dell'Italia\". - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/","og_locale":"it_IT","og_type":"article","og_title":"Giovanardi (Idea): \"Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la Russia sospender\u00e0 l'adozione di bambini russi da parte dell'Italia\".","og_description":"L'intervento del governo italiano e della Cai (Commissione per le adozioni internazionali) per evitare il congelamento dei rapporti con la Russia sulla questione delle adozioni. A chiederlo \u00e8 il senatore Carlo Giovanardi (Idea) in un interpellanza presentata al Presidente del Consiglio e al Ministro degli Esteri.","og_url":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-04-20T11:00:48+00:00","article_modified_time":"2016-04-22T16:00:55+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/giovanardi21.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Giovanardi (Idea): &#8220;Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la Russia sospender\u00e0 l&#8217;adozione di bambini russi da parte dell&#8217;Italia&#8221;.","datePublished":"2016-04-20T11:00:48+00:00","dateModified":"2016-04-22T16:00:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/"},"wordCount":337,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/giovanardi21.jpg","articleSection":["AiBiNews","La guerra delle adozioni internazionali"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/","url":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/","name":"Giovanardi (Idea): \"Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la Russia sospender\u00e0 l'adozione di bambini russi da parte dell'Italia\". - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/giovanardi21.jpg","datePublished":"2016-04-20T11:00:48+00:00","dateModified":"2016-04-22T16:00:55+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/giovanardi21.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/giovanardi21.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/giovanardi-idea-se-la-cai-non-fornira-le-informazioni-richieste-da-piu-di-un-anno-la-russia-sospendera-ladozione-di-bambini-russi-da-parte-dellitalia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Giovanardi (Idea): &#8220;Se la CAI non fornir\u00e0 le informazioni richieste da pi\u00f9 di un anno, la Russia sospender\u00e0 l&#8217;adozione di bambini russi da parte dell&#8217;Italia&#8221;."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:32:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/125174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=125174"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/125174\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=125174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=125174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=125174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}