﻿


{"id":126484,"date":"2016-05-10T18:17:16","date_gmt":"2016-05-10T16:17:16","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=126484"},"modified":"2016-05-10T18:17:26","modified_gmt":"2016-05-10T16:17:26","slug":"con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/","title":{"rendered":"Con Care e Ai.Bi., i prof vanno a scuola di accoglienza"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-126485 alignnone\" alt=\"incontro linee guida miur salerno con care\" src=\"https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care.png\" width=\"634\" height=\"406\" data-id=\"126485\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care.png 634w, https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care-150x96.png 150w, https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care-300x192.png 300w, https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care-86x55.png 86w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/p>\n<p>Proseguono gli incontri di formazione per i docenti delle scuole della provincia di Salerno nell\u2019ambito del progetto \u201cInsegnami ad accogliere\u201d, finanziato dalla Cassa di Risparmio Salernitana. A presentare le Linee guida per il diritto allo studio dei minori adottati, elaborate da Miur, \u00e8 stata la presidente del coordinamento Care Monya Ferritti, intervenuta all\u2019appuntamento del 5 maggio, introdotta dalla referente di Ai.Bi. Campania Antonella Spadafora. Presenti all\u2019incontro, a cui hanno partecipato 45 docenti di 17 scuole, anche il Direttore generale della Provincia di Salerno Bruno Di Nesta, il presidente della Fondazione Cassa di Risparmio Salernitana Alfonso Cantarella e l\u2019assessore comunale alla Pubblica Istruzione Eva Avossa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proseguono gli incontri di formazione per i docenti delle scuole della provincia di Salerno nell\u2019ambito del progetto \u201cInsegnami ad accogliere\u201d, finanziato dalla Cassa di Risparmio Salernitana. A presentare le Linee guida per il diritto allo studio dei minori adottati, elaborate da Miur, \u00e8 stata la presidente del coordinamento Care Monya Ferritti, intervenuta all\u2019appuntamento del 5 maggio, introdotta dalla referente di Ai.Bi. Campania Antonella Spadafora. Presenti all\u2019incontro, a cui hanno partecipato 45 docenti di 17 scuole, anche il Direttore generale della Provincia di Salerno Bruno Di Nesta, il presidente della Fondazione Cassa di Risparmio Salernitana Alfonso Cantarella e l\u2019assessore comunale alla Pubblica Istruzione Eva Avossa.<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-126484","post","type-post","status-publish","format-standard","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Con Care e Ai.Bi., i prof vanno a scuola di accoglienza - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con Care e Ai.Bi., i prof vanno a scuola di accoglienza\" \/>\n<meta property=\"og:description\" content=\"Proseguono gli incontri di formazione per i docenti delle scuole della provincia di Salerno nell\u2019ambito del progetto \u201cInsegnami ad accogliere\u201d, finanziato dalla Cassa di Risparmio Salernitana. A presentare le Linee guida per il diritto allo studio dei minori adottati, elaborate da Miur, \u00e8 stata la presidente del coordinamento Care Monya Ferritti, intervenuta all\u2019appuntamento del 5 maggio, introdotta dalla referente di Ai.Bi. Campania Antonella Spadafora. Presenti all\u2019incontro, a cui hanno partecipato 45 docenti di 17 scuole, anche il Direttore generale della Provincia di Salerno Bruno Di Nesta, il presidente della Fondazione Cassa di Risparmio Salernitana Alfonso Cantarella e l\u2019assessore comunale alla Pubblica Istruzione Eva Avossa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-10T16:17:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-10T16:17:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care.png\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Con Care e Ai.Bi., i prof vanno a scuola di accoglienza\",\"datePublished\":\"2016-05-10T16:17:16+00:00\",\"dateModified\":\"2016-05-10T16:17:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/\"},\"wordCount\":117,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/incontro-linee-guida-miur-salerno-con-care.png\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/\",\"name\":\"Con Care e Ai.Bi., i prof vanno a scuola di accoglienza - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/incontro-linee-guida-miur-salerno-con-care.png\",\"datePublished\":\"2016-05-10T16:17:16+00:00\",\"dateModified\":\"2016-05-10T16:17:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/incontro-linee-guida-miur-salerno-con-care.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/incontro-linee-guida-miur-salerno-con-care.png\",\"width\":634,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Con Care e Ai.Bi., i prof vanno a scuola di accoglienza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Con Care e Ai.Bi., i prof vanno a scuola di accoglienza - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/","og_locale":"it_IT","og_type":"article","og_title":"Con Care e Ai.Bi., i prof vanno a scuola di accoglienza","og_description":"Proseguono gli incontri di formazione per i docenti delle scuole della provincia di Salerno nell\u2019ambito del progetto \u201cInsegnami ad accogliere\u201d, finanziato dalla Cassa di Risparmio Salernitana. A presentare le Linee guida per il diritto allo studio dei minori adottati, elaborate da Miur, \u00e8 stata la presidente del coordinamento Care Monya Ferritti, intervenuta all\u2019appuntamento del 5 maggio, introdotta dalla referente di Ai.Bi. Campania Antonella Spadafora. Presenti all\u2019incontro, a cui hanno partecipato 45 docenti di 17 scuole, anche il Direttore generale della Provincia di Salerno Bruno Di Nesta, il presidente della Fondazione Cassa di Risparmio Salernitana Alfonso Cantarella e l\u2019assessore comunale alla Pubblica Istruzione Eva Avossa.","og_url":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-05-10T16:17:16+00:00","article_modified_time":"2016-05-10T16:17:26+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care.png","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Con Care e Ai.Bi., i prof vanno a scuola di accoglienza","datePublished":"2016-05-10T16:17:16+00:00","dateModified":"2016-05-10T16:17:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/"},"wordCount":117,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care.png","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/","url":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/","name":"Con Care e Ai.Bi., i prof vanno a scuola di accoglienza - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care.png","datePublished":"2016-05-10T16:17:16+00:00","dateModified":"2016-05-10T16:17:26+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/incontro-linee-guida-miur-salerno-con-care.png","width":634,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/con-care-e-ai-bi-i-prof-vanno-a-scuola-di-accoglienza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Con Care e Ai.Bi., i prof vanno a scuola di accoglienza"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:56:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/126484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=126484"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/126484\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=126484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=126484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=126484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}