﻿


{"id":126941,"date":"2016-05-16T18:06:07","date_gmt":"2016-05-16T16:06:07","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=126941"},"modified":"2016-05-16T18:06:07","modified_gmt":"2016-05-16T16:06:07","slug":"barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/","title":{"rendered":"Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-126942 alignnone\" alt=\"CiiHKnLXEAA4C8K\" src=\"https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K.jpg\" width=\"634\" height=\"406\" data-id=\"126942\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K.jpg 634w, https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K-150x96.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K-300x192.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K-86x55.jpg 86w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/p>\n<p>Domenica 15 maggio, a Barletta, in occasione della V edizione del Pro Kombat Fight Show, organizzato dall\u2019associazione sportiva Asd Pro Kombat Barletta, gli operatori e i volontari di Ai.Bi. con i loro bambini, accompagnati dal coordinatore regionale di Ai.Bi. Puglia Antonio Gorgoglione, hanno organizzato una raccolta fondi a favore del progetto <i><a href=\"https:\/\/www.aibi.it\/bam\/\">Non lasciamoli soli<\/a><\/i> per portare aiuto alla popolazione siriana. Tra i sostenitori dell\u2019iniziativa anche lo scrittore, amico di Ai.Bi., Tommy Di Bari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Domenica 15 maggio, a Barletta, in occasione della V edizione del Pro Kombat Fight Show, organizzato dall\u2019associazione sportiva Asd Pro Kombat Barletta, gli operatori e i volontari di Ai.Bi. con i loro bambini, accompagnati dal coordinatore regionale di Ai.Bi. Puglia Antonio Gorgoglione, hanno organizzato una raccolta fondi a favore del progetto <i><a href=\"https:\/\/www.aibi.it\/bam\/\">Non lasciamoli soli<\/a><\/i> per portare aiuto alla popolazione siriana. Tra i sostenitori dell\u2019iniziativa anche lo scrittore, amico di Ai.Bi., Tommy Di Bari.<\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-126941","post","type-post","status-publish","format-standard","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra\" \/>\n<meta property=\"og:description\" content=\"Domenica 15 maggio, a Barletta, in occasione della V edizione del Pro Kombat Fight Show, organizzato dall\u2019associazione sportiva Asd Pro Kombat Barletta, gli operatori e i volontari di Ai.Bi. con i loro bambini, accompagnati dal coordinatore regionale di Ai.Bi. Puglia Antonio Gorgoglione, hanno organizzato una raccolta fondi a favore del progetto Non lasciamoli soli per portare aiuto alla popolazione siriana. Tra i sostenitori dell\u2019iniziativa anche lo scrittore, amico di Ai.Bi., Tommy Di Bari.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-16T16:06:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra\",\"datePublished\":\"2016-05-16T16:06:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/\"},\"wordCount\":95,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/CiiHKnLXEAA4C8K.jpg\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/\",\"name\":\"Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/CiiHKnLXEAA4C8K.jpg\",\"datePublished\":\"2016-05-16T16:06:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/CiiHKnLXEAA4C8K.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/CiiHKnLXEAA4C8K.jpg\",\"width\":634,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/","og_locale":"it_IT","og_type":"article","og_title":"Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra","og_description":"Domenica 15 maggio, a Barletta, in occasione della V edizione del Pro Kombat Fight Show, organizzato dall\u2019associazione sportiva Asd Pro Kombat Barletta, gli operatori e i volontari di Ai.Bi. con i loro bambini, accompagnati dal coordinatore regionale di Ai.Bi. Puglia Antonio Gorgoglione, hanno organizzato una raccolta fondi a favore del progetto Non lasciamoli soli per portare aiuto alla popolazione siriana. Tra i sostenitori dell\u2019iniziativa anche lo scrittore, amico di Ai.Bi., Tommy Di Bari.","og_url":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-05-16T16:06:07+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra","datePublished":"2016-05-16T16:06:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/"},"wordCount":95,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K.jpg","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/","url":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/","name":"Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K.jpg","datePublished":"2016-05-16T16:06:07+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/CiiHKnLXEAA4C8K.jpg","width":634,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/barletta-for-siria-con-pro-kombat-e-ai-bi-la-solidarieta-da-un-calcio-alle-sofferenze-della-guerra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Barletta for Siria: con Pro Kombat e Ai.Bi. la solidariet\u00e0 d\u00e0 un calcio alle sofferenze della guerra"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:56:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/126941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=126941"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/126941\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=126941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=126941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=126941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}