﻿


{"id":127221,"date":"2016-05-18T18:29:58","date_gmt":"2016-05-18T16:29:58","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=127221"},"modified":"2016-05-18T18:29:58","modified_gmt":"2016-05-18T16:29:58","slug":"tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/","title":{"rendered":"Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d"},"content":{"rendered":"<p><a href=\"https:\/\/www.youtube.com\/watch?v=y1z0SM5Zm8U\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-127222 alignnone\" alt=\"valentina griffini tv2000\" src=\"https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000.jpg\" width=\"634\" height=\"406\" data-id=\"127222\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000.jpg 634w, https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000-150x96.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000-300x192.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000-86x55.jpg 86w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/p>\n<p><\/a><\/p>\n<p>\u201cPrendere per mano e rilanciare l\u2019adozione internazionale in un clima di collegialit\u00e0 e di condivisione che coinvolga enti, famiglie e Paesi\u201d. Questa l\u2019appello rivolto, ai microfoni di Tv2000, dalla responsabile Adozioni internazionali di Ai.Bi. Valentina Griffini alla neopresidente della Cai, il ministro Maria Elena Boschi. \u201cRiportare l\u2019attenzione su milioni di bambini che stanno aspettando un pap\u00e0 e una mamma\u201d. <a href=\"https:\/\/www.youtube.com\/watch?v=y1z0SM5Zm8U\" target=\"_blank\"><strong>GUARDA IL VIDEO<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cPrendere per mano e rilanciare l\u2019adozione internazionale in un clima di collegialit\u00e0 e di condivisione che coinvolga enti, famiglie e Paesi\u201d. Questa l\u2019appello rivolto, ai microfoni di Tv2000, dalla responsabile Adozioni internazionali di Ai.Bi. Valentina Griffini alla neopresidente della Cai, il ministro Maria Elena Boschi. \u201cRiportare l\u2019attenzione su milioni di bambini che stanno aspettando un pap\u00e0 e una mamma\u201d.\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=y1z0SM5Zm8U\" target=\"_blank\"><strong>GUARDA IL VIDEO<\/strong><\/a><\/p>\n","protected":false},"author":61,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-127221","post","type-post","status-publish","format-standard","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d\" \/>\n<meta property=\"og:description\" content=\"\u201cPrendere per mano e rilanciare l\u2019adozione internazionale in un clima di collegialit\u00e0 e di condivisione che coinvolga enti, famiglie e Paesi\u201d. Questa l\u2019appello rivolto, ai microfoni di Tv2000, dalla responsabile Adozioni internazionali di Ai.Bi. Valentina Griffini alla neopresidente della Cai, il ministro Maria Elena Boschi. \u201cRiportare l\u2019attenzione su milioni di bambini che stanno aspettando un pap\u00e0 e una mamma\u201d.\u00a0GUARDA IL VIDEO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-18T16:29:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000.jpg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d\",\"datePublished\":\"2016-05-18T16:29:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/\"},\"wordCount\":80,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/valentina-griffini-tv2000.jpg\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/\",\"name\":\"Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/valentina-griffini-tv2000.jpg\",\"datePublished\":\"2016-05-18T16:29:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/valentina-griffini-tv2000.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/valentina-griffini-tv2000.jpg\",\"width\":634,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/","og_locale":"it_IT","og_type":"article","og_title":"Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d","og_description":"\u201cPrendere per mano e rilanciare l\u2019adozione internazionale in un clima di collegialit\u00e0 e di condivisione che coinvolga enti, famiglie e Paesi\u201d. Questa l\u2019appello rivolto, ai microfoni di Tv2000, dalla responsabile Adozioni internazionali di Ai.Bi. Valentina Griffini alla neopresidente della Cai, il ministro Maria Elena Boschi. \u201cRiportare l\u2019attenzione su milioni di bambini che stanno aspettando un pap\u00e0 e una mamma\u201d.\u00a0GUARDA IL VIDEO","og_url":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-05-18T16:29:58+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000.jpg","type":"","width":"","height":""}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d","datePublished":"2016-05-18T16:29:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/"},"wordCount":80,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000.jpg","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/","url":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/","name":"Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000.jpg","datePublished":"2016-05-18T16:29:58+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/valentina-griffini-tv2000.jpg","width":634,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/tv2000-lappello-di-ai-bi-alla-neopresidente-cai-boschi-rilanciare-ladozione-internazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Tv2000. L\u2019appello di Ai.Bi. alla neopresidente Cai Boschi: \u201cRilanciare l\u2019adozione internazionale\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:56:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/127221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=127221"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/127221\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=127221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=127221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=127221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}