﻿


{"id":127454,"date":"2016-05-23T16:15:48","date_gmt":"2016-05-23T14:15:48","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=127454"},"modified":"2016-05-26T18:02:11","modified_gmt":"2016-05-26T16:02:11","slug":"siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/","title":{"rendered":"Siria. Amid: &#8220;Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini&#8221;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-127467\" style=\"margin: 5px;\" alt=\"amid siria\" src=\"https:\/\/www.aibi.it\/ita\/images\/amid-siria.png\" width=\"400\" height=\"286\" data-id=\"127467\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/amid-siria.png 400w, https:\/\/www.aibi.it\/ita\/images\/amid-siria-150x107.png 150w, https:\/\/www.aibi.it\/ita\/images\/amid-siria-300x215.png 300w, https:\/\/www.aibi.it\/ita\/images\/amid-siria-77x55.png 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\u201c<i>Se Ai.Bi smetter\u00e0 di aiutare noi e gli altri come possiamo vivere? Abbiamo bisogno di tutto: cibo, kit per l&#8217;igiene, utensili da cucina, materassi e coperte. Abbiamo bisogno di tutto per vivere, perch\u00e9 siamo venuti con nulla\u201d. <\/i>A parlare \u00e8 <b>Amid uno degli oltre 13 mila beneficiari della<\/b> <b><a href=\"https:\/\/www.aibi.it\/bam\/wp-content\/uploads\/2016\/05\/spot-radio-siria.mp3\">campagna \u201cNon lasciamoli soli\u201d<\/a> <\/b>che Amici dei Bambini ha lanciato per aiutare le famiglie di sfollati, di mamme e bambini siriani che hanno perso tutto a causa della guerra.<\/p>\n<p>Amid \u00e8 uno dei 5,6 milioni che hanno perso tutto: una parte dei 13,5 milioni di persone che vivono oggi all\u2019interno del Paese in stato di estrema necessit\u00e0. Proprio per garantire almeno a una parte di loro i diritti fondamentali e la speranza in un futuro di pace Ai.Bi. ha lanciato la campagna di emergenza \u201c<b>Non lasciamoli soli\u201d<\/b> grazie alla quale in collaborazione con i suoi partner, Amici dei Bambini \u00e8 riuscita a garantire la sussistenza a <b>3mila profughi di Aleppo<\/b> grazie alla distribuzione di <b>17.460 razioni alimentari \u201cready to eat\u201d.<\/b><\/p>\n<p>Altre 5.450 persone hanno ricevuto <b>generi alimentari di prima necessit\u00e0 nella provincia di Idlib. <\/b>Nella stessa area, grazie a <b>un forno<\/b> attivato nella cittadina di <b>Binnish, 3mila famiglie<\/b> hanno accesso al pane a prezzi calmierati e <b>altre 1.090 lo ricevono gratuitamente.<\/b> Ma l\u2019impegno di Ai.Bi. va oltre il sostegno alimentare, con la realizzazione di <b>una ludoteca sotterranea e alla formazione di 100 operatori per il supporto psicosociale di 3200 bambini<\/b> affetti da stress post traumatico.<\/p>\n<p>\u201c<i>Siamo fuggiti senza niente &#8211;<\/i> continua Amid &#8211; <i>e dormito fuori casa, senza alcun riparo e i bombardamenti che ci circondavano. <\/i>\u00a0<i>Siamo della zona rurale a nord di Aleppo della citt\u00e0 di Hayyan; siamo venuti qui dopo l&#8217;aumento dei bombardamenti e 120 attacchi aerei in una giornata cos\u00ec siamo fuggiti solo con noi stessi\u201d.<\/i><\/p>\n<p><i>\u201cE &#8216; stato davvero difficile <\/i>\u2013 ricorda \u2013<i> <b>per questo vorrei ringraziare Ai.Bi. : <\/b>le ceste alimentari sono molto buone e <b>sono ricche di alimenti di cui i bambini hanno bisogno come il formaggio e i legumi<\/b>\u201d<\/i><\/p>\n<p>In Siria attualmente vivono 7,6 milioni di profughi interni: tra i bambini, 2 milioni non hanno accesso all\u2019educazione e 2,4 milioni di quelli <b>sotto i 5 anni sono a rischio di malnutrizione.<\/b><\/p>\n<p>\u201c<i>In realt\u00e0 abbiamo bisogno di tutto per vivere, perch\u00e9 siamo venuti con nulla <\/i>\u2013 continua Amid <i>&#8211; <\/i>\u00a0<i>Ho <b>cinque bambini dai 2 mesi ai 12 anni<\/b> e hanno bisogno di tutto in particolare <b>latte e pannolini\u201d.<\/b><\/i><\/p>\n<p>Ma se in Siria ovunque ti giri c\u2019\u00e8 distruzione, si vive con la paura delle bombe e costantemente la tua vita e quella dei tuoi bambini \u00e8 in pericolo \u201c<b>Perch\u00e9 hai deciso di restare qui e non hai\u00a0 un lavoro? \u00a0<\/b><i>La ragione principale per stare in Siria \u00e8 <\/i>\u2013 conclude Amid- <b><i>se lascio la Siria come gli altri, chi rimarr\u00e0 qui per ricostruirla?<\/i><\/b><i>\u201d<\/i><\/p>\n<p>Allora \u00e8 proprio a chi come Amid, che nonostante tutto decide di rimanere nella propria terra, che Ai.Bi rivolge il suo aiuto con la Campagna \u201cNon lasciamoli soli\u201d, fornendo supporto alimentare, sanitario, educativo e psicologico di cui hanno beneficiato finora migliaia di bambini e famiglie. Ed \u00e8 proprio per sostenere i bambini e le famiglie siriane in questa drammatica fase della loro vita, puoi effettuare una donazione a favore della <a href=\"https:\/\/www.aibi.it\/bam\/wp-content\/uploads\/2016\/05\/spot-radio-siria.mp3\">campagna \u201cNon lasciamoli soli\u201d.<\/a> Per scoprire in che cosa consister\u00e0 concretamente il tuo aiuto, visita la <a href=\"https:\/\/www.aibi.it\/bam\/wp-content\/uploads\/2016\/05\/spot-radio-siria.mp3\">pagina dedicata.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c<i>Se Ai.Bi smetter\u00e0 di aiutare noi e gli altri come possiamo vivere? Abbiamo bisogno di tutto: cibo, kit per l&#8217;igiene, utensili da cucina, materassi e coperte. Abbiamo bisogno di tutto per vivere, perch\u00e9 siamo venuti con nulla\u201d.\u00a0<\/i>A parlare \u00e8\u00a0<b>Amid uno degli oltre 13 mila beneficiari della<\/b>\u00a0<b><a href=\"https:\/\/www.aibi.it\/bam\/wp-content\/uploads\/2016\/05\/spot-radio-siria.mp3\">campagna \u201cNon lasciamoli soli\u201d<\/a>\u00a0<\/b>che Ai.Bi. ha lanciato per aiutare le famiglie di sfollati, di mamme e bambini siriani che hanno perso tutto a causa della guerra. Amid \u00e8 uno dei 5,6 milioni che hanno perso tutto: una parte dei 13,5 milioni di persone che vivono oggi all\u2019interno del Paese in stato di estrema necessit\u00e0.<\/p>\n","protected":false},"author":61,"featured_media":127467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114,66],"tags":[],"class_list":["post-127454","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-bambini-in-alto-mare","category-sad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Siria. Amid: &quot;Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini&quot; - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siria. Amid: &quot;Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini&quot;\" \/>\n<meta property=\"og:description\" content=\"\u201cSe Ai.Bi smetter\u00e0 di aiutare noi e gli altri come possiamo vivere? Abbiamo bisogno di tutto: cibo, kit per l&#039;igiene, utensili da cucina, materassi e coperte. Abbiamo bisogno di tutto per vivere, perch\u00e9 siamo venuti con nulla\u201d.\u00a0A parlare \u00e8\u00a0Amid uno degli oltre 13 mila beneficiari della\u00a0campagna \u201cNon lasciamoli soli\u201d\u00a0che Ai.Bi. ha lanciato per aiutare le famiglie di sfollati, di mamme e bambini siriani che hanno perso tutto a causa della guerra. Amid \u00e8 uno dei 5,6 milioni che hanno perso tutto: una parte dei 13,5 milioni di persone che vivono oggi all\u2019interno del Paese in stato di estrema necessit\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-23T14:15:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-26T16:02:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/amid-siria.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Siria. Amid: &#8220;Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini&#8221;\",\"datePublished\":\"2016-05-23T14:15:48+00:00\",\"dateModified\":\"2016-05-26T16:02:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/\"},\"wordCount\":560,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/amid-siria.png\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\",\"Sostegno a Distanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/\",\"name\":\"Siria. Amid: \\\"Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/amid-siria.png\",\"datePublished\":\"2016-05-23T14:15:48+00:00\",\"dateModified\":\"2016-05-26T16:02:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/amid-siria.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/amid-siria.png\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Siria. Amid: &#8220;Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Siria. Amid: \"Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini\" - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/","og_locale":"it_IT","og_type":"article","og_title":"Siria. Amid: \"Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini\"","og_description":"\u201cSe Ai.Bi smetter\u00e0 di aiutare noi e gli altri come possiamo vivere? Abbiamo bisogno di tutto: cibo, kit per l'igiene, utensili da cucina, materassi e coperte. Abbiamo bisogno di tutto per vivere, perch\u00e9 siamo venuti con nulla\u201d.\u00a0A parlare \u00e8\u00a0Amid uno degli oltre 13 mila beneficiari della\u00a0campagna \u201cNon lasciamoli soli\u201d\u00a0che Ai.Bi. ha lanciato per aiutare le famiglie di sfollati, di mamme e bambini siriani che hanno perso tutto a causa della guerra. Amid \u00e8 uno dei 5,6 milioni che hanno perso tutto: una parte dei 13,5 milioni di persone che vivono oggi all\u2019interno del Paese in stato di estrema necessit\u00e0.","og_url":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-05-23T14:15:48+00:00","article_modified_time":"2016-05-26T16:02:11+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/amid-siria.png","type":"image\/png"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Siria. Amid: &#8220;Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini&#8221;","datePublished":"2016-05-23T14:15:48+00:00","dateModified":"2016-05-26T16:02:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/"},"wordCount":560,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/amid-siria.png","articleSection":["AiBiNews","Bambini in alto mare","Sostegno a Distanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/","url":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/","name":"Siria. Amid: \"Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/amid-siria.png","datePublished":"2016-05-23T14:15:48+00:00","dateModified":"2016-05-26T16:02:11+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/amid-siria.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/amid-siria.png","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/siria-grazie-ad-ai-bi-i-miei-bambini-hanno-da-mangiare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Siria. Amid: &#8220;Se lascio la mia terra come gli altri, chi rimarr\u00e0 qui per ricostruirla? Ma abbiamo bisogno di tutto, soprattutto per i nostri bambini&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:01:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/127454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=127454"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/127454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/127467"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=127454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=127454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=127454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}