﻿


{"id":127551,"date":"2016-05-24T17:22:23","date_gmt":"2016-05-24T15:22:23","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=127551"},"modified":"2016-05-26T18:24:19","modified_gmt":"2016-05-26T16:24:19","slug":"siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/","title":{"rendered":"Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-127552\" style=\"margin: 5px;\" alt=\"Luigi - Reyhanli\" src=\"https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli.jpg\" width=\"400\" height=\"286\" data-id=\"127552\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>C\u2019era un luogo di Aleppo che, fin\u2019ora, la guerra aveva risparmiato. Era il polmone verde della citt\u00e0, meta di <b>tranquille passeggiate delle famiglie con i loro bambini<\/b>, serbatoio di quella poca tranquillit\u00e0 ancora ritrovabile in una citt\u00e0 sconvolta da 5 anni di violenze di ogni tipo. Poi, <b>un missile ha centrato l\u2019edificio<\/b> che lo circondava. Spazzando via anche quel che restava della calma e della serenit\u00e0 di un tempo.<\/p>\n<p>Siamo nel convento di Sant\u2019Antonio, nel quartiere di Al Ram. La struttura, gestita dai frati francescani, ospita il collegio Terre Sainte, adibito a casa di riposo per anziani. O meglio. \u201cospitava\u201d. Perch\u00e9 nel tardo pomeriggio di sabato 21 maggio <b>un missile ha sventrato le mura del collegio<\/b>, provocando la morte di una sua ospite e generando il panico tra le altre, impegnate in quel momento nella recita del Rosario. Solo un anno prima, le stesse anziane avevano dovuto abbandonare la casa di riposo che le ospitava fino a quel momento, colpita anch\u2019essa da un bombardamento.<\/p>\n<p><i>\u201cPer la gente di Aleppo<\/i> \u2013 ha detto padre <b>Ibrahim Sabbagh<\/b>, parroco latino della citt\u00e0 \u2013 <i>il convento di Sant\u2019Antonio \u00e8 considerato una sorta di polmone dove andare a riprendere fiato. <b>Le famiglie vanno l\u00ec per far giocare i bambini.<\/b> \u00c8 l\u2019unico spazio dove rimane un po\u2019 di verde\u201d<\/i>.<\/p>\n<p>Un piccolo angolo di pace destinato per\u00f2 a rimanere solo un bel ricordo. La serena precariet\u00e0 che si respirava all\u2019interno del convento \u00e8 finita anch\u2019essa sotto le macerie provocate dal missile che ha centrato l\u2019edificio, confermando il peggioramento della violenta <i>escalation<\/i> degli ultimi giorni.<\/p>\n<p>Ad Aleppo \u00e8 dunque andata in scena l\u2019ultima drammatica privazione per i bambini della citt\u00e0: quella alla passeggiata all\u2019aria aperta e ai giochi immersi nel verde. Il diritto al cibo e alla casa, molti di loro lo avevano gi\u00e0 perso. \u00c8 per questo che <b>Amici dei Bambini<\/b>, con la sua campagna <b><i><a href=\"https:\/\/www.aibi.it\/bam\/\">Non lasciamoli soli<\/a><\/i><\/b>, porta avanti interventi di prima e seconda emergenza per <b>la sicurezza alimentare e la protezione dei minori<\/b>, anche attraverso la distribuzione di ceste alimentari e razioni di cibo pronto per gli sfollati interni delle aree di Aleppo e Idlib. Proprio nella provincia di Idlib, Ai.Bi. ha attivato anche <b>una ludoteca sotterranea<\/b>, per permettere a 100 bambini di continuare a giocare al riparo dalle bombe. Per poter garantire la prosecuzione di questi interventi, che recentemente sono stati ampliati anche nelle zone di <b>Homs e Rural Damasco<\/b>, Ai.Bi. ha attivato la possibilit\u00e0 di effettuare una donazione a favore della campagna <b><i><a href=\"https:\/\/www.aibi.it\/bam\/\">Non lasciamoli soli<\/a><\/i><\/b>.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Avvenire<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019era un luogo di Aleppo che, fin\u2019ora, la guerra aveva risparmiato. Era il polmone verde della citt\u00e0, meta di\u00a0<b>tranquille passeggiate delle famiglie con i loro bambini<\/b>, serbatoio di quella poca tranquillit\u00e0 ancora ritrovabile in una citt\u00e0 sconvolta da 5 anni di violenze di ogni tipo.<\/p>\n","protected":false},"author":61,"featured_media":127552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114],"tags":[],"class_list":["post-127551","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-bambini-in-alto-mare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini<\/title>\n<meta name=\"description\" content=\"C\u2019era un luogo di Aleppo che, fin\u2019ora, la guerra aveva risparmiato. Era il polmone verde della citt\u00e0, meta di tranquille passeggiate delle famiglie con i loro bambini, serbatoio di quella poca tranquillit\u00e0 ancora ritrovabile in una citt\u00e0 sconvolta da 5 anni di violenze di ogni tipo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini\" \/>\n<meta property=\"og:description\" content=\"C\u2019era un luogo di Aleppo che, fin\u2019ora, la guerra aveva risparmiato. Era il polmone verde della citt\u00e0, meta di tranquille passeggiate delle famiglie con i loro bambini, serbatoio di quella poca tranquillit\u00e0 ancora ritrovabile in una citt\u00e0 sconvolta da 5 anni di violenze di ogni tipo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-24T15:22:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-26T16:24:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini\",\"datePublished\":\"2016-05-24T15:22:23+00:00\",\"dateModified\":\"2016-05-26T16:24:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/\"},\"wordCount\":435,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Luigi-Reyhanli.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/\",\"name\":\"Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Luigi-Reyhanli.jpg\",\"datePublished\":\"2016-05-24T15:22:23+00:00\",\"dateModified\":\"2016-05-26T16:24:19+00:00\",\"description\":\"C\u2019era un luogo di Aleppo che, fin\u2019ora, la guerra aveva risparmiato. Era il polmone verde della citt\u00e0, meta di tranquille passeggiate delle famiglie con i loro bambini, serbatoio di quella poca tranquillit\u00e0 ancora ritrovabile in una citt\u00e0 sconvolta da 5 anni di violenze di ogni tipo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Luigi-Reyhanli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Luigi-Reyhanli.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini","description":"C\u2019era un luogo di Aleppo che, fin\u2019ora, la guerra aveva risparmiato. Era il polmone verde della citt\u00e0, meta di tranquille passeggiate delle famiglie con i loro bambini, serbatoio di quella poca tranquillit\u00e0 ancora ritrovabile in una citt\u00e0 sconvolta da 5 anni di violenze di ogni tipo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/","og_locale":"it_IT","og_type":"article","og_title":"Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini","og_description":"C\u2019era un luogo di Aleppo che, fin\u2019ora, la guerra aveva risparmiato. Era il polmone verde della citt\u00e0, meta di tranquille passeggiate delle famiglie con i loro bambini, serbatoio di quella poca tranquillit\u00e0 ancora ritrovabile in una citt\u00e0 sconvolta da 5 anni di violenze di ogni tipo.","og_url":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-05-24T15:22:23+00:00","article_modified_time":"2016-05-26T16:24:19+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini","datePublished":"2016-05-24T15:22:23+00:00","dateModified":"2016-05-26T16:24:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/"},"wordCount":435,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli.jpg","articleSection":["AiBiNews","Bambini in alto mare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/","url":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/","name":"Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli.jpg","datePublished":"2016-05-24T15:22:23+00:00","dateModified":"2016-05-26T16:24:19+00:00","description":"C\u2019era un luogo di Aleppo che, fin\u2019ora, la guerra aveva risparmiato. Era il polmone verde della citt\u00e0, meta di tranquille passeggiate delle famiglie con i loro bambini, serbatoio di quella poca tranquillit\u00e0 ancora ritrovabile in una citt\u00e0 sconvolta da 5 anni di violenze di ogni tipo.","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Luigi-Reyhanli.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/siria-ad-aleppo-piovono-missili-anche-sullunico-spazio-verde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Siria. Ad Aleppo piovono missili anche sull\u2019unico spazio verde rimasto per i giochi dei bambini"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:02:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/127551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=127551"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/127551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/127552"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=127551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=127551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=127551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}