﻿


{"id":12858,"date":"2010-05-03T18:18:27","date_gmt":"2010-05-03T17:18:27","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=12858"},"modified":"2010-05-03T18:18:27","modified_gmt":"2010-05-03T17:18:27","slug":"adozioni-colella-ripristinare-il-dialogo-con-la-cai","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/","title":{"rendered":"Adozioni, Colella: ripristinare il dialogo con la CAI"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12594\" style=\"margin: 5px;\" title=\"famiglia\" src=\"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg\" alt=\"famiglia\" width=\"150\" height=\"150\" \/><\/a>In un momento in cui l\u2019attenzione mediatica \u00e8 concentrata sul mondo delle adozioni internazionali per il pronunciamento della procura generale della Cassazione contro i decreti di idoneit\u00e0 all\u2019adozione \u201cvincolati\u201d (ossia contenenti limiti sull\u2019et\u00e0, l\u2019etnia e lo stato di salute dei minori da adottare) arrivano proposte per un miglioramento del sistema da Anna Maria Colella, direttore dell\u2019Agenzia Regionale per le Adozioni Internazionali della Regione Piemonte.<\/p>\n<p><strong>Colella ha evidenziato la necessit\u00e0 di ripristinare quanto prima possibile i Tavoli di lavoro tra Commissione per le Adozioni Internazionali (CAI) ed enti autorizzati<\/strong>, sospesi dalla stessa Commissione a partire da gennaio 2010<\/p>\n<p><em>\u201cIn questi primi cinque mesi dell\u2019anno gli enti hanno sentito un contraccolpo dovuto alla mancanza dell\u2019unica possibilit\u00e0 di confronto con la CAI, i tavoli di lavoro appunto, che da sempre rappresentano un importante momento di dialogo tra chi concretamente si confronta ogni giorno con le sfide dell\u2019adozione (gli enti) e chi \u00e8 deputato a tracciare le linee politiche e strategiche dell\u2019adozione (la CAI).\u201d<\/em><\/p>\n<p>Secondo Colella servono quindi nuovi momenti di confronto tra i due principali attori del sistema per superare le attuali sfide del sistema.<\/p>\n<p><em>\u201cAd oggi abbiamo un organo composto da numerosi esperti, rappresentanti di diverse istituzioni, che per\u00f2 non dialoga con gli enti e quindi <strong>non pu\u00f2 avere una visione a 360\u00b0 delle sfide e delle difficolt\u00e0 delle adozioni. <\/strong>Sarebbe auspicabile quindi impostare una nuova metodologia di lavoro, impostata su una capacit\u00e0 di dialogo e condivisione.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In un momento in cui l\u2019attenzione mediatica \u00e8 concentrata sul mondo delle adozioni internazionali per il pronunciamento della procura generale della Cassazione contro i decreti di idoneit\u00e0 all\u2019adozione \u201cvincolati\u201d (ossia contenenti limiti sull\u2019et\u00e0, l\u2019etnia e lo stato di salute dei minori da adottare) arrivano proposte per un miglioramento del sistema da Anna Maria Colella, direttore dell\u2019Agenzia Regionale per le Adozioni Internazionali della Regione Piemonte.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-12858","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni, Colella: ripristinare il dialogo con la CAI - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni, Colella: ripristinare il dialogo con la CAI\" \/>\n<meta property=\"og:description\" content=\"In un momento in cui l\u2019attenzione mediatica \u00e8 concentrata sul mondo delle adozioni internazionali per il pronunciamento della procura generale della Cassazione contro i decreti di idoneit\u00e0 all\u2019adozione \u201cvincolati\u201d (ossia contenenti limiti sull\u2019et\u00e0, l\u2019etnia e lo stato di salute dei minori da adottare) arrivano proposte per un miglioramento del sistema da Anna Maria Colella, direttore dell\u2019Agenzia Regionale per le Adozioni Internazionali della Regione Piemonte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-03T17:18:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Adozioni, Colella: ripristinare il dialogo con la CAI\",\"datePublished\":\"2010-05-03T17:18:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/\"},\"wordCount\":248,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia1.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/\",\"name\":\"Adozioni, Colella: ripristinare il dialogo con la CAI - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia1.jpg\",\"datePublished\":\"2010-05-03T17:18:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/famiglia1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni, Colella: ripristinare il dialogo con la CAI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni, Colella: ripristinare il dialogo con la CAI - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni, Colella: ripristinare il dialogo con la CAI","og_description":"In un momento in cui l\u2019attenzione mediatica \u00e8 concentrata sul mondo delle adozioni internazionali per il pronunciamento della procura generale della Cassazione contro i decreti di idoneit\u00e0 all\u2019adozione \u201cvincolati\u201d (ossia contenenti limiti sull\u2019et\u00e0, l\u2019etnia e lo stato di salute dei minori da adottare) arrivano proposte per un miglioramento del sistema da Anna Maria Colella, direttore dell\u2019Agenzia Regionale per le Adozioni Internazionali della Regione Piemonte.","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-05-03T17:18:27+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Adozioni, Colella: ripristinare il dialogo con la CAI","datePublished":"2010-05-03T17:18:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/"},"wordCount":248,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/","name":"Adozioni, Colella: ripristinare il dialogo con la CAI - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg","datePublished":"2010-05-03T17:18:27+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/famiglia1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-colella-ripristinare-il-dialogo-con-la-cai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni, Colella: ripristinare il dialogo con la CAI"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:03:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/12858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=12858"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/12858\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=12858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=12858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=12858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}