﻿


{"id":12871,"date":"2010-05-04T12:30:11","date_gmt":"2010-05-04T11:30:11","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=12871"},"modified":"2010-05-04T13:31:27","modified_gmt":"2010-05-04T12:31:27","slug":"maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\/","title":{"rendered":"Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d"},"content":{"rendered":"<p>Doppio appuntamento per lo spettacolo teatrale \u201c..E io Pago!! (morto che parla)\u201d. Gioved\u00ec 6 maggio 2010 andr\u00e0 in scena al teatro delle Arti di Salerno, mentre venerd\u00ec 7 maggio sar\u00e0 la volta del Palapartenope di Napoli. Gli spettacoli sono organizzati da Gema Ticket  Srl.<\/p>\n<p>Andare a teatro \u00e8 anche un modo per sostenere le attivit\u00e0 di Ai.Bi. a favore dell\u2019infanzia abbandonata e in difficolt\u00e0 in Italia e in 26 Paesi del mondo; parte del ricavato della serata sar\u00e0 destinato, infatti, ai progetti dell\u2019associazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doppio appuntamento per lo spettacolo teatrale &ldquo;..E io Pago!! (morto che parla)&rdquo;. Gioved&igrave; 6 maggio 2010 andr&agrave; in scena al teatro delle Arti di Salerno, mentre venerd&igrave; 7 maggio sar&agrave; la volta del Palapartenope di Napoli. Gli spettacoli sono organizzati da Gema Ticket Srl. Andare a teatro &egrave; anche un [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-12871","post","type-post","status-publish","format-standard","category-campagne-ed-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-\u201c-e-io-pago-morto-che-parla\u201d\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d\" \/>\n<meta property=\"og:description\" content=\"Doppio appuntamento per lo spettacolo teatrale &ldquo;..E io Pago!! (morto che parla)&rdquo;. Gioved&igrave; 6 maggio 2010 andr&agrave; in scena al teatro delle Arti di Salerno, mentre venerd&igrave; 7 maggio sar&agrave; la volta del Palapartenope di Napoli. Gli spettacoli sono organizzati da Gema Ticket Srl. Andare a teatro &egrave; anche un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-\u201c-e-io-pago-morto-che-parla\u201d\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-04T11:30:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-05-04T12:31:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d\",\"datePublished\":\"2010-05-04T11:30:11+00:00\",\"dateModified\":\"2010-05-04T12:31:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\\\/\"},\"wordCount\":91,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"Campagne ed Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\\\/\",\"name\":\"Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2010-05-04T11:30:11+00:00\",\"dateModified\":\"2010-05-04T12:31:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne ed Eventi\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/campagne-ed-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-\u201c-e-io-pago-morto-che-parla\u201d\/","og_locale":"it_IT","og_type":"article","og_title":"Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d","og_description":"Doppio appuntamento per lo spettacolo teatrale &ldquo;..E io Pago!! (morto che parla)&rdquo;. Gioved&igrave; 6 maggio 2010 andr&agrave; in scena al teatro delle Arti di Salerno, mentre venerd&igrave; 7 maggio sar&agrave; la volta del Palapartenope di Napoli. Gli spettacoli sono organizzati da Gema Ticket Srl. Andare a teatro &egrave; anche un [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-\u201c-e-io-pago-morto-che-parla\u201d\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-05-04T11:30:11+00:00","article_modified_time":"2010-05-04T12:31:27+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d","datePublished":"2010-05-04T11:30:11+00:00","dateModified":"2010-05-04T12:31:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\/"},"wordCount":91,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["Campagne ed Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\/","url":"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\/","name":"Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2010-05-04T11:30:11+00:00","dateModified":"2010-05-04T12:31:27+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/maggio-doppio-appuntamento-per-%e2%80%9c-e-io-pago-morto-che-parla%e2%80%9d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Campagne ed Eventi","item":"https:\/\/www.aibi.it\/ita\/category\/campagne-ed-eventi\/"},{"@type":"ListItem","position":3,"name":"Maggio: doppio appuntamento per \u201c..E io Pago!! (morto che parla)\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:10:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/12871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=12871"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/12871\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=12871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=12871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=12871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}