﻿


{"id":129180,"date":"2016-06-15T08:00:43","date_gmt":"2016-06-15T06:00:43","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=129180"},"modified":"2016-06-17T16:14:25","modified_gmt":"2016-06-17T14:14:25","slug":"castellammare-di-stabia-na-riscoprire-ladozione-internazionale","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/","title":{"rendered":"Castellammare di Stabia (Na). Riscoprire l&#8217;adozione internazionale: Ai.Bi. incontra le famiglie del territorio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-129181 alignleft\" style=\"margin: 5px;\" alt=\"16-giugno-castellammare\" src=\"https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare.png\" width=\"400\" height=\"286\" data-id=\"129181\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare.png 400w, https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare-150x107.png 150w, https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare-300x215.png 300w, https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare-77x55.png 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>L\u2019adozione \u00e8 un meraviglioso atto di giustizia che una persona possa compiere nella propria vita, \u00e8 una scelta spirituale. Per riscoprire e rivivere il senso profondo dell\u2019accoglienza, <b>Amici dei Bambini<\/b> e l\u2019associazione <b>La Pietra Scartata<\/b>, in collaborazione con il <b>Gruppo Vangelo Cultura e Territorio<\/b> di Castellammare di Stabia, in provincia di Napoli, hanno organizzato l\u2019incontro <b>\u201cLa pietra scartata \u00e8 divenuta testata d\u2019angolo. Adozione: una meravigliosa esperienza poco conosciuta\u201d<\/b>.<\/p>\n<p>L\u2019obiettivo dell\u2019evento, che si terr\u00e0 gioved\u00ec 16 giugno alle 19 presso la Parrocchia di Sant\u2019Antonio di Padova, sar\u00e0 quello di approfondire il tema dell\u2019accoglienza e le sue \u201cvenature cromatiche\u201d.<\/p>\n<p>Un vero e proprio \u201ctuffo\u201d tra i colori che dipingono la bellezza della realt\u00e0 adottiva, per analizzarne gli aspetti psicologici, giuridici e sociali.<\/p>\n<p>Ad aprire l\u2019incontro sar\u00e0 <b>Luigi D\u2019Antonio, Coordinatore Famiglie Locali Ai.Bi. Campania<\/b>, che svilupper\u00e0 un excursus biblico sul tema dell\u2019adozione. La <b>psicologa della sede di Ai.Bi. Campania<\/b>, <b>Giovanna Buonocore<\/b>, coinvolger\u00e0 i presenti parlando dell\u2019iter adottivo, dell\u2019importanza per il bambino di essere accolto in una famiglia stabile, affinch\u00e9 possa trovare la sua identit\u00e0.<\/p>\n<p><b>Maria ed Enrico Gallozzi, <\/b><b>coniugi del Gruppo Famiglie Locali di Ai.Bi.,<\/b> interverranno per parlare dell\u2019Amoris Laetitia, l\u2019esortazione apostolica che parla della gioia dell\u2019amore nella famiglia.<\/p>\n<p>\u201c<i>Nel momento in cui due coniugi mettono al mondo un bambino sono cooperatori di Dio Creatore<\/i> \u2013 ha spiegato Maria Gallozzi\u00a0 &#8211; : ma <i>quando adottano un bambino diventano cooperatori di Dio Salvatore<\/i>\u201d.<\/p>\n<p>La bellezza dell\u2019accoglienza verr\u00e0 narrata dai testimoni attivi dell\u2019adozioni. <b>Olga e Antonio Mormone, referenti dello Spazio Famiglie Ai.Bi.<\/b>, parleranno dell\u2019adozione da una prospettiva diversa: \u201c<i>Abbiamo ricevuto un dono, nostro figlio che ci ha accolti nella sua vita<\/i>\u201d .<\/p>\n<p>Una serata all\u2019insegna della riflessione per chi, riprendendo un passo di Isaia, \u201cnon dimentica mai chi \u00e8 stato dimenticato da sua madre\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019adozione \u00e8 un meraviglioso atto di giustizia che una persona possa compiere nella propria vita, \u00e8 una scelta spirituale. Per riscoprire e rivivere il senso profondo dell\u2019accoglienza,\u00a0<b>Amici dei Bambini<\/b>\u00a0e l\u2019associazione\u00a0<b>La Pietra Scartata<\/b>, in collaborazione con il\u00a0<b>Gruppo Vangelo Cultura e Territorio<\/b>\u00a0di Castellammare di Stabia, in provincia di Napoli, hanno organizzato l\u2019incontro\u00a0<b>\u201cLa pietra scartata \u00e8 divenuta testata d\u2019angolo. Adozione: una meravigliosa esperienza poco conosciuta\u201d<\/b>.<\/p>\n","protected":false},"author":61,"featured_media":129181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-129180","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Castellammare di Stabia (Na). Riscoprire l&#039;adozione internazionale: Ai.Bi. incontra le famiglie del territorio  - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castellammare di Stabia (Na). Riscoprire l&#039;adozione internazionale: Ai.Bi. incontra le famiglie del territorio\" \/>\n<meta property=\"og:description\" content=\"L\u2019adozione \u00e8 un meraviglioso atto di giustizia che una persona possa compiere nella propria vita, \u00e8 una scelta spirituale. Per riscoprire e rivivere il senso profondo dell\u2019accoglienza,\u00a0Amici dei Bambini\u00a0e l\u2019associazione\u00a0La Pietra Scartata, in collaborazione con il\u00a0Gruppo Vangelo Cultura e Territorio\u00a0di Castellammare di Stabia, in provincia di Napoli, hanno organizzato l\u2019incontro\u00a0\u201cLa pietra scartata \u00e8 divenuta testata d\u2019angolo. Adozione: una meravigliosa esperienza poco conosciuta\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-15T06:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-17T14:14:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Castellammare di Stabia (Na). Riscoprire l&#8217;adozione internazionale: Ai.Bi. incontra le famiglie del territorio\",\"datePublished\":\"2016-06-15T06:00:43+00:00\",\"dateModified\":\"2016-06-17T14:14:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/\"},\"wordCount\":320,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/16-giugno-castellammare.png\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/\",\"name\":\"Castellammare di Stabia (Na). Riscoprire l'adozione internazionale: Ai.Bi. incontra le famiglie del territorio - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/16-giugno-castellammare.png\",\"datePublished\":\"2016-06-15T06:00:43+00:00\",\"dateModified\":\"2016-06-17T14:14:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/16-giugno-castellammare.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/16-giugno-castellammare.png\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Castellammare di Stabia (Na). Riscoprire l&#8217;adozione internazionale: Ai.Bi. incontra le famiglie del territorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Castellammare di Stabia (Na). Riscoprire l'adozione internazionale: Ai.Bi. incontra le famiglie del territorio  - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/","og_locale":"it_IT","og_type":"article","og_title":"Castellammare di Stabia (Na). Riscoprire l'adozione internazionale: Ai.Bi. incontra le famiglie del territorio","og_description":"L\u2019adozione \u00e8 un meraviglioso atto di giustizia che una persona possa compiere nella propria vita, \u00e8 una scelta spirituale. Per riscoprire e rivivere il senso profondo dell\u2019accoglienza,\u00a0Amici dei Bambini\u00a0e l\u2019associazione\u00a0La Pietra Scartata, in collaborazione con il\u00a0Gruppo Vangelo Cultura e Territorio\u00a0di Castellammare di Stabia, in provincia di Napoli, hanno organizzato l\u2019incontro\u00a0\u201cLa pietra scartata \u00e8 divenuta testata d\u2019angolo. Adozione: una meravigliosa esperienza poco conosciuta\u201d.","og_url":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-06-15T06:00:43+00:00","article_modified_time":"2016-06-17T14:14:25+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare.png","type":"image\/png"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Castellammare di Stabia (Na). Riscoprire l&#8217;adozione internazionale: Ai.Bi. incontra le famiglie del territorio","datePublished":"2016-06-15T06:00:43+00:00","dateModified":"2016-06-17T14:14:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/"},"wordCount":320,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare.png","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/","url":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/","name":"Castellammare di Stabia (Na). Riscoprire l'adozione internazionale: Ai.Bi. incontra le famiglie del territorio - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare.png","datePublished":"2016-06-15T06:00:43+00:00","dateModified":"2016-06-17T14:14:25+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/16-giugno-castellammare.png","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/castellammare-di-stabia-na-riscoprire-ladozione-internazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Castellammare di Stabia (Na). Riscoprire l&#8217;adozione internazionale: Ai.Bi. incontra le famiglie del territorio"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:55:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/129180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=129180"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/129180\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/129181"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=129180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=129180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=129180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}