﻿{"id":130900,"date":"2016-07-15T18:20:25","date_gmt":"2016-07-15T16:20:25","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=130900"},"modified":"2016-07-21T16:12:29","modified_gmt":"2016-07-21T14:12:29","slug":"dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/","title":{"rendered":"Come \u00e8 scoppiata questa  guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo"},"content":{"rendered":"<p><b><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-125513\" style=\"margin: 5px;\" alt=\"sede cai\" src=\"https:\/\/www.aibi.it\/ita\/images\/sede-cai.jpg\" width=\"400\" height=\"286\" data-id=\"125513\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/sede-cai.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/sede-cai-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/sede-cai-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/sede-cai-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Dove \u00e8 cominciata questa \u201cguerra\u201d che sta lacerando il mondo dell\u2019adozione internazionale in Italia? Andando a ricostruire il recente passato la risposta appare quanto mai chiara: dalla pessima gestione della crisi relativa alle adozioni nella Repubblica Democratica del Congo da parte di Silvia Della Monica, vicepresidente della Commissione Adozioni Internazionali. La quale, oltre a riservare alle famiglie interessate solo anni di disinformazione e silenzio, ha anche rifiutato la collaborazione con gli enti per una migliore gestione della crisi. Generando cos\u00ec un clima di odio che ha visto fronteggiarsi famiglie contro famiglie, enti contro enti, famiglie ed enti contro la Cai. Per arrivare alla \u201cciliegina sulla torta\u201d: la campagna diffamatoria contro Ai.Bi. attraverso gli articoli pubblicati su \u201cL\u2019Espresso\u201d in queste settimane.\u00a0<\/b><\/p>\n<p><strong>Ma entriamo nei particolari e vediamo come sono andate le cose.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Era il\u00a0<b>6 marzo 2014<\/b>. Pochi giorni prima\u00a0<b>Silvia Della Monica<\/b>\u00a0si era insediata come\u00a0<b>vicepresidente della Commissione Adozioni Internazionali<\/b>. Nel frattempo,\u00a0<b>151 bambini della Repubblica Democratica del Congo<\/b>, regolarmente adottati da coppie italiane, erano\u00a0<b>bloccati nel loro Paese di origine<\/b>\u00a0che, il 25 settembre precedente, aveva avviato una moratoria sulle adozioni internazionali, fermando di fatto tutti gli iter adottivi in corso.\u00a0<b>Centinaia di famiglie stavano vivendo un incubo.<\/b>\u00a0A fronte di una situazione \u201cdi precariet\u00e0 e di estrema incertezza informativa\u201d, gli\u00a0<b>8 enti autorizzati<\/b>\u00a0che seguivano le procedure adottive dei minori congolesi\u00a0<b>scrivono alla Cai nel tentativo di fare \u201cfronte comune\u201d nella gestione dell\u2019emergenza<\/b>. Nello specifico, inviano una lettera alla nostra Autorit\u00e0 Centrale, chiedendo \u201cla convocazione d\u2019urgenza di un tavolo di coordinamento degli Enti\u201d e di \u201cessere ricevuti per fare il punto della situazione e per coordinare una buona comunicazione alle centinaia di coppie di attesa\u201d, oltre che di \u201cessere aggiornati riguardo la visita della delegazione congolese in Italia\u201d.\u00a0 Gli enti quindi\u00a0<b>cercano di coordinarsi con la Cai<\/b>\u00a0per stabilire come gestire le informazioni alle famiglie e i contatti con le autorit\u00e0, con quale periodicit\u00e0 dare aggiornamenti, come organizzare le visite dei genitori nel Paese africano.<\/p>\n<p>Proprio come accaduto in passato per analoghe crisi. Come quella del\u00a0<b>Nepal<\/b>, dove, a partire dal 2007, Cai, enti e famiglie dovettero affrontare il sospetto che una parte dei minori abbinati alle coppie non fosse in realt\u00e0 adottabile. O quella della\u00a0<b>Cambogia<\/b>, che nel 2009 blocc\u00f2 le procedure di adozione in corso, in vista della revisione della legge locale. In entrambi i casi, l\u2019unit\u00e0 di azione tra enti e Cai port\u00f2 alla\u00a0<b>condivisione di informazioni<\/b>\u00a0e a una gestione della vicenda sempre al fianco delle famiglie. Il massimo esempio, a questo proposito, si \u00e8 avuto nel caso della crisi avvenuta con le adozioni in\u00a0<b>Ucraina<\/b>\u00a0tra il 2005 e il 2007. In quel caso l\u2019emergenza coinvolse\u00a0<b>pi\u00f9 di 700 coppie<\/b>. Ma la brillante collaborazione tra enti e Cai port\u00f2 a un\u2019eccellente risoluzione della vicenda.<\/p>\n<p>Nel recente caso della Repubblica Democratica del Congo, invece, la Commissione sceglie un\u2019altra strada. Silvia Della Monica, nella sua doppia veste di presidente e vicepresidente,\u00a0<b>decide di non rispondere<\/b>. Nello sbigottimento generale, enti e famiglie assistono a una politica del silenzio e della non collaborazione. Della Monica concentra tutto nelle sue mani, senza lasciare spazio al dialogo. Ispirandosi forse alla monarchia assoluta di\u00a0<b>Luigi XIV<\/b>:\u00a0<i>\u201cL\u2019\u00c9tat c\u2019est moi\u201d<\/i>, diceva il Re Sole.<\/p>\n<p>L\u2019esasperazione aumenta a ogni atto con cui la Cai rafforza la sua strategia dello scontro. Nell\u2019autunno del 2014 \u2013 a un anno dal blocco \u2013 la Commissione interviene per\u00a0<b>diffidare gli enti dall\u2019assumere iniziative individuali<\/b>\u00a0non preventivamente concordate con la Cai. Alle famiglie, Della Monica d\u00e0 solo\u00a0<b>generiche rassicurazioni<\/b>, diffidando anch\u2019esse dall\u2019intraprendere iniziative spontanee, anche a livello mediatico. Indicazioni, queste, ripetute anche nel corso del 2015. E aggiungendo poi un\u2019ulteriore beffa. Molte coppie hanno raccontato che la Cai avrebbe mostrato loro delle\u00a0<b>cartelline rosa<\/b>\u00a0in cui \u2013 stando a quanto sarebbe stato detto loro \u2013 erano contenuti i documenti relativi al loro iter adottivo. Invece, in quelle cartelline apparentemente tranquillizzanti, ci sarebbero stati errori di procedura. Nel frattempo i documenti, quelli necessari,\u00a0<b>non venivano preparati<\/b>, con conseguenti ulteriori perdite di tempo. Nell\u2019agosto 2015, poi, la Cai interviene con un comunicato sul suo sito per stigmatizzare l\u2019iniziativa mediatica di alcuni genitori intrapresa nel tentativo di sbloccare la situazione.<\/p>\n<p>A che cosa ha portato questa politica del muro contro muro scelta dalla Cai? Solo a\u00a0<b>un ritardo nella soluzione della crisi<\/b>\u00a0e soprattutto\u00a0<b>all\u2019instaurarsi di un clima di odio sfrenato<\/b>. Famiglie pro-Cai contro famiglie critiche nei confronti della Commissione, enti contro enti, coppie ed enti contro Cai. E ad avere \u2013 ora che la vicenda si \u00e8 finalmente conclusa, dopo quasi 3 anni di attese, disinformazioni, scontri \u2013\u00a0<b>un mondo dell\u2019adozione internazionale lacerato<\/b>. E il trattamento riservato ai genitori in occasione dell\u2019arrivo degli ultimi 3 gruppi di bambini dal Congo, con coppie avvisate all\u2019ultimo momento e costrette a incontrare i loro figli in caserma, non pu\u00f2 fare altro che esasperare ulteriormente il clima di tensione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dove \u00e8 cominciata questa \u201cguerra\u201d che sta lacerando il mondo dell\u2019adozione internazionale in Italia? Andando a ricostruire il recente passato la risposta appare quanto mai chiara: dalla pessima gestione della crisi relativa alle adozioni nella Repubblica Democratica del Congo da parte di Silvia Della Monica, vicepresidente della Commissione Adozioni Internazionali.<\/p>\n","protected":false},"author":61,"featured_media":125513,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,181],"tags":[],"class_list":["post-130900","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-speciale-inchiesta-espresso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Come \u00e8 scoppiata questa guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come \u00e8 scoppiata questa guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo\" \/>\n<meta property=\"og:description\" content=\"Dove \u00e8 cominciata questa \u201cguerra\u201d che sta lacerando il mondo dell\u2019adozione internazionale in Italia? Andando a ricostruire il recente passato la risposta appare quanto mai chiara: dalla pessima gestione della crisi relativa alle adozioni nella Repubblica Democratica del Congo da parte di Silvia Della Monica, vicepresidente della Commissione Adozioni Internazionali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-15T16:20:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-21T14:12:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/sede-cai.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Come \u00e8 scoppiata questa guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo\",\"datePublished\":\"2016-07-15T16:20:25+00:00\",\"dateModified\":\"2016-07-21T14:12:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/\"},\"wordCount\":828,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/sede-cai.jpg\",\"articleSection\":[\"AiBiNews\",\"Speciale inchiesta Espresso Congo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/\",\"name\":\"Come \u00e8 scoppiata questa guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/sede-cai.jpg\",\"datePublished\":\"2016-07-15T16:20:25+00:00\",\"dateModified\":\"2016-07-21T14:12:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/sede-cai.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/sede-cai.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come \u00e8 scoppiata questa guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come \u00e8 scoppiata questa guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/","og_locale":"it_IT","og_type":"article","og_title":"Come \u00e8 scoppiata questa guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo","og_description":"Dove \u00e8 cominciata questa \u201cguerra\u201d che sta lacerando il mondo dell\u2019adozione internazionale in Italia? Andando a ricostruire il recente passato la risposta appare quanto mai chiara: dalla pessima gestione della crisi relativa alle adozioni nella Repubblica Democratica del Congo da parte di Silvia Della Monica, vicepresidente della Commissione Adozioni Internazionali.","og_url":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-07-15T16:20:25+00:00","article_modified_time":"2016-07-21T14:12:29+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/sede-cai.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Come \u00e8 scoppiata questa guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo","datePublished":"2016-07-15T16:20:25+00:00","dateModified":"2016-07-21T14:12:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/"},"wordCount":828,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/sede-cai.jpg","articleSection":["AiBiNews","Speciale inchiesta Espresso Congo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/","url":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/","name":"Come \u00e8 scoppiata questa guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/sede-cai.jpg","datePublished":"2016-07-15T16:20:25+00:00","dateModified":"2016-07-21T14:12:29+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/sede-cai.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/sede-cai.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/dove-nasce-la-guerra-sulle-adozioni-internazionali-dallincapacita-di-silvia-della-monica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Come \u00e8 scoppiata questa guerra nelle adozioni internazionali? Sotto accusa l\u2019incapacit\u00e0 di Silvia Della Monica a gestire la crisi del Congo"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:08:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/130900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=130900"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/130900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/125513"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=130900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=130900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=130900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}