﻿


{"id":132436,"date":"2016-08-22T17:31:21","date_gmt":"2016-08-22T15:31:21","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=132436"},"modified":"2020-08-27T11:26:49","modified_gmt":"2020-08-27T09:26:49","slug":"ad-aleppo-non-si-muore-solo-per-le-bombe","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/","title":{"rendered":"Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino."},"content":{"rendered":"<h2>Ad Aleppo non si muore solo per le bombe: per 100mila bambini anche bere \u00e8 diventato un pericolo<\/h2>\n<p><b><i><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-131115\" style=\"margin: 5px;\" src=\"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg\" alt=\"aleppo assedio\" width=\"400\" height=\"286\" data-id=\"131115\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\u201cDove sono mio padre e mia madre?\u201d<\/i><\/b> E\u2019 stata questa l\u2019unica domanda che \u00e8 riuscito a rivolgere ai suoi soccorritori il piccolo <b>Omran<\/b>, il bambino di 5 anni la cui foto ha fatto il giro del mondo simboleggiando la tragedia della <strong>guerra in Siria<\/strong>. Eppure sapeva che sotto le macerie della sua casa, bombardata dai raid aerei che stanno distruggendo <b>Aleppo<\/b>, c\u2019era anche suo fratello. Ma non ha chiesto di lui. Forse, nell\u2019incoscienza di un bambino, <b>aveva gi\u00e0 intuito che Al\u00ec, 10 anni, non l\u2019avrebbe pi\u00f9 rivisto<\/b>. Non poteva certo capire la gravit\u00e0 delle ferite riportate da suo fratello, ma forse aveva presagito tutto. E infatti, oggi, Al\u00ec non c\u2019\u00e8 pi\u00f9. Dopo giorni di agonia, non \u00e8 sopravvissuto alle ferite, apparse da subito molto gravi. Era stato portato nello stesso ospedale dove era stato condotto anche Omran. Quell\u2019ospedale, nella parte orientale della citt\u00e0, trasformato\u00a0 in un bunker, dove <b>i medici possono operare soltanto nei sotterranei<\/b>.<\/p>\n<h3>Quale \u00e8 la situazione della Gurra in Siria?<\/h3>\n<p>Dopo la diffusione su scala mondiale di quella foto, emergono le prime testimonianze su quel giorno. Divenuto per\u00f2 uno dei tanti: perch\u00e9 ogni giorni Aleppo \u00e8 fatta bersaglio di bombardamenti e attacchi armati. <i>\u201cE\u2019 la prima volta che mi capita un bimbo come lui<\/i> \u2013 racconta Ammar, il volontario che ha estratto Omran dalle macerie e l\u2019ha portato in braccio fino all\u2019ambulanza -. <i>Di solito quando scampano a un bombardamento urlano e strillano. Questo non parlava, ho cercato di comunicare, ma lui non ha detto una parola\u201d<\/i>. Fino a quella frase, piena di angoscia per la sorte dei suoi genitori e probabilmente colma di rassegnata disperazione per quella del fratello.<\/p>\n<p>Tre anni fa le Nazioni Unite smisero di contare i morti della guerra in Siria. Quel che \u00e8 certo \u00e8 che, dal 31 luglio, nella sola Aleppo \u2013 divenuta citt\u00e0 cardine per le sorti del conflitto \u2013 sono <b>442 in pi\u00f9, di cui 97 bambini e 54 donne<\/b>. Uno stillicidio di violenza che ogni giorno presenta il suo triste bilancio, colpendo in particolare l\u2019infanzia. I feriti della battaglia di Aleppo, inaspritasi nelle ultime settimane, possono contare ormai su <b>soli 35 medici per le oltre 300mila persone<\/b> che vivono nella parte orientale della citt\u00e0, quella pi\u00f9 colpita dai bombardamenti.<\/p>\n<p>In Siria, del resto, <b><i>\u201cnessun bambino pu\u00f2 dirsi al sicuro fino a quando si trasciner\u00e0 il conflitto\u201d<\/i><\/b>, come denunciano le organizzazioni non governative attive in Siria. Dove i numeri sono sempre pi\u00f9 drammatici. <b>Sono 8,4 milioni i bambini\u00a0 siriani che hanno bisogno di aiuti umanitari<\/b>. Di questi\u00a0 <b>3,7 milioni hanno meno di 5 anni<\/b> e non conoscono altro che fughe, violenze e insicurezza. Nella sola Aleppo 100mila bambini devono affrontare i pericoli di focolai di malattie trasmesse dall\u2019acqua. Perch\u00e9 la guerra non uccide solo con le bombe. Pu\u00f2 farlo anche con l\u2019acqua contaminata. L\u2019accesso a quella potabile \u00e8 notevolmente peggiorata, la rete di distribuzione pubblica \u00e8 in tilt e intere zone della citt\u00e0 hanno i rubinetti a secco. L\u2019<i>escalation<\/i> di violenze iniziata tra fine luglio e inizio agosto impedisce ai tecnici di riparare i sistemi idrici ed elettrici. Cos\u00ec i rischi continuano a crescere ogni giorno e <b>anche bere \u00e8 diventato pericoloso<\/b>.<\/p>\n<p>In questo contesto, ogni minuto perso vorrebbe dire fare salire il numero delle vittime anche tra i pi\u00f9 piccoli. Ma <b>Amici dei Bambini <\/b>ha deciso di non abbandonare la popolazione siriana al suo destino. In 4 aree del Paese \u2013 quelle di Idlib, Homs, Rural Damasco e della stessa Aleppo \u2013 Ai.Bi. porta avanti interventi di prima e seconda emergenza che garantiscono <b><a href=\"https:\/\/www.aibi.it\/ita\/emergenza-siria\/\">supporto alimentare e di protezione<\/a> psico-fisica dei minori<\/b>. Per andare avanti in tutto questo, per\u00f2, serve sempre pi\u00f9 il contributo di tutti noi. Attraverso una donazione\u00a0 alla campagna <b><i><a href=\"https:\/\/www.aibi.it\/ita\/emergenza-siria\/\">Non lasciamoli soli<\/a><\/i><\/b> di Ai.Bi. in Siria, i bambini e le famiglie di questo martoriato Paese potranno avere una speranza in pi\u00f9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ad Aleppo non si muore solo per le bombe: per 100mila bambini anche bere &egrave; diventato un pericolo &ldquo;Dove sono mio padre e mia madre?&rdquo; E&rsquo; stata questa l&rsquo;unica domanda che &egrave; riuscito a rivolgere ai suoi soccorritori il piccolo Omran, il bambino di 5 anni la cui foto ha [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":131115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114],"tags":[],"class_list":["post-132436","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-bambini-in-alto-mare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"description\" content=\"Guerra in Siria \u201cDove sono mio padre e mia madre?\u201d E\u2019 stata questa l\u2019unica domanda che \u00e8 riuscito a rivolgere ai suoi soccorritori il piccolo Omran, il bambino di 5 anni la cui foto ha fatto il giro del mondo simboleggiando la tragedia della guerra in Siria\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino.\" \/>\n<meta property=\"og:description\" content=\"Guerra in Siria \u201cDove sono mio padre e mia madre?\u201d E\u2019 stata questa l\u2019unica domanda che \u00e8 riuscito a rivolgere ai suoi soccorritori il piccolo Omran, il bambino di 5 anni la cui foto ha fatto il giro del mondo simboleggiando la tragedia della guerra in Siria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-22T15:31:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-27T09:26:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino.\",\"datePublished\":\"2016-08-22T15:31:21+00:00\",\"dateModified\":\"2020-08-27T09:26:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/\"},\"wordCount\":656,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aleppo-assedio.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/\",\"name\":\"Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aleppo-assedio.jpg\",\"datePublished\":\"2016-08-22T15:31:21+00:00\",\"dateModified\":\"2020-08-27T09:26:49+00:00\",\"description\":\"Guerra in Siria \u201cDove sono mio padre e mia madre?\u201d E\u2019 stata questa l\u2019unica domanda che \u00e8 riuscito a rivolgere ai suoi soccorritori il piccolo Omran, il bambino di 5 anni la cui foto ha fatto il giro del mondo simboleggiando la tragedia della guerra in Siria\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aleppo-assedio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aleppo-assedio.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/ad-aleppo-non-si-muore-solo-per-le-bombe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino. - Ai.Bi. Amici dei Bambini","description":"Guerra in Siria \u201cDove sono mio padre e mia madre?\u201d E\u2019 stata questa l\u2019unica domanda che \u00e8 riuscito a rivolgere ai suoi soccorritori il piccolo Omran, il bambino di 5 anni la cui foto ha fatto il giro del mondo simboleggiando la tragedia della guerra in Siria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/","og_locale":"it_IT","og_type":"article","og_title":"Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino.","og_description":"Guerra in Siria \u201cDove sono mio padre e mia madre?\u201d E\u2019 stata questa l\u2019unica domanda che \u00e8 riuscito a rivolgere ai suoi soccorritori il piccolo Omran, il bambino di 5 anni la cui foto ha fatto il giro del mondo simboleggiando la tragedia della guerra in Siria","og_url":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-08-22T15:31:21+00:00","article_modified_time":"2020-08-27T09:26:49+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino.","datePublished":"2016-08-22T15:31:21+00:00","dateModified":"2020-08-27T09:26:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/"},"wordCount":656,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg","articleSection":["AiBiNews","Bambini in alto mare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/","url":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/","name":"Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg","datePublished":"2016-08-22T15:31:21+00:00","dateModified":"2020-08-27T09:26:49+00:00","description":"Guerra in Siria \u201cDove sono mio padre e mia madre?\u201d E\u2019 stata questa l\u2019unica domanda che \u00e8 riuscito a rivolgere ai suoi soccorritori il piccolo Omran, il bambino di 5 anni la cui foto ha fatto il giro del mondo simboleggiando la tragedia della guerra in Siria","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/ad-aleppo-non-si-muore-solo-per-le-bombe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Guerra in Siria, Omran ha ritrovato la parola ma ha perso per sempre il fratellino."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:46:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/132436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=132436"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/132436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/131115"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=132436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=132436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=132436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}