﻿


{"id":133335,"date":"2016-03-16T16:50:16","date_gmt":"2016-03-16T15:50:16","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=133335"},"modified":"2016-09-14T10:24:17","modified_gmt":"2016-09-14T08:24:17","slug":"conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/","title":{"rendered":"Conciliazione lavoro famiglia: la situazione italiana preoccupa"},"content":{"rendered":"<p><strong>La Confartigianato posiziona l\u2019Italia al 22esimo posto in UE per investimenti nel nucleo familiare. La conciliazione lavoro e famiglia per le donne attive professionalmente resta difficile.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>In Italia la\u00a0<strong>conciliazione tra lavoro e famiglia per le donne lavoratrici<\/strong>\u00a0(e, pi\u00f9 in generale, anche per l\u2019intera sfera dell\u2019imprenditoria femminile)<strong>\u00a0resta piuttosto problematica<\/strong>.<\/p>\n<p>Questo il risultato di un recente studio condotto da\u00a0<strong>Confartigianato<\/strong>, che parla di una<strong>differenza pari a 19 punti percentuali tra le esponenti del gentil sesso con e senza figli attive dal punto di vista professionale<\/strong>: delle giovani comprese\u00a0<strong>tra i 25 ed i 44 anni<\/strong>, infatti, quelle \u00a0sprovviste di prole si dedicano ad un mestiere<strong>nell\u201982,1%<\/strong>\u00a0dei casi, mentre le lavoratrici della stessa et\u00e0 con bambini a carico scendono drasticamente al\u00a0<strong>63%.<\/strong><\/p>\n<p>Notevole gap associato in primis all\u2019<strong>impossibilit\u00e0 per le madri di raggiungere una buona conciliazione tra famiglia e lavoro a causa dello scarso supporto economico garantito dallo Stato.<\/strong><\/p>\n<p>Se nel nostro Paese la\u00a0<strong>spesa pubblica destinata ai nuclei<\/strong>\u00a0domestici (mamma, pap\u00e0 e figli) corrisponde all\u2019<strong>1% del Pil<\/strong>\u00a0totale collocandoci\u00a0<strong>nell\u2019UE al 22esimo posto<\/strong>, nel resto del Vecchio Continente tale valore sale in media raggiungendo quota 1,7%. Per meglio capire la ristrettezza del tasso indicato, basti ad esempio pensare che, tra pensioni e costi per la salute, le sovvenzioni per gli anziani raggiungono il 20% del Pil (15,1% in Europa).<\/p>\n<p><strong>Conciliazione lavoro e famiglia: gli ostacoli riscontrati<\/strong><\/p>\n<p>Ma, nella realt\u00e0 dei fatti, cosa rappresenta per le donne la difficolt\u00e0 a conciliare il lavoro e la famiglia? Del\u00a0<strong>42,7% di madri occupate<\/strong>\u00a0che dichiarano di faticare a coniugare la sfera professionale con quella privata, la maggior parte chiede<strong>\u00a0per la cura dei figli un aiuto informale:<\/strong><\/p>\n<ul>\n<li>il\u00a0<strong>51,4% dei bambini entro i 2 anni<\/strong>viene accudito da parenti come i nonni;<\/li>\n<li>il\u00a0<strong>37,8%<\/strong>\u00e8 iscritto ad un<strong>\u00a0asilo nido<\/strong>;<\/li>\n<li>e\u00a0<strong>solo il 4,2%<\/strong>viene affidato a<strong>\u00a0baby sitter full time<\/strong>.<\/li>\n<\/ul>\n<p><strong>Risorse dedicate ai nuclei familiari: la situazione\u00a0in Italia<\/strong><\/p>\n<p>Per quanto concerne la\u00a0<strong>spesa media dei Comuni italiani per i minori e per le famiglie<\/strong>, a livello nazionale, le\u00a0<strong>risorse indirizzate ai servizi sociali arrivano al 40%<\/strong>, con\u00a0<strong>picchi maggiori<\/strong>\u00a0in regioni come\u00a0<strong>l\u2019Umbria<\/strong>\u00a0(<strong>55,7%<\/strong>), l\u2019<strong>Emilia Romagna<\/strong>(<strong>49,8%<\/strong>), la\u00a0<strong>Liguria ed il Molise<\/strong>\u00a0(<strong>49,6%<\/strong>).<\/p>\n<p>Riguardo la\u00a0<strong>spesa media pro capite<\/strong>\u00a0<strong>stanziata delle amministrazioni municipali ai nuclei domestici<\/strong>, invece, siamo sui\u00a0<strong>113 euro<\/strong>, che salgono a\u00a0<strong>187 euro in Liguria<\/strong>, a\u00a0<strong>194 euro in Valle d\u2019Aosta<\/strong>\u00a0ed a\u00a0<strong>198 euro in Trentino Alto Adige<\/strong>, fino ad arrivare a\u00a0<strong>237 euro<\/strong>\u00a0nella zona dell\u2019<strong>Emilia Romagna<\/strong>.<\/p>\n<p>A detta della\u00a0<strong>Presidentessa di Donne Impresa Confartigianato Edgarda Fiorini<\/strong>, la nostra Penisola, oltre a concedere uno\u00a0<strong>scarso sostegno alle mamme occupate<\/strong>, penalizza anche l\u2019intera sfera dell\u2019imprenditoria femminile, non prevedendo\u00a0<strong>alcuna agevolazione per la maternit\u00e0 delle lavoratrici autonome<\/strong>.<\/p>\n<p>Sempre secondo la Fiorini, per di pi\u00f9, tutto questo (aggiunto alla crisi finanziaria ed alla limitatezza dei servizi pubblici rivolti alla famiglia) ha portato negli ultimi 10 anni (dal 2005 al 2015) ad una\u00a0<strong>riduzione nel numero delle imprenditrici<\/strong>\u00a0di oltre 5 punti percentuali (-5,6%).<\/p>\n<p><strong>Proposte\u00a0di Donne Impresa Confartigianato<\/strong><\/p>\n<p>Affinch\u00e9 sia possibile\u00a0<strong>migliorare per le lavoratrici autonome la conciliazione tra vita e lavoro<\/strong>, Donne Impresa Confartigianato chiede:<\/p>\n<ul>\n<li><strong>voucher babysitting<\/strong>e\u00a0<strong>voucher per l\u2019assistenza<\/strong>\u00a0dei parenti di una certa et\u00e0 e per i\u00a0<strong>familiari disabili;<\/strong><\/li>\n<li>v<strong>oucher per la formazione di collaboratori<\/strong>interpellati in modo temporaneo per sostituire la titolare nella propria attivit\u00e0;<\/li>\n<li><strong>crediti d\u2019imposta<\/strong>come incentivi per la diffusione di aziende operanti nei servizi di welfare per infanzia e famiglia;<\/li>\n<li><strong>sgravi fiscali-contributivi<\/strong>per l\u2019ingaggio a tempo determinato di sostituti da inserire in azienda nei periodi di maternit\u00e0 e\/o di assistenza a figli minorenni e familiari anziani;<\/li>\n<li>creazione di un\u00a0<strong>Fondo completamente dedicato all\u2019imprenditoria in rosa<\/strong>.<\/li>\n<\/ul>\n<p>Visto che, almeno stando ad un report di\u00a0<strong>McKinsey<\/strong>\u00a0intitolato\u00a0<strong>The power of parity<\/strong>,\u00a0<strong>la parit\u00e0 nella sfera professionale<\/strong>\u00a0tra uomini e donne, riuscirebbe ad\u00a0<strong>aumentare il Pil mondiale di 28 miliardi<\/strong>\u00a0di dollari gi\u00e0 entro il 2025 (+26%).<\/p>\n<p>Il miglioramento della conciliazione tra lavoro e famiglia consentendo alle madri imprenditrici di gestire i propri impegni con maggiore semplicit\u00e0, \u00e8 ormai diventato a tutti gli effetti un\u00a0<strong>bisogno concreto<\/strong>: un\u2019esigenza a portata globale che, volenti o nolenti, non possiamo pi\u00f9 permetterci di sottovalutare.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: <a href=\"http:\/\/danea.it\">danea.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>La Confartigianato posiziona l\u2019Italia al 22esimo posto in UE per investimenti nel nucleo familiare. La conciliazione lavoro e famiglia per le donne attive professionalmente resta difficile.\u00a0<\/strong>In Italia la\u00a0<strong>conciliazione tra lavoro e famiglia per le donne lavoratrici<\/strong>\u00a0(e, pi\u00f9 in generale, anche per l\u2019intera sfera dell\u2019imprenditoria femminile)<strong>\u00a0resta piuttosto problematica<\/strong>.<\/p>\n","protected":false},"author":61,"featured_media":117834,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[],"class_list":["post-133335","post","type-post","status-publish","format-standard","has-post-thumbnail","category-family-audit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conciliazione lavoro famiglia: la situazione italiana preoccupa - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conciliazione lavoro famiglia: la situazione italiana preoccupa\" \/>\n<meta property=\"og:description\" content=\"La Confartigianato posiziona l\u2019Italia al 22esimo posto in UE per investimenti nel nucleo familiare. La conciliazione lavoro e famiglia per le donne attive professionalmente resta difficile.\u00a0In Italia la\u00a0conciliazione tra lavoro e famiglia per le donne lavoratrici\u00a0(e, pi\u00f9 in generale, anche per l\u2019intera sfera dell\u2019imprenditoria femminile)\u00a0resta piuttosto problematica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-16T15:50:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-09-14T08:24:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/family-audit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Conciliazione lavoro famiglia: la situazione italiana preoccupa\",\"datePublished\":\"2016-03-16T15:50:16+00:00\",\"dateModified\":\"2016-09-14T08:24:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/\"},\"wordCount\":682,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/family-audit.jpg\",\"articleSection\":[\"Family Audit\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/\",\"name\":\"Conciliazione lavoro famiglia: la situazione italiana preoccupa - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/family-audit.jpg\",\"datePublished\":\"2016-03-16T15:50:16+00:00\",\"dateModified\":\"2016-09-14T08:24:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/family-audit.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/family-audit.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Family Audit\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/family-audit\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conciliazione lavoro famiglia: la situazione italiana preoccupa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conciliazione lavoro famiglia: la situazione italiana preoccupa - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/","og_locale":"it_IT","og_type":"article","og_title":"Conciliazione lavoro famiglia: la situazione italiana preoccupa","og_description":"La Confartigianato posiziona l\u2019Italia al 22esimo posto in UE per investimenti nel nucleo familiare. La conciliazione lavoro e famiglia per le donne attive professionalmente resta difficile.\u00a0In Italia la\u00a0conciliazione tra lavoro e famiglia per le donne lavoratrici\u00a0(e, pi\u00f9 in generale, anche per l\u2019intera sfera dell\u2019imprenditoria femminile)\u00a0resta piuttosto problematica.","og_url":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-03-16T15:50:16+00:00","article_modified_time":"2016-09-14T08:24:17+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/family-audit.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Conciliazione lavoro famiglia: la situazione italiana preoccupa","datePublished":"2016-03-16T15:50:16+00:00","dateModified":"2016-09-14T08:24:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/"},"wordCount":682,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/family-audit.jpg","articleSection":["Family Audit"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/","url":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/","name":"Conciliazione lavoro famiglia: la situazione italiana preoccupa - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/family-audit.jpg","datePublished":"2016-03-16T15:50:16+00:00","dateModified":"2016-09-14T08:24:17+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/family-audit.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/family-audit.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/conciliazione-lavoro-famiglia-la-situazione-italiana-preoccupa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Family Audit","item":"https:\/\/www.aibi.it\/ita\/category\/family-audit\/"},{"@type":"ListItem","position":3,"name":"Conciliazione lavoro famiglia: la situazione italiana preoccupa"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:14:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/133335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=133335"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/133335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/117834"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=133335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=133335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=133335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}