﻿


{"id":133981,"date":"2016-09-30T18:31:46","date_gmt":"2016-09-30T16:31:46","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=133981"},"modified":"2016-09-30T18:31:46","modified_gmt":"2016-09-30T16:31:46","slug":"siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/","title":{"rendered":"Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-120231 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis.jpg\" alt=\"siria ceste alimentari 1bis\" width=\"400\" height=\"286\" data-id=\"120231\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>Una crisi umanitaria senza precedenti<\/strong> e un\u2019intera generazione che rischia di andare perduta per sempre. Ma anche <strong>l\u2019impegno costante di Amici dei Bambini<\/strong> nel cercare di garantire sicurezza alimentare e protezione alle piccole vittime della guerra. Questa \u00e8 la Siria oggi, dopo oltre 5 anni e mezzo di un conflitto che sembra non avere mai fine. Nei suoi 3 anni di presenza nel Paese, Ai.Bi. ha alleviato le sofferenze di <strong>decine di migliaia di siriani<\/strong>, ma molto altro \u00e8 ancora da fare per poter assicurare loro condizioni di vita dignitose e un futuro di pace.<\/p>\n<p>Da marzo 2011, <strong>la guerra ha ucciso circa 11mila bambini<\/strong>. In tutto il Paese sono <strong>13,5 milioni le persone che necessitano di assistenza umanitaria<\/strong>, di cui 6 milioni sono\u00a0 minori. La crisi alimentare colpisce attualmente 9 milioni di siriani, oltre un terzo dei quali \u00e8 costituito da bambini. Le persone che hanno dovuto abbandonare la propria casa sono 10,8 milioni, ma meno della met\u00e0 \u00e8 fuggito all\u2019estero. La maggior parte, pari a 6,5 milioni, \u00e8 fatta di sfollati interni che sono rimasti all\u2019interno del Paese. E sono <strong>7,5 milioni i bambini\u00a0 che non hanno visto nient\u2019altro che la guerra<\/strong>. I sistemi scolastico e sanitario sono ormai al collasso. Sono quasi 3 milioni i piccoli siriani che <strong>non hanno pi\u00f9 accesso all\u2019educazione<\/strong> e il 50% delle strutture sanitarie sono state danneggiate o distrutte dai combattimenti, nel corso dei quali hanno perso la vita circa 700 tra medici e infermieri.<\/p>\n<p>Davanti a tutto questo, Ai.Bi. non \u00e8 mai rimasta a guardare. Nell\u2019ambito della campagna <strong><em><a href=\"https:\/\/www.aibi.it\/sms\/\">Bambini in Alto Mare<\/a><\/em><\/strong> e in collaborazione con i suoi partner locali \u2013 le associazioni <strong>Syrian Children Relief, Shafak, Ihsan RD, Kids Paradise e Gauth Voluntary Group<\/strong> -, Ai.Bi. ha effettuato interventi di prima e seconda emergenza nelle aree di Idlib, Aleppo, Homs e Rural Damasco. In concreto, sono state distribuite <strong>ceste alimentari a 1.160 famiglie<\/strong> e <strong>17.460 razioni alimentari<\/strong> a circa 3mila sfollati. Ma non solo. Sono stati allestiti anche <strong>una ludoteca sotterranea<\/strong> per permettere a 200 bambini di giocare al riparo dalle bombe e <strong>un forno<\/strong> per la produzione di pane destinato a 3mila famiglie. Senza dimenticare le 100 mamme che hanno avuto la possibilit\u00e0 di lavorare nella <strong>sartoria<\/strong> allestita da Ai.Bi. nel nord del Paese.<\/p>\n<p>L\u2019impegno di Amici dei Bambini non si \u00e8 mai fermato. In questo periodo si sta provvedendo alla <strong>formazione di 191 operatori sociali<\/strong> che svolgeranno attivit\u00e0 ricreative di sensibilizzazione per 20.750 tra adulti e bambini delle zone pi\u00f9 disagiate raggiunte per mezzo di <strong>9 apposite unit\u00e0 mobili<\/strong>, oltre a gestire le attivit\u00e0 di <strong>3 spazi sicuri<\/strong> per l\u2019attenzione e il supporto psicosociale di 2.300 minori.\u00a0 Oltre a loro, Ai.Bi. sta formando anche <strong>4.500 donne<\/strong> sulle prevenzione della violenza di genere. Nel frattempo prosegue la distribuzione di ceste alimentari\u00a0 ed \u00e8 iniziata quella di voucher per 262 famiglie.<\/p>\n<p>Per il futuro Ai.Bi. ha gi\u00e0 avviato due nuovi grandi progetti. Il primo \u00e8 quello di <strong>un forno mobile<\/strong> che produrr\u00e0 cibo per 18mila sfollati. Il secondo, ancora pi\u00f9 impegnativo, prevede invece la costruzione di <strong>un ospedale pediatrico ricavato sotto una collina<\/strong>, al riparo dalle bombe. La struttura sar\u00e0 raggiungibile da 300mila civili e si svilupper\u00e0 su una superficie di 2mila metri quadrati all\u2019interno della roccia e 300 in esterno. Offrir\u00e0 servizi di emergenza e sar\u00e0 dotato di 35 posti letto, 19 incubatrici e reparti di pediatria, ginecologia e servizi ostetrici capaci di soccorrere 300 persone al giorno.<\/p>\n<p>Per quest\u2019ultima grande iniziativa, Ai.Bi. chiede anche il tuo aiuto: <strong>fino al 3 ottobre puoi donare 2 euro con un sms oppure 2 o 5 euro con una chiamata da rete fissa al numero 45507 a favore della campagna <em><a href=\"https:\/\/www.aibi.it\/sms\/\">Bambini\u00a0 in Alto Mare<\/a><\/em>.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Una crisi umanitaria senza precedenti<\/strong> e un\u2019intera generazione che rischia di andare perduta per sempre. Ma anche <strong>l\u2019impegno costante di Amici dei Bambini<\/strong> nel cercare di garantire sicurezza alimentare e protezione alle piccole vittime della guerra.<\/p>\n","protected":false},"author":61,"featured_media":120231,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114],"tags":[],"class_list":["post-133981","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-bambini-in-alto-mare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico\" \/>\n<meta property=\"og:description\" content=\"Una crisi umanitaria senza precedenti e un\u2019intera generazione che rischia di andare perduta per sempre. Ma anche l\u2019impegno costante di Amici dei Bambini nel cercare di garantire sicurezza alimentare e protezione alle piccole vittime della guerra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-30T16:31:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico\",\"datePublished\":\"2016-09-30T16:31:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/\"},\"wordCount\":621,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/siria-ceste-alimentari-1bis.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/\",\"name\":\"Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/siria-ceste-alimentari-1bis.jpg\",\"datePublished\":\"2016-09-30T16:31:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/siria-ceste-alimentari-1bis.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/siria-ceste-alimentari-1bis.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/","og_locale":"it_IT","og_type":"article","og_title":"Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico","og_description":"Una crisi umanitaria senza precedenti e un\u2019intera generazione che rischia di andare perduta per sempre. Ma anche l\u2019impegno costante di Amici dei Bambini nel cercare di garantire sicurezza alimentare e protezione alle piccole vittime della guerra.","og_url":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-09-30T16:31:46+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico","datePublished":"2016-09-30T16:31:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/"},"wordCount":621,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis.jpg","articleSection":["AiBiNews","Bambini in alto mare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/","url":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/","name":"Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis.jpg","datePublished":"2016-09-30T16:31:46+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/siria-ceste-alimentari-1bis.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/siria-in-una-crisi-umanitaria-senza-precedenti-ai-bi-ha-distribuito-cibo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Siria. In una crisi umanitaria senza precedenti, Ai.Bi. ha distribuito cibo e assicurato supporto psico-sociale a migliaia di piccoli sfollati. E nel futuro ci sono un forno mobile e un ospedale pediatrico"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:01:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/133981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=133981"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/133981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/120231"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=133981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=133981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=133981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}