﻿{"id":134454,"date":"2016-10-17T18:35:10","date_gmt":"2016-10-17T16:35:10","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=134454"},"modified":"2016-10-17T18:45:46","modified_gmt":"2016-10-17T16:45:46","slug":"adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/","title":{"rendered":"Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-118585 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/dellamonica.png\" alt=\"dellamonica\" width=\"400\" height=\"286\" data-id=\"118585\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/dellamonica.png 400w, https:\/\/www.aibi.it\/ita\/images\/dellamonica-150x107.png 150w, https:\/\/www.aibi.it\/ita\/images\/dellamonica-300x215.png 300w, https:\/\/www.aibi.it\/ita\/images\/dellamonica-77x55.png 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/strong><\/p>\n<p><strong>Silvia Della Monica<\/strong>, vicepresidente (ed ex presidente) della Commissione Adozioni Internazionali (CAI)\u00a0 mercoled\u00ec 12 ottobre con il suo intervento in commissione Giustizia della Camera dei Deputati ha concluso le audizioni per l\u2019indagine conoscitiva sullo stato di attuazione delle disposizioni legislative\u00a0 in materia di adozione e affido.<\/p>\n<p>Un intervento colmo di <strong>inesattezze, menzogne e paradossi.<\/strong> Talmente tanti da spingerci a<strong> raccoglierli e pubblicarli su Aibinews <\/strong>giorno dopo giorno con delle <strong>news ad hoc<\/strong> in modo <strong>fare capire come siano andate realmente le cose.<\/strong><\/p>\n<p>Ecco le prime: <strong>il 13 e il 14 ottobre<\/strong>, abbiamo pubblicato\u00a0 due news in cui vengono denunciate le bugie\u00a0di<strong> Della Monica e Fabrizio Gatti<\/strong>, autore dell\u2019articolo pubblicato su <strong>L\u2019Espresso.<\/strong><\/p>\n<p>Come abbiamo riportato nella news del <strong>13 ottobre<\/strong>\u00a0 ne <a href=\"https:\/\/www.aibi.it\/ita\/il-procuratore-della-repubblica-di-goma-i-fatti-descritti-da-gatti-non-sono-mai-esistiti\/\"><strong>\u201cIl Procuratore della Repubblica di Goma: \u201cI fatti descritti da Gatti non sono mai esistiti!\u201d. Perch\u00e9 Silvia Della Monica non ha detto la verit\u00e0 alla Camera?\u201d<\/strong><\/a>\u00a0, Della Monica ha dichiarato\u00a0\u201c<em>l\u2019inchiesta di Fabrizio Gatti pubblicata su L\u2019Espresso riporta fatti gravissimi di cui la Commissione \u00e8 pienamente consapevole. Il tentativo di banalizzazione o anche un atteggiamento negazionista non risponde alla priorit\u00e0 di chiarezza e di sostegno all&#8217;ineludibile azione di pulizia che deve essere necessariamente portata fino in fondo e che io intendo portare fino in fondo<\/em>\u201d.<\/p>\n<p>Peccato per\u00f2 che \u00a0proprio sull\u2019inchiesta de \u201cL\u2019Espresso\u201d, le autorit\u00e0 congolesi \u2013 e precisamente il Presidente del Tribunale per i Minorenni e il Procuratore della Repubblica di Goma Saleh Katamea Daniel \u2013 dichiarano che \u201c<strong><em>i fatti descritti da Gatti non sono mai esistiti!<\/em><\/strong>\u201d.<\/p>\n<p>Il <strong>14 ottobre<\/strong> ne \u201c<a href=\"https:\/\/www.aibi.it\/ita\/il-presidente-del-tribunale-per-i-minorenni-di-goma-silvia-della-monica-ha-spinto-i-suoi-collaboratori\/\"><strong>Il Presidente del Tribunale per i Minorenni di Goma: \u201cSilvia Della Monica ha spinto i suoi collaboratori in Congo a violare le leggi della Repubblica\u201d. Il conflitto tra la Cai e le Autorit\u00e0 Congolesi<\/strong><\/a><strong>\u201d <\/strong>si mette in evidenza uno dei punti pi\u00f9 assurdi di quanto affermato dalla vicepresidente: quello relativo ai bambini congolesi che sarebbero stati \u201c<strong><em>trattenuti illecitamente<\/em><\/strong>\u201d. Un episodio che ha visto il verificarsi di <strong>un conflitto tra la Cai e le autorit\u00e0 congolesi,<\/strong> come esposto chiaramente dal Primo Presidente della Corte d\u2019Appello di Goma Lazare Banide Wafole e dal Presidente del Tribunale per i Minorenni di Goma Sumaili Kanyangolo Charles Wilfrid.<\/p>\n<p><strong>La realt\u00e0 dei fatti \u00e8 diametralmente opposta, come riportiamo nella news,<\/strong> rispetto a quanto dichiarato irresponsabilmente <strong>da Della Monica e alle assurde fantasie di Gatti su \u201cL\u2019Espresso\u201d. <\/strong>I <strong>bambini di Goma hanno corso un rischio notevole: <\/strong>quello di non poter arrivare in Italia, dove li attendevano le loro famiglie adottive. <strong>Se ci\u00f2 non \u00e8 accaduto lo si deve soprattutto alla buona volont\u00e0 della Magistratura di Goma, <\/strong>preoccupata \u2013 essa s\u00ec \u2013 del superiore interesse dei minori e impegnata a sbloccare la situazione, nonostante gli atti commessi dai delegati della Cai, incaricati di portare via i bambini dagli orfanotrofi in cui erano accolti per decisione precauzionale del Presidente del Tribunale per i Minorenni di Goma.<\/p>\n<p>Nei giorni seguenti, gi\u00e0 <strong>da domani (18 ottobre) continueremo a snocciolare le molteplici \u201cfantasie<\/strong>\u201d e bugie.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Silvia Della Monica<\/strong>, vicepresidente (ed ex presidente) della Commissione Adozioni Internazionali (CAI)\u00a0 mercoled\u00ec 12 ottobre con il suo intervento in commissione Giustizia della Camera dei Deputati ha concluso le audizioni per l\u2019indagine conoscitiva sullo stato di attuazione delle disposizioni legislative\u00a0 in materia di adozione e affido.\u00a0Un intervento colmo di <strong>inesattezze, paradossi e falsit\u00e0.<\/strong>\u00a0Ecco una prima sintesi.<\/p>\n","protected":false},"author":61,"featured_media":118585,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,181],"tags":[],"class_list":["post-134454","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-speciale-inchiesta-espresso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi\" \/>\n<meta property=\"og:description\" content=\"Silvia Della Monica, vicepresidente (ed ex presidente) della Commissione Adozioni Internazionali (CAI)\u00a0 mercoled\u00ec 12 ottobre con il suo intervento in commissione Giustizia della Camera dei Deputati ha concluso le audizioni per l\u2019indagine conoscitiva sullo stato di attuazione delle disposizioni legislative\u00a0 in materia di adozione e affido.\u00a0Un intervento colmo di inesattezze, paradossi e falsit\u00e0.\u00a0Ecco una prima sintesi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-17T16:35:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-17T16:45:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/dellamonica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi\",\"datePublished\":\"2016-10-17T16:35:10+00:00\",\"dateModified\":\"2016-10-17T16:45:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/\"},\"wordCount\":516,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/dellamonica.png\",\"articleSection\":[\"AiBiNews\",\"Speciale inchiesta Espresso Congo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/\",\"name\":\"Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/dellamonica.png\",\"datePublished\":\"2016-10-17T16:35:10+00:00\",\"dateModified\":\"2016-10-17T16:45:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/dellamonica.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/dellamonica.png\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/","og_locale":"it_IT","og_type":"article","og_title":"Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi","og_description":"Silvia Della Monica, vicepresidente (ed ex presidente) della Commissione Adozioni Internazionali (CAI)\u00a0 mercoled\u00ec 12 ottobre con il suo intervento in commissione Giustizia della Camera dei Deputati ha concluso le audizioni per l\u2019indagine conoscitiva sullo stato di attuazione delle disposizioni legislative\u00a0 in materia di adozione e affido.\u00a0Un intervento colmo di inesattezze, paradossi e falsit\u00e0.\u00a0Ecco una prima sintesi.","og_url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-10-17T16:35:10+00:00","article_modified_time":"2016-10-17T16:45:46+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/dellamonica.png","type":"image\/png"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi","datePublished":"2016-10-17T16:35:10+00:00","dateModified":"2016-10-17T16:45:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/"},"wordCount":516,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/dellamonica.png","articleSection":["AiBiNews","Speciale inchiesta Espresso Congo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/","url":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/","name":"Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/dellamonica.png","datePublished":"2016-10-17T16:35:10+00:00","dateModified":"2016-10-17T16:45:46+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/dellamonica.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/dellamonica.png","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioni-internazionali-tutte-le-menzogne-della-vicepresidente-silvia-della-monica-dai-fatti-inventati-dallespresso-al-conflitto-tra-la-cai-e-le-autorita-congolesi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Adozioni internazionali. Tutte le menzogne della Vicepresidente Silvia Della Monica: dai fatti inventati da L\u2019Espresso al conflitto tra la Cai e le autorit\u00e0 congolesi"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:23:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/134454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=134454"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/134454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/118585"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=134454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=134454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=134454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}