﻿{"id":134457,"date":"2016-10-17T19:20:43","date_gmt":"2016-10-17T17:20:43","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=134457"},"modified":"2016-10-19T17:13:23","modified_gmt":"2016-10-19T15:13:23","slug":"i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/","title":{"rendered":"I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-131650 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica.jpg\" alt=\"boschi-dellamonica\" width=\"400\" height=\"286\" data-id=\"131650\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/strong><\/p>\n<p><strong>Due giorni fa, il 15 ottobre, <\/strong><strong>la Ministra con delega alle Pari Opportunit\u00e0, Maria Elena Boschi,<\/strong><strong>\u00a0 ha twittato \u201c<\/strong><em><a href=\"https:\/\/twitter.com\/meb\/status\/787335797972279297\">Per le pari opportunit\u00e0 60 milioni in bilancio. Contro la tratta di esseri umani, contro la violenza sulle donne #passodopopasso<\/a><\/em>\u201d. Oggi, 17 ottobre, il ministro per gli Affari regionali e le Autonomie, con delega alla Famiglia, <strong>Enrico Costa<\/strong>, le fa eco dichiarando \u201c<em>Per la prima volta la legge di bilancio comprende un capo specifico dedicato alla famiglia: le risorse stanziate ammontano a <strong>600 milioni di euro<\/strong><\/em>\u201d. Cifre importanti, quasi da capogiro.<\/p>\n<p>Insomma ancora manca il testo definitivo e ufficiale della legge di stabilit\u00e0 2017 ma gi\u00e0 trapelano delle <strong>indiscrezioni<\/strong> che, riguardando settori delicati, non passano inosservate.<strong>\u00a0<\/strong><\/p>\n<p><strong>Ma una cosa su tutte spicca: al momento nessuno fa riferimento a stanziamenti e fondi\u00a0<\/strong><strong>destinati alle adozioni internazionali. Che languono e che stanno spirando il loro ultimo respiro.<\/strong><\/p>\n<p>Se infatti, nella nuova finanziaria non ci saranno risorse destinate ad hoc,<strong> questa sar\u00e0 la pietra tombale per un settore in agonia da 3 anni, <\/strong>ovvero da quando a capo della CAI (Commissione Adozioni internazionali) Renzi ha messo,<strong> nel doppio ruolo di controllore e controllato, Silvia Della Monica. <\/strong>Contemporaneamente<strong> presidente e vicepresidente dello stesso organo collegiale: una paralisi annunciata!\u00a0<\/strong><\/p>\n<p><strong>Assurda \u00a0stasi <\/strong>che, giorno dopo giorno, come nelle sabbie mobili, sta portando sempre pi\u00f9 gi\u00f9, <strong>negli abissi le adozioni internazionali<\/strong> (quest&#8217;anno secondo proiezioni non verranno superate 1700 adozioni, quindi crollo ulteriore del 20%): uno stallo \u201csostanziato\u201d da <strong>una Commissione riunitasi, in oltre mille giorni, una sola volta<\/strong>;\u00a0 da <strong>decisioni illegittime<\/strong>,\u00a0 <strong>abusi di potere<\/strong>, <strong>clima di veleni<\/strong> tra associazioni familiari e coppie, <strong>lotta fra enti<\/strong>, fra famiglie, <strong>comunicazioni inesistenti<\/strong> tra la CAI e le coppie, il\u00a0<strong>sito ufficiale<\/strong> della Commissione <strong>fermo<\/strong> da 3 anni, uffici CAI vuoti funzionari dismessi e non sostituiti,\u00a0nessun nuovo Paese aperto e ancora rimborsi alle copie non concessi: insomma un vero disastro!<\/p>\n<p>Per questo <strong>la nomina agli inizi di giugno di quest&#8217;anno, della ministra Boschi<\/strong> a Presidente della Commissione era stata salutata e accolta come \u00a0un segnale di \u201csvolta\u201d, ma <strong>in questo arco temporale purtroppo nulla sembra essere cambiato<\/strong>: anzi secondo quanto riportato da Panorama, ci sarebbe <strong>in atto uno scontro con Silvia Della Monica<\/strong> che di fatto la bloccherebbe dal prendere iniziative<strong>.<\/strong><\/p>\n<p>Ci coglie quindi il sospetto che tale &#8221; importante &#8221; nomina sia stata fatta solo per &#8220;prendere&#8221; tempo e tacitare le proteste di centinaia di famiglie di decine e decine di parlamentari (pi\u00f9 di 60 interpellanze firmate da circa 250 fra deputati e senatori) \u00a0delle associazioni familiari e degli enti autorizzati.<br \/>\nE dire che <strong>l\u2019occasione per ridare fiato alle adozioni internazionali ora ci sarebbe:<\/strong> <strong>prevedere in Finanziaria degli stanziamenti,<\/strong> ovvero concreti <strong>segnali di speranza<\/strong> per le decine di migliaia di coppie che vogliono ritornare a credere nella adozione internazionale.<\/p>\n<p><strong>Qualora ci\u00f2 non dovesse avverarsi, un plauso amaro andrebbe a Renzi. <\/strong>Cos\u00ec facendo, il Premier <strong>riuscirebbe nel suo intento: rottamare l\u2019adozione internazionale <\/strong>accentrando tutto il potere nella mani di Silvia Della Monica \u00a0mettendo in pratica la sua idea di &#8220;welfare stato-stato&#8221;.<\/p>\n<p><strong>Quale speranza ci rimane per salvare \u00a0la &#8220;nostra&#8221; adozione internazionale \u00a0fondata sul fondamentale e insostituibile apporto del movimento delle famiglie adottive!\u00a0<\/strong><\/p>\n<p><strong>Forse il referendum del 4 dicembre?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Due giorni fa, il 15 ottobre, <\/strong><strong>la Ministra con delega alle Pari Opportunit\u00e0, Maria Elena Boschi,<\/strong><strong>\u00a0 ha twittato \u201c<\/strong><em><a href=\"https:\/\/twitter.com\/meb\/status\/787335797972279297\">Per le pari opportunit\u00e0 60 milioni in bilancio. Contro la tratta di esseri umani, contro la violenza sulle donne #passodopopasso<\/a><\/em>\u201d. Oggi, 17 ottobre, il ministro per gli Affari regionali e le Autonomie, con delega alla Famiglia, <strong>Enrico Costa<\/strong>, le fa eco dichiarando \u201c<em>Per la prima volta la legge di bilancio comprende un capo specifico dedicato alla famiglia: le risorse stanziate ammontano a <strong>600 milioni di euro<\/strong><\/em>\u201d.<\/p>\n","protected":false},"author":61,"featured_media":131650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,181],"tags":[],"class_list":["post-134457","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-speciale-inchiesta-espresso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente\" \/>\n<meta property=\"og:description\" content=\"Due giorni fa, il 15 ottobre, la Ministra con delega alle Pari Opportunit\u00e0, Maria Elena Boschi,\u00a0 ha twittato \u201cPer le pari opportunit\u00e0 60 milioni in bilancio. Contro la tratta di esseri umani, contro la violenza sulle donne #passodopopasso\u201d. Oggi, 17 ottobre, il ministro per gli Affari regionali e le Autonomie, con delega alla Famiglia, Enrico Costa, le fa eco dichiarando \u201cPer la prima volta la legge di bilancio comprende un capo specifico dedicato alla famiglia: le risorse stanziate ammontano a 600 milioni di euro\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-17T17:20:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-19T15:13:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente\",\"datePublished\":\"2016-10-17T17:20:43+00:00\",\"dateModified\":\"2016-10-19T15:13:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/\"},\"wordCount\":544,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/boschi-dellamonica.jpg\",\"articleSection\":[\"AiBiNews\",\"Speciale inchiesta Espresso Congo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/\",\"name\":\"I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/boschi-dellamonica.jpg\",\"datePublished\":\"2016-10-17T17:20:43+00:00\",\"dateModified\":\"2016-10-19T15:13:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/boschi-dellamonica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/boschi-dellamonica.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/","og_locale":"it_IT","og_type":"article","og_title":"I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente","og_description":"Due giorni fa, il 15 ottobre, la Ministra con delega alle Pari Opportunit\u00e0, Maria Elena Boschi,\u00a0 ha twittato \u201cPer le pari opportunit\u00e0 60 milioni in bilancio. Contro la tratta di esseri umani, contro la violenza sulle donne #passodopopasso\u201d. Oggi, 17 ottobre, il ministro per gli Affari regionali e le Autonomie, con delega alla Famiglia, Enrico Costa, le fa eco dichiarando \u201cPer la prima volta la legge di bilancio comprende un capo specifico dedicato alla famiglia: le risorse stanziate ammontano a 600 milioni di euro\u201d.","og_url":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-10-17T17:20:43+00:00","article_modified_time":"2016-10-19T15:13:23+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente","datePublished":"2016-10-17T17:20:43+00:00","dateModified":"2016-10-19T15:13:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/"},"wordCount":544,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica.jpg","articleSection":["AiBiNews","Speciale inchiesta Espresso Congo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/","url":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/","name":"I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica.jpg","datePublished":"2016-10-17T17:20:43+00:00","dateModified":"2016-10-19T15:13:23+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/boschi-dellamonica.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/i-bambini-abbandonati-non-valgono-niente-renzi-mette-la-parola-fine-alladozione-internazionale-zero-euro-in-legge-di-stabilita-cai-paralizzata-e-ministra-boschi-inesistente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"I bambini abbandonati non valgono niente. Renzi mette la parola fine all\u2019adozione internazionale? Zero euro in legge di Stabilit\u00e0, Cai paralizzata e Ministra Boschi inesistente"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:01:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/134457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=134457"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/134457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/131650"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=134457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=134457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=134457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}