﻿{"id":134873,"date":"2016-10-27T18:52:45","date_gmt":"2016-10-27T16:52:45","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=134873"},"modified":"2016-10-31T17:18:45","modified_gmt":"2016-10-31T16:18:45","slug":"il-caso-tulinabo-il-procuratore-della-repubblica-di-goma","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/","title":{"rendered":"Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-110024 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC.png\" alt=\"BAMBINO RDC\" width=\"400\" height=\"286\" data-id=\"110024\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC.png 400w, https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC-150x107.png 150w, https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC-300x215.png 300w, https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC-77x55.png 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>A smentire il fatto che Raymond Tulinabo sia stato arrestato e torturato nella prigione di Goma, secondo quanto scritto invece dal giornalista Fabrizio Gatti nella sua inchiesta pubblicata a luglio 2016 sul settimanale \u201cL\u2019Espresso\u201d, non \u00e8 solo il Presidente del Tribunale per i Minorenni della citt\u00e0 congolese Charles Wilfrid Sumaili Kanyongolo, la cui posizione \u00e8 stata presentata <a href=\"https:\/\/www.aibi.it\/ita\/tulinabo-non-e-mai-stato-incarcerato-invito-gatti-a-verificare\/\">nell\u2019articolo pubblicato da Aibinews il 25 ottobre<\/a>. Analoga, secca e sdegnata smentita arriva infatti dal Procuratore della Repubblica di Goma presso la Corte d\u2019Appello di Goma Daniel Saleh Katamea che, il 30 agosto 2016, ha inviato una lettera al direttore de \u201cL\u2019Espresso\u201d al fine di chiarire e ristabilire la verit\u00e0 dei fatti.<\/p>\n<p>Vediamo oggi quanto il Procuratore scrive a proposito proprio dei presunti arresto e\u00a0 torture perpetrate a Tulinabo.<\/p>\n<p>Ricordiamo che quest\u2019ultimo \u00e8 il rappresentante dell\u2019organizzazione congolese Mulirano pour combatre la pauvrete au Congo (Mucopc), a cui era stata affidata la tutela, tra gli altri di 4 minori con sentenze di adozione gi\u00e0 emesse a favore di altrettante famiglie italiane seguite, per le procedure adottive, da Amici dei Bambini e contemporaneamente assistiti attraverso una rete di famiglie locali facenti capo a Mucopc.<\/p>\n<p>&nbsp;<\/p>\n<p>Nella sua lettera del 30 agosto, il Procuratore della Repubblica di Goma ricorda ci\u00f2 che \u201cL\u2019Espresso\u201d scrisse su quanto sarebbe accaduto a Tulinabo, al momento del presunto arresto. All\u2019uomo sarebbe stato detto:<\/p>\n<p>&nbsp;<\/p>\n<p>\u201c<em>Lei ha deciso di collaborare con \u2018I Cinque Pani\u2019 diretti da una cosiddetta religiosa, riconosciuta come trafficante di bambini cos\u00ec come la vostra storia della CAI (Commissione Adozioni internazionali, ndr), altri trafficanti di bambini<\/em>\u2026\u201d. <em>Dopo un quarto d\u2019ora appare in ufficio il primo sostituto procuratore della Repubblica: <\/em>\u201c<em>Ecco qui uno di questi banditi che rapiscono i bambini a Goma per venderli in Europa\u201d gli dice il presidente Sumaili. \u201cTulinabo viene caricato su un\u2019auto. Lo portano in una camera di sicurezza. E dopo un giorno lo rinchiudono nel carcere centrale di Munzenze. La mattina dopo, verso le 9 del 3 giugno, il povero Raymond Tulinabo vede un\u00a0 agente del Tribunale dei minori intrattenersi con\u00a0 il vice capo dei sorveglianti. Quando l\u2019agente se ne va, \u00e8 il suo turno. Il comandante lo chiama e comincia il pestaggio. Le torture proseguono con il waterboarding, il trattamento riservato ai prigionieri di Guantanamo: solo qui immergono Tulinabo nella buca con gli escrementi della prigione. Poi gli ustionano i genitali. Lo torturano anche il mercoled\u00ec sera e anche il gioved\u00ec mattina<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>Come detto nel citato articolo del 25 ottobre, la vicepresidente (ed ex presidente) della Cai, nella sua audizione in\u00a0 commissione Giustizia della Camera del 12 ottobre, ha avvalorato quanto scritto da Gatti.<\/p>\n<p><strong>Ma i fatti descritti<\/strong> nell\u2019inchiesta de \u201cL\u2019Espresso\u201d sono stati invece <strong>definiti dal Procuratore <\/strong>della Repubblica di Goma come \u201c<strong>dichiarazioni false<\/strong>\u201d e nella sua lettera del 30 agosto dice:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Il suo atteggiamento instancabile di denigrare la Procura mi ha portato a giudicare che lei \u00e8 in malafede, o vittima di una mancanza di informazioni, o ignorante del diritto congolese. Se mi venisse richiesto di scegliere tra le tre ipotesi fatte quale sarebbe la pi\u00f9 adatta, preferirei consolarmi con l\u2019idea che\u00a0 sia per ignoranza della legge congolese che\u00a0 lei ha scritto ingiustamente e negativamente della Procura, anche se il deficit di informazione e la malafede possono validamente essere provate e usate contro di lei. Infatti, in qualit\u00e0 di \u201cgiornalista\u201d, doveva essere per lei un dovere primario trattare le informazioni con rigore e competenza, vale a dire, ottenere il massimo di informazioni, analizzarle, e poi entrare nel merito<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>Demolendo l\u2019articolo di Gatti, il Procuratore della Repubblica di Goma ricorre anche all\u2019ironia, in particolare nel passaggio in cui afferma:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Mi sembra che L\u2019Espresso o Raymond Tulinabo \u2013 dipende \u2013 amano dipingere le immagini con colori vividi, anche quando le regole dell\u2019arte non si prestano a ci\u00f2. Forse Raymond Tulinabo racconta questa storia perch\u00e9 si abbia piet\u00e0 della sua sorte. Purtroppo, i fatti che racconta e presenta fino al parossismo, non si sono mai prodotti come lui li racconta.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Senza mezzi termini, per far capire, anche a Gatti, che, con chi infrange le leggi, \u201canche in Repubblica Democratica del Congo\u201d, non si scherza, il Procuratore della Repubblica afferma:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Tuttavia vorrei rassicurare il direttore del giornale L\u2019Espresso che nei confronti del signor Raymond Tulinabo \u00e8 aperto un procedimento penale ancora in istruttoria presso la Procura di Grande Istanza. Questa azione nasce da una denuncia del Presidente del Tribunale dei Minori di Goma presentata in conformit\u00e0 alle leggi e ai regolamenti della Repubblica Democratica del Congo. <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Rispetto a questo procedimento, il Magistrato spiega che, con rifermento alla legge congolese, ha <em>\u201cdegli obblighi di riservatezza, stante che la procedura dell\u2019inchiesta e dell\u2019istruzione pre-giurisdizionale \u00e8 segreta\u201d<\/em>, smentendo quindi quanto affermato da Gatti, secondo cui <em>\u201cle false accuse\u201d<\/em> sarebbe state <em>\u201carchiviate\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Nel merito il Procuratore precisa che:<\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Tulinabo \u00e8 stato oggetto di un mandato di arresto provvisorio, in conformit\u00e0 con le leggi della Repubblica. Inoltre (\u2026) \u00e8 stato rilasciato entro 72 ore dalla sua detenzione, mentre l\u2019accusa ha l\u2019autorit\u00e0 legale per trattenerlo anche oltre tale periodo. Tulinabo non ha soggiornato nella prigione Munzenze come racconta L\u2019Espresso. Non \u00e8 mai stato n\u00e9 torturato n\u00e9 sottoposto a \u201cpseudo-trattamenti riservati ai prigionieri di Guantanamo\u201d, ai decorsi funesti e specifici che voi attribuite maliziosamente e a torto alla prigione centrale di Goma\u201d.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>Quindi il Procuratore esprime tutto il suo sdegno per le falsit\u00e0 scritte da Gatti:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Il carcere di Goma non \u00e8 nulla di simile. Se voi aveste verificato direttamente e aveste fatto indagini serie prima di pubblicare il vostro giornale, avreste potuto evitare a tante persone oneste e serie che vi leggono e credono in quello che scrivete, di leggere incongruenze come quelle che avete loro servito. Mi vergogno di ritornare sul dettaglio menzognero che L\u2019Espresso ha il coraggio di raccontare su quello che sarebbe successo a Raymond Tulinabo.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019unica cosa vera in tutto ci\u00f2 che ha scritto Gatti, a detta del Procuratore, \u00e8 <em>\u201csolo il fatto che Tulinabo \u00e8 stato detenuto preventivamente. Il fermo \u00e8 stato eseguito dal pubblico ministero. Non \u00e8 mai stato torturato\u201d.<\/em><\/p>\n<p>Pertanto il Procuratore della Repubblica conclude che il signor Raymond Tulinabo \u00e8 stato detenuto legalmente su denuncia regolarmente promossa contro di lui, e ci\u00f2 sulla base di un atto procedurale da parte del Procuratore della Repubblica. Non \u00e8 mai stato arbitrariamente arrestato e non \u00e8 mai stato detenuto nella prigione centrale di Munzenze di Goma.<\/p>\n<p>I fatti raccontati da Gatti\u00a0<em>\u201cnon hanno mai avuto luogo e non sono mai esistiti. Tutto ci\u00f2 rivela un orientamento pernicioso degli informatori e del giornale. Ci\u00f2 \u00e8 segno di un\u2019affabulazione pericolosa e criminale\u201d.<\/em><\/p>\n<p>Fatti viceversa avvalorati da Silvia Della Monica in sede istituzionale. Ma le menzogne raccontate da Gatti non si fermano qui e il Procuratore della Repubblica di Goma le ha passate in rassegna una per una.<\/p>\n<p>&nbsp;<\/p>\n<p>(6\/continua\u2026)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A smentire il fatto che Raymond Tulinabo sia stato arrestato e torturato nella prigione di Goma, secondo quanto scritto invece dal giornalista Fabrizio Gatti nella sua inchiesta pubblicata a luglio 2016 sul settimanale \u201cL\u2019Espresso\u201d, non \u00e8 solo il Presidente del Tribunale per i Minorenni della citt\u00e0 congolese Charles Wilfrid Sumaili Kanyongolo, la cui posizione \u00e8 stata presentata <a href=\"https:\/\/www.aibi.it\/ita\/tulinabo-non-e-mai-stato-incarcerato-invito-gatti-a-verificare\/\">nell\u2019articolo pubblicato da Aibinews il 25 ottobre<\/a>.<\/p>\n","protected":false},"author":61,"featured_media":110024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,181],"tags":[],"class_list":["post-134873","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-speciale-inchiesta-espresso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d\" \/>\n<meta property=\"og:description\" content=\"A smentire il fatto che Raymond Tulinabo sia stato arrestato e torturato nella prigione di Goma, secondo quanto scritto invece dal giornalista Fabrizio Gatti nella sua inchiesta pubblicata a luglio 2016 sul settimanale \u201cL\u2019Espresso\u201d, non \u00e8 solo il Presidente del Tribunale per i Minorenni della citt\u00e0 congolese Charles Wilfrid Sumaili Kanyongolo, la cui posizione \u00e8 stata presentata nell\u2019articolo pubblicato da Aibinews il 25 ottobre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-27T16:52:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-31T16:18:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d\",\"datePublished\":\"2016-10-27T16:52:45+00:00\",\"dateModified\":\"2016-10-31T16:18:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/\"},\"wordCount\":1149,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/BAMBINO-RDC.png\",\"articleSection\":[\"AiBiNews\",\"Speciale inchiesta Espresso Congo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/\",\"name\":\"Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/BAMBINO-RDC.png\",\"datePublished\":\"2016-10-27T16:52:45+00:00\",\"dateModified\":\"2016-10-31T16:18:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/BAMBINO-RDC.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/BAMBINO-RDC.png\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/","og_locale":"it_IT","og_type":"article","og_title":"Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d","og_description":"A smentire il fatto che Raymond Tulinabo sia stato arrestato e torturato nella prigione di Goma, secondo quanto scritto invece dal giornalista Fabrizio Gatti nella sua inchiesta pubblicata a luglio 2016 sul settimanale \u201cL\u2019Espresso\u201d, non \u00e8 solo il Presidente del Tribunale per i Minorenni della citt\u00e0 congolese Charles Wilfrid Sumaili Kanyongolo, la cui posizione \u00e8 stata presentata nell\u2019articolo pubblicato da Aibinews il 25 ottobre.","og_url":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-10-27T16:52:45+00:00","article_modified_time":"2016-10-31T16:18:45+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC.png","type":"image\/png"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d","datePublished":"2016-10-27T16:52:45+00:00","dateModified":"2016-10-31T16:18:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/"},"wordCount":1149,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC.png","articleSection":["AiBiNews","Speciale inchiesta Espresso Congo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/","url":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/","name":"Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC.png","datePublished":"2016-10-27T16:52:45+00:00","dateModified":"2016-10-31T16:18:45+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/BAMBINO-RDC.png","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/il-caso-tulinabo-il-procuratore-della-repubblica-di-goma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Il caso Tulinabo. Il Procuratore della Repubblica di Goma: \u201cImpugno come false le dichiarazioni menzognere di Gatti veicolate a difesa di imputati perseguiti penalmente davanti alla Procura\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:06:55","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/134873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=134873"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/134873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/110024"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=134873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=134873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=134873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}