﻿


{"id":135202,"date":"2016-11-08T15:46:12","date_gmt":"2016-11-08T14:46:12","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=135202"},"modified":"2016-11-10T16:32:06","modified_gmt":"2016-11-10T15:32:06","slug":"siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/","title":{"rendered":"Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni"},"content":{"rendered":"<p><strong> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-135228 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/siria-08-nov.jpg\" alt=\"siria-08-nov\" width=\"400\" height=\"286\" data-id=\"135228\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/siria-08-nov.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/siria-08-nov-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/siria-08-nov-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/siria-08-nov-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Mentre si combatte ancora ad Aleppo, <\/strong>(come documenta la rete siriana per i diritti umani, il quartiere di Salah al Din \u00e8 stato colpito dalle bombe sganciate nelle ultime ore)<strong> non si ferma la distribuzione di ceste alimentari da parte di<\/strong> <strong>Ai.Bi.<\/strong><\/p>\n<p>Amici dei Bambini con il partner locale <strong>Shafak,<\/strong> non perde tempo e dopo il successo delle precedenti distribuzioni di viveri, \u00e8 gi\u00e0 sulla strada <strong>per sfamare tante altre famiglie e bambini in difficolt\u00e0 e sfollati interni.<\/strong><\/p>\n<p>Gli operatori locali raggiungeranno <strong>280 famiglie<\/strong> (1.680 persone circa) a cui garantiranno <strong>5 distribuzioni di ceste alimentari mensili <\/strong>nella regione di <strong>Aleppo<\/strong>; e ancora <strong>262 famiglie<\/strong> (1572 individui circa) riceveranno voucher mensili nella regione <strong>di Idleb<\/strong>.<\/p>\n<p>Ecco cosa conterr\u00e0 ogni cesta: 1.650 kcal- <strong>lenticchi<\/strong>e curde grezze (4 kg), lenticchie curde rosse (4 kg), <strong>olio<\/strong> d\u2019oliva (2 litri), olio di semi (3 litri), <strong>zucchero <\/strong>(5 kg), <strong>sal<\/strong>e (1 kg), <strong>marmellata <\/strong>(2 kg), <strong>datteri <\/strong>(3kg), <strong>bulghur<\/strong> (10 kg), <strong>tonno <\/strong>in olio d\u2019oliva (15 scatole da 198 g), <strong>mortadella <\/strong>di manzo (15 scatole da 234 g), <strong>riso<\/strong> (10 kg), concentrato di <strong>pomodoro<\/strong> (1 kg), <strong>margarina<\/strong> (1 kg), <strong>ceci<\/strong> secchi (5 kg), <strong>fagioli <\/strong>rossi (4 kg), <strong>formaggio<\/strong> in scatola (1 confezione da 48 pezzi), <strong>fave <\/strong>(5 kg) e <strong>halva<\/strong> (2kg).<\/p>\n<p>Il valore del voucher sar\u00e0 pari a 82 USD (dollari statunitensi) a famiglia <strong>con i quali potranno comprare beni alimentari di prima necessit\u00e0<\/strong> (gli stessi elencati sopra) in maniera indipendente e autonoma <strong>presso attivit\u00e0 commerciali locali legate ai partner locali tramite contratti di fornitura<\/strong>. Il vantaggio della distribuzione di voucher \u00e8 legato <strong>alla stimolazione della resilienza<\/strong> e <strong>al ridare dignit\u00e0 alle famiglie<\/strong> che hanno maggiore indipendenza e libert\u00e0 di scelta potendosi recare autonomamente ai negozi per il riscatto dei beni alimentari pi\u00f9 desiderati.<\/p>\n<p>Se vuoi sostenere anche tu le attivit\u00e0 di <a href=\"https:\/\/www.aibi.it\/bam\/\">Ai.Bi in Siria<\/a>, visita la nostra pagina e scopri come puoi farlo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Mentre si combatte ancora ad Aleppo, <\/strong>(come documenta la rete siriana per i diritti umani, il quartiere di Salah al Din \u00e8 stato colpito dalle bombe sganciate nelle ultime ore)<strong> non si ferma la distribuzione di ceste alimentari da parte di<\/strong> <strong>Ai.Bi.\u00a0<\/strong>con il partner locale <strong>Shafak,<\/strong> non perde tempo e dopo il successo delle precedenti distribuzioni di viveri, \u00e8 gi\u00e0 sulla strada <strong>per sfamare tante altre famiglie e bambini in difficolt\u00e0 e sfollati interni.\u00a0<\/strong><\/p>\n","protected":false},"author":61,"featured_media":135228,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114],"tags":[],"class_list":["post-135202","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-bambini-in-alto-mare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni\" \/>\n<meta property=\"og:description\" content=\"Mentre si combatte ancora ad Aleppo, (come documenta la rete siriana per i diritti umani, il quartiere di Salah al Din \u00e8 stato colpito dalle bombe sganciate nelle ultime ore) non si ferma la distribuzione di ceste alimentari da parte di Ai.Bi.\u00a0con il partner locale Shafak, non perde tempo e dopo il successo delle precedenti distribuzioni di viveri, \u00e8 gi\u00e0 sulla strada per sfamare tante altre famiglie e bambini in difficolt\u00e0 e sfollati interni.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-08T14:46:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-10T15:32:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/siria-08-nov.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni\",\"datePublished\":\"2016-11-08T14:46:12+00:00\",\"dateModified\":\"2016-11-10T15:32:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/\"},\"wordCount\":305,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/siria-08-nov.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/\",\"name\":\"Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/siria-08-nov.jpg\",\"datePublished\":\"2016-11-08T14:46:12+00:00\",\"dateModified\":\"2016-11-10T15:32:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/siria-08-nov.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/siria-08-nov.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/","og_locale":"it_IT","og_type":"article","og_title":"Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni","og_description":"Mentre si combatte ancora ad Aleppo, (come documenta la rete siriana per i diritti umani, il quartiere di Salah al Din \u00e8 stato colpito dalle bombe sganciate nelle ultime ore) non si ferma la distribuzione di ceste alimentari da parte di Ai.Bi.\u00a0con il partner locale Shafak, non perde tempo e dopo il successo delle precedenti distribuzioni di viveri, \u00e8 gi\u00e0 sulla strada per sfamare tante altre famiglie e bambini in difficolt\u00e0 e sfollati interni.\u00a0","og_url":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-11-08T14:46:12+00:00","article_modified_time":"2016-11-10T15:32:06+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/siria-08-nov.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni","datePublished":"2016-11-08T14:46:12+00:00","dateModified":"2016-11-10T15:32:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/"},"wordCount":305,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/siria-08-nov.jpg","articleSection":["AiBiNews","Bambini in alto mare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/","url":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/","name":"Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/siria-08-nov.jpg","datePublished":"2016-11-08T14:46:12+00:00","dateModified":"2016-11-10T15:32:06+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/siria-08-nov.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/siria-08-nov.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/siria-ai-bi-avvia-un-nuovo-progetto-distribuzione-di-ceste-alimentari-e-di-voucher-mensili-ad-aleppo-e-idleb-per-oltre-3-mila-sfollati-interni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Siria. Ai.Bi avvia un nuovo progetto: distribuzione di ceste alimentari e di voucher mensili ad Aleppo e Idleb per oltre 3 mila sfollati interni"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:59:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/135202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=135202"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/135202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/135228"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=135202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=135202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=135202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}