﻿


{"id":135537,"date":"2016-11-17T16:01:03","date_gmt":"2016-11-17T15:01:03","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=135537"},"modified":"2016-11-17T16:01:03","modified_gmt":"2016-11-17T15:01:03","slug":"roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/","title":{"rendered":"Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-135538 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano.png\" alt=\"primaria-roe-volciano\" width=\"634\" height=\"406\" data-id=\"135538\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano.png 634w, https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano-150x96.png 150w, https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano-300x192.png 300w, https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano-86x55.png 86w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Ecco i nuovi amici a distanza dei bambini del Sancare Preparatory School di Nairobi, dove Ai.Bi. \u00e8 presente con uno dei suoi tanti progetti di<strong><em><a href=\"https:\/\/www.aibi.it\/sostegnoadistanza\/kenya\/\"> Sostegno a Distanza<\/a><\/em><\/strong>: sono gli alunni della scuola primaria di Ro\u00e8 Volciano (Bs) che, da sabato 12 novembre, sono gemellati con quelli del Sancare. Il gemellaggio \u00e8 stato sancito <strong><em><a href=\"https:\/\/www.youtube.com\/watch?v=6AF93hHpVIA&amp;feature=youtu.be\">con la proiezione di un video<\/a><\/em><\/strong> in cui i bambini kenyoti hanno presentato s\u00e9 stessi e la loro scuola. L\u2019iniziativa \u00e8 stata illustrata in serata anche nel corso del tradizionale appuntamento con \u201cLo Spiedo\u201d organizzato dalle famiglie Ai.Bi. della Valsabbia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ecco i nuovi amici a distanza dei bambini del Sancare Preparatory School di Nairobi, dove Ai.Bi. \u00e8 presente con uno dei suoi tanti progetti di<strong><em><a href=\"https:\/\/www.aibi.it\/sostegnoadistanza\/kenya\/\"> Sostegno a Distanza<\/a><\/em><\/strong>: sono gli alunni della scuola primaria di Ro\u00e8 Volciano (Bs) che, da sabato 12 novembre, sono gemellati con quelli del Sancare. Il gemellaggio \u00e8 stato sancito <strong><em><a href=\"https:\/\/www.youtube.com\/watch?v=6AF93hHpVIA&amp;feature=youtu.be\">con la proiezione di un video<\/a><\/em><\/strong> in cui i bambini kenyoti hanno presentato s\u00e9 stessi e la loro scuola. L\u2019iniziativa \u00e8 stata illustrata in serata anche nel corso del tradizionale appuntamento con \u201cLo Spiedo\u201d organizzato dalle famiglie Ai.Bi. della Valsabbia.<\/p>\n","protected":false},"author":61,"featured_media":135538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-135537","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine\" \/>\n<meta property=\"og:description\" content=\"Ecco i nuovi amici a distanza dei bambini del Sancare Preparatory School di Nairobi, dove Ai.Bi. \u00e8 presente con uno dei suoi tanti progetti di Sostegno a Distanza: sono gli alunni della scuola primaria di Ro\u00e8 Volciano (Bs) che, da sabato 12 novembre, sono gemellati con quelli del Sancare. Il gemellaggio \u00e8 stato sancito con la proiezione di un video in cui i bambini kenyoti hanno presentato s\u00e9 stessi e la loro scuola. L\u2019iniziativa \u00e8 stata illustrata in serata anche nel corso del tradizionale appuntamento con \u201cLo Spiedo\u201d organizzato dalle famiglie Ai.Bi. della Valsabbia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-17T15:01:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano.png\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine\",\"datePublished\":\"2016-11-17T15:01:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/\"},\"wordCount\":123,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/primaria-ro\u00e8-volciano.png\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/\",\"name\":\"Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/primaria-ro\u00e8-volciano.png\",\"datePublished\":\"2016-11-17T15:01:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/primaria-ro\u00e8-volciano.png\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/primaria-ro\u00e8-volciano.png\",\"width\":634,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/","og_locale":"it_IT","og_type":"article","og_title":"Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine","og_description":"Ecco i nuovi amici a distanza dei bambini del Sancare Preparatory School di Nairobi, dove Ai.Bi. \u00e8 presente con uno dei suoi tanti progetti di Sostegno a Distanza: sono gli alunni della scuola primaria di Ro\u00e8 Volciano (Bs) che, da sabato 12 novembre, sono gemellati con quelli del Sancare. Il gemellaggio \u00e8 stato sancito con la proiezione di un video in cui i bambini kenyoti hanno presentato s\u00e9 stessi e la loro scuola. L\u2019iniziativa \u00e8 stata illustrata in serata anche nel corso del tradizionale appuntamento con \u201cLo Spiedo\u201d organizzato dalle famiglie Ai.Bi. della Valsabbia.","og_url":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-11-17T15:01:03+00:00","og_image":[{"width":634,"height":406,"url":"https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano.png","type":"image\/png"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine","datePublished":"2016-11-17T15:01:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/"},"wordCount":123,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano.png","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/","url":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/","name":"Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano.png","datePublished":"2016-11-17T15:01:03+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano.png","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/primaria-ro\u00e8-volciano.png","width":634,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/roe-volciano-bs-con-lamicizia-a-distanza-la-valsabbia-e-nairob\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Ro\u00e8 Volciano (Bs), con l\u2019amicizia a distanza la Valsabbia e Nairobi sono sempre pi\u00f9 vicine"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:56:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/135537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=135537"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/135537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/135538"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=135537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=135537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=135537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}