﻿


{"id":136106,"date":"2016-12-06T18:49:37","date_gmt":"2016-12-06T17:49:37","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=136106"},"modified":"2016-12-12T16:52:31","modified_gmt":"2016-12-12T15:52:31","slug":"milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/","title":{"rendered":"Milano. Grande successo al \u201cBello che fa bene 2016&#8243;. Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-136124 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news.jpg\" alt=\"aibi-bb-30-anni-torta-news\" width=\"400\" height=\"286\" data-id=\"136124\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>\u201c<strong>La bellezza salver\u00e0 il mondo<\/strong>\u201d dice il principe Mi\u0161kin ne \u201cL&#8217;idiota\u201d di <strong>Dostoevskij<\/strong>. E prima dello scrittore russo. i filosofi antichi hanno insegnato che ogni essere, per differente che sia, \u00e8 \u201c<strong>unum, verum et bonum\u201d<\/strong>, per continuare con San Bonaventura che aggiunge all\u2019uomo un\u2019altra caratteristica: <strong>pulchrum, cio\u00e8 bello<\/strong>. Fino a <strong>Papa Francesco<\/strong> che ha dato speciale importanza alla trasmissione della fede cristiana attraverso la \u201cvia Pulchritudinis\u201d: dove <strong>non basta che il messaggio sia buono e giusto. \u201cDeve essere anche bello<\/strong>, perch\u00e9 solo cos\u00ec arriva <strong>al cuore delle persone e suscita l\u2019amore che attrae\u201d<\/strong> (Esortazione La gioia del Vangelo, n.\u00b0167).<\/p>\n<p>Insomma un \u201c<strong>Bello che fa del bene<\/strong>\u201d, non a caso proprio il leitmotiv della tradizionale <strong>Cena di gala natalizia<\/strong> \u201c<strong>Il Bello che fa Bene<\/strong>\u201d che <strong>Amici dei Bambini<\/strong> organizza ogni anno a dicembre e che quest\u2019anno ha avuto un valore affettivo ulteriore: <strong>i primi 30 anni di vita di Ai.Bi<\/strong>.<\/p>\n[nggallery id=71]\n<p>Trent\u2019anni nel corso dei quali giorno dopo giorno l\u2019associazione, costituita da un movimento di famiglie adottive e affidatarie, \u00e8 sempre stata <strong>fedele alla sua mission<\/strong>: <strong>prevenire e salvare i bambini dall\u2019abbandono<\/strong> e <strong>trovare loro una casa con una mamma e un pap\u00e0<\/strong> in grado di dare loro una chance di vita.<\/p>\n<p><strong>Un \u201ccompleanno\u201d speciale<\/strong> che ieri sera, 05 dicembre, <strong>in oltre 300 tra grandi aziende, testimonial e amici affezionati di Ai.Bi<\/strong> \u00e8 stato festeggiato <strong>con grande successo<\/strong>.<\/p>\n<p>Una <strong>vera e propria festa<\/strong> che si \u00e8 svolta nella splendida cornice della <strong>sala delle Colonne del Museo nazionale della Scienza e della Tecnologia \u201cLeonardo Da Vinci\u201d<\/strong> e che ha avuto come primario tema <strong><em>\u201cIl diritto di essere figlio\u201d<\/em><\/strong> . Nel corso dell\u2019evento di solidariet\u00e0 \u00e8 stato, infatti, raccontato <strong>quanto Amici dei Bambini ha fatto fino ad oggi e i traguardi ancora da raggiungere<\/strong>.<\/p>\n<p>In 30 anni: <strong>3230 bambini sono stati adottati; 60.000 sono le adozioni a distanza<\/strong>; sono stati avviati <strong>progetti di cooperazione in 31 Paesi<\/strong> e aperte <strong>18 strutture di accoglienza<\/strong> in <strong>Italia; 156 minori sono stati dati in affido<\/strong> o accolti in Casa famiglia; <strong>52 mamme fragili e in difficolt\u00e0 <\/strong>sono state accolte insieme ai loro figli nelle Comunit\u00e0 Mamma-bambino; <strong>112 i minori accolti in Case per adolescenti e 46 famiglie migranti<\/strong> hanno trovato un tetto nelle Case di prima accoglienza.<\/p>\n<p><strong>Ma non \u00e8 ancora abbastanza. <\/strong>Per questo Ai.Bi si \u00e8 fissata <strong>altre sfide da vincere<\/strong>: perch\u00e9 finch\u00e9 nel mondo ci sar\u00e0 anche <strong>solo un bambino abbandonato, Ai.Bi non smetter\u00e0 di lottare.\u00a0<\/strong>Uno scopo che tutti i presenti hanno condiviso e <strong>incoraggiato rinnovando il proprio sostegno all\u2019associazione di Melegnano <\/strong>presente in oltre 30 Paesi nel mondo.<\/p>\n<p>Come ogni anno, anche ieri sera, gli oltre 300 intervenuti hanno preso parte ai due momenti top dell\u2019evento di solidariet\u00e0<strong>: il cocktail di benvenuto<\/strong> con esposizione di <strong>oggetti di lusso e design donati <\/strong>dalle pi\u00f9 grandi e famose aziende e <strong>la cena di gala con l\u2019asta di solidariet\u00e0<\/strong>.<\/p>\n<p>Entrambi i momenti sono stati accompagnati da <strong>piatti di altissima cucina<\/strong>\u2026da vero <strong>masterchef <\/strong>che ha letteralmente incantato i presenti.<\/p>\n<p>E cos\u00ec tra <strong>risultati raggiunti e prossime sfide<\/strong> che Ai.Bi con <strong>rinnovato e sempre pi\u00f9 convinto entusiasmo<\/strong> porter\u00e0 avanti, si \u00e8 conclusa la 15\/ma edizione del \u201c<strong>Bello che fa bene\u201d<\/strong> dando appuntamento alla prossima edizione. <strong>Perch\u00e9 L\u2019abbandono minorile \u00e8 la quarta emergenza umanitaria del XXI secolo: <\/strong>di fame si muore e si vede di malattia si muore e si vede in guerra si muore e si vede.<strong> Di abbandono si muore dentro e non si vede.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201c<strong>La bellezza salver\u00e0 il mondo<\/strong>\u201d dice il principe Mi\u0161kin ne \u201cL&#8217;idiota\u201d di <strong>Dostoevskij<\/strong>. E, aggiungiamo noi, soprattutto quando il bello fa anche del bene. Insomma un\u00a0\u201c<strong>Bello che fa del bene<\/strong>\u201d, non a caso \u00a0il leitmotiv della tradizionale <strong>Cena di gala natalizia<\/strong> \u201c<strong>Il Bello che Bene<\/strong>\u201d che <strong>Amici dei Bambini<\/strong> organizza ogni anno a dicembre e che quest\u2019anno ha avuto un valore affettivo ulteriore: <strong>i primi 30 anni di vita di Ai.Bi<\/strong>. Trent\u2019anni nel corso dei quali giorno dopo giorno l\u2019associazione costituita da un movimento di famiglie adottive e affidatarie, \u00e8 sempre stata <strong>fedele alla sua mission<\/strong>: <strong>prevenire e salvare i bambini dall\u2019abbandono<\/strong> e <strong>trovare loro una casa con una mamma e un pap\u00e0<\/strong> in grado di dare loro una chance di vita.\u00a0<strong>Un \u201ccompleanno\u201d speciale<\/strong> che ieri sera, 05 dicembre, <strong>in oltre 300 tra grandi aziende, testimonial e amici affezionati di Ai.Bi<\/strong> \u00e8 stato festeggiato <strong>con grande successo<\/strong>.<\/p>\n","protected":false},"author":61,"featured_media":136124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-136106","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Milano. Grande successo al \u201cBello che fa bene 2016&quot;. Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milano. Grande successo al \u201cBello che fa bene 2016&quot;. Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala\" \/>\n<meta property=\"og:description\" content=\"\u201cLa bellezza salver\u00e0 il mondo\u201d dice il principe Mi\u0161kin ne \u201cL&#039;idiota\u201d di Dostoevskij. E, aggiungiamo noi, soprattutto quando il bello fa anche del bene. Insomma un\u00a0\u201cBello che fa del bene\u201d, non a caso \u00a0il leitmotiv della tradizionale Cena di gala natalizia \u201cIl Bello che Bene\u201d che Amici dei Bambini organizza ogni anno a dicembre e che quest\u2019anno ha avuto un valore affettivo ulteriore: i primi 30 anni di vita di Ai.Bi. Trent\u2019anni nel corso dei quali giorno dopo giorno l\u2019associazione costituita da un movimento di famiglie adottive e affidatarie, \u00e8 sempre stata fedele alla sua mission: prevenire e salvare i bambini dall\u2019abbandono e trovare loro una casa con una mamma e un pap\u00e0 in grado di dare loro una chance di vita.\u00a0Un \u201ccompleanno\u201d speciale che ieri sera, 05 dicembre, in oltre 300 tra grandi aziende, testimonial e amici affezionati di Ai.Bi \u00e8 stato festeggiato con grande successo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-06T17:49:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-12T15:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Milano. Grande successo al \u201cBello che fa bene 2016&#8243;. Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala\",\"datePublished\":\"2016-12-06T17:49:37+00:00\",\"dateModified\":\"2016-12-12T15:52:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/\"},\"wordCount\":595,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-bb-30-anni-torta-news.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/\",\"name\":\"Milano. Grande successo al \u201cBello che fa bene 2016\\\". Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-bb-30-anni-torta-news.jpg\",\"datePublished\":\"2016-12-06T17:49:37+00:00\",\"dateModified\":\"2016-12-12T15:52:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-bb-30-anni-torta-news.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aibi-bb-30-anni-torta-news.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Milano. Grande successo al \u201cBello che fa bene 2016&#8243;. Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Milano. Grande successo al \u201cBello che fa bene 2016\". Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/","og_locale":"it_IT","og_type":"article","og_title":"Milano. Grande successo al \u201cBello che fa bene 2016\". Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala","og_description":"\u201cLa bellezza salver\u00e0 il mondo\u201d dice il principe Mi\u0161kin ne \u201cL'idiota\u201d di Dostoevskij. E, aggiungiamo noi, soprattutto quando il bello fa anche del bene. Insomma un\u00a0\u201cBello che fa del bene\u201d, non a caso \u00a0il leitmotiv della tradizionale Cena di gala natalizia \u201cIl Bello che Bene\u201d che Amici dei Bambini organizza ogni anno a dicembre e che quest\u2019anno ha avuto un valore affettivo ulteriore: i primi 30 anni di vita di Ai.Bi. Trent\u2019anni nel corso dei quali giorno dopo giorno l\u2019associazione costituita da un movimento di famiglie adottive e affidatarie, \u00e8 sempre stata fedele alla sua mission: prevenire e salvare i bambini dall\u2019abbandono e trovare loro una casa con una mamma e un pap\u00e0 in grado di dare loro una chance di vita.\u00a0Un \u201ccompleanno\u201d speciale che ieri sera, 05 dicembre, in oltre 300 tra grandi aziende, testimonial e amici affezionati di Ai.Bi \u00e8 stato festeggiato con grande successo.","og_url":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-12-06T17:49:37+00:00","article_modified_time":"2016-12-12T15:52:31+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Milano. Grande successo al \u201cBello che fa bene 2016&#8243;. Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala","datePublished":"2016-12-06T17:49:37+00:00","dateModified":"2016-12-12T15:52:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/"},"wordCount":595,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/","url":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/","name":"Milano. Grande successo al \u201cBello che fa bene 2016\". Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news.jpg","datePublished":"2016-12-06T17:49:37+00:00","dateModified":"2016-12-12T15:52:31+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/aibi-bb-30-anni-torta-news.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/milano-grande-successo-al-bello-che-fa-bene-2016-ai-bi-festeggia-i-suoi-30-anni-al-servizio-dei-bambini-abbandonati-leonardo-da-vinci-stupisce-i-300-ospiti-alla-cena-di-gala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Milano. Grande successo al \u201cBello che fa bene 2016&#8243;. Ai.Bi festeggia i suoi 30 anni al servizio dei bambini abbandonati. Leonardo Da Vinci stupisce i 300 ospiti alla Cena di gala"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:56:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/136106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=136106"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/136106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/136124"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=136106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=136106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=136106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}