﻿


{"id":136462,"date":"2016-12-19T14:23:50","date_gmt":"2016-12-19T13:23:50","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=136462"},"modified":"2016-12-19T14:23:50","modified_gmt":"2016-12-19T13:23:50","slug":"lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/","title":{"rendered":"Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-136463 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016.jpg\" alt=\"pranzo-di-natale-lecce-2016\" width=\"634\" height=\"406\" data-id=\"136463\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016.jpg 634w, https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016-150x96.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016-300x192.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016-86x55.jpg 86w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Grande successo per la festa di Natale organizzata da Ai.Bi. a Lecce il 18 dicembre: oltre 40 tra genitori e figli adottivi del Salento hanno animato una giornata iniziata con la Santa Messa, celebrata da don Gerardo Ippolito, e proseguita con il pranzo comunitario e la \u201criffa\u201d di beneficenza a sostegno delle attivit\u00e0 di Ai.Bi. in Puglia, resa possibile dagli imprenditori e sostenitori locali che hanno offerto tanti ricchi premi. Per l\u2019occasione sono giunti da Barletta anche i coordinatori regionali e la referente di Ai.Bi. Puglia, Lisia e Antonio Gorgoglione e Floriana Canfora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande successo per la festa di Natale organizzata da Ai.Bi. a Lecce il 18 dicembre: oltre 40 tra genitori e figli adottivi del Salento hanno animato una giornata iniziata con la Santa Messa, celebrata da don Gerardo Ippolito, e proseguita con il pranzo comunitario e la \u201criffa\u201d di beneficenza a sostegno delle attivit\u00e0 di Ai.Bi. in Puglia, resa possibile dagli imprenditori e sostenitori locali che hanno offerto tanti ricchi premi. Per l\u2019occasione sono giunti da Barletta anche i coordinatori regionali e la referente di Ai.Bi. Puglia, Lisia e Antonio Gorgoglione e Floriana Canfora.<\/p>\n","protected":false},"author":61,"featured_media":136463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-136462","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza\" \/>\n<meta property=\"og:description\" content=\"Grande successo per la festa di Natale organizzata da Ai.Bi. a Lecce il 18 dicembre: oltre 40 tra genitori e figli adottivi del Salento hanno animato una giornata iniziata con la Santa Messa, celebrata da don Gerardo Ippolito, e proseguita con il pranzo comunitario e la \u201criffa\u201d di beneficenza a sostegno delle attivit\u00e0 di Ai.Bi. in Puglia, resa possibile dagli imprenditori e sostenitori locali che hanno offerto tanti ricchi premi. Per l\u2019occasione sono giunti da Barletta anche i coordinatori regionali e la referente di Ai.Bi. Puglia, Lisia e Antonio Gorgoglione e Floriana Canfora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-19T13:23:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza\",\"datePublished\":\"2016-12-19T13:23:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/\"},\"wordCount\":121,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/pranzo-di-natale-lecce-2016.jpg\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/\",\"name\":\"Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/pranzo-di-natale-lecce-2016.jpg\",\"datePublished\":\"2016-12-19T13:23:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/pranzo-di-natale-lecce-2016.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/pranzo-di-natale-lecce-2016.jpg\",\"width\":634,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/","og_locale":"it_IT","og_type":"article","og_title":"Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza","og_description":"Grande successo per la festa di Natale organizzata da Ai.Bi. a Lecce il 18 dicembre: oltre 40 tra genitori e figli adottivi del Salento hanno animato una giornata iniziata con la Santa Messa, celebrata da don Gerardo Ippolito, e proseguita con il pranzo comunitario e la \u201criffa\u201d di beneficenza a sostegno delle attivit\u00e0 di Ai.Bi. in Puglia, resa possibile dagli imprenditori e sostenitori locali che hanno offerto tanti ricchi premi. Per l\u2019occasione sono giunti da Barletta anche i coordinatori regionali e la referente di Ai.Bi. Puglia, Lisia e Antonio Gorgoglione e Floriana Canfora.","og_url":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2016-12-19T13:23:50+00:00","og_image":[{"width":634,"height":406,"url":"https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza","datePublished":"2016-12-19T13:23:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/"},"wordCount":121,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016.jpg","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/","url":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/","name":"Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016.jpg","datePublished":"2016-12-19T13:23:50+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/pranzo-di-natale-lecce-2016.jpg","width":634,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/lecce-genitori-e-figli-adottivi-di-ai-bi-in-festa-per-il-natale-dellaccoglienza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"Lecce, genitori e figli adottivi di Ai.Bi. in festa per il Natale dell\u2019accoglienza"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:57:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/136462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=136462"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/136462\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/136463"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=136462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=136462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=136462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}