﻿


{"id":138249,"date":"2017-02-08T18:13:12","date_gmt":"2017-02-08T17:13:12","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=138249"},"modified":"2017-02-10T17:46:22","modified_gmt":"2017-02-10T16:46:22","slug":"emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/","title":{"rendered":"Emergenza aborti. Sberna\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l&#8217; \u2018adozione in pancia\u2019 degli USA"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-100730 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/aborto3.jpg\" alt=\"aborto\" width=\"400\" height=\"286\" data-id=\"100730\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/aborto3.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/aborto3-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/aborto3-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/aborto3-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>&#8220;Sono c<em>irca <strong>200 mila i bambini abortiti nell&#8217;arco di due anni<\/strong>. E&#8217; come se la popolazione di un&#8217;intera citt\u00e0 come Brescia non fosse mai venuta alla luce. <strong>Che altro aspettiamo per consentire alla vita di sorgere?<\/strong><\/em>&#8220;. Lo ha detto il deputato <strong>Mario Sberna <\/strong>(gruppo parlamentare &#8216;Democrazia Solidale-Centro Democratico&#8217;) presentando oggi, 08 febbraio, con il deputato Gian Luigi Gigli in conferenza stampa alla Camera <strong><a href=\"http:\/\/www.camera.it\/_dati\/leg17\/lavori\/stampati\/pdf\/17PDL0048720.pdf\">la proposta di legge<\/a> per consentire l&#8217;adozione del concepito<\/strong>, prevedendo <strong>l&#8217;obbligatoriet\u00e0 per medici e consultori di informare la gestante <\/strong>e il pap\u00e0 della possibilit\u00e0 di usufruire di questa alternativa.<\/p>\n<p>&#8220;<em>Alle mamme che non desiderano il figlio concepito<\/em> \u2013 ha spiegato Sberna &#8211; <em>viene offerta <strong>la possibilit\u00e0 di compiere un gesto d&#8217;amore<\/strong>, <strong>donandolo a chi quel figlio vorrebbe averlo ma non pu\u00f2.<\/strong> L&#8217;adozione del concepito \u00e8 un atto d&#8217;amore per gli altri, ma anche per s\u00e9 stessi: l&#8217;aborto \u00e8 una tragedia che ogni donna porta con s\u00e9 per tutta la vita<\/em>&#8220;.<\/p>\n<p><strong>Ovvero l\u2019adozione come alternativa all\u2019interruzione di gravidanza.<\/strong> \u201c<em>I consultori hanno l\u2019obbligo di informare la donna in stato di gravidanza<\/em> \u2013 ha continuato \u2013 <em>che esistono <strong>misure alternative all\u2019Interruzione volontaria di gravidanza<\/strong><\/em>\u201d.<\/p>\n<p>Inoltre secondo l\u2019Iss (Istituto superiore di sanit\u00e0), il numero di <strong>aborti clandestini per le donne italiane va dai 12 ai 15mila casi<\/strong>. Mentre per quanto riguarda le donne straniere, la stima \u00e8 tra i 3 e i 5mila aborti clandestini.<\/p>\n<p>\u201c<em>Numeri importanti nei confronti dei quali si deve trovare una soluzione <\/em>\u2013 ha precisato Sberna<em> -. Questa potrebbe essere <strong>l\u2019 \u2018adozione in pancia\u2019<\/strong><\/em><strong>:<\/strong> <em>un modo per conciliare<\/em> <em>l\u2019elevato numero di concepiti \u2018indesiderati\u2019 <strong>e il desiderio reale di coppie disponibili all\u2019adozione<\/strong><\/em><strong>\u201d.<\/strong><\/p>\n<p><strong>\u00a0<\/strong>Un\u2019idea avanzata anche da <strong>Ai.Bi, Amici dei Bambini nel <a href=\"https:\/\/www.aibi.it\/ita\/pdf\/Manifesto_AI_raccolta_firme.pdf\">Manifesto per una nuova legge dell\u2019Adozione internazionale \u201cOltre La crisi. Pi\u00f9 famiglie &amp; pi\u00f9 adozioni\u201d<\/a> <\/strong>che al punto 6 \u201cLe accoglienze innovative\u201d riporta testualmente \u201c<em>Riconoscere i provvedimenti, pronunciati in Paesi che hanno ratificato la Convenzione de L\u2019Aja del 1993, che prevedono, <strong>come misura di prevenzione dell\u2019aborto, il mantenimento e l\u2019adozione del nascituro durante la gestazione, sotto il controllo dell\u2019autorit\u00e0 giudiziaria\u201d.<\/strong><\/em><\/p>\n<p>Una forma di adozione, con alcune differenze, gi\u00e0 in atto <strong>negli Stati Uniti<\/strong>: prevede il contatto tra la gestante in difficolt\u00e0 e una coppia disponibile ad adottare il suo neonato. E funziona: <strong>in America \u00e8 un metodo vincente per evitare l\u2019abbandono ma, soprattutto, per la prevenzione dell\u2019aborto<\/strong>. Una gestante che sia in gravi difficolt\u00e0, che abbia una gravidanza imprevista e scarse prospettive di crescere il suo bambino, ha la possibilit\u00e0 di conoscere <strong>due genitori adottivi che, per legge, possono assumersi tutto il carico delle spese del parto<\/strong>.<\/p>\n<p>Un accordo da prendere durante la gravidanza, che lascia aperta alla madre ogni via: <strong>le permette di tornare sui propri passi e decidere, anche all\u2019ultimo momento, di tenere il bambino con s\u00e9 senza obbligo di restituzione delle spese<\/strong>. La madre biologica ha il diritto di scegliere per prima gli adottanti e di confermare la sua decisione davanti al giudice, ed <strong>\u00e8 sempre e comunque il tribunale a pronunciare l\u2019esito definitivo della procedura.<\/strong><\/p>\n<p><strong>In Italia, secondo la proposta di legge di Sberna, <\/strong>il presupposto \u00e8 che \u201c<em>il concepito \u00e8 un essere umano, non un grumo di cellule<\/em>\u201c e un\u2019efficace azione di prevenzione all\u2019aborto aiuterebbe tante<em> \u201ca riflettere sulla scelta di interrompere la gravidanza, anche in relazione al fatto che vi sono persone in attesa di un bimbo da adottare<\/em>. <em>Che desiderano essere madri ma non ne hanno avuta la possibilit\u00e0.<\/em> <em>Quindi piuttosto che pensare ad abortire, chi aspetta un bimbo potrebbe considerare lo stato di adottabilit\u00e0 del nascituro<\/em>\u201c.<\/p>\n<p><strong>La legge, inoltre, semplificherebbe il processo di adozione.<\/strong> \u201c<em>Chi partorisce ha una settimana di tempo per revocare il proprio consenso allo stato di adottabilit\u00e0. Dal momento che acconsente, l\u2019iter adottivo \u2013 all\u2019esito delle verifiche \u2013 \u00e8 molto veloce<\/em>\u201c, spiega Sberna.<\/p>\n<p><strong>Tre sono i capisaldi della proposta<\/strong>. <strong>La donna<\/strong>, in alternativa all\u2019Ivg per le ipotesi previste dalla legge 194 del 1978 <strong>pu\u00f2 ottenere lo stato di adottabilit\u00e0 del concepito<\/strong>, che \u00e8 disposto, con rito abbreviato, con decreto del tribunale per i minorenni prima della nascita del concepito; <strong>la donna, fino al momento della nascita e nei sette giorni successivi, pu\u00f2 sempre e liberamente revocare il proprio consenso<\/strong> allo stato di adottabilit\u00e0 del concepito; <strong>il tribunale per i minorenni, entro sette giorni<\/strong>, dalla nascita del concepito dichiarato adottabile, <strong>sceglie la coppia tra un apposito elenco di coppie<\/strong> la cui residenza \u00e8 posta a una distanza non inferiore a 500 chilometri dal luogo di nascita del concepito e dispone l\u2019affidamento preadottivo, ai fini della successiva adozione. <strong>La scelta del tribunale per i minorenni preclude ogni possibile forma di \u2018commercio\u2019 tra la madre naturale e la coppia.<\/strong><\/p>\n<p>Inoltre, <strong>le misure non comportano aumenti di spesa<\/strong>, non essendo prevista l\u2019istituzione di nuovi organismi ma una semplice rimodulazione delle funzioni delle strutture socio-sanitarie gi\u00e0 esistenti e degli uffici giudiziari competenti. L\u2019aumento di spesa legato all\u2019assistenza ospedaliera per il parto \u00e8, poi, compensato dal risparmio legato alla corrispondente diminuzione di accesso alle strutture sanitarie per l\u2019intervento abortivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono allarmanti i dati relativi agli aborti in Italia. Per questo Sberna e Gigli hanno presentato una proposta di legge con cui si mira alla prevenzione dell\u2019aborto e a una sorta di conciliazione tra \u201cl\u2019elevato numero di concepiti \u2018indesiderati\u2019 \u2013 dice Sberna \u2013 e il desiderio reale di coppie disponibili all\u2019adozione\u201d \u201cI consultori hanno l\u2019obbligo di informare la donna in stato di gravidanza \u2013 precisa \u2013 che esistono misure alternative all\u2019Interruzione volontaria di gravidanza\u201d. Una \u2018proposta\u2019 che Ai.Bi aveva gi\u00e0 messo nero su bianco nel Manifesto per una nuova legge dell\u2019Adozione internazionale \u201cOltre La crisi. Pi\u00f9 famiglie &amp; pi\u00f9 adozioni\u201d<\/p>\n","protected":false},"author":61,"featured_media":100730,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-138249","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Emergenza aborti. Sberna\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l&#039; \u2018adozione in pancia\u2019 degli USA - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emergenza aborti. Sberna\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l&#039; \u2018adozione in pancia\u2019 degli USA\" \/>\n<meta property=\"og:description\" content=\"Sono allarmanti i dati relativi agli aborti in Italia. Per questo Sberna e Gigli hanno presentato una proposta di legge con cui si mira alla prevenzione dell\u2019aborto e a una sorta di conciliazione tra \u201cl\u2019elevato numero di concepiti \u2018indesiderati\u2019 \u2013 dice Sberna \u2013 e il desiderio reale di coppie disponibili all\u2019adozione\u201d \u201cI consultori hanno l\u2019obbligo di informare la donna in stato di gravidanza \u2013 precisa \u2013 che esistono misure alternative all\u2019Interruzione volontaria di gravidanza\u201d. Una \u2018proposta\u2019 che Ai.Bi aveva gi\u00e0 messo nero su bianco nel Manifesto per una nuova legge dell\u2019Adozione internazionale \u201cOltre La crisi. Pi\u00f9 famiglie &amp; pi\u00f9 adozioni\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-08T17:13:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-10T16:46:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/aborto3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Emergenza aborti. Sberna\\\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l&#8217; \u2018adozione in pancia\u2019 degli USA\",\"datePublished\":\"2017-02-08T17:13:12+00:00\",\"dateModified\":\"2017-02-10T16:46:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/\"},\"wordCount\":863,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aborto3.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/\",\"name\":\"Emergenza aborti. Sberna\\\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l' \u2018adozione in pancia\u2019 degli USA - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aborto3.jpg\",\"datePublished\":\"2017-02-08T17:13:12+00:00\",\"dateModified\":\"2017-02-10T16:46:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aborto3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aborto3.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Emergenza aborti. Sberna\\\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l&#8217; \u2018adozione in pancia\u2019 degli USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Emergenza aborti. Sberna\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l' \u2018adozione in pancia\u2019 degli USA - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/","og_locale":"it_IT","og_type":"article","og_title":"Emergenza aborti. Sberna\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l' \u2018adozione in pancia\u2019 degli USA","og_description":"Sono allarmanti i dati relativi agli aborti in Italia. Per questo Sberna e Gigli hanno presentato una proposta di legge con cui si mira alla prevenzione dell\u2019aborto e a una sorta di conciliazione tra \u201cl\u2019elevato numero di concepiti \u2018indesiderati\u2019 \u2013 dice Sberna \u2013 e il desiderio reale di coppie disponibili all\u2019adozione\u201d \u201cI consultori hanno l\u2019obbligo di informare la donna in stato di gravidanza \u2013 precisa \u2013 che esistono misure alternative all\u2019Interruzione volontaria di gravidanza\u201d. Una \u2018proposta\u2019 che Ai.Bi aveva gi\u00e0 messo nero su bianco nel Manifesto per una nuova legge dell\u2019Adozione internazionale \u201cOltre La crisi. Pi\u00f9 famiglie &amp; pi\u00f9 adozioni\u201d","og_url":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-02-08T17:13:12+00:00","article_modified_time":"2017-02-10T16:46:22+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/aborto3.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Emergenza aborti. Sberna\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l&#8217; \u2018adozione in pancia\u2019 degli USA","datePublished":"2017-02-08T17:13:12+00:00","dateModified":"2017-02-10T16:46:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/"},"wordCount":863,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aborto3.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/","url":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/","name":"Emergenza aborti. Sberna\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l' \u2018adozione in pancia\u2019 degli USA - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aborto3.jpg","datePublished":"2017-02-08T17:13:12+00:00","dateModified":"2017-02-10T16:46:22+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/aborto3.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/aborto3.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/emergenza-aborti-sbernagigli-des-cd-sono-200-mila-i-bambini-non-nati-in-italia-in-2-anni-urge-unalternativa-allinterruzione-volontaria-di-gravidanza-ladozio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Emergenza aborti. Sberna\/Gigli (Des-Cd) : \u201cSono 200 mila i bambini non nati in Italia in 2 anni. Urge un\u2019alternativa all\u2019interruzione volontaria di gravidanza: l\u2019adozione del nascituro\u201d. Le differenze con l&#8217; \u2018adozione in pancia\u2019 degli USA"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 19:46:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/138249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=138249"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/138249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/100730"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=138249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=138249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=138249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}