﻿


{"id":138407,"date":"2017-02-13T16:29:08","date_gmt":"2017-02-13T15:29:08","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=138407"},"modified":"2020-08-27T12:56:20","modified_gmt":"2020-08-27T10:56:20","slug":"siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/","title":{"rendered":"Siria. Dopo 6 anni di  guerra, ancora drammi per i bambini di Aleppo: l&#8217;Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-131115 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg\" alt=\"aleppo assedio\" width=\"400\" height=\"286\" data-id=\"131115\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Acqua, carburante, elettricit\u00e0, medicine.<\/strong> Nell\u2019infinito elenco dei beni di prima necessit\u00e0 che mancano ormai in modo cronico alla popolazione siriana<strong> stremata da quasi 6 anni di guerra<\/strong>, oggi ci concentriamo su questi 4. La cui grave carenza <strong>paralizza di fatto milioni di famiglie<\/strong> e contribuisce a togliere speranza a uomini, donne e bambini di un Paese ormai distrutto.<\/p>\n<p>Ad Aleppo si sta registrando <strong>la pi\u00f9 grave crisi idrica che si ricordi<\/strong>. Una parte della citt\u00e0, la zona di al-Kafsa, \u00e8 ancora sotto il controllo dell\u2019Isis che ha chiuso i canali che conducono l\u2019acqua alla stazione di pompaggio. Per approvvigionarsi di risorse idriche sono rimasti ormai solo i pozzi in citt\u00e0, ma i generatori per il pompaggio funzionano a orari sempre pi\u00f9 dirotti.<\/p>\n<p>Questo a causa della <strong>penuria di gasolio che ha lasciato fermi anche molti autoveicoli<\/strong>. La crisi dei carburanti paralizza il traffico e crea code anche di 3 ore ai distributori per i rifornimenti razionati. Taxi e mezzi pubblici sono quasi del tutto bloccati e questo obbliga la gente a spostarsi a piedi camminando anche per ore, con tutti i pericoli di un Paese in guerra. La mancanza di carburante si fa sentire anche nelle case, dove quasi sempre <strong>manca il riscaldamento<\/strong>\u00a0perch\u00e9 il metano \u00e8 diventato quasi introvabile e le bombole del gas si reperiscono solo al mercato nero.<\/p>\n<p>Nel frattempo anche <strong>la fornitura di energia elettrica \u00e8 stata razionata<\/strong>: l\u2019erogazione avviene solo 5 volte al giorno a riprese di non pi\u00f9 di un\u2019ora ciascuna.<\/p>\n<p>La situazione non \u00e8 migliore nei Paesi confinanti che ospitano centinaia di migliaia di rifugiati. La carenza di acqua e di elettricit\u00e0 \u00e8 pesante anche in Libano per almeno <strong>365mila siriani che vivono in insediamenti informali<\/strong> e non possono permettersi di pagarsi le cure mediche. Non migliore, da quest\u2019ultimo punto di vista, la situazione della Giordania, dove l\u2019elevato numero di rifugiati ha messo una forte pressione sul sistema sanitario del Paese. Cos\u00ec, i profughi siriani <strong>non hanno accesso all\u2019assistenza medica<\/strong> e vedono gli effetti delle malattie croniche \u2013 ipertensione, diabete o patologie cardiovascolari \u2013 generare conseguenze gravissime e spesso mortali.<\/p>\n<p><strong>Amici dei Bambini<\/strong> \u00e8 impegnata ogni giorno per limitare l\u2019incidenza di tutto questo sui bambini e le famiglie siriane. Con il suo progetto <a href=\"https:\/\/www.aibi.it\/ita\/emergenza-siria\/\"><strong><em>Non lasciamoli soli<\/em><\/strong><\/a>, fino a oggi, Ai.Bi. \u00e8 riuscita a fornire<strong> supporto alimentare, psicologico e sanitario a oltre 35mila minori e alle loro famiglie<\/strong>. Ma in un Paese in cui pi\u00f9 di 13,5 milioni di persone hanno dovuto abbandonare la propria casa e 6 milioni di bambini hanno bisogno di aiuti umanitari urgenti, ci\u00f2 che occorre fare \u00e8 ancora tantissimo. Per questo ti chiediamo di aiutarci a sostenere i nostri interventi di prima e seconda emergenza nelle aree di Aleppo, Idlib, Homs e Rural Damasco. Il progetto pi\u00f9 grande che ci vede impegnati in Siria \u00e8 quello per la costruzione di<strong> un ospedale pediatrico in condizioni di totale sicurezza<\/strong>, capace di assistere <strong>fino a 300 pazienti al giorno<\/strong>\u00a0e dotato di servizi di emergenza e reparti di ostetricia, ginecologia e neonatologia, con 35 posti letto e 19 incubatrici.<br \/>\n<a href=\"https:\/\/www.aibi.it\/ita\/emergenza-siria\/\">DONA ORA &gt;&gt;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Siria, stremata da 6 anni di guerra, sta affrontando la crisi idrica pi\u00f9 grave che si ricordi. Nel frattempo la carenza di carburante ha di fatto paralizzato il sistema dei trasporti pubblici e privati e privato molte case del riscaldamento. Nelle abitazioni anche l\u2019energia elettrica viene fornita con il contagocce. E l\u2019assistenza medica \u00e8 ormai quasi inaccessibile sia per chi \u00e8 rimasto in patria che per chi ha trovato rifugio nei Paesi confinanti. Ai.Bi. \u00e8 presente in Siria al fianco dei bambini e delle famiglie e sta lavorando alla realizzazione di un nuovo ospedale pediatrico.<\/p>\n","protected":false},"author":61,"featured_media":131115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114],"tags":[],"class_list":["post-138407","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-bambini-in-alto-mare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Siria. Dopo 6 anni di guerra, ancora drammi per i bambini di Aleppo: l&#039;Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Siria. Dopo 6 anni di guerra, ancora drammi per i bambini di Aleppo: l&#039;Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua\" \/>\n<meta property=\"og:description\" content=\"La Siria, stremata da 6 anni di guerra, sta affrontando la crisi idrica pi\u00f9 grave che si ricordi. Nel frattempo la carenza di carburante ha di fatto paralizzato il sistema dei trasporti pubblici e privati e privato molte case del riscaldamento. Nelle abitazioni anche l\u2019energia elettrica viene fornita con il contagocce. E l\u2019assistenza medica \u00e8 ormai quasi inaccessibile sia per chi \u00e8 rimasto in patria che per chi ha trovato rifugio nei Paesi confinanti. Ai.Bi. \u00e8 presente in Siria al fianco dei bambini e delle famiglie e sta lavorando alla realizzazione di un nuovo ospedale pediatrico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-13T15:29:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-27T10:56:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Siria. Dopo 6 anni di guerra, ancora drammi per i bambini di Aleppo: l&#8217;Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua\",\"datePublished\":\"2017-02-13T15:29:08+00:00\",\"dateModified\":\"2020-08-27T10:56:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/\"},\"wordCount\":525,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aleppo-assedio.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/\",\"name\":\"Siria. Dopo 6 anni di guerra, ancora drammi per i bambini di Aleppo: l'Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aleppo-assedio.jpg\",\"datePublished\":\"2017-02-13T15:29:08+00:00\",\"dateModified\":\"2020-08-27T10:56:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aleppo-assedio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/aleppo-assedio.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Siria. Dopo 6 anni di guerra, ancora drammi per i bambini di Aleppo: l&#8217;Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Siria. Dopo 6 anni di guerra, ancora drammi per i bambini di Aleppo: l'Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/","og_locale":"it_IT","og_type":"article","og_title":"Siria. Dopo 6 anni di guerra, ancora drammi per i bambini di Aleppo: l'Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua","og_description":"La Siria, stremata da 6 anni di guerra, sta affrontando la crisi idrica pi\u00f9 grave che si ricordi. Nel frattempo la carenza di carburante ha di fatto paralizzato il sistema dei trasporti pubblici e privati e privato molte case del riscaldamento. Nelle abitazioni anche l\u2019energia elettrica viene fornita con il contagocce. E l\u2019assistenza medica \u00e8 ormai quasi inaccessibile sia per chi \u00e8 rimasto in patria che per chi ha trovato rifugio nei Paesi confinanti. Ai.Bi. \u00e8 presente in Siria al fianco dei bambini e delle famiglie e sta lavorando alla realizzazione di un nuovo ospedale pediatrico.","og_url":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-02-13T15:29:08+00:00","article_modified_time":"2020-08-27T10:56:20+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Siria. Dopo 6 anni di guerra, ancora drammi per i bambini di Aleppo: l&#8217;Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua","datePublished":"2017-02-13T15:29:08+00:00","dateModified":"2020-08-27T10:56:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/"},"wordCount":525,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg","articleSection":["AiBiNews","Bambini in alto mare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/","url":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/","name":"Siria. Dopo 6 anni di guerra, ancora drammi per i bambini di Aleppo: l'Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg","datePublished":"2017-02-13T15:29:08+00:00","dateModified":"2020-08-27T10:56:20+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/aleppo-assedio.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/siria-dopo-6-anni-di-guerra-ancora-drammi-per-i-bambini-di-aleppo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Siria. Dopo 6 anni di guerra, ancora drammi per i bambini di Aleppo: l&#8217;Isis chiude i rubinetti e mezza citt\u00e0 rimane senza acqua"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:11:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/138407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=138407"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/138407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/131115"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=138407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=138407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=138407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}