﻿


{"id":139138,"date":"2017-03-03T17:06:07","date_gmt":"2017-03-03T16:06:07","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=139138"},"modified":"2017-03-07T18:09:01","modified_gmt":"2017-03-07T17:09:01","slug":"milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/","title":{"rendered":"Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-139144 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente.jpg\" alt=\"foto-aldini-bonucci-presidente\" width=\"400\" height=\"286\" data-id=\"139144\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>La stagione sportiva \u00e8 ancora nel vivo, ma alcuni dei pi\u00f9 importanti campioni, allenatori e dirigenti del calcio italiano hanno gi\u00e0 sollevato un premio. Lo hanno fatto tutti insieme,<strong> nel nome dei bambini, delle famiglie della Siria e dei calciatori in erba<\/strong>. Stiamo parlando dei premi <strong>\u201cAmico dei bambini\u2026 Un esempio per loro\u201d<\/strong>, istituito dall\u2019<strong>Unione Sportiva Aldini Bariviera<\/strong> di Milano con <strong>Ai.Bi.<\/strong> e assegnati gioved\u00ec 2 marzo ai protagonisti del nostro calcio che nell\u2019ultimo anno di sono distinti come modelli di riferimento per i pi\u00f9 giovani. La premiazione, avvenuta a Milano, nella sala Orlando dell\u2019Unione del Commercio e del Turismo, \u00e8 stata anche l\u2019occasione per la presentazione della <strong>XIII edizione del torneo \u201cAmici dei Bambini\u201d<\/strong>, organizzata dall\u2019Aldini che nei prossimi mesi vedr\u00e0 impegnate le formazioni giovanili di 24 societ\u00e0 dilettantistiche e professionistiche. Una manifestazione che, come da tradizione, coniugher\u00e0 sport e solidariet\u00e0: anche quest\u2019anno il ricavato del torneo sar\u00e0 devoluto a <strong>sostenere l\u2019impegno di Ai.Bi. al fianco dell\u2019infanzia pi\u00f9 fragile<\/strong>. Per questo 2017, si \u00e8 scelto di supportare la costruzione del <strong>nuovo ospedale pediatrico<\/strong> che Ai.Bi. sta realizzando in Siria.<\/p>\n<p>La serata del 2 marzo, condotta dai giornalisti<strong> Ivan Zazzaroni<\/strong> e <strong>Fabio Caressa<\/strong> con la partecipazione, in veste di <em>special guest<\/em>, di<strong> Cristina Chiabotto<\/strong>, ha visto tra i premiati il difensore della Juventus e della Nazionale <strong>Leonardo Bonucci<\/strong>, i giocatori <strong>Roberto Gagliardini<\/strong> dell\u2019Inter, <strong>Suso<\/strong> del Milan, <strong>Andrea Petagna<\/strong> dell\u2019Atalanta, <strong>Andrea Belotti<\/strong> del Torino, <strong>Alex Meret<\/strong> della Spal e <strong>Francesco Cassata<\/strong> dell\u2019Ascoli. Oltre a loro hanno ricevuto il premio \u201cAmico dei Bambini\u201d <strong>Gianpiero Gasperini<\/strong>, allenatore dell\u2019Atalanta, <strong>Gianpaolo Castorina<\/strong>, tecnico della squadra Primavera della Virtus Entella e <strong>Arrigo Sacchi<\/strong>, storico allenatore del Milan e commissario tecnico della Nazionale vicecampione del mondo nel 1994 e oggi opinionista tv. Premi anche per i dirigenti: <strong>Fabio Paratici<\/strong> e <strong>Rocco Maiorino<\/strong>, direttori sportivi rispettivamente di Juve e Milan, <strong>Stefano Braghin<\/strong>, direttore del settore giovanile bianconero, e <strong>Giuseppe Corrado<\/strong>, presidente del Pisa.<\/p>\n<p>Entusiasta al termine della serata il presidente dell\u2019Aldini <strong>Massimiliano Borsani<\/strong>.<em> \u201cQuasi non ci credo che siamo gi\u00e0 arrivati alla 13esima edizione<\/em> \u2013 ha commentato -. <em>Quando abbiamo istituito il premio, nel 2005, non avrei mai pensato che avrebbe avuto un tale seguito. Ringrazio tutti coloro che si prodigano per la buona riuscita dell\u2019evento: le squadre di calcio che ogni anno fanno venire i loro tesserati, i premiati, gli ospiti, gli sponsor, Ivan Zazzaroni e il mio staff. Spero che continueremo cos\u00ec, soprattutto perch\u00e9 <strong>lo scopo del premio \u00e8 benefico<\/strong>\u201d<\/em>.\u00a0 Quest\u2019anno il ricavato del torneo sosterr\u00e0 il progetto <strong>Non lasciamoli soli<\/strong> di Ai.Bi. in Siria, che da 3 anni garantisce interventi di prima e seconda emergenza nelle aree di Idlib, Aleppo, Homs e Rural Damasco. In Siria, le strutture sanitarie sono completamente o parzialmente fuori uso e non pi\u00f9 sicure: ecco perch\u00e9 Ai.Bi. ha deciso di ampliare il proprio intervento con la costruzione di un ospedale pediatrico.<em> \u201c<strong>Dal 12 aprile all\u201911 giugno<\/strong> si svolger\u00e0 il torneo presso il nostro centro sportivo<\/em> \u2013 conclude Borsani -. <em>Vi aspetto tutti, \u00e8 per una buona causa\u201d<\/em>.<\/p>\n<p>La finalit\u00e0 benefica dell\u2019iniziativa \u00e8 stata sottolineata, nel corso della serata, anche dal presidente di Ai.Bi. <strong>Marco Griffini.<\/strong> <em>\u201cIn questo difficile momento<strong> occorre infondere speranza ai milioni di bambini e mamme in difficolt\u00e0<\/strong><\/em> \u2013 ha detto Griffini \u2013.<em> Ognuno di noi pu\u00f2 fare molto per fermare questa guerra senza fine: <strong>il disinteresse \u00e8 il principale nemico da combattere<\/strong>. Per tutti i bambini che vivono sotto le bombe, la cosa peggiore che si possa fare sarebbe non fare niente\u201d<\/em>. In 6 anni di conflitto, in Siria si sono contati 382 attacchi ai centri sanitari e per i civili non c\u2019\u00e8 quasi pi\u00f9 un luogo in cui ricevere delle cure. <em>\u201cPer questo Ai.Bi. si impegna a costruire un nuovo ospedale<\/em> \u2013 ha spiegato Griffini -,<em> in condizioni di assoluta sicurezza, ampliando cos\u00ec il fronte degli interventi anche con la distribuzione di ceste alimentari nella regione di Aleppo e di voucher mensili nella zona di Idlib. Con le nostre attivit\u00e0<\/em> \u2013 ha ricordato il presidente di Ai.Bi. \u2013 <em>a<strong>bbiamo gi\u00e0 raggiunto circa 40mila bambini e famiglie<\/strong>, beneficiari di interventi di sicurezza alimentare e sanitaria e di servizi di protezione dei minori e delle donne vulnerabili\u201d<\/em>. <em>\u201cLa popolazione siriana\u00a0 ha bisogno oggi pi\u00f9 di ieri del nostro aiuto<\/em> \u2013 ha concluso Griffini -. <em>Per questo ringrazio l\u2019Aldini e il suo presidente per la sensibilit\u00e0 e l\u2019attenzione che anche quest\u2019anno rivolgono ai nostri progetti\u201d<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 2 marzo a Milano sono stati consegnati i premi \u201cAmico dei bambini\u2026 Un esempio per loro\u201d, istituito dall\u2019Us Aldini con Ai.Bi. e dedicato ai protagonisti del calcio italiano che si sono distinti come modelli di riferimento per i campioni in erba. Nel corso della serata \u00e8 stato presentato il XIII torneo \u201cAmici dei Bambini\u201d che, dal 12 aprile all\u201911 giugno, sosterr\u00e0 il progetto Non lasciamoli soli di Ai.Bi. in Siria e in particolare la costruzione di un nuovo ospedale pediatrico.<\/p>\n","protected":false},"author":61,"featured_media":139144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,114],"tags":[],"class_list":["post-139138","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-bambini-in-alto-mare"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria\" \/>\n<meta property=\"og:description\" content=\"Gioved\u00ec 2 marzo a Milano sono stati consegnati i premi \u201cAmico dei bambini\u2026 Un esempio per loro\u201d, istituito dall\u2019Us Aldini con Ai.Bi. e dedicato ai protagonisti del calcio italiano che si sono distinti come modelli di riferimento per i campioni in erba. Nel corso della serata \u00e8 stato presentato il XIII torneo \u201cAmici dei Bambini\u201d che, dal 12 aprile all\u201911 giugno, sosterr\u00e0 il progetto Non lasciamoli soli di Ai.Bi. in Siria e in particolare la costruzione di un nuovo ospedale pediatrico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-03T16:06:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-07T17:09:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria\",\"datePublished\":\"2017-03-03T16:06:07+00:00\",\"dateModified\":\"2017-03-07T17:09:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/\"},\"wordCount\":761,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-aldini-bonucci-presidente.jpg\",\"articleSection\":[\"AiBiNews\",\"Bambini in alto mare\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/\",\"name\":\"Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-aldini-bonucci-presidente.jpg\",\"datePublished\":\"2017-03-03T16:06:07+00:00\",\"dateModified\":\"2017-03-07T17:09:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-aldini-bonucci-presidente.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-aldini-bonucci-presidente.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/","og_locale":"it_IT","og_type":"article","og_title":"Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria","og_description":"Gioved\u00ec 2 marzo a Milano sono stati consegnati i premi \u201cAmico dei bambini\u2026 Un esempio per loro\u201d, istituito dall\u2019Us Aldini con Ai.Bi. e dedicato ai protagonisti del calcio italiano che si sono distinti come modelli di riferimento per i campioni in erba. Nel corso della serata \u00e8 stato presentato il XIII torneo \u201cAmici dei Bambini\u201d che, dal 12 aprile all\u201911 giugno, sosterr\u00e0 il progetto Non lasciamoli soli di Ai.Bi. in Siria e in particolare la costruzione di un nuovo ospedale pediatrico.","og_url":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-03-03T16:06:07+00:00","article_modified_time":"2017-03-07T17:09:01+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria","datePublished":"2017-03-03T16:06:07+00:00","dateModified":"2017-03-07T17:09:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/"},"wordCount":761,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente.jpg","articleSection":["AiBiNews","Bambini in alto mare"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/","url":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/","name":"Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente.jpg","datePublished":"2017-03-03T16:06:07+00:00","dateModified":"2017-03-07T17:09:01+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/foto-aldini-bonucci-presidente.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/milano-con-aldini-e-ai-bi-i-campioni-dello-sport-diventano-eroi-di-solidarieta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Milano. Con Aldini e Ai.Bi. i campioni dello sport diventano eroi di solidariet\u00e0. Al via il XIII torneo \u201cAmici dei Bambini\u201d: ogni gol sar\u00e0 un mattone del nuovo ospedale pediatrico in Siria"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:25:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/139138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=139138"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/139138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/139144"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=139138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=139138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=139138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}