﻿


{"id":139655,"date":"2017-03-20T18:01:11","date_gmt":"2017-03-20T17:01:11","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=139655"},"modified":"2017-03-20T18:01:11","modified_gmt":"2017-03-20T17:01:11","slug":"i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/","title":{"rendered":"I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica?"},"content":{"rendered":"<p><strong>Buongiorno Ai.Bi.<\/strong><\/p>\n<p><strong>Mi rivolgo a voi in virt\u00f9 della vostra pluriennale esperienza nel settore delle adozioni. Sono un figlio adottivo ormai adulto, accolto nel 1979, all\u2019et\u00e0 di 2 anni, da quella che \u00e8 diventata la mia nuova famiglia. Alcuni mesi fa ho avuto notizie relative alla mia famiglia di origine: a quanto pare, il mio pap\u00e0 biologico \u00e8 ancora vivo e, dopo aver superato i mille problemi famigliari che hanno portato, a suo tempo, anche al\u00a0 mio collocamento in istituto e alla mia successiva adozione, ha recuperato un tenore di vita pi\u00f9 che dignitoso. Ora \u00e8 molto anziano e vorrei capire che cosa potrebbe accadere quando, un giorno \u2013 che spero comunque lontano \u2013 non ci dovesse essere pi\u00f9. In quanto figlio biologico, ho qualche diritto in merito alla successione? Un mio conoscente, adottato una quindicina di anni prima di me, ha potuto esercitare i suoi diritti di successione rispetto alla sua famiglia di origine. Tuttavia, l\u2019avvocato a cui ho chiesto informazioni relativamente alla mia situazione mi ha detto che io non potrei fare lo stesso. Come stanno effettivamente le cose? <\/strong><\/p>\n<p><strong>Grazie<\/strong><\/p>\n<p><strong>Daniele<\/strong><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-108862 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111.jpg\" alt=\"MACCHINA-DA-SCRIVERE11\" width=\"400\" height=\"286\" data-id=\"108862\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Caro Daniele,<\/p>\n<p>prima del 1967 le adozioni erano regolate dall\u2019affiliazione e non comportavano l\u2019instaurarsi di un vero rapporto &#8220;genitori-figli&#8221; tra adottanti e adottati. L\u2019affiliazione era sempre revocabile, mentre l\u2019adozione ordinaria era prevista solo per i maggiorenni e per i minorenni a patto che l\u2019adottante non avesse figli e avesse superato i 50 anni di et\u00e0. L\u2019adottato rimaneva quindi sempre figlio dei suoi genitori biologici. Di conseguenza, l\u2019adozione avvenuta prima del 1967 non comporta una perdita dei rapporti e dei diritti ereditari dell\u2019adottato verso la sua famiglia di origine, poich\u00e9, con l\u2019adozione in vigore a quei tempi, ordinaria e non legittimante, avveniva l\u2019assunzione del doppio cognome da parte del figlio. Il quale, quindi, conservava anche rapporti con la famiglia di origine. Il diritto successorio, pertanto, per coloro che sono stati adottati prima del 1967, permane.<\/p>\n<p>Per le adozioni avvenute dopo quella data, invece, la situazione \u00e8 diversa. La legge di quell\u2019anno (con il tempo comunque superata), infatti, esclude i diritti successori verso la famiglia biologica perch\u00e9 l\u2019adottato \u00e8 equiparato in tutto e per tutto a un figlio legittimo. Con le adozioni successiva al 1967, quindi, vi \u00e8 una cessazione di ogni rapporto giuridico con la famiglia di origine. Quella adottiva, dunque, diviene l\u2019unica famiglia del minore, per il quale cessa ogni rapporto con i genitori biologici. Ivi compreso, quindi, il diritto di successione.<\/p>\n<p>Un caro saluto,<\/p>\n<p>&nbsp;<\/p>\n<p>Ufficio Stampa\u00a0di Ai.Bi.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Mi rivolgo a voi in virt\u00f9 della vostra pluriennale esperienza nel settore delle adozioni. Sono un figlio adottivo ormai adulto, accolto nel 1979, all\u2019et\u00e0 di 2 anni, da quella che \u00e8 diventata la mia nuova famiglia. &#8211; <em>Risponde l&#8217;Ufficio Stampa\u00a0di Ai.Bi.<\/em><\/p>\n","protected":false},"author":61,"featured_media":108862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[50],"tags":[],"class_list":["post-139655","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lettere-al-direttore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica?\" \/>\n<meta property=\"og:description\" content=\"Mi rivolgo a voi in virt\u00f9 della vostra pluriennale esperienza nel settore delle adozioni. Sono un figlio adottivo ormai adulto, accolto nel 1979, all\u2019et\u00e0 di 2 anni, da quella che \u00e8 diventata la mia nuova famiglia. - Risponde l&#039;Ufficio Stampa\u00a0di Ai.Bi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-20T17:01:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica?\",\"datePublished\":\"2017-03-20T17:01:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/\"},\"wordCount\":429,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MACCHINA-DA-SCRIVERE111.jpg\",\"articleSection\":[\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/\",\"name\":\"I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MACCHINA-DA-SCRIVERE111.jpg\",\"datePublished\":\"2017-03-20T17:01:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MACCHINA-DA-SCRIVERE111.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/MACCHINA-DA-SCRIVERE111.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettere al direttore\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/lettere-al-direttore\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica? - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/","og_locale":"it_IT","og_type":"article","og_title":"I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica?","og_description":"Mi rivolgo a voi in virt\u00f9 della vostra pluriennale esperienza nel settore delle adozioni. Sono un figlio adottivo ormai adulto, accolto nel 1979, all\u2019et\u00e0 di 2 anni, da quella che \u00e8 diventata la mia nuova famiglia. - Risponde l'Ufficio Stampa\u00a0di Ai.Bi.","og_url":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-03-20T17:01:11+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica?","datePublished":"2017-03-20T17:01:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/"},"wordCount":429,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111.jpg","articleSection":["Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/","url":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/","name":"I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111.jpg","datePublished":"2017-03-20T17:01:11+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/MACCHINA-DA-SCRIVERE111.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/i-figli-adottivi-hanno-diritti-di-successione-nei-confronti-della-loro-famiglia-biologica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Lettere al direttore","item":"https:\/\/www.aibi.it\/ita\/category\/lettere-al-direttore\/"},{"@type":"ListItem","position":3,"name":"I figli adottivi hanno diritti di successione nei confronti della loro famiglia biologica?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:01:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/139655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=139655"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/139655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/108862"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=139655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=139655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=139655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}