﻿


{"id":140966,"date":"2017-05-02T18:19:24","date_gmt":"2017-05-02T16:19:24","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=140966"},"modified":"2017-05-02T18:19:45","modified_gmt":"2017-05-02T16:19:45","slug":"adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/","title":{"rendered":"#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi&#8221;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-141005 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news.jpg\" alt=\"\" width=\"634\" height=\"406\" data-id=\"141005\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news.jpg 634w, https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news-150x96.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news-300x192.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news-86x55.jpg 86w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/>Valery e Alessandro, oggi madre e padre del piccolo Natan, raccontano nel corso della puntata di \u201cA Sua Immagine\u201d di domenica 30 aprile la loro storia di adozione con Ai.Bi. in Cina. Un cammino fatto di molti ostacoli e prove per arrivare alla gioia di cui oggi sono testimoni.\u00a0\u201cNatan \u00e8 nostro figlio al 100%. E\u2019 il primo dei figli che Dio da sempre ha pensato per noi\u201d.<\/p>\n<p><a href=\"http:\/\/www.raiplay.it\/video\/2017\/04\/A-Sua-immagine-Le-ragioni-della-speranza-3aab3af4-6733-4fab-9094-416cea1b2f08.html\">Guarda l\u2019intervista<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valery e Alessandro, oggi madre e padre del piccolo Natan, raccontano nel corso della puntata di \u201cA Sua Immagine\u201d di domenica 30 aprile la loro storia di adozione con Ai.Bi. in Cina. Un cammino fatto di molti ostacoli e prove per arrivare alla gioia di cui oggi sono testimoni.\u00a0\u201cNatan \u00e8 nostro figlio al 100%. E\u2019 il primo dei figli che Dio da sempre ha pensato per noi\u201d.<\/p>\n","protected":false},"author":61,"featured_media":141005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,174],"tags":[],"class_list":["post-140966","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi&quot; - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi&quot;\" \/>\n<meta property=\"og:description\" content=\"Valery e Alessandro, oggi madre e padre del piccolo Natan, raccontano nel corso della puntata di \u201cA Sua Immagine\u201d di domenica 30 aprile la loro storia di adozione con Ai.Bi. in Cina. Un cammino fatto di molti ostacoli e prove per arrivare alla gioia di cui oggi sono testimoni.\u00a0\u201cNatan \u00e8 nostro figlio al 100%. E\u2019 il primo dei figli che Dio da sempre ha pensato per noi\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-02T16:19:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-02T16:19:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi&#8221;\",\"datePublished\":\"2017-05-02T16:19:24+00:00\",\"dateModified\":\"2017-05-02T16:19:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/\"},\"wordCount\":92,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-famiglia-a-sua-immagine-news.jpg\",\"articleSection\":[\"AiBiNews\",\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/\",\"name\":\"#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-famiglia-a-sua-immagine-news.jpg\",\"datePublished\":\"2017-05-02T16:19:24+00:00\",\"dateModified\":\"2017-05-02T16:19:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-famiglia-a-sua-immagine-news.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/foto-famiglia-a-sua-immagine-news.jpg\",\"width\":634,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi\" - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/","og_locale":"it_IT","og_type":"article","og_title":"#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi\"","og_description":"Valery e Alessandro, oggi madre e padre del piccolo Natan, raccontano nel corso della puntata di \u201cA Sua Immagine\u201d di domenica 30 aprile la loro storia di adozione con Ai.Bi. in Cina. Un cammino fatto di molti ostacoli e prove per arrivare alla gioia di cui oggi sono testimoni.\u00a0\u201cNatan \u00e8 nostro figlio al 100%. E\u2019 il primo dei figli che Dio da sempre ha pensato per noi\u201d.","og_url":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-05-02T16:19:24+00:00","article_modified_time":"2017-05-02T16:19:45+00:00","og_image":[{"width":634,"height":406,"url":"https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi&#8221;","datePublished":"2017-05-02T16:19:24+00:00","dateModified":"2017-05-02T16:19:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/"},"wordCount":92,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news.jpg","articleSection":["AiBiNews","Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/","url":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/","name":"#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news.jpg","datePublished":"2017-05-02T16:19:24+00:00","dateModified":"2017-05-02T16:19:45+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/foto-famiglia-a-sua-immagine-news.jpg","width":634,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozioneunacosameravigliosa-natan-e-il-primo-dei-figli-che-dio-da-sempre-ha-pensato-per-la-nostra-famiglia-anche-se-non-nato-da-noi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"#adozioneunacosameravigliosa \u201cNatan \u00e8 il primo dei figli che Dio da sempre ha pensato per la nostra famiglia, anche se non nato da noi&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:29:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/140966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=140966"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/140966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/141005"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=140966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=140966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=140966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}