﻿


{"id":141494,"date":"2017-05-15T17:24:54","date_gmt":"2017-05-15T15:24:54","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=141494"},"modified":"2017-05-17T19:06:46","modified_gmt":"2017-05-17T17:06:46","slug":"adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/","title":{"rendered":"Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-141526 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina.jpg\" alt=\"\" width=\"400\" height=\"286\" data-id=\"141526\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Una nuova vita \u00e8 iniziata nel giorno della Festa della Mamma per 5 famiglie <\/strong>che sabato 13 maggio <strong>sono atterrate nei vari aeroporti italiani con i loro bambini.<\/strong> Nord, centro, sud e isole italiane si sono infatti ritrovati <strong>a Pechino nel nome dell\u2019accoglienza<\/strong>: sono volati alla volta della Cina a fine aprile dove sono andati a prendere i loro nuovi figli e tornati due giorni fa. <strong>Amici dei Bambini ha, cos\u00ec, portato altre 5 coppie in Estremo Oriente<\/strong> per completare il lungo e affascinante percorso dell\u2019adozione internazionale.<\/p>\n<p>Quattro di queste coppie sono partite il 21 aprile alla volta di <strong>Xi\u2019An<\/strong>, dove si trova l\u2019istituto con il quale prosegue il positivo rapporto di collaborazione con Ai.Bi. Sono partite <strong>dall\u2019Abruzzo, dalla Sicilia, dall\u2019Emilia Romagna e dalla Campania<\/strong> e nel pomeriggio di domenica 23 hanno abbracciato i loro figli. Un maschietto e 3 femminucce, tutti piccolini, nati nel 2015, che, fin da poco dopo la loro nascita, attendevano di poter tornare a sentirsi figli. <strong>Un diritto che finalmente viene loro restituito<\/strong> proprio da queste 4 coppie che hanno scelto <strong>Ai.Bi. per essere accompagnate all\u2019incontro con i loro figli<\/strong>.<\/p>\n<p>Una di loro, la bambina adottata dalla coppia di Salerno, al suo ritorno in Italia ha trovato ad aspettarla anche <strong>una sorellina sua connazionale<\/strong>. I suoi genitori, infatti, avevano gi\u00e0 accolto una bambina cinese <strong>nel 2014<\/strong>, <strong>dopo aver letto di lei nella nostra rubrica Figli in Attesa<\/strong>. E pochi anni dopo <strong>hanno scelto di nuovo Ai.Bi. per ridare una famiglia a un altro bambino abband<\/strong>onato e bisognoso di amore e di cure.<\/p>\n<p>A distanza di 24 ore da questo primo gruppo di 4 coppie, e precisamente il 22 aprile, <strong>altri 2 genitori italiani si sono imbarcati alla volta della Cina per incontrare il proprio figlio<\/strong>. Si tratta di un\u2019altra coppia della Campania, pronta ad accogliere un maschietto un po\u2019 pi\u00f9 grande, che a settembre compir\u00e0 7 anni.<\/p>\n<p>La loro meta per\u00f2, a differenza delle altre 4 coppie, non \u00e8 stata Xi\u2019An. <strong>Il loro bambino infatti li aspettava a Guanzhou, nella regione del Guandong.<\/strong><\/p>\n<p>Le strade delle 5 coppie in partenza si sono riunite poi <strong>sabato<\/strong> <strong>29 a Pechino<\/strong>. Come sempre, infatti, il <strong>viaggio in Cina<\/strong> delle coppie adottive ha previsto <strong>una permanenza di 3 settimane<\/strong>: la prima nel luogo in cui i bambini hanno vissuto fino a quel momento e le ultime 2 a Pechino.<\/p>\n<p>Qui \u00e8 presente una dottoressa che, di prassi, visita tutti i bambini e resta a disposizione per eventuali imprevisti. Ma la permanenza <strong>nella capitale cinese \u00e8 soprattutto una grande e prolungata festa<\/strong>, che permette a genitori e figli di conoscersi meglio e di iniziare a vivere le dinamiche e le emozioni della vita famigliare, oltre a fare amicizia anche con le altre coppie. Non mancano mai le <strong>escursioni turistiche<\/strong>, per le quali grandi e piccoli sono sempre accompagnati dal personale di Ai.Bi. e da una guida del Blas, (Bridge of Love Adoption Services), un\u2019agenzia che si occupa di viaggi e traduzione di documenti tra la Cina e il resto del mondo.<\/p>\n<p>Al ritorno in Italia di queste famiglie<strong>, sono gi\u00e0 10 i bambini cinesi adottati con Ai.Bi. nel 2017.<\/strong> Si conferma quindi la <strong>tradizione positiva che fa del Paese dell\u2019Estremo Oriente uno dei principali Paesi di origine dei piccoli accolti con Ai.Bi<\/strong>.<\/p>\n<p>Non a caso, infatti, negli ultimi 4 anni dal 2013 al 2016, la Cina ha sempre primeggiato in questa speciale classifica, con un totale di 165 minori adottati e un picco di 59 nel 2013.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una nuova vita \u00e8 iniziata per 5 famiglie che sabato scorso sono atterrate nei vari aeroporti italiani con i loro bambini. Sono volati alla volta della Cina a fine aprile dove sono andati a prendere i loro nuovi figli e tornati due giorni fa. Ai.Bi. ha, cos\u00ec, portato altre 5 coppie in Estremo Oriente per completare il lungo e affascinante percorso dell\u2019adozione internazionale<\/p>\n","protected":false},"author":61,"featured_media":141526,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172,71],"tags":[],"class_list":["post-141494","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita\" \/>\n<meta property=\"og:description\" content=\"Una nuova vita \u00e8 iniziata per 5 famiglie che sabato scorso sono atterrate nei vari aeroporti italiani con i loro bambini. Sono volati alla volta della Cina a fine aprile dove sono andati a prendere i loro nuovi figli e tornati due giorni fa. Ai.Bi. ha, cos\u00ec, portato altre 5 coppie in Estremo Oriente per completare il lungo e affascinante percorso dell\u2019adozione internazionale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-15T15:24:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-17T17:06:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita\",\"datePublished\":\"2017-05-15T15:24:54+00:00\",\"dateModified\":\"2017-05-17T17:06:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/\"},\"wordCount\":584,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-internazionale-cina.jpg\",\"articleSection\":[\"Adozione Internazionale\",\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/\",\"name\":\"Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-internazionale-cina.jpg\",\"datePublished\":\"2017-05-15T15:24:54+00:00\",\"dateModified\":\"2017-05-17T17:06:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-internazionale-cina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/adozione-internazionale-cina.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita","og_description":"Una nuova vita \u00e8 iniziata per 5 famiglie che sabato scorso sono atterrate nei vari aeroporti italiani con i loro bambini. Sono volati alla volta della Cina a fine aprile dove sono andati a prendere i loro nuovi figli e tornati due giorni fa. Ai.Bi. ha, cos\u00ec, portato altre 5 coppie in Estremo Oriente per completare il lungo e affascinante percorso dell\u2019adozione internazionale","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-05-15T15:24:54+00:00","article_modified_time":"2017-05-17T17:06:46+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita","datePublished":"2017-05-15T15:24:54+00:00","dateModified":"2017-05-17T17:06:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/"},"wordCount":584,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina.jpg","articleSection":["Adozione Internazionale","AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/","name":"Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina.jpg","datePublished":"2017-05-15T15:24:54+00:00","dateModified":"2017-05-17T17:06:46+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/adozione-internazionale-cina.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-ben-tornate-famiglie-di-ai-bi-per-festa-della-mamma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. Cina, ben tornate famiglie di Ai.Bi. ! Nel giorno della Festa della Mamma per 5 bambini \u00e8 iniziata una nuova vita"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:01:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/141494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=141494"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/141494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/141526"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=141494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=141494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=141494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}