﻿


{"id":142517,"date":"2017-06-07T18:59:11","date_gmt":"2017-06-07T16:59:11","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=142517"},"modified":"2018-01-25T11:49:31","modified_gmt":"2018-01-25T10:49:31","slug":"perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/","title":{"rendered":"Perch\u00e9 per l&#8217;adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25?"},"content":{"rendered":"<p><strong>Gentili operatori di Ai.Bi.,<\/strong><\/p>\n<p><strong>ho dato uno sguardo ai vostri progetti di Adozione a Distanza e di Sostegno a Distanza. Avrei il desiderio di avviare un contributo a favore di uno o pi\u00f9 bambini abbandonati che vivono in istituto. Ho visto che, a seconda della forma di sostegno scelta, l\u2019importo della quota da versare \u00e8 diversa. Vorrei capire come viene impiegata tale quota e quali sono le differenze nell\u2019utilizzo di questa somma a seconda che si scelga l\u2019adozione a distanza o il sostegno a distanza.<\/strong><\/p>\n<p><strong>Grazie per la preziosa informazione.<\/strong><\/p>\n<p><strong>Lucia<\/strong><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-142523 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg\" alt=\"\" width=\"400\" height=\"286\" data-id=\"142523\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg 400w, https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286-150x107.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286-300x215.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286-77x55.jpg 77w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Ciao Lucia,<\/p>\n<p>intanto grazie per la sensibilit\u00e0 e l\u2019attenzione che rivolgi a questa meravigliosa forma di aiuto nei confronti di bambini che meno fortunati possono essere aiutati con un semplice gesto da parte tua e nostra.<\/p>\n<p>Per rispondere alla tua domanda, puoi scegliere tra <strong>due tipi<\/strong> di sostegno continuativo a distanza: l\u2019 <a href=\"https:\/\/www.aibi.it\/adozioneadistanza\/\">adotta un bambino a distanza<\/a> e il <a href=\"https:\/\/www.aibi.it\/adozioneadistanza\/\">adotta un bambino a distanza<\/a><\/p>\n<p><strong>Con l\u2019adozione a distanza<\/strong> avrai la possibilit\u00e0 di creare un rapporto personalizzato ed esclusivo con un bambino. Ci\u00f2 vuol dire che sarai l\u2019unico e il solo a sostenere quel bambino e <strong>con un contributo di 50 euro al mese<\/strong> provvederai a tutti i suoi bisogni (vitto, istruzione, assistenza medica, vestiti, giochi ecc.) testimoniati da un\u2019 effettiva possibilit\u00e0 di comunicare con lui\/lei, ricevendo foto e aggiornamenti sul suo percorso di crescita.<\/p>\n<p>Subito dopo l\u2019attivazione, ti invieremo via e-mail il kit del sostenitore con tutte le informazioni relative alla tua adozione a distanza (lettera di attivazione del sostegno, scheda di presentazione del bambino con una sua fotografia, opuscoli informativi) e ti saranno fornite le credenziali per accedere alla nostra esclusiva area riservata, una grande finestra on line da aprire ogni volta che lo desideri, per essere sempre aggiornata sul tuo bambino adottato a distanza, inoltre potrai consultare tutte le donazioni da te effettuate e scaricare le note di riepilogo utili ai fini delle detrazioni fiscali. Periodicamente riceverai via e-mail gli aggiornamenti sul tuo bambino e potremo restare sempre in contatto, per qualsiasi informazione di cui tu abbia bisogno, utilizzando la posta elettronica.<\/p>\n<p><strong>La seconda opzione consiste nel Sostegno a Distanza<\/strong>, con il quale non sosterrai specificatamente un bambino, ma un\u2019intera comunit\u00e0, partecipando alle attivit\u00e0 progettuali di Ai.Bi. per i minori nei vari istituti nel mondo. Con un contributo di <strong>25 euro mensili<\/strong>, potrai contribuire al sostegno di tutti i bambini presenti negli istituti.<\/p>\n<p>Ai.Bi destiner\u00e0, con la massima trasparenza, l\u201980% dell\u2019importo della quota mensile al bambino qualora si tratti di Adozione a Distanza o al centro, qualora si decida di intraprendere il Sostegno a Distanza; il restante 20% sar\u00e0 una fondamentale quota utilizzata in Italia per le campagne di sensibilizzazione, facendo rientrare le spese operative di gestione.<\/p>\n<p>Non esitare, dunque, a contattarci per ulteriori informazioni, saremo ben felici di rispondere alle tue domande! Puoi farlo scrivendoci all\u2019indirizzo sad@aibi.it oppure chiamandoci al numero 02.98822372<\/p>\n<p>Un caro saluto,<\/p>\n<p>Ufficio Adozione e Sostegno a Distanza<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Avrei il desiderio di avviare un contributo a favore di uno o pi\u00f9 bambini abbandonati che vivono in istituto. Ho visto che, a seconda della forma di sostegno scelta, l\u2019importo della quota da versare \u00e8 diversa. Vorrei capire come viene impiegata tale quota e quali sono le differenze nell\u2019utilizzo di questa somma a seconda che si scelga l\u2019adozione a distanza o il sostegno a distanza.<\/p>\n","protected":false},"author":61,"featured_media":142523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,50],"tags":[],"class_list":["post-142517","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-lettere-al-direttore"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Perch\u00e9 per l&#039;adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch\u00e9 per l&#039;adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25?\" \/>\n<meta property=\"og:description\" content=\"Avrei il desiderio di avviare un contributo a favore di uno o pi\u00f9 bambini abbandonati che vivono in istituto. Ho visto che, a seconda della forma di sostegno scelta, l\u2019importo della quota da versare \u00e8 diversa. Vorrei capire come viene impiegata tale quota e quali sono le differenze nell\u2019utilizzo di questa somma a seconda che si scelga l\u2019adozione a distanza o il sostegno a distanza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-07T16:59:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-25T10:49:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Perch\u00e9 per l&#8217;adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25?\",\"datePublished\":\"2017-06-07T16:59:11+00:00\",\"dateModified\":\"2018-01-25T10:49:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/\"},\"wordCount\":515,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg\",\"articleSection\":[\"AiBiNews\",\"Lettere al direttore\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/\",\"name\":\"Perch\u00e9 per l'adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg\",\"datePublished\":\"2017-06-07T16:59:11+00:00\",\"dateModified\":\"2018-01-25T10:49:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg\",\"width\":400,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Perch\u00e9 per l&#8217;adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Perch\u00e9 per l'adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25? - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/","og_locale":"it_IT","og_type":"article","og_title":"Perch\u00e9 per l'adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25?","og_description":"Avrei il desiderio di avviare un contributo a favore di uno o pi\u00f9 bambini abbandonati che vivono in istituto. Ho visto che, a seconda della forma di sostegno scelta, l\u2019importo della quota da versare \u00e8 diversa. Vorrei capire come viene impiegata tale quota e quali sono le differenze nell\u2019utilizzo di questa somma a seconda che si scelga l\u2019adozione a distanza o il sostegno a distanza.","og_url":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-06-07T16:59:11+00:00","article_modified_time":"2018-01-25T10:49:31+00:00","og_image":[{"width":400,"height":286,"url":"https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Perch\u00e9 per l&#8217;adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25?","datePublished":"2017-06-07T16:59:11+00:00","dateModified":"2018-01-25T10:49:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/"},"wordCount":515,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg","articleSection":["AiBiNews","Lettere al direttore"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/","url":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/","name":"Perch\u00e9 per l'adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg","datePublished":"2017-06-07T16:59:11+00:00","dateModified":"2018-01-25T10:49:31+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/lettera-al-direttore-sostegno-a-distanza_400x286.jpg","width":400,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/perche-per-ladozione-a-distanza-la-quota-mensile-e-di-50-euro-mentre-per-il-sostegno-a-distanza-e-di-25-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Perch\u00e9 per l&#8217;adozione a distanza la quota mensile \u00e8 di 50 euro, mentre per il sostegno a distanza \u00e8 di 25?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:13:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/142517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=142517"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/142517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/142523"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=142517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=142517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=142517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}