﻿


{"id":143605,"date":"2017-07-05T17:38:08","date_gmt":"2017-07-05T15:38:08","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=143605"},"modified":"2017-07-05T17:38:08","modified_gmt":"2017-07-05T15:38:08","slug":"open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/","title":{"rendered":"Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d"},"content":{"rendered":"<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-143617 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406.jpg\" alt=\"\" width=\"634\" height=\"406\" data-id=\"143617\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406.jpg 634w, https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406-150x96.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406-300x192.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406-86x55.jpg 86w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>\u201c&#8230;in un tempo multi-connettivo e di esasperata socialit\u00e0, la quarta emergenza del XXI secolo \u00e8 l&#8217;abbandono (che fa rima con solitudine). La politica non pu\u00f2 dirigere il benessere familiare ma pu\u00f2 (anzi deve) creare condizioni, ambiente sociale in cui le famiglie possono fare esperienza di vita e di dono #ecologiaumana Le ACLI sede provinciale Salerno sostengono Ai.Bi Amici dei Bambini di Salerno e vi invitano all&#8217;open day #genitorialit\u00e0 #futuro #accoglienza #leAclicisono con Antonella Spadafora<\/em>\u201d. Questo il messaggio molto sensibile e accalorato di Gianluca Mastrovito, presidente Acli Salerno che condividiamo e ringraziamo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><em>\u201c&#8230;in un tempo multi-connettivo e di esasperata socialit\u00e0, la quarta emergenza del XXI secolo \u00e8 l&#8217;abbandono (che fa rima con solitudine). La politica non pu\u00f2 dirigere il benessere familiare ma pu\u00f2 (anzi deve) creare condizioni, ambiente sociale in cui le famiglie possono fare esperienza di vita e di dono #ecologiaumana Le ACLI sede provinciale Salerno sostengono Ai.Bi Amici dei Bambini di Salerno e vi invitano all&#8217;open day #genitorialit\u00e0 #futuro #accoglienza #leAclicisono con Antonella Spadafora<\/em>\u201d. Questo il messaggio molto sensibile e accalorato di Gianluca Mastrovito, presidente Acli Salerno che condividiamo e ringraziamo.<\/p>\n","protected":false},"author":61,"featured_media":143617,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,174],"tags":[],"class_list":["post-143605","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d\" \/>\n<meta property=\"og:description\" content=\"\u201c...in un tempo multi-connettivo e di esasperata socialit\u00e0, la quarta emergenza del XXI secolo \u00e8 l&#039;abbandono (che fa rima con solitudine). La politica non pu\u00f2 dirigere il benessere familiare ma pu\u00f2 (anzi deve) creare condizioni, ambiente sociale in cui le famiglie possono fare esperienza di vita e di dono #ecologiaumana Le ACLI sede provinciale Salerno sostengono Ai.Bi Amici dei Bambini di Salerno e vi invitano all&#039;open day #genitorialit\u00e0 #futuro #accoglienza #leAclicisono con Antonella Spadafora\u201d. Questo il messaggio molto sensibile e accalorato di Gianluca Mastrovito, presidente Acli Salerno che condividiamo e ringraziamo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-05T15:38:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d\",\"datePublished\":\"2017-07-05T15:38:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/\"},\"wordCount\":127,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Fotonotizia-mastrovito_634x406.jpg\",\"articleSection\":[\"AiBiNews\",\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/\",\"name\":\"Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Fotonotizia-mastrovito_634x406.jpg\",\"datePublished\":\"2017-07-05T15:38:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Fotonotizia-mastrovito_634x406.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Fotonotizia-mastrovito_634x406.jpg\",\"width\":634,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/","og_locale":"it_IT","og_type":"article","og_title":"Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d","og_description":"\u201c...in un tempo multi-connettivo e di esasperata socialit\u00e0, la quarta emergenza del XXI secolo \u00e8 l'abbandono (che fa rima con solitudine). La politica non pu\u00f2 dirigere il benessere familiare ma pu\u00f2 (anzi deve) creare condizioni, ambiente sociale in cui le famiglie possono fare esperienza di vita e di dono #ecologiaumana Le ACLI sede provinciale Salerno sostengono Ai.Bi Amici dei Bambini di Salerno e vi invitano all'open day #genitorialit\u00e0 #futuro #accoglienza #leAclicisono con Antonella Spadafora\u201d. Questo il messaggio molto sensibile e accalorato di Gianluca Mastrovito, presidente Acli Salerno che condividiamo e ringraziamo.","og_url":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-07-05T15:38:08+00:00","og_image":[{"width":634,"height":406,"url":"https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d","datePublished":"2017-07-05T15:38:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/"},"wordCount":127,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406.jpg","articleSection":["AiBiNews","Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/","url":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/","name":"Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406.jpg","datePublished":"2017-07-05T15:38:08+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Fotonotizia-mastrovito_634x406.jpg","width":634,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/open-day-salerno-acli-salerno-sostiene-ai-bi-la-politica-crei-condizioni-in-cui-le-famiglie-facciano-esperienza-di-vita-e-di-dono\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Open day Salerno. ACLI Salerno sostiene Ai.Bi \u201cLa politica crei condizioni in cui le famiglie facciano esperienza di vita e di dono\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:29:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/143605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=143605"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/143605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/143617"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=143605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=143605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=143605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}