﻿


{"id":144956,"date":"2017-08-22T21:34:50","date_gmt":"2017-08-22T19:34:50","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=144956"},"modified":"2017-08-22T21:34:50","modified_gmt":"2017-08-22T19:34:50","slug":"papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/","title":{"rendered":"Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati."},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-144957 alignleft\" src=\"https:\/\/www.aibi.it\/ita\/images\/papa-francesco_400x286.jpg\" alt=\"\" width=\"400\" height=\"286\" data-id=\"144957\" \/>Riportiamo integralmente l\u2019articolo Gianmario Fogliazza\u00a0 di\u00a0<em>\u201cLa Pietra Scartata\u201d.<\/em><\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p>La Santa Sede ha reso noto oggi il messaggio di <strong>Papa\u00a0Francesco<\/strong>, firmato dal Santo Padre il 15 Agosto u.s., per la <a href=\"https:\/\/w2.vatican.va\/content\/francesco\/it\/messages\/migration\/documents\/papa-francesco_20170815_world-migrants-day-2018.html#_ftn2\"><strong>104^\u00a0Giornata Mondiale del Migrante e del Rifugiato<\/strong> <\/a>che sar\u00e0 celebrata dalla Chiesa\u00a0il 14 gennaio 2018.<\/p>\n<p>Il titolo del Messaggio richiama quattro azioni, sollecitudini, premure\u00a0e sensibilit\u00e0 che vengono proposte da Papa Francesco il quale desidera cos\u00ec riaffermare che di fronte alle numerose sfide poste dalle migrazioni contemporanee, \u00ab<strong><em>la nostra comune risposta si potrebbe articolare attorno a quattro verbi fondati sui principi della dottrina della Chiesa: accogliere, proteggere, promuovere e integrare<\/em><\/strong>\u00bb. Richiamando cos\u00ec esplicitamente quanto gi\u00e0 affermato in occasione del suo discorso ai partecipanti al Forum internazionale \u201c<em>Migrazioni e Pace<\/em>\u201d (21 Febbraio 2017), Papa Francesco sottolinea che \u00ab<strong><em>ogni forestiero che bussa alla nostra porta \u00e8 un\u2019occasione di incontro con Ges\u00f9<\/em><\/strong><em> Cristo, il quale si identifica con lo straniero accolto o rifiutato di ogni epoca (cfr Mt 25,35.43). <strong>Il Signore affida all\u2019amore materno della Chiesa ogni essere umano costretto a lasciare la propria patria alla ricerca di un futuro migliore<\/strong>.<\/em>\u201c<\/p>\n<p>Si tratta di un\u2019attenzione chiamata ad esprimersi concretamente e coerentemente in ogni tappa dell\u2019esperienza migratoria (dalla partenza al viaggio, dall\u2019arrivo al ritorno),\u00a0una <strong>grande responsabilit\u00e0 che la Chiesa intende condividere coi credenti e con\u00a0le persone di buona volont\u00e0<\/strong>: tutti insieme, interpellati dagli eventi della storia, sono chiamati a rispondere alle numerose sfide poste dalle migrazioni \u00ab<em>con generosit\u00e0, alacrit\u00e0, saggezza e lungimiranza, ciascuno secondo le proprie possibilit\u00e0<\/em>\u00bb.<\/p>\n<p><strong>Accogliere<\/strong><\/p>\n<p><em>\u00ab<strong>Accogliere<\/strong><\/em> \u2013 afferma Papa Francesco \u2013 <strong><em>significa innanzitutto offrire a migranti e rifugiati possibilit\u00e0 pi\u00f9 ampie di ingresso sicuro e legale nei paesi di destinazione<\/em><\/strong>\u00bb.<\/p>\n<p><strong>Desiderabile<\/strong> per il Santo Padre\u00a0un concreto impegno per\u00a0incrementare e semplificare la concessione di visti umanitari e per il ricongiungimento familiare; <strong>auspicabile<\/strong> l\u2019adozione di programmi di <em>sponsorship<\/em> privata e comunitaria da parte di un numero maggiore di Paesi con l\u2019apertura di corridoi umanitari per i rifugiati pi\u00f9 vulnerabili.<\/p>\n<p><strong>Opportuna<\/strong> \u00e8 indicata la previsione di\u00a0visti temporanei speciali per le persone che scappano dai conflitti nei paesi confinanti; <strong>non idonea<\/strong> la soluzione che prevede\u00a0espulsioni collettive e arbitrarie di migranti e rifugiati, soprattutto quando esse vengono eseguite verso Paesi che non possono garantire il rispetto della dignit\u00e0 e dei diritti fondamentali. Papa Francesco ribadisce che\u00a0\u00ab<em>i programmi di accoglienza diffusa, gi\u00e0 avviati in diverse localit\u00e0, sembrano invece facilitare l\u2019incontro personale, permettere una migliore qualit\u00e0 dei servizi e offrire maggiori garanzie di successo<\/em>\u00bb.<\/p>\n<p>Atteso che il principio della <strong>centralit\u00e0 della persona umana<\/strong> ci obbliga ad anteporre sempre la sicurezza personale a quella nazionale, risulta doveroso garantire la sicurezza personale e l\u2019accesso ai servizi di base a migranti, richiedenti asilo e rifugiati.\u00a0\u00ab<strong><em>In nome della dignit\u00e0 fondamentale di ogni persona, occorre sforzarsi di preferire soluzioni alternative alla detenzione per coloro che entrano nel territorio nazionale senza essere autorizzati<\/em><\/strong>\u00bb.<\/p>\n<p><strong>Proteggere<\/strong><\/p>\n<p>Il secondo verbo, <em>proteggere<\/em>, si declina in diverse azioni in difesa dei diritti e della dignit\u00e0 dei migranti e dei rifugiati, indipendentemente dal loro <em>status<\/em> migratorio.<\/p>\n<p>Papa Francesco richiama la <strong>Convenzione internazionale sui diritti del fanciullo<\/strong> che offre una base giuridica universale per la <strong>protezione dei minori migranti<\/strong>: \u00ab<em>Ad essi occorre <strong>evitare ogni forma di detenzione<\/strong> in ragione del loro status migratorio, mentre va assicurato l\u2019accesso regolare all\u2019istruzione primaria e secondaria. Parimenti \u00e8 necessario garantire la permanenza regolare al compimento della maggiore et\u00e0 e la possibilit\u00e0 di continuare degli studi. <strong>Per i minori non accompagnati o separati dalla loro famiglia \u00e8 importante prevedere programmi di custodia temporanea o affidamento<\/strong><\/em>\u00bb.<\/p>\n<p>Per il Santo Padre la nazionalit\u00e0 dovrebbe essere\u00a0riconosciuta e opportunamente certificata a tutti i bambini e le bambine al momento della nascita.<\/p>\n<p><strong>Promuovere<\/strong><\/p>\n<p>\u00ab<em>Promuovere <\/em>\u2013 sottolinea Papa Francesco \u2013 <em>vuol dire adoperarsi affinch\u00e9 tutti i migranti e i rifugiati cos\u00ec come le comunit\u00e0 che li accolgono, siano messi in condizione di <strong>realizzarsi come persone<\/strong> in tutte le dimensioni<\/em>\u00bb.<\/p>\n<p>Tra queste deve essere riconosciuto il <strong>giusto valore alla dimensione religiosa<\/strong>, garantendo a tutti gli stranieri presenti sul territorio la libert\u00e0 di professione e pratica religiosa.<\/p>\n<p>Occorre sempre <strong>promuovere l\u2019integrit\u00e0 della famiglia <\/strong>nel contesto migratorio \u00ab<strong><em>favorendo il ricongiungimento familiare senza mai farlo dipendere da requisiti economici<\/em><\/strong>\u00bb.<\/p>\n<p>Inoltre,\u00a0migranti e rifugiati hanno competenze che vanno adeguatamente certificate e valorizzate; se\u00a0\u201cil lavoro umano per sua natura \u00e8 destinato ad unire i popoli\u201d, Papa Francesco incoraggia a \u00ab<em>prodigarsi affinch\u00e9 venga promosso l\u2019inserimento socio-lavorativo di migranti e rifugiati, garantendo a tutti\u00a0la possibilit\u00e0 di lavorare<\/em>\u00bb assicurando che sia <strong>regolamentato\u00a0\u00a0il coinvolgimento in attivit\u00e0 lavorative dei minori migranti\u00a0al fine di\u00a0prevenire abusi e minacce<\/strong> alla loro normale crescita.<\/p>\n<p><strong>Integrare<\/strong><\/p>\n<p>La crescente presenza di migranti genera al contempo opportunit\u00e0 di arricchimento interculturale. \u00ab<em>L\u2019integrazione<\/em> \u2013 affermava San Giovanni Paolo II per la medesima occasione nel 2005 \u2013 <em>non<\/em> \u00e8 <em>un\u2019assimilazione, che induce a sopprimere o a dimenticare la propria identit\u00e0 culturale. Il contatto con l\u2019altro porta piuttosto a scoprirne il \u201csegreto\u201d, ad aprirsi a lui per accoglierne gli aspetti validi e contribuire cos\u00ec ad una maggior conoscenza reciproca. \u00c8 un processo prolungato che mira a formare societ\u00e0 e culture, rendendole sempre pi\u00f9 riflesso dei multiformi doni di Dio agli uomini<\/em>\u00bb. Per consentire tale processo viene suggerita\u00a0l\u2019offerta di cittadinanza slegata da requisiti economici e linguistici e di percorsi di regolarizzazione straordinaria per migranti che possano vantare una lunga permanenza in un Paese. Papa Francesco insiste sulla \u00ab<em>necessit\u00e0 di favorire in ogni modo la cultura dell\u2019incontro, moltiplicando le opportunit\u00e0 di scambio interculturale, documentando e diffondendo le buone pratiche di integrazione e sviluppando programmi tesi a preparare le comunit\u00e0 locali ai processi integrativi\u00bb.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riportiamo integralmente l&rsquo;articolo Gianmario Fogliazza&nbsp; di&nbsp;&ldquo;La Pietra Scartata&rdquo;. &nbsp; La Santa Sede ha reso noto oggi il messaggio di Papa&nbsp;Francesco, firmato dal Santo Padre il 15 Agosto u.s., per la 104^&nbsp;Giornata Mondiale del Migrante e del Rifugiato che sar&agrave; celebrata dalla Chiesa&nbsp;il 14 gennaio 2018. Il titolo del Messaggio richiama [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":144957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-144956","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati.\" \/>\n<meta property=\"og:description\" content=\"Riportiamo integralmente l&rsquo;articolo Gianmario Fogliazza&nbsp; di&nbsp;&ldquo;La Pietra Scartata&rdquo;. &nbsp; La Santa Sede ha reso noto oggi il messaggio di Papa&nbsp;Francesco, firmato dal Santo Padre il 15 Agosto u.s., per la 104^&nbsp;Giornata Mondiale del Migrante e del Rifugiato che sar&agrave; celebrata dalla Chiesa&nbsp;il 14 gennaio 2018. Il titolo del Messaggio richiama [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-22T19:34:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati.\",\"datePublished\":\"2017-08-22T19:34:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/\"},\"wordCount\":924,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/\",\"name\":\"Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2017-08-22T19:34:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati. - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/","og_locale":"it_IT","og_type":"article","og_title":"Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati.","og_description":"Riportiamo integralmente l&rsquo;articolo Gianmario Fogliazza&nbsp; di&nbsp;&ldquo;La Pietra Scartata&rdquo;. &nbsp; La Santa Sede ha reso noto oggi il messaggio di Papa&nbsp;Francesco, firmato dal Santo Padre il 15 Agosto u.s., per la 104^&nbsp;Giornata Mondiale del Migrante e del Rifugiato che sar&agrave; celebrata dalla Chiesa&nbsp;il 14 gennaio 2018. Il titolo del Messaggio richiama [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-08-22T19:34:50+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati.","datePublished":"2017-08-22T19:34:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/"},"wordCount":924,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/#primaryimage"},"thumbnailUrl":"","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/","url":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/","name":"Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/#primaryimage"},"thumbnailUrl":"","datePublished":"2017-08-22T19:34:50+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/papa-francesco-accogliere-proteggere-promuovere-integrare-migranti-rifugiati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Papa Francesco: accogliere, proteggere, promuovere e integrare migranti e rifugiati."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 01:51:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/144956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=144956"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/144956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=144956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=144956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=144956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}