﻿


{"id":145079,"date":"2017-08-28T16:46:01","date_gmt":"2017-08-28T14:46:01","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=145079"},"modified":"2017-08-28T16:46:01","modified_gmt":"2017-08-28T14:46:01","slug":"adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/","title":{"rendered":"Adozione internazionale. Cina, Liang &#8220;Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre&#8221;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-145106 size-full\" src=\"https:\/\/www.aibi.it\/ita\/images\/io-sono-un-dono-cina_400x286.jpg\" alt=\"\" width=\"400\" height=\"286\" data-id=\"145106\" \/>\u201c<strong><em>Sono passati gi\u00e0 tre anni?<\/em>\u201d,<\/strong> spesso mi sento dire da amici o parenti. \u201c<em>S\u00ec, e li ho sentiti proprio tutti<\/em>\u201d, rispondo, tra espressioni sconcertate di chi pensa di aver fatto una gaffe. \u201c<em>Niente affatto, non fraintendiamo: <strong>l\u2019adozione di nostro figlio<\/strong> &#8211; che oggi ha 8 anni e mezzo &#8211; <strong>procede bene<\/strong> ma sarebbe una bugia dover descrivere gli ultimi tre anni dipinti di rosa<\/em>\u201d. A parlare a cuore aperto \u00e8 Francesca, di Milano e mamma adottiva di Liang (<em>nome di fantasia ndr<\/em>) .<\/p>\n<p>Ogni settimana <strong>la rubrica #iosonoundono propone storie di famiglie adottive <\/strong>rientrate da ogni Paese del mondo:\u00a0 <strong>prevale, come \u00e8 naturale, la gioia di essere diventati famiglia<\/strong> grazie a un bambino che, malgrado la sua sofferenza, <strong>\u00e8 stato\u00a0 in grado di far rifiorire la vita<\/strong>.<\/p>\n<p>Ma non c\u2019\u00e8 famiglia che, a qualche anno di distanza, non racconti <strong>anche le fatiche di crescere loro figlio <\/strong>che, non dimentichiamolo, <strong>porta con s\u00e9 il trauma dell\u2019abbandono<\/strong>.<\/p>\n<p>\u201c<strong><em>Essere adottivi \u00e8 una condizione, uno stato dell\u2019anima e dell\u2019esistenza<\/em><\/strong> &#8211; \u00a0precisa Francesca &#8211; <em>ci auguriamo che <strong>questi appunti sparsi<\/strong> possano far comprendere cosa voglia dire, in concreto, vivere tutti insieme l\u2019adozione, nel nostro caso da quel giorno di fine giugno 2014\u201d. <\/em><\/p>\n<p><strong>E cos\u00ec Francesca raccoglie e ci confida ricordi ed emozioni \u201ccatalogandoli\u201d in \u201cappunti tematici\u201d.<\/strong><\/p>\n<p><u>Mezzi di trasporto<\/u> \u2013 \u201c<em>Siamo diventati <strong>famiglia prendendo voli intercontinentali,<\/strong> voli interni alla Cina, autobus, metropolitane, taxi. <strong>La sala parto, per cos\u00ec dire, \u00e8 stato una salone comunitario <\/strong>dove uomini e donne di vari Paesi del mondo vivevano <strong>il loro travaglio, cessato solo quando tanti bambini sono entrati in braccio o accompagnati da tate<\/strong> che, nel giro di 10 minuti, hanno ringraziato e arrivederci. <strong>Noi, con quei bambini impauriti l\u00ec davanti, a simulare tranquillit\u00e0<\/strong><\/em><strong>\u201d.<\/strong><\/p>\n<p>Abbondanza di mezzi di trasporto anche per arrivare in Italia dove l\u2019adozione \u00e8 iniziata sul serio. \u201c<em>Il primo anno mi sentivo perennemente sotto un treno \u2013 <\/em>racconta &#8211;<em> , il secondo sotto un tram, il terzo sotto un autobus o veicolo simile. Questo per dire che, al netto di tutto quello che di bello c\u2019\u00e8 in una adozione, si sente la fatica di accompagnare un bambino di quasi 6 anni; fatica che si stempera man mano che il ragazzino acquisisce certezze e autonomia<\/em>. <em>E non parlo della normale vita di un figlio che va all\u2019asilo, poi a scuola, ha impegni sportivi e sociali: questo c\u2019\u00e8 stato e, per fortuna, nel nostro caso non ha generato difficolt\u00e0. <strong>Pi\u00f9 impegnativo \u00e8 stato invece vivere faccia a faccia con il suo abbandono <\/strong>che, con varie modalit\u00e0 e espedienti, \u00e8 emerso nella quotidianit\u00e0 dei tre anni\u201d<\/em>.<\/p>\n<p>\u201c<em>Per questo siamo stati <strong>preparati e accompagnati da Ai.Bi \u2013 <\/strong><\/em>precisa Francesca<strong><em> -: senza la formazione e il supporto degli esperti<\/em><\/strong><em> sarebbe stato complicato e forse avremmo commesso errori importanti per nostri figlio. Insomma, esperienza bellissima e sfiancante, per tutti. Per i genitori pu\u00f2 esserci anche un leggero ringiovanimento e il recupero del peso forma a causa di frequenti rincorse dietro al suo monopattino. <strong>Per nostro figlio: tanta fatica, molta rielaborazione del passato, tanta felicit\u00e0 per essere riuscito a superare gli ostacoli. <\/strong>Questa estate, durante una gita in barca in cui non ha smesso di sorridere e divertirsi ha detto: <strong>\u201cSto proprio bene!\u201d. In definitiva: si pu\u00f2 fare\u201d.<\/strong><\/em><\/p>\n<p><strong><u>L&#8217;italiano nato in Cina &#8211;<\/u><\/strong> <em>Non passa giorno che nostro figlio non si senta in un certo senso sdoppiato: <strong>italiano s\u00ec, non solo perch\u00e9 lo \u00e8 diventato all\u2019istante con l\u2019adozione,<\/strong> perch\u00e9 vive in Italia, perch\u00e9 ormai <strong>parla con inflessione lombarda<\/strong> e come ogni milanese <strong>sale sulla sinistra delle scale mobili<\/strong> della metropolitana per conquistare l\u2019uscita. <strong>Ma cinese sempre<\/strong>: non solo per i suoi tratti somatici ma anche perch\u00e9 quasi 6 anni di vita in Cina sono una vita per un bambino. Ad oggi lui ha vissuto pi\u00f9 in Cina che con noi. <strong>La lingua italiana \u00e8 stata accolta solo quando anche io sono stata scelta definitivamente come madre,<\/strong> quasi un anno dopo il rientro dalla Cina\u201d. <\/em><\/p>\n<p><em>\u00a0<\/em><em>\u201cSolo negli ultimi mesi \u00e8 subentrato <strong>l\u2019interesse per il dialetto lombardo<\/strong>: il brano del quartetto Cetra \u201cCrapapelada\u201d va per la maggiore, ma anche Jannacci non dispiace.\u00a0 <strong>Se va in crisi o i suoi fantasmi del passato riaffiorano, \u00e8 il cibo cinese che lo conforta.<\/strong> Perfino quello <strong>cucinato da me<\/strong> che deve essere come per noi gli spaghetti al pomodori cucinati in Svezia. <strong>Sono le foto o i ricordi della nostra vita insieme in Cina\u00a0 a fargli riannodare le fila della matassa ingarbugliata<\/strong>; \u00e8 il pensiero di poter un giorno tornare a salutare le persone dell\u2019istituto e della casa famiglia in cui \u00e8 vissuto a placare il suo animo tormentato\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Francesca e Luca hanno adottato 3 anni fa il piccolo Liang dalla Cina. Quello che segue \u00e8 il racconto di Francesca che confida gioia e impegno che l\u2019adozione richiede.\u00a0\u201c<strong><em>Essere adottivi \u00e8 una condizione, uno stato dell\u2019anima e dell\u2019esistenza<\/em><\/strong> &#8211; \u00a0precisa Francesca &#8211; <em>ci auguriamo che <strong>questi appunti sparsi<\/strong> possano far comprendere cosa voglia dire, in concreto, vivere tutti insieme l\u2019adozione, nel nostro caso da quel giorno di fine giugno 2014\u201d.\u00a0<\/em><strong>E cos\u00ec Francesca raccoglie e ci confida ricordi ed emozioni \u201ccatalogandoli\u201d in \u201cappunti tematici\u201d.<\/strong><\/p>\n","protected":false},"author":61,"featured_media":145105,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172,71],"tags":[],"class_list":["post-145079","post","type-post","status-publish","format-standard","has-post-thumbnail","category-adozione-internazionale","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adozione internazionale. Cina, Liang &quot;Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre&quot; - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adozione internazionale. Cina, Liang &quot;Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre&quot;\" \/>\n<meta property=\"og:description\" content=\"Francesca e Luca hanno adottato 3 anni fa il piccolo Liang dalla Cina. Quello che segue \u00e8 il racconto di Francesca che confida gioia e impegno che l\u2019adozione richiede.\u00a0\u201cEssere adottivi \u00e8 una condizione, uno stato dell\u2019anima e dell\u2019esistenza - \u00a0precisa Francesca - ci auguriamo che questi appunti sparsi possano far comprendere cosa voglia dire, in concreto, vivere tutti insieme l\u2019adozione, nel nostro caso da quel giorno di fine giugno 2014\u201d.\u00a0E cos\u00ec Francesca raccoglie e ci confida ricordi ed emozioni \u201ccatalogandoli\u201d in \u201cappunti tematici\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-28T14:46:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ufficio Stampa Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/\"},\"author\":{\"name\":\"Ufficio Stampa Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\"},\"headline\":\"Adozione internazionale. Cina, Liang &#8220;Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre&#8221;\",\"datePublished\":\"2017-08-28T14:46:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/\"},\"wordCount\":770,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Adozione Internazionale\",\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/\",\"name\":\"Adozione internazionale. Cina, Liang \\\"Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre\\\" - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2017-08-28T14:46:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adozione Internazionale\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/adozione-internazionale\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adozione internazionale. Cina, Liang &#8220;Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/514c6a2077023a1aa437fed4b1fbb26b\",\"name\":\"Ufficio Stampa Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/giorgia-governale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adozione internazionale. Cina, Liang \"Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre\" - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/","og_locale":"it_IT","og_type":"article","og_title":"Adozione internazionale. Cina, Liang \"Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre\"","og_description":"Francesca e Luca hanno adottato 3 anni fa il piccolo Liang dalla Cina. Quello che segue \u00e8 il racconto di Francesca che confida gioia e impegno che l\u2019adozione richiede.\u00a0\u201cEssere adottivi \u00e8 una condizione, uno stato dell\u2019anima e dell\u2019esistenza - \u00a0precisa Francesca - ci auguriamo che questi appunti sparsi possano far comprendere cosa voglia dire, in concreto, vivere tutti insieme l\u2019adozione, nel nostro caso da quel giorno di fine giugno 2014\u201d.\u00a0E cos\u00ec Francesca raccoglie e ci confida ricordi ed emozioni \u201ccatalogandoli\u201d in \u201cappunti tematici\u201d.","og_url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-08-28T14:46:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Ufficio Stampa Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Ufficio Stampa Ai.Bi.","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/"},"author":{"name":"Ufficio Stampa Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b"},"headline":"Adozione internazionale. Cina, Liang &#8220;Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre&#8221;","datePublished":"2017-08-28T14:46:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/"},"wordCount":770,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/#primaryimage"},"thumbnailUrl":"","articleSection":["Adozione Internazionale","AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/","url":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/","name":"Adozione internazionale. Cina, Liang \"Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre\" - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/#primaryimage"},"thumbnailUrl":"","datePublished":"2017-08-28T14:46:01+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/adozione-internazionale-cina-liang-ha-iniziato-a-parlare-in-italiano-solo-quando-anche-io-sono-stata-scelta-definitivamente-come-madre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Adozione Internazionale","item":"https:\/\/www.aibi.it\/ita\/category\/adozione-internazionale\/"},{"@type":"ListItem","position":3,"name":"Adozione internazionale. Cina, Liang &#8220;Ha iniziato a parlare in italiano solo quando anche io sono stata scelta definitivamente come madre&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/514c6a2077023a1aa437fed4b1fbb26b","name":"Ufficio Stampa Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/giorgia-governale\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-21 00:15:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/145079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=145079"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/145079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=145079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=145079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=145079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}