﻿{"id":14582,"date":"2010-07-08T18:29:10","date_gmt":"2010-07-08T17:29:10","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=14582"},"modified":"2010-07-08T18:29:10","modified_gmt":"2010-07-08T17:29:10","slug":"la-ruota-degli-esposti-un-pericolo-per-le-madri","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/","title":{"rendered":"La ruota degli esposti? Un pericolo per le madri"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/M.CavallocASC.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9999\" style=\"margin: 5px;\" title=\"M.CavallocASC\" src=\"https:\/\/www.aibi.it\/ita\/images\/M.CavallocASC.jpg\" alt=\"M.CavallocASC\" width=\"150\" height=\"150\" \/><\/a>\u00abLa culla termica? Una follia. Significa incoraggiare il fenomeno del parto in situazione di rischio, al di fuori di strutture ospedaliere attrezzate\u00bb. \u00c8 contraria la presidente del Tribunale dei minorenni Melita Cavallo, all&#8217; iniziativa della Farmacap di istallare una sorta di &#8220;Ruota degli innocenti&#8221; in una delle farmacie comunali della citt\u00e0.<\/p>\n<p>Si legge sul sito di Repubblica.it che pubblica un&#8217;intervista a Melita Cavallo.<\/p>\n<p><strong>Presidente, quale \u00e8 la ricetta per aiutare le donne che, una volta partorito, non se la sentono di essere le madri? <\/strong><\/p>\n<p>\u00abTanto per cominciare i soldi spesi per queste culle termiche andrebbero utilizzati per far sapere a tutti che negli ospedali si pu\u00f2 partorire in totale sicurezza e in totale anonimato.<\/p>\n<p><strong>Ma quanti sono i bambini abbandonati ogni anno nella capitale? <\/strong><\/p>\n<p>\u00abSono pochi. In tutta la regione nel 2009 sono stati 61, a Roma poco pi\u00f9 della met\u00e0. Da gennaio a d oggi 25 in tutto il Lazio\u00bb. C&#8217; \u00e8 una sorta di identikit di queste mamme costrettea un passo cos\u00ec doloroso? \u00abMolte sono extracomunitarie. Donne che non hanno possibilit\u00e0 economiche, non hanno casa n\u00e9 lavoro o non possono tornare nel loro paese con un bambino\u00bb.<\/p>\n<p><strong>Un bimbo lasciato in ospedale rispettando l&#8217; anonimato della madre, pu\u00f2 una volta adulto conoscere l&#8217; identit\u00e0 di chi l&#8217; ha partorito?<\/strong><\/p>\n<p>\u00abAttualmente non pu\u00f2; ma vi sono pi\u00f9 proposte di legge che consentono all&#8217; adottato non riconosciuto alla nascita, raggiunta un determinata et\u00e0 (40 anni), la possibilit\u00e0 di conoscere le sue origini. La Commissione Giustizia della Camera presieduta da Giulia Bongiorno ha fatto al riguardo pi\u00f9 audizioni di esperti, ed in questa sede ho ritenuto di proporre che alla madre sia richiesto, al momento del parto, se intende consentire al figlio biologico adottato, una volta adulto, di avere notizie sulla sua persona. Gi\u00e0 da subito, comunque, potrebbe esserle chiesto di lasciare agli atti notizie quali nazionalit\u00e0, et\u00e0, eventuali malattie genetiche e, ove possibile, i motivi dell&#8217; abbandono. In tal senso ho fatto, da alcuni mesi, apposita richiesta al Ministro della Salute\u00bb. Accade spesso che qualcuno adottato si rivolga al tribunale per sapere qualcosa sui genitori naturali? \u00abOggi \u00e8 riconosciuto questo diritto all&#8217; adottato, e le istanze inoltrate nello scorso anno 2009 sono state 43. Nessuno di loro ha mai espressamente chiesto il nome della madre, ma sempre il perch\u00e9 dell&#8217; abbandono e l&#8217; esistenza di fratelli o sorelle\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLa culla termica? Una follia. Significa incoraggiare il fenomeno del parto in situazione di rischio, al di fuori di strutture ospedaliere attrezzate\u00bb. \u00c8 contraria la presidente del Tribunale dei minorenni Melita Cavallo, all&#8217; iniziativa della Farmacap di istallare una sorta di &#8220;Ruota degli innocenti&#8221; in una delle farmacie comunali della citt\u00e0. <\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-14582","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La ruota degli esposti? Un pericolo per le madri - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ruota degli esposti? Un pericolo per le madri\" \/>\n<meta property=\"og:description\" content=\"\u00abLa culla termica? Una follia. Significa incoraggiare il fenomeno del parto in situazione di rischio, al di fuori di strutture ospedaliere attrezzate\u00bb. \u00c8 contraria la presidente del Tribunale dei minorenni Melita Cavallo, all&#039; iniziativa della Farmacap di istallare una sorta di &quot;Ruota degli innocenti&quot; in una delle farmacie comunali della citt\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-08T17:29:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/M.CavallocASC.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"La ruota degli esposti? Un pericolo per le madri\",\"datePublished\":\"2010-07-08T17:29:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/\"},\"wordCount\":389,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/M.CavallocASC.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/\",\"name\":\"La ruota degli esposti? Un pericolo per le madri - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/M.CavallocASC.jpg\",\"datePublished\":\"2010-07-08T17:29:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/M.CavallocASC.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/M.CavallocASC.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/la-ruota-degli-esposti-un-pericolo-per-le-madri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La ruota degli esposti? Un pericolo per le madri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La ruota degli esposti? Un pericolo per le madri - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/","og_locale":"it_IT","og_type":"article","og_title":"La ruota degli esposti? Un pericolo per le madri","og_description":"\u00abLa culla termica? Una follia. Significa incoraggiare il fenomeno del parto in situazione di rischio, al di fuori di strutture ospedaliere attrezzate\u00bb. \u00c8 contraria la presidente del Tribunale dei minorenni Melita Cavallo, all' iniziativa della Farmacap di istallare una sorta di \"Ruota degli innocenti\" in una delle farmacie comunali della citt\u00e0.","og_url":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-07-08T17:29:10+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/M.CavallocASC.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"La ruota degli esposti? Un pericolo per le madri","datePublished":"2010-07-08T17:29:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/"},"wordCount":389,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/M.CavallocASC.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/","url":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/","name":"La ruota degli esposti? Un pericolo per le madri - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/M.CavallocASC.jpg","datePublished":"2010-07-08T17:29:10+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/M.CavallocASC.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/M.CavallocASC.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/la-ruota-degli-esposti-un-pericolo-per-le-madri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"La ruota degli esposti? Un pericolo per le madri"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:51:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/14582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=14582"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/14582\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=14582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=14582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=14582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}