﻿


{"id":146909,"date":"2017-10-19T18:02:54","date_gmt":"2017-10-19T16:02:54","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=146909"},"modified":"2017-10-19T18:03:11","modified_gmt":"2017-10-19T16:03:11","slug":"casa-di-accoglienza-di-xian","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/","title":{"rendered":"Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-146910 aligncenter\" src=\"https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo.jpg\" alt=\"\" width=\"634\" height=\"406\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo.jpg 634w, https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo-150x96.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo-300x192.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo-86x55.jpg 86w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/p>\n<p>Nemmeno i forti temporali cinesi riescono a frenare le frenesia dei bambini della\u00a0<strong>Casa di Accoglienza \u201cVittorino Colombo\u201d di Xi\u2019An<\/strong>; anzi , l\u2019arrivo del freddo \u00e8 stata un\u2019ottima scusa per continuare a giocare all\u2019aria aperta: \u201c<strong><em>ma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?<\/em><\/strong>\u201d, ha chiesto Yun pochi giorni fa alla sua tata!<br \/>\nE allora via:\u00a0<strong>vestiti pesanti e\u2026 tutti fuori di corsa!<\/strong>\u00a0Dai pi\u00f9 grandi ai pi\u00f9 piccoli, tutti ad immergere i piedi nelle pozzanghere per scoprire quanto sono profonde!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nemmeno i forti temporali cinesi riescono a frenare le frenesia dei bambini della\u00a0<strong>Casa di Accoglienza \u201cVittorino Colombo\u201d di Xi\u2019An<\/strong>; anzi , l\u2019arrivo del freddo \u00e8 stata un\u2019ottima scusa per continuare a giocare all\u2019aria aperta: \u201c<strong><em>ma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?<\/em><\/strong>\u201d, ha chiesto Yun pochi giorni fa alla sua tata!<br \/>\nE allora via:\u00a0<strong>vestiti pesanti e\u2026 tutti fuori di corsa!<\/strong>\u00a0Dai pi\u00f9 grandi ai pi\u00f9 piccoli, tutti ad immergere i piedi nelle pozzanghere per scoprire quanto sono profonde!<\/p>\n","protected":false},"author":4,"featured_media":146910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,174],"tags":[],"class_list":["post-146909","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aibinews","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare? - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?\" \/>\n<meta property=\"og:description\" content=\"Nemmeno i forti temporali cinesi riescono a frenare le frenesia dei bambini della\u00a0Casa di Accoglienza \u201cVittorino Colombo\u201d di Xi\u2019An; anzi , l\u2019arrivo del freddo \u00e8 stata un\u2019ottima scusa per continuare a giocare all\u2019aria aperta: \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?\u201d, ha chiesto Yun pochi giorni fa alla sua tata! E allora via:\u00a0vestiti pesanti e\u2026 tutti fuori di corsa!\u00a0Dai pi\u00f9 grandi ai pi\u00f9 piccoli, tutti ad immergere i piedi nelle pozzanghere per scoprire quanto sono profonde!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-19T16:02:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-19T16:03:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?\",\"datePublished\":\"2017-10-19T16:02:54+00:00\",\"dateModified\":\"2017-10-19T16:03:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/\"},\"wordCount\":112,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/fotonotizia-bimbo.jpg\",\"articleSection\":[\"AiBiNews\",\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/\",\"name\":\"Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare? - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/fotonotizia-bimbo.jpg\",\"datePublished\":\"2017-10-19T16:02:54+00:00\",\"dateModified\":\"2017-10-19T16:03:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/fotonotizia-bimbo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/fotonotizia-bimbo.jpg\",\"width\":634,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/casa-di-accoglienza-di-xian\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare? - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/","og_locale":"it_IT","og_type":"article","og_title":"Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?","og_description":"Nemmeno i forti temporali cinesi riescono a frenare le frenesia dei bambini della\u00a0Casa di Accoglienza \u201cVittorino Colombo\u201d di Xi\u2019An; anzi , l\u2019arrivo del freddo \u00e8 stata un\u2019ottima scusa per continuare a giocare all\u2019aria aperta: \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?\u201d, ha chiesto Yun pochi giorni fa alla sua tata! E allora via:\u00a0vestiti pesanti e\u2026 tutti fuori di corsa!\u00a0Dai pi\u00f9 grandi ai pi\u00f9 piccoli, tutti ad immergere i piedi nelle pozzanghere per scoprire quanto sono profonde!","og_url":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-10-19T16:02:54+00:00","article_modified_time":"2017-10-19T16:03:11+00:00","og_image":[{"width":634,"height":406,"url":"https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?","datePublished":"2017-10-19T16:02:54+00:00","dateModified":"2017-10-19T16:03:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/"},"wordCount":112,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo.jpg","articleSection":["AiBiNews","Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/","url":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/","name":"Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare? - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo.jpg","datePublished":"2017-10-19T16:02:54+00:00","dateModified":"2017-10-19T16:03:11+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/fotonotizia-bimbo.jpg","width":634,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/casa-di-accoglienza-di-xian\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Casa di Accoglienza di Xi\u2019An \u201cma Mamma Liu, adesso che finalmente non fa pi\u00f9 caldo\u2026 perch\u00e8 non possiamo uscire a giocare?"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:38:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/146909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=146909"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/146909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/146910"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=146909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=146909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=146909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}