﻿{"id":14693,"date":"2010-07-14T17:20:01","date_gmt":"2010-07-14T16:20:01","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=14693"},"modified":"2010-07-14T17:20:01","modified_gmt":"2010-07-14T16:20:01","slug":"scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/","title":{"rendered":"Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall&#8217;Italia"},"content":{"rendered":"<p><a href=\"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-14694\" style=\"margin: 5px;\" title=\"Ai.Bi. - bambino in un istituto marocchino\" src=\"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg\" alt=\"Ai.Bi. - bambino in un istituto marocchino\" width=\"150\" height=\"150\" \/><\/a><strong>Avere accolto un figlio, ma non potere vivere con lui.<\/strong><\/p>\n<p>E\u2019 questo il dramma che riguarda una coppia mista residente nelle Marche che ha ottenuto in kafala Munir, un bambino egiziano, ma che non riesce a portarlo in Italia a vivere con s\u00e9 perch\u00e9 le autorit\u00e0 consolari italiane a <strong>Il Cairo hanno rifiutato cinque volte la richiesta di visto.<\/strong><\/p>\n<p>Di seguito il testo della lettera dei genitori di Munir: \u00a0un bambino orfano che l\u2019Italia non permette di fare entrare nel nostro Paese.<\/p>\n<p><em>\u201cSiamo una coppia sposata ormai da venti anni e abbiamo un bambino di 11. Mio marito e&#8217; di origine Egiziana con doppia cittadinanza, io sono Italiana. Per una pregressa malattia, non posso piu&#8217; avere altri figli. Cosi, nella totale convinzione di fare una cosa assolutamente bella e legale, abbiamo chiesto al Ministero degli Affari sociali dell&#8217;Egitto l&#8217;affido tramite kafala di un bambino orfano che, dopo i dovuti controlli patrimoniali, economici e psicologici, ci e&#8217; stato affidato.<\/em><\/p>\n<p><em>Abbiamo tentato 5 volte di presentare la richiesta di visto al Consolato Italiano al Cairo: trattati come dei farabutti. Alla fine, cosa odiosa ma necessaria, abbiamo chiesto l&#8217;intervento dell&#8217;unico amico &#8220;influente&#8221; che abbiamo e in due giorni i documenti erano al Ministero degli Esteri, dove a distanza  di un mese, sono ancora li, in attesa di decisione della Commissione Visti.<\/em><\/p>\n<p><em>Lei nella sua lettera ha parlato della situazione in Marocco, ma anche in Egitto, in Tunisia, in tanti paesi Musulmani i bambini orfani sono migliaia!<\/em><\/p>\n<p><em>Il nostro piccolo Munir ora si trova in orfanotrofio, non possiamo portarlo con noi e lui rischia di rimanere confinato in quel posto per sempre!<\/em><\/p>\n<p><em>Parlando con diversi avvocati esperti in materia, a noi sembra che il governo Italiano non solo violi delle Convenzioni internazionali come quella dei diritti sull&#8217;infanzia di New York, ma anche la stessa Costituzione che tutela tutti i cittadini di qualsiasi religione. Noi siamo Musulmani e ci viene vietata l&#8217;unico istituto legale  che ci permette l&#8217;affido di un bambino. Per noi Musulmani, perche&#8217; la famiglia e la sua composizione sono una volonta&#8217; di Dio e non dell&#8217;uomo, e&#8217; vietata l&#8217;adozione intesa come totale inserimento anagrafico dell&#8217;orfano in una nuova famiglia.<\/em><\/p>\n<p><em>Ma non puo&#8217; esserci vietato l&#8217;affido tramite kafala. Paradossalmente viene anche leso il diritto di protezione, l&#8217;unico esistente, che hanno i bambini orfani di estrazione Islamica.<\/em><\/p>\n<p><em>Ma secondo Lei perche&#8217; l&#8217;Italia si rifiuta di ratificare la Convenzione dell&#8217;Aja?<\/em><\/p>\n<p><em>Che possiamo fare noi nel frattempo, nel nostro piccolo?<\/em><\/p>\n<p><em>La ringrazio infinitamente anche a nome di tutti quei bambini che non hanno voce, ne&#8217; diritti.\u201d<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avere accolto un figlio, ma non potere vivere con lui. E\u2019 questo il dramma che riguarda una coppia mista residente nelle Marche che ha ottenuto in kafala Munir, un bambino egiziano, ma che non riesce a portarlo in Italia a vivere con s\u00e9 perch\u00e9 le autorit\u00e0 consolari italiane a Il Cairo hanno rifiutato cinque volte la richiesta di visto.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-14693","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall&#039;Italia - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall&#039;Italia\" \/>\n<meta property=\"og:description\" content=\"Avere accolto un figlio, ma non potere vivere con lui. E\u2019 questo il dramma che riguarda una coppia mista residente nelle Marche che ha ottenuto in kafala Munir, un bambino egiziano, ma che non riesce a portarlo in Italia a vivere con s\u00e9 perch\u00e9 le autorit\u00e0 consolari italiane a Il Cairo hanno rifiutato cinque volte la richiesta di visto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-14T16:20:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall&#8217;Italia\",\"datePublished\":\"2010-07-14T16:20:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/\"},\"wordCount\":445,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg\",\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/\",\"name\":\"Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall'Italia - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg\",\"datePublished\":\"2010-07-14T16:20:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg\",\"width\":150,\"height\":150},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall&#8217;Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall'Italia - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/","og_locale":"it_IT","og_type":"article","og_title":"Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall'Italia","og_description":"Avere accolto un figlio, ma non potere vivere con lui. E\u2019 questo il dramma che riguarda una coppia mista residente nelle Marche che ha ottenuto in kafala Munir, un bambino egiziano, ma che non riesce a portarlo in Italia a vivere con s\u00e9 perch\u00e9 le autorit\u00e0 consolari italiane a Il Cairo hanno rifiutato cinque volte la richiesta di visto.","og_url":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2010-07-14T16:20:01+00:00","og_image":[{"url":"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg","type":"","width":"","height":""}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall&#8217;Italia","datePublished":"2010-07-14T16:20:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/"},"wordCount":445,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg","articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/","url":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/","name":"Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall'Italia - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg","datePublished":"2010-07-14T16:20:01+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/Ai.Bi.-bambino-in-un-istituto-marocchino.jpg","width":150,"height":150},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/scandalo-mancata-ratifica-convenzione-aja-munir-bambino-orfano-rifiutato-5-volte-dallitalia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Scandalo mancata ratifica Convenzione Aja: Munir, bambino orfano rifiutato 5 volte dall&#8217;Italia"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:48:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/14693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=14693"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/14693\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=14693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=14693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=14693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}