﻿


{"id":148065,"date":"2017-11-02T15:14:51","date_gmt":"2017-11-02T14:14:51","guid":{"rendered":"https:\/\/www.aibi.it\/ita\/?p=148065"},"modified":"2017-11-02T15:14:51","modified_gmt":"2017-11-02T14:14:51","slug":"giornata-dei-defunti-bolivia","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/","title":{"rendered":"La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-148066 aligncenter\" src=\"https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia.jpg\" alt=\"\" width=\"634\" height=\"406\" srcset=\"https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia.jpg 634w, https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia-150x96.jpg 150w, https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia-300x192.jpg 300w, https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia-86x55.jpg 86w\" sizes=\"auto, (max-width: 634px) 100vw, 634px\" \/><\/p>\n<p>Negli istituti di La Paz, piccoli e grandi alle prese con i preparativi per accogliere le anime delle persone che se ne sono andate. Per loro \u00e8 stata \u00a0imbandita la tavola con\u00a0diverse paste, piatti, bevande e\u00a0dolci a forma di scala, sole, cavallo e tutte quelle forme che\u00a0hanno un significato soprattutto nelle culture Aymara e Quechua. Sulla tavola anche i biberon con del latte per i bambini che\u00a0non ci sono pi\u00f9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Negli istituti di La Paz, piccoli e grandi alle prese con i preparativi per accogliere le anime delle persone che se ne sono andate. Per loro \u00e8 stata \u00a0imbandita la tavola con\u00a0diverse paste, piatti, bevande e\u00a0dolci a forma di scala, sole, cavallo e tutte quelle forme che\u00a0hanno un significato soprattutto nelle culture Aymara e Quechua. Sulla tavola anche i biberon con del latte per i bambini che\u00a0non ci sono pi\u00f9.<\/p>\n","protected":false},"author":4,"featured_media":148066,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[],"class_list":["post-148065","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fotonotizia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9. - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9.\" \/>\n<meta property=\"og:description\" content=\"Negli istituti di La Paz, piccoli e grandi alle prese con i preparativi per accogliere le anime delle persone che se ne sono andate. Per loro \u00e8 stata \u00a0imbandita la tavola con\u00a0diverse paste, piatti, bevande e\u00a0dolci a forma di scala, sole, cavallo e tutte quelle forme che\u00a0hanno un significato soprattutto nelle culture Aymara e Quechua. Sulla tavola anche i biberon con del latte per i bambini che\u00a0non ci sono pi\u00f9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-02T14:14:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9.\",\"datePublished\":\"2017-11-02T14:14:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/\"},\"wordCount\":89,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bolivia_fotonotizia.jpg\",\"articleSection\":[\"Video &amp; Fotonotizia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/\",\"name\":\"La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9. - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bolivia_fotonotizia.jpg\",\"datePublished\":\"2017-11-02T14:14:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bolivia_fotonotizia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/bolivia_fotonotizia.jpg\",\"width\":634,\"height\":406},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/giornata-dei-defunti-bolivia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video &amp; Fotonotizia\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/fotonotizia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9. - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/","og_locale":"it_IT","og_type":"article","og_title":"La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9.","og_description":"Negli istituti di La Paz, piccoli e grandi alle prese con i preparativi per accogliere le anime delle persone che se ne sono andate. Per loro \u00e8 stata \u00a0imbandita la tavola con\u00a0diverse paste, piatti, bevande e\u00a0dolci a forma di scala, sole, cavallo e tutte quelle forme che\u00a0hanno un significato soprattutto nelle culture Aymara e Quechua. Sulla tavola anche i biberon con del latte per i bambini che\u00a0non ci sono pi\u00f9.","og_url":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2017-11-02T14:14:51+00:00","og_image":[{"width":634,"height":406,"url":"https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi."},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9.","datePublished":"2017-11-02T14:14:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/"},"wordCount":89,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia.jpg","articleSection":["Video &amp; Fotonotizia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/","url":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/","name":"La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9. - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/#primaryimage"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia.jpg","datePublished":"2017-11-02T14:14:51+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/#primaryimage","url":"https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia.jpg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/bolivia_fotonotizia.jpg","width":634,"height":406},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/giornata-dei-defunti-bolivia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"Video &amp; Fotonotizia","item":"https:\/\/www.aibi.it\/ita\/category\/fotonotizia\/"},{"@type":"ListItem","position":3,"name":"La giornata dei Defunti in Bolivia. Una tavola ricca di cibo per chi non c\u2019\u00e8 pi\u00f9."}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:16:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/148065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=148065"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/148065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media\/148066"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=148065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=148065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=148065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}