﻿


{"id":15,"date":"2008-07-01T16:02:16","date_gmt":"2008-07-01T14:02:16","guid":{"rendered":"http:\/\/www.amicideibambini.com\/?p=8"},"modified":"2008-07-01T16:02:16","modified_gmt":"2008-07-01T14:02:16","slug":"cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno","status":"publish","type":"post","link":"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/","title":{"rendered":"Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno"},"content":{"rendered":"<p>(Santiago) Secondo i dati del SENAME, l&#8217;autorit\u00e0 cilena che si occupa di adozioni, il 70% delle aspiranti famiglie adottive chiede di poter accogliere bambini con meno di un anno di et\u00e0. Solo il 19% \u00e8 disponibile ad adottare minori fino a 4 anni.<\/p>\n<p>Le aspettative delle coppie cilene che iniziano il percorso dell&#8217;adozione sono molto simili: entrambi i genitori desiderano un figlio sano, di qualche mese di et\u00e0 e con caratteristiche fisiche simili a quelle dei genitori. Tuttavia, come fanno sapere da una delle associazioni cilene che fa adozioni, la Fondazioni Mi Casa, nel lavoro di accompagnamento per i futuri genitori, spesso \u00e8 possibile ampliare la disponibilit\u00e0 di accoglienza e cos\u00ec l&#8217;aspirante famiglia adottiva si apre all&#8217;accoglienza di bambini pi\u00f9 grandi.<\/p>\n<p>Altro dato rilevante del sistema adozioni cileno \u00e8 il basso numero di minori accolti: nel 2007 sono stati 442 i bambini che hanno trovato una famiglia cilena disposti ad accoglierli, dato poco significativo se si considera la disponibilit\u00e0 di migliaia di coppie cilene e straniere.<\/p>\n<p><strong>(quotidiano cileno &#8220;El Mercurio&#8221;)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Santiago) Secondo i dati del SENAME, l&rsquo;autorit&agrave; cilena che si occupa di adozioni, il 70% delle aspiranti famiglie adottive chiede di poter accogliere bambini con meno di un anno di et&agrave;. Solo il 19% &egrave; disponibile ad adottare minori fino a 4 anni. Le aspettative delle coppie cilene che iniziano [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-15","post","type-post","status-publish","format-standard","category-aibinews"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno - Ai.Bi. Amici dei Bambini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno\" \/>\n<meta property=\"og:description\" content=\"(Santiago) Secondo i dati del SENAME, l&rsquo;autorit&agrave; cilena che si occupa di adozioni, il 70% delle aspiranti famiglie adottive chiede di poter accogliere bambini con meno di un anno di et&agrave;. Solo il 19% &egrave; disponibile ad adottare minori fino a 4 anni. Le aspettative delle coppie cilene che iniziano [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/\" \/>\n<meta property=\"og:site_name\" content=\"Ai.Bi. Amici dei Bambini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Amicideibambini\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-07-01T14:02:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Staff Ai.Bi.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:site\" content=\"@amicideibambini\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Staff Ai.Bi.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\\\/\"},\"author\":{\"name\":\"Staff Ai.Bi.\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\"},\"headline\":\"Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno\",\"datePublished\":\"2008-07-01T14:02:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\\\/\"},\"wordCount\":178,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"articleSection\":[\"AiBiNews\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\\\/\",\"name\":\"Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno - Ai.Bi. Amici dei Bambini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\"},\"datePublished\":\"2008-07-01T14:02:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AiBiNews\",\"item\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/category\\\/aibinews\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#website\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"description\":\"Il diritto di essere figlio\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#organization\",\"name\":\"Ai.Bi. Amici dei Bambini\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"contentUrl\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/images\\\/2024\\\/06\\\/logoAIBI.svg\",\"width\":500,\"height\":221,\"caption\":\"Ai.Bi. Amici dei Bambini\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Amicideibambini\\\/\",\"https:\\\/\\\/x.com\\\/amicideibambini\",\"https:\\\/\\\/www.instagram.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/430194\\\/\",\"https:\\\/\\\/it.pinterest.com\\\/amicideibambini\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AmicideiBambini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/#\\\/schema\\\/person\\\/3bceb270b8467ac3893c79c449b9045c\",\"name\":\"Staff Ai.Bi.\",\"url\":\"https:\\\/\\\/www.aibi.it\\\/ita\\\/author\\\/cellos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno - Ai.Bi. Amici dei Bambini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/","og_locale":"it_IT","og_type":"article","og_title":"Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno","og_description":"(Santiago) Secondo i dati del SENAME, l&rsquo;autorit&agrave; cilena che si occupa di adozioni, il 70% delle aspiranti famiglie adottive chiede di poter accogliere bambini con meno di un anno di et&agrave;. Solo il 19% &egrave; disponibile ad adottare minori fino a 4 anni. Le aspettative delle coppie cilene che iniziano [&hellip;]","og_url":"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/","og_site_name":"Ai.Bi. Amici dei Bambini","article_publisher":"https:\/\/www.facebook.com\/Amicideibambini\/","article_published_time":"2008-07-01T14:02:16+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.aibi.it\/ita\/images\/2020\/05\/aibi_fb.jpg","type":"image\/jpeg"}],"author":"Staff Ai.Bi.","twitter_card":"summary_large_image","twitter_creator":"@amicideibambini","twitter_site":"@amicideibambini","twitter_misc":{"Scritto da":"Staff Ai.Bi.","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/#article","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/"},"author":{"name":"Staff Ai.Bi.","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c"},"headline":"Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno","datePublished":"2008-07-01T14:02:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/"},"wordCount":178,"publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"articleSection":["AiBiNews"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/","url":"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/","name":"Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno - Ai.Bi. Amici dei Bambini","isPartOf":{"@id":"https:\/\/www.aibi.it\/ita\/#website"},"datePublished":"2008-07-01T14:02:16+00:00","breadcrumb":{"@id":"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.aibi.it\/ita\/cile-il-70-delle-famiglie-vuole-adottare-bimbi-con-meno-di-un-anno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aibi.it\/ita\/"},{"@type":"ListItem","position":2,"name":"AiBiNews","item":"https:\/\/www.aibi.it\/ita\/category\/aibinews\/"},{"@type":"ListItem","position":3,"name":"Cile: il 70% delle famiglie vuole adottare bimbi con meno di un anno"}]},{"@type":"WebSite","@id":"https:\/\/www.aibi.it\/ita\/#website","url":"https:\/\/www.aibi.it\/ita\/","name":"Ai.Bi. Amici dei Bambini","description":"Il diritto di essere figlio","publisher":{"@id":"https:\/\/www.aibi.it\/ita\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aibi.it\/ita\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.aibi.it\/ita\/#organization","name":"Ai.Bi. Amici dei Bambini","url":"https:\/\/www.aibi.it\/ita\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/","url":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","contentUrl":"https:\/\/www.aibi.it\/ita\/images\/2024\/06\/logoAIBI.svg","width":500,"height":221,"caption":"Ai.Bi. Amici dei Bambini"},"image":{"@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Amicideibambini\/","https:\/\/x.com\/amicideibambini","https:\/\/www.instagram.com\/amicideibambini\/","https:\/\/www.linkedin.com\/company\/430194\/","https:\/\/it.pinterest.com\/amicideibambini\/","https:\/\/www.youtube.com\/user\/AmicideiBambini"]},{"@type":"Person","@id":"https:\/\/www.aibi.it\/ita\/#\/schema\/person\/3bceb270b8467ac3893c79c449b9045c","name":"Staff Ai.Bi.","url":"https:\/\/www.aibi.it\/ita\/author\/cellos\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:30:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":0,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/posts\/15\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/media?parent=15"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/categories?post=15"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aibi.it\/ita\/wp-json\/wp\/v2\/tags?post=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}